{"id":99882,"date":"2025-03-19T13:29:46","date_gmt":"2025-03-19T13:29:46","guid":{"rendered":"https:\/\/www.ole.com.ar\/river-plate\/crespo-mundial-clubes-river-inter_0_7dtDzbguYg.html"},"modified":"2025-03-19T13:29:46","modified_gmt":"2025-03-19T13:29:46","slug":"crespo-palpito-el-mundial-de-clubes-y-dejo-un-aviso-todos-dirian-que-inter-es-superior-pero-ojo-con-river","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2025\/03\/19\/crespo-palpito-el-mundial-de-clubes-y-dejo-un-aviso-todos-dirian-que-inter-es-superior-pero-ojo-con-river\/","title":{"rendered":"Crespo palpit\u00f3 el Mundial de Clubes y dej\u00f3 un aviso: \u00abTodos dir\u00edan que Inter es superior, pero ojo con River\u00bb"},"content":{"rendered":"<p><img src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/03\/crespo-palpito-el-mundial-de-clubes-y-dejo-un-aviso-todos-dirian-que-inter-es-superior-pero-ojo-con-river.jpg\"><\/p>\n<p><time class=\"createDate\" datetime=\"2025-03-19T10:29:46-03:00\">19\/03\/2025 10:29hs.<\/time><\/p>\n<div id=\"storyBody\">\n<div class=\"custom-text \" readability=\"37.19587628866\">\n<p><a href=\"https:\/\/www.ole.com.ar\/tema\/hernan-crespo.html\" title=\"Hern\u00e1n Crespo\" alt=\"Hern\u00e1n Crespo\" class=\"slug\">Hern\u00e1n Crespo<\/a> fue uno de los grandes goleadores argentinos de las \u00faltimas d\u00e9cadas. Cuarto artillero hist\u00f3rico de la <a href=\"https:\/\/www.ole.com.ar\/tema\/seleccion-argentina.html\" title=\"Selecci\u00f3n Argentina\" alt=\"Selecci\u00f3n Argentina\" class=\"slug\">Selecci\u00f3n<\/a>, Valdanito se hizo grande en <a href=\"https:\/\/www.ole.com.ar\/tema\/river-plate.html\" title=\"River Plate\" alt=\"River Plate\" class=\"slug\">River<\/a>, donde conquist\u00f3 la Libertadores 1996 como figura, y luego llev\u00f3 sus gritos al Viejo Continente, donde se destac\u00f3 en varios equipos. Uno de ellos fue el<strong> <a href=\"https:\/\/www.ole.com.ar\/tema\/internazionale.html\" title=\"Internazionale\" alt=\"Internazionale\" class=\"slug\">Inter<\/a>, que ser\u00e1 rival de su amado CARP en el Mundial de Clubes<\/strong> que tendr\u00e1 lugar a mitad de a\u00f1o en los Estados Unidos. \u00bfLo ve con chances al equipo de Gallardo?<\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"39\">\n<p>\u00abEst\u00e1 dif\u00edcil, <strong>son dos clubes grandes que se enfrentan y cuando eso pasa cualquier cosa puede pasar.<\/strong> Es l\u00f3gico que uno piense siempre que el equipo Europeo es superior al equipo sudamericano, porque en Europa vienen a comprar a Sudam\u00e9rica y supuestamente los mejores van para Europa y deber\u00eda haber un desnivel. Pero es una competencia por grupos, hay una situaci\u00f3n de resultados alrededor y todo puede pasar\u00bb, asegur\u00f3 Crespo.<\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"38\">\n<p>En esa l\u00ednea, el DT campe\u00f3n de la Sudamericana con Defensa y Justicia le deja una ventana abierta al CARP para dar el golpe: <strong>\u00abTodos dir\u00edan que el Inter es superior, pero River es River. Ojo con River porque puede, no digo dar la sorpresa porque son grandes equipos, pero todo puede pasar&#8230;\u00bb.<\/strong><\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"36\">\n<p>Por otra parte, si bien dijo que <strong>\u00abla l\u00f3gica dice que los favoritos deber\u00edan ser los europeos\u00bb<\/strong>, Valdanito marc\u00f3 como una posible ventaja que \u00abellos est\u00e1n en el final de la temporada y los sudamericanos que les podr\u00edan competir est\u00e1n en la mitad\u00bb.<\/p>\n<\/div>\n<div class=\"sc-e7b891c4-0 ifHnQL image-embed\"><img alt=\"Crespo gan\u00f3 la Libertadores con River en 1996.\" loading=\"lazy\" width=\"720\" height=\"100\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/03\/crespo-palpito-el-mundial-de-clubes-y-dejo-un-aviso-todos-dirian-que-inter-es-superior-pero-ojo-con-river-2.jpg\"><span class=\"epigraphe\">Crespo gan\u00f3 la Libertadores con River en 1996.<\/span><\/div>\n<div class=\"custom-text \" readability=\"38\">\n<p>No obstante, en charla con ESPN, tambi\u00e9n sostuvo que \u00abel recorrido para ser campe\u00f3n del mundo conlleva siete partidos, lo que significa que ten\u00e9s que tener un plantel amplio y de alt\u00edsimo nivel, as\u00ed que <strong>no se le deber\u00eda escapar a un Europeo\u00bb.<\/strong><\/p>\n<\/div>\n<p><h2>Los otros rivales de River<\/h2>\n<\/p>\n<div class=\"custom-text \" readability=\"37\">\n<p>Adem\u00e1s de Inter, River deber\u00e1 enfrentar en fase de grupos a <strong>Urawa Reds de Ja\u00f3n y Rayados de M\u00e9xico,<\/strong> actualmente dirigido por otro nacido en N\u00fa\u00f1ez como Mart\u00edn Demichelis. Para Crespo, ning\u00fan rival ser\u00e1 sencillo.<\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"39\">\n<p>\u00abEl grupo es muy complicado. Tuvimos la posibilidad de seguir un poquito a Urawa, tiene una defensa muy fuerte.<strong> Los equipos japoneses no han perdido finales salvo con nosotros Al Ain, culturalmente son muy competitivos\u00bb,<\/strong> asegur\u00f3 Crespo, quien gan\u00f3 la Copa de Campeones de Asia en 2024 con el equipo de Emiratos \u00c1rabes. <\/p>\n<\/div>\n<div class=\"sc-e7b891c4-0 ifHnQL image-embed\"><img alt=\"En 2024 gan\u00f3 la Champions de Asia con Al Ain (EFE).\" loading=\"lazy\" width=\"720\" height=\"100\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/03\/crespo-palpito-el-mundial-de-clubes-y-dejo-un-aviso-todos-dirian-que-inter-es-superior-pero-ojo-con-river-3.jpg\"><span class=\"epigraphe\">En 2024 gan\u00f3 la Champions de Asia con Al Ain (EFE).<\/span><\/div>\n<div class=\"custom-text \" readability=\"38\">\n<p>Y sigui\u00f3: \u00abA Monterrey no lo voy a descubrir yo, siempre es un equipo competitivo, hace grandes competiciones, va a ser muy dif\u00edcil todo. Imaginate las sensaciones que tiene un pa\u00eds atr\u00e1s de un Mundial, pero ahora con tu club. Va a ser una locura\u00bb.<\/p>\n<\/div>\n<p><h2>El sue\u00f1o de dirigir a River<\/h2>\n<\/p>\n<div class=\"custom-text \" readability=\"39\">\n<p>\u00abEl \u00fanico lugar donde me gustar\u00eda dirigir, siempre respetando los lugares que un colega tiene, que es Marcelo Gallardo, por mi pasado en River es normal anhelar, el d\u00eda de ma\u00f1ana estar ah\u00ed. <strong>Pero no lo veo inminente volver a dirigir en el f\u00fatbol argentino.<\/strong> S\u00ed tengo muchas ganas de seguir probando por el mundo\u00bb.<\/p>\n<\/div>\n<div class=\"sc-e7b891c4-0 ifHnQL image-embed\"><img alt=\"Crespo, como DT de Defensa, ovacionado en el Monumental (FOTO MARCELO CARROLL).\" loading=\"lazy\" width=\"720\" height=\"100\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/03\/crespo-palpito-el-mundial-de-clubes-y-dejo-un-aviso-todos-dirian-que-inter-es-superior-pero-ojo-con-river-4.jpg\"><span class=\"epigraphe\">Crespo, como DT de Defensa, ovacionado en el Monumental (FOTO MARCELO CARROLL).<\/span><\/div>\n<div class=\"sc-a7166897-0 eoLsBE\" readability=\"7.5\">\n<section readability=\"5\"><picture><img alt=\"Juli\u00e1n \u00c1lvarez, en la mejor temporada de su carrera antes de enfrentar a Uruguay y Brasil: sus goles, asistencias y m\u00e1s\" loading=\"lazy\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/03\/crespo-palpito-el-mundial-de-clubes-y-dejo-un-aviso-todos-dirian-que-inter-es-superior-pero-ojo-con-river-5.jpg\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>Juli\u00e1n \u00c1lvarez, en la mejor temporada de su carrera antes de enfrentar a Uruguay y Brasil: sus goles, asistencias y m\u00e1s<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<div class=\"sc-a7166897-0 eoLsBE\" readability=\"6.5\">\n<section readability=\"3\"><picture><img alt=\"Con muchas ausencias, River pone primera en una de las Copas favoritas de Gallardo\" loading=\"lazy\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/03\/crespo-palpito-el-mundial-de-clubes-y-dejo-un-aviso-todos-dirian-que-inter-es-superior-pero-ojo-con-river-6.jpg\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>Con muchas ausencias, River pone primera en una de las Copas favoritas de Gallardo<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<div class=\"sc-a7166897-0 eoLsBE\" readability=\"6\">\n<section readability=\"2\"><picture><img alt=\"Video: Gallardo sali\u00f3 a saludar y emocion\u00f3 a los hinchas en Santiago del Estero\" loading=\"lazy\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/03\/crespo-palpito-el-mundial-de-clubes-y-dejo-un-aviso-todos-dirian-que-inter-es-superior-pero-ojo-con-river-7.jpg\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>Video: Gallardo sali\u00f3 a saludar y emocion\u00f3 a los hinchas en Santiago del Estero<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>19\/03\/2025 10:29hs. Hern\u00e1n Crespo fue uno de los grandes goleadores argentinos de las \u00faltimas d\u00e9cadas. Cuarto artillero hist\u00f3rico de la Selecci\u00f3n, Valdanito se hizo grande en River, donde conquist\u00f3 la Libertadores 1996 como figura, y luego llev\u00f3 sus gritos al Viejo Continente, donde se destac\u00f3 en varios equipos. Uno de ellos fue el Inter, que [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":99883,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[16],"tags":[],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/99882"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=99882"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/99882\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media\/99883"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=99882"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=99882"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=99882"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}