{"id":99224,"date":"2025-03-12T04:39:00","date_gmt":"2025-03-12T04:39:00","guid":{"rendered":"http:\/\/hoycordobaweb.com\/index.php\/2025\/03\/12\/cocaina-adulterada-el-25-de-abril-arranca-el-juicio-contra-mameluco-villalba-y-su-banda-por-los-22-fallecidos\/"},"modified":"2025-03-12T04:39:00","modified_gmt":"2025-03-12T04:39:00","slug":"cocaina-adulterada-el-25-de-abril-arranca-el-juicio-contra-mameluco-villalba-y-su-banda-por-los-22-fallecidos","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2025\/03\/12\/cocaina-adulterada-el-25-de-abril-arranca-el-juicio-contra-mameluco-villalba-y-su-banda-por-los-22-fallecidos\/","title":{"rendered":"Coca\u00edna adulterada: el 25 de abril arranca el juicio contra \u00abMameluco\u00bb Villalba y su banda por los 22 fallecidos"},"content":{"rendered":"<div class=\"media_block\"><\/div>\n<div><img src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/03\/cocaina-adulterada-el-25-de-abril-arranca-el-juicio-contra-mameluco-villalba-y-su-banda-por-los-22-fallecidos.jpg\" class=\"ff-og-image-inserted\"><\/div>\n<p>El <strong>Tribunal Oral Federal (TOF) n\u00famero 5 de San Mart\u00edn<\/strong> fij\u00f3 para el pr\u00f3ximo <strong>25 de abril<\/strong> el inicio del juicio contra <a target=\"_blank\" href=\"https:\/\/www.perfil.com\/noticias\/politica\/cuneo-libarona-desmintio-haber-defendido-al-capo-narco-mameluco-villalba.phtml\" rel=\"noopener noreferrer\"><strong>Miguel \u00c1ngel \u201cMameluco\u201d Villalba<\/strong><\/a>, por haber vendido, en febrero de 2022, <a target=\"_blank\" href=\"https:\/\/www.perfil.com\/noticias\/policia\/acusan-a-mameluco-villalba-de-lavar-22-millones-por-dia.phtml\" rel=\"noopener noreferrer\"><strong>coca\u00edna con carfentanilo<\/strong><\/a>, que caus\u00f3 la muerte de <strong>24 personas<\/strong> en Tres de Febrero y la Villa 18. El hombre lideraba una organizaci\u00f3n delictiva integrada por su hijo <a target=\"_blank\" href=\"https:\/\/www.perfil.com\/noticias\/politica\/de-narcotraficante-a-intendente-peronista-20100328-0004.phtml\" rel=\"noopener noreferrer\"><strong>Iv\u00e1n Gabriel<\/strong><\/a> y otros 18 miembros, quienes tambi\u00e9n ser\u00e1n juzgados.<\/p>\n<p>La investigaci\u00f3n contra \u201cMameluco\u201d comenz\u00f3 en 2020 como desprendimiento de otro expediente, aunque en ese momento el hombre ya estaba en la c\u00e1rcel de Rawson, <strong>cumpliendo una pena a 27 a\u00f1os de prisi\u00f3n por narcomenudeo y lavado de activos<\/strong>, pero su organizaci\u00f3n igual segu\u00eda trabajando. El a\u00f1o pasado, adem\u00e1s, <a target=\"_blank\" href=\"https:\/\/www.perfil.com\/noticias\/sociedad\/absolvieron-a-mameluco-villalba-por-el-crimen-de-candela-rodriguez-y-se-dio-de-baja-la-hipotesis-de-venganza.phtml\" rel=\"noopener noreferrer\">Villalba fue absuelto<\/a> por el secuestro y muerte de Candela Rodr\u00edguez. <\/p>\n<p>La <strong>jueza federal Alicia Vence y el fiscal Paul Starc<\/strong> les recriminaron a los Villalba la comercializaci\u00f3n de coca\u00edna con carfentanilo porque, a pesar de las muertes que ya se hab\u00edan registrado, <strong>ten\u00edan m\u00e1s droga de ese tipo para vender<\/strong>; incluso varios integrantes de su banda, catalogados como \u201cprobadores de droga\u201d, debieron ser hospitalizados tras ingerir una dosis.<\/p>\n<div class=\"subscription\" readability=\"6.683257918552\">\n<p> Esto no les gusta a los autoritarios <\/p>\n<div class=\"subscription__container\" readability=\"6.1467391304348\">\n<div class=\"subscription__text-wrapper\" readability=\"31.20652173913\">\n<p> El ejercicio del periodismo profesional y cr\u00edtico es un pilar fundamental de la democracia. Por eso molesta a quienes creen ser los due\u00f1os de la verdad. <\/p>\n<\/p><\/div><\/div><\/div>\n<p class=\"destacadoNota\"><a target=\"_blank\" href=\"https:\/\/www.perfil.com\/noticias\/judiciales\/el-juicio-por-la-muerte-de-diego-maradona-minuto-a-minuto-los-abogados-pediran-la-absolucion-de-leopoldo-luque-y-agustina-cosachov.phtml\" rel=\"noopener noreferrer\">El d\u00eda 1 del juicio por la muerte de Maradona expuso \u00abun teatro del horror\u00bb y se pidi\u00f3 la absoluci\u00f3n de los acusados<\/a><\/p>\n<p>La magistrada envi\u00f3 a juicio a <strong>Villalba<\/strong> por la venta de la coca\u00edna con carfentanilo, aunque \u00e9ste habr\u00eda dicho que pretend\u00eda retirar del mercado la droga tras enterarse de la muerte de algunos clientes, lo cual todav\u00eda no pudo ser comprobado.<\/p>\n<p>En la investigaci\u00f3n tambi\u00e9n particip\u00f3 la DEA, cuyas autoridades declararon que <strong>la droga con carfentanilo es cien veces m\u00e1s potente que el fentanilo<\/strong>, la sustancia que actualmente provoca desastres en todo Estados Unidos y Europa.<\/p>\n<h2>La tragedia por la venta de coca\u00edna con carfentanilo <\/h2>\n<p>El 1 de febrero del 2022, los <em>transas <\/em>de \u201cMameluco\u201d vendieron bolsas con <strong>coca\u00edna adulterada, de color rosa, en la difusa zona conocida como Puerta 8<\/strong>, un asentamiento del noroeste bonaerense, entre la Ruta 8 y el Camino del Buen Ayre, un matadero, el arroyo Mor\u00f3n y m\u00e1s all\u00e1 los basurales del Ceamse. Esa madrugada, <strong>casi un centenar de personas tuvieron que ser hospitalizadas <\/strong>producto de una intoxicaci\u00f3n causada por la mezcla del estupefaciente y el opioide.<\/p>\n<p>Tr\u00e1gicamente, <strong>24 personas murieron<\/strong> y desde el Ministerio de Salud provincial se debi\u00f3 emitir una \u00abalerta epidemiol\u00f3gica\u00bb ante \u00abla identificaci\u00f3n de casos con signos de shock, depresi\u00f3n del sensorio, dificultad respiratoria, excitaci\u00f3n psicomotriz\u201d en casos de consumo reciente de coca\u00edna. Incluso, el exministro de Seguridad provincial, <strong>Sergio Berni<\/strong>, inst\u00f3 a quienes hab\u00edan comprado estupefacientes durante esas 24 horas a que <strong>\u00abdescarten la droga\u00bb<\/strong>.<\/p>\n<p><em>HM\/ML<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Tribunal Oral Federal (TOF) n\u00famero 5 de San Mart\u00edn fij\u00f3 para el pr\u00f3ximo 25 de abril el inicio del juicio contra Miguel \u00c1ngel \u201cMameluco\u201d Villalba, por haber vendido, en febrero de 2022, coca\u00edna con carfentanilo, que caus\u00f3 la muerte de 24 personas en Tres de Febrero y la Villa 18. El hombre lideraba una [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":99225,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[19],"tags":[1044,1045,1043,1046,1047],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/99224"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=99224"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/99224\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media\/99225"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=99224"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=99224"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=99224"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}