{"id":94447,"date":"2025-01-16T23:35:17","date_gmt":"2025-01-16T23:35:17","guid":{"rendered":"https:\/\/www.ole.com.ar\/futbol-internacional\/contundente-frase-medel-salida-boca_0_xHQ7Yon1Aj.html"},"modified":"2025-01-16T23:35:17","modified_gmt":"2025-01-16T23:35:17","slug":"la-contundente-frase-de-medel-tras-su-salida-de-boca-no-me-sentia-feliz","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2025\/01\/16\/la-contundente-frase-de-medel-tras-su-salida-de-boca-no-me-sentia-feliz\/","title":{"rendered":"La contundente frase de Medel tras su salida de Boca: \u00abNo me sent\u00eda feliz\u00bb"},"content":{"rendered":"<p><img src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/01\/la-contundente-frase-de-medel-tras-su-salida-de-boca-no-me-sentia-feliz.jpg\"><\/p>\n<p><time class=\"createDate\" datetime=\"2025-01-16T20:35:17-03:00\">16\/01\/2025 20:35hs.<\/time><\/p>\n<div id=\"storyBody\">\n<div class=\"custom-text \" readability=\"37.601049868766\">\n<p>Tras un paso intrascendente por el f\u00fatbol argentino, el experimentado defensor chileno y bicampe\u00f3n de Am\u00e9rica regres\u00f3 a su pa\u00eds, donde fue anunciado oficialmente como refuerzo de <strong>Universidad Cat\u00f3lica<\/strong> para la pr\u00f3xima temporada. Durante su presentaci\u00f3n con Los Cruzados dej\u00f3 una fuerte declaraci\u00f3n sobre su etapa en <strong><a href=\"https:\/\/www.ole.com.ar\/boca-juniors\" target=\"_blank\" title=\"Boca\" alt=\"Boca\" rel=\"noopener noreferrer\">Boca<\/a><\/strong>, donde remarco<strong> que no fue feliz durante su estad\u00eda.<\/strong><\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"37\">\n<p>El chileno arrib\u00f3 en la \u00faltima etapa de <strong>Diego Mart\u00ednez<\/strong>, t\u00e9cnico que ya no lo ten\u00eda demasiado en cuenta. Tras la llegada de <strong>Fernando Gago<\/strong>, el defensor qued\u00f3 m\u00e1s marginado. La falta de oportunidades llev\u00f3 al chileno a la necesidad de cerrar la etapa y sumarse a Universidad Cat\u00f3lica para as\u00ed recuperar el protagonismo al que acostumbr\u00f3 durante su trayectoria como futbolista.<\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"36\">\n<p>Con Gago, apenas disputo 40 minutos repartidos entre dos partidos (derrota contra Lan\u00fas y victoria ante Uni\u00f3n). La relaci\u00f3n futbol\u00edstica entre ellos nunca fue buena, <strong>Pintita lo tuvo muy poco en cuenta e incluso se supo por un amigo de Medel que su concepto sobre el DT es que es \u00abraro\u00bb.<\/strong><\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"35\">\n<p>Consultado sobre c\u00f3mo la pas\u00f3 en Boca en el \u00faltimo tiempo, Medel respondi\u00f3: <strong>\u00abEstaba jugando poco y no era feliz.<\/strong> Necesitaba volver a encontrarme conmigo mismo y la alegr\u00eda del f\u00fatbol que siento al estar adentro de la cancha\u00bb.<\/p>\n<\/div>\n<div class=\"sc-e7b891c4-0 ifHnQL image-embed\"><img alt=\"El chileno apenas disput\u00f3 11 partidos con el Xeneize.\" loading=\"lazy\" width=\"720\" height=\"100\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/01\/la-contundente-frase-de-medel-tras-su-salida-de-boca-no-me-sentia-feliz-2.jpg\"><span class=\"epigraphe\">El chileno apenas disput\u00f3 11 partidos con el Xeneize.<\/span><\/div>\n<div class=\"custom-text \" readability=\"39\">\n<p>A pesar de no haberse mostrado conforme tras su paso por el club, el defensor chileno les agradeci\u00f3 a sus ex compa\u00f1eros y a los dirigentes: <strong>\u00abObviamente, estoy agradecido con Boca porque siempre me trataron bien: Juan Rom\u00e1n (Riquelme), mis compa\u00f1eros, la dirigencia; les estoy agradecido a ellos\u00bb.<\/strong><\/p>\n<\/div>\n<p><h2><strong>Video: la confesi\u00f3n de Medel<\/strong><\/h2>\n<\/p>\n<div class=\"sc-734b4696-1 kFfZtB\" readability=\"6\">\n<div class=\"sc-d00d9e74-0 hnHYbk vertical\" type=\"embed\">\n<div class=\"sc-d00d9e74-1 iKVbz videoText\" id=\"contentTitleembedDBJeCWGQ\" type=\"embed\"><svg fill=\"#ffffff\"><symbol id=\"play\" viewBox=\"0 0 512 512\"><path d=\"M512 256C512 397.4 397.4 512 256 512C114.6 512 0 397.4 0 256C0 114.6 114.6 0 256 0C397.4 0 512 114.6 512 256zM176 168V344C176 352.7 180.7 360.7 188.3 364.9C195.8 369.2 205.1 369 212.5 364.5L356.5 276.5C363.6 272.1 368 264.4 368 256C368 247.6 363.6 239.9 356.5 235.5L212.5 147.5C205.1 142.1 195.8 142.8 188.3 147.1C180.7 151.3 176 159.3 176 168V168z\" \/><\/symbol><use xlink:href=\"#play\" \/><\/svg><\/p>\n<div class=\"right\">\n<p>Gary Medel<!-- --> &#8211; <span>&nbsp;<\/span><\/p>\n<h2 class=\"title-vid\">La explicaci\u00f3n de Medel sobre por qu\u00e9 se fue de Boca<\/h2>\n<\/div>\n<\/div>\n<p><span class=\"back\" id=\"spanBackembedDBJeCWGQ\"><\/span><\/div>\n<div class=\"JWvideoNota_title\" readability=\"7\">\n<p>Cr\u00e9ditos: @espnargentina<\/p>\n<\/div>\n<\/div>\n<p><h2><strong>Gary Medel, de regreso a casa<\/strong><\/h2>\n<\/p>\n<div class=\"custom-text \" readability=\"35.158008658009\">\n<p>Universidad Cat\u00f3lica busca reforzarse de la mejor manera tras un 2024 en el que los resultados no fueron los esperados para el club. Los Cruzados quedaron eliminados tempranamente del torneo continental y no pudieron mantenerse en la lucha por el t\u00edtulo de la liga chilena. Finalmente, terminaron en el quinto puesto de la tabla con 46 puntos, perdiendo en las \u00faltimas fechas la oportunidad de asegurar un lugar en la fase previa de la <strong><a href=\"https:\/\/www.ole.com.ar\/futbol-internacional\/libertadores?gad_source=1&amp;gclid=Cj0KCQiA-aK8BhCDARIsAL_-H9kz77d488lw4VQF6kzutwXMnjBkMcAWj9cCy947R0ImNLuSjdIc6LcaAla3EALw_wcB\" target=\"_blank\" title=\"Copa Libertadores 2025.\" alt=\"Copa Libertadores 2025.\" rel=\"noopener noreferrer\">Copa Libertadores 2025.<\/a><\/strong><\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"37\">\n<p>Tras su llegada, Gary Medel expres\u00f3 su deseo de defender la camiseta del cuadro chileno durante mucho tiempo y so\u00f1ar con la posibilidad de conquistar t\u00edtulos para el club: \u00abVengo con muchos m\u00e1s a\u00f1os. Estuve jugando poco y tengo que empezar a agarrar ritmo. Estamos haciendo una mini pretemporada. <strong>Quiero aportar jerarqu\u00eda, experiencia y dar lo mejor por el club para lograr cosas importantes\u00bb. <\/strong><\/p>\n<\/div>\n<div class=\"sc-e7b891c4-0 ifHnQL image-embed\"><img alt=\"Gary Medel sum\u00f3 un total de 80 partidos con Los Cruzados durante su etapa entre 2006 y 2009. EFE\/ Elvis Gonz\u00e1lez\" loading=\"lazy\" width=\"720\" height=\"100\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/01\/la-contundente-frase-de-medel-tras-su-salida-de-boca-no-me-sentia-feliz-3.jpg\"><span class=\"epigraphe\">Gary Medel sum\u00f3 un total de 80 partidos con Los Cruzados durante su etapa entre 2006 y 2009. EFE\/ Elvis Gonz\u00e1lez<\/span><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>16\/01\/2025 20:35hs. Tras un paso intrascendente por el f\u00fatbol argentino, el experimentado defensor chileno y bicampe\u00f3n de Am\u00e9rica regres\u00f3 a su pa\u00eds, donde fue anunciado oficialmente como refuerzo de Universidad Cat\u00f3lica para la pr\u00f3xima temporada. Durante su presentaci\u00f3n con Los Cruzados dej\u00f3 una fuerte declaraci\u00f3n sobre su etapa en Boca, donde remarco que no fue [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":94448,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[16],"tags":[],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/94447"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=94447"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/94447\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media\/94448"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=94447"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=94447"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=94447"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}