{"id":93774,"date":"2025-01-10T17:44:12","date_gmt":"2025-01-10T17:44:12","guid":{"rendered":"https:\/\/www.trendencias.com\/upeka\/como-funciona-cerebro-personas-autistas-nos-adentramos-lleno-para-saber-todo-que-no-han-preguntado-antes"},"modified":"2025-01-10T17:44:12","modified_gmt":"2025-01-10T17:44:12","slug":"como-funciona-el-cerebro-de-las-personas-autistas-nos-adentramos-de-lleno-para-saber-todo-lo-que-no-han-preguntado-antes","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2025\/01\/10\/como-funciona-el-cerebro-de-las-personas-autistas-nos-adentramos-de-lleno-para-saber-todo-lo-que-no-han-preguntado-antes\/","title":{"rendered":"\u00bfC\u00f3mo funciona el cerebro de las personas autistas? Nos adentramos de lleno para saber todo lo que no han preguntado antes"},"content":{"rendered":"<p>Seguro que alguna vez has pensado qu\u00e9 pasa por la cabeza de las personas y es que hay mentes tan diferentes a las nuestras que nos hacen plantearnos est\u00e1 pregunta. <strong>Ning\u00fan ser humano tiene exactamente el mismo <\/strong>y el funcionamiento tambi\u00e9n var\u00eda, por eso hoy vamos a ver uno de ellos para entenderlo por completo.<\/p>\n<p><!-- BREAK 1 --> <\/p>\n<p>En <strong>Upeka by Aegon<\/strong> esta semana aprendemos en el nuevo programa todo sobre el autismo y c\u00f3mo son las personas que est\u00e1n dentro de esta diversidad ya que en nuestro pa\u00eds forman parte de ella una gran poblaci\u00f3n y es casi necesario saber c\u00f3mo son. Muchos no entienden c\u00f3mo una persona autista es diferente a otra y la clave est\u00e1 en su cerebro ya que no trabaja igual que el de una persona normativa y de ah\u00ed que su comportamiento o forma de ser var\u00ede y gracias a<a rel=\"noopener, noreferrer\" href=\"https:\/\/www.instagram.com\/raquelmascaraque\/\"> Raquel Mascaraque <\/a>conocemos todo lo que sucede dentro de nuestras cabezas y de las personas que viven dentro del especto autista que seguro que nos va a dejar con la boca abierta.<\/p>\n<p><!-- BREAK 2 --><\/p>\n<div class=\"article-asset article-asset-normal article-asset-center\">\n<div class=\"desvio-container\">\n<div class=\"desvio\">\n<div class=\"desvio-figure js-desvio-figure\"> <a href=\"https:\/\/www.trendencias.com\/upeka\/como-vivir-autismo-aprendemos-senales-improtantes-para-su-diagnostico\" class=\"pivot-outboundlink\" data-vars-post-title=\"\u00bfC\u00f3mo es vivir con autismo? Aprendemos las se\u00f1ales m\u00e1s improtantes para su diagn\u00f3stico \"> <img loading=\"lazy\" alt=\"\u00bfC\u00f3mo es vivir con autismo? Aprendemos las se\u00f1ales m\u00e1s improtantes para su diagn\u00f3stico \" width=\"375\" height=\"142\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/01\/como-funciona-el-cerebro-de-las-personas-autistas-nos-adentramos-de-lleno-para-saber-todo-lo-que-no-han-preguntado-antes.jpg\"> <\/a> <\/div><\/div><\/div>\n<\/div>\n<p>Para entenderlo, debemos saber de primeras que<strong> el cerebro se comunica a trav\u00e9s de conexiones<\/strong> y las neuronas tienen como forma de \u00e1rbol con ramas llamadas dentritas y tronco por donde pasa la informaci\u00f3n. Entonces dependiendo del tama\u00f1o y de la forma, los mensajes pasan de una manera m\u00e1s clara o confusa llegando incluso a no comunicar nada. La forma en que realiza esta tarea un cerebro neurotipico en comparaci\u00f3n con uno autista es diferente por el tama\u00f1o de las dentritas.<\/p>\n<p><!-- BREAK 3 --> <\/p>\n<p>Todo esto adem\u00e1s se intensifica por la <a rel=\"noopener, noreferrer\" href=\"https:\/\/es.wikipedia.org\/wiki\/Poda_neuronal#:~:text=neurol%C3%B3gicos%20y%20neuropsiqui%C3%A1tricos.-,Trastornos,la%20informaci%C3%B3n%20en%20los%20circuitos.\">poda sin\u00e1ptica<\/a> ya que nacemos con muchas m\u00e1s neuronas de las que necesitamos cuando somos adultos y desechamos las que no necesitamos como ocurre por ejemplo con los tel\u00e9fonos m\u00f3viles. En las personas autistas, este proceso de desechar neuronas es solo de un 15% y el resto de personas de un 45% por lo que<strong> las personas con esta patolog\u00eda tienen m\u00e1s terminaciones nerviosas.<\/strong><\/p>\n<p><!-- BREAK 4 --><\/p>\n<p>Por lo tanto, toda esa cantidad de dentritas que tienen en cantidad son las que hacen que<strong> las personas autistas perciban el mundo de manera distinta<\/strong> a nivel sensorial y en los patrones de comportamiento. Que un cerebro sea diferente no significa que sea malo, sino que es distinto y es igual de v\u00e1lido que el resto.<\/p>\n<p><!-- BREAK 5 --><\/p>\n<p>Amamoz aprender todo sobre nuestra mente y del resto del munco para poder tener una armon\u00eda com\u00fan. Y t\u00fa, \u00bfLo sab\u00edas?<\/p>\n<p>Im\u00e1genes | <a rel=\"noopener, noreferrer\" href=\"https:\/\/www.instagram.com\/upeka_oficial\/\">@upeka_oficial<\/a> y Foto de <a rel=\"noopener, noreferrer\" href=\"https:\/\/unsplash.com\/es\/@averey?utm_content=creditCopyText&amp;utm_medium=referral&amp;utm_source=unsplash\">Robina Weermeijer<\/a> en <a rel=\"noopener, noreferrer\" href=\"https:\/\/unsplash.com\/es\/fotos\/decoracion-de-cerebro-marron-en-la-fotografia-de-enfoque-selectivo-3KGF9R_0oHs?utm_content=creditCopyText&amp;utm_medium=referral&amp;utm_source=unsplash\">Unsplash<\/a><\/p>\n<p>En Trendencias |<a class=\"text-outboundlink\" href=\"https:\/\/www.trendencias.com\/silver\/7-ideas-origami-faciles-que-ideales-para-reducir-estres-mejorar-capacidad-mental\" data-vars-post-title=\"7 ideas de origami f\u00e1ciles que son ideales para reducir el estr\u00e9s y mejorar la capacidad mental\" data-vars-post-url=\"https:\/\/www.trendencias.com\/silver\/7-ideas-origami-faciles-que-ideales-para-reducir-estres-mejorar-capacidad-mental\">7 ideas de origami f\u00e1ciles que son ideales para reducir el estr\u00e9s y mejorar la capacidad mental<\/a><\/p>\n<p>En Trendencias | <a class=\"text-outboundlink\" href=\"https:\/\/www.trendencias.com\/sexo-y-relaciones\/sexo-mujeres-a-partir-50-que-hay-que-saber-nunca-te-atreviste-a-preguntar\" data-vars-post-title=\"Sexo en las mujeres a partir de los 50: lo que hay que saber y nunca te atreviste a preguntar\" data-vars-post-url=\"https:\/\/www.trendencias.com\/sexo-y-relaciones\/sexo-mujeres-a-partir-50-que-hay-que-saber-nunca-te-atreviste-a-preguntar\">Sexo en las mujeres a partir de los 50: lo que hay que saber y nunca te atreviste a preguntar<\/a>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Seguro que alguna vez has pensado qu\u00e9 pasa por la cabeza de las personas y es que hay mentes tan diferentes a las nuestras que nos hacen plantearnos est\u00e1 pregunta. Ning\u00fan ser humano tiene exactamente el mismo y el funcionamiento tambi\u00e9n var\u00eda, por eso hoy vamos a ver uno de ellos para entenderlo por completo. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":93775,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[],"tags":[],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/93774"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=93774"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/93774\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media\/93775"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=93774"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=93774"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=93774"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}