{"id":9217,"date":"2021-01-05T09:00:45","date_gmt":"2021-01-05T09:00:45","guid":{"rendered":"https:\/\/www.espinof.com\/directores-y-guionistas\/guia-mank-conoce-mundo-herman-mankiewicz-hollywood-dorado-que-retrata-pelicula-netflix-david-fincher"},"modified":"2021-01-05T09:00:45","modified_gmt":"2021-01-05T09:00:45","slug":"la-guia-de-mank-conoce-el-mundo-de-herman-mankiewicz-en-el-hollywood-dorado-que-retrata-la-pelicula-de-netflix-y-david-fincher","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2021\/01\/05\/la-guia-de-mank-conoce-el-mundo-de-herman-mankiewicz-en-el-hollywood-dorado-que-retrata-la-pelicula-de-netflix-y-david-fincher\/","title":{"rendered":"La gu\u00eda de \u2018Mank\u2019: conoce el mundo de Herman Mankiewicz en el Hollywood dorado que retrata la pel\u00edcula de Netflix y David Fincher"},"content":{"rendered":"<p>Lleg\u00f3 tarde, pero no tanto como para quedarse fuera de muchas de las listas de lo mejor de 2020. &#8216;<a href=\"https:\/\/www.espinof.com\/tag\/mank\">Mank<\/a>&#8216;, la pel\u00edcula de <a href=\"https:\/\/www.espinof.com\/tag\/david-fincher\">David Fincher<\/a> para Netflix, se ha convertido en una de las indispensables de buena parte de la actual cinefilia online. Herman Mankiewicz, co-escritor de &#8216;<a href=\"https:\/\/www.espinof.com\/tag\/ciudadano-kane\">Ciudadano Kane<\/a>&#8216; fue <strong>un genio autodestructivo<\/strong> a quien la historia hab\u00eda olvidado injustamente y la pel\u00edcula de Fincher lo ha colocado en boca de todos.<\/p>\n<p><!-- BREAK 1 --><\/p>\n<h2>El hombre en la sombra<\/h2>\n<p>Como suele pasar despu\u00e9s de ver una pel\u00edcula biogr\u00e1fica o leer un libro del estilo, son muchas las preguntas que se agolpan en nuestras cabezas. La principal, claro, concierne a Herman Mankiewicz, a quien los Fincher, padre e hijo, dan <strong>una visi\u00f3n completamente subjetiva<\/strong>, alimentada por su deseo conjunto de poner al guionista de &#8216;Ciudadano Kane&#8217; en el lugar que le corresponde y de colocar los m\u00e9ritos de su director, Orson Welles, en un nivel algo m\u00e1s discreto. \u00bfFue realmente \u00abMank\u00bb un genio de la escritura incomprendido? M\u00e1s o menos, eso parece, salvo que es dif\u00edcil evaluar su contribuci\u00f3n real a la edad de oro de Hollywood, ya que no se le atribuye ninguna pel\u00edcula importante, excepto la de Welles.<\/p>\n<p><!-- BREAK 2 --> <\/p>\n<div class=\"article-asset article-asset-normal article-asset-center\">\n<div class=\"desvio-container\">\n<div class=\"desvio\">\n<div class=\"desvio-figure js-desvio-figure\"> <a href=\"https:\/\/www.espinof.com\/listas\/mejores-peliculas-biograficas-historia-cine\"> <img alt=\"Las 22 mejores pel\u00edculas biogr\u00e1ficas de la historia del cine\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2021\/01\/la-guia-de-mank-conoce-el-mundo-de-herman-mankiewicz-en-el-hollywood-dorado-que-retrata-la-pelicula-de-netflix-y-david-fincher.jpg\"> <\/a> <\/div><\/div><\/div>\n<\/div>\n<p>Nacido el 7 de noviembre de 1897 en Nueva York, Herman es el mayor de tres hermanos. Graduado en la prestigiosa Universidad de Columbia a la edad de 19 a\u00f1os, se uni\u00f3 al ej\u00e9rcito y sirvi\u00f3 en los marines, hasta que se convirti\u00f3 en corresponsal del Chicago Tribune en Berl\u00edn. De regreso a Estados Unidos en 1922, escribi\u00f3 para Vanity Fair, The New York Times y The New Yorker. Su pluma es brillante y popular, y acabar\u00e1 teniendo su parcela en La Table Ronde de l&#8217;Algonquin, un club privado para intelectuales de la Costa Este, local reservado a miembros tan selectos como los dramaturgos Noel Coward y George S. Kaufman, el compositor Irving Berlin, la poeta Dorothy Parker o el mism\u00edsimo Harpo Marx. Herman Mankiewicz era entonces <strong>un nombre importante<\/strong>. Hasta el punto de despertar el inter\u00e9s del destacado productor de Paramount, Walter Wanger, quien lo llev\u00f3 a California en 1926. Ah\u00ed comienza una nueva vida para Mankiewicz, interpretado por Gary Oldman en un papel que ya hizo suyo <a href=\"https:\/\/www.espinof.com\/tag\/john-malkovich\">John Malkovich<\/a> en la &#8216;RKO 281&#8217; de Benjamin Ross hace m\u00e1s de veinte a\u00f1os.<\/p>\n<p><!-- BREAK 3 --><\/p>\n<p>Como reflejaba &#8216;<a href=\"https:\/\/www.espinof.com\/criticas\/barton-fink-el-infierno-del-escritor\">Barton Fink<\/a>&#8216; a la perfecci\u00f3n, la vida de los guionistas en aquel Hollywood era una llena de frustraci\u00f3n e ira, a pesar de los d\u00f3lares que llenaban sus bolsillos. La historiadora y cr\u00edtica Pauline Kael afirmaba que entre 1927 y 1928, <em>Mank<\/em> habr\u00eda escrito los r\u00edtulos explicativos de m\u00e1s de 20 pel\u00edculas mudas. <strong>Casi siempre pegado a la botella<\/strong>, sus borracheras con Ben Hecht, futuro guionista de Lubitsch y Hitchcock, eran antol\u00f3gicas. Analista de guiones antes de que se inventase el t\u00e9rmino, retoca todo lo que le llega (sin que se le acredite la mayor parte del tiempo), definiendo de manera informal un estilo sarc\u00e1stico.<\/p>\n<p><!-- BREAK 4 --><\/p>\n<div class=\"article-asset-image article-asset-normal article-asset-center\">\n<div class=\"asset-content\"> <img class=\"sf-lazy centro_sinmarco\" data-sf-srcset=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2021\/01\/la-guia-de-mank-conoce-el-mundo-de-herman-mankiewicz-en-el-hollywood-dorado-que-retrata-la-pelicula-de-netflix-y-david-fincher-1.jpg 450w, http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2021\/01\/la-guia-de-mank-conoce-el-mundo-de-herman-mankiewicz-en-el-hollywood-dorado-que-retrata-la-pelicula-de-netflix-y-david-fincher-4.jpg 681w,http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2021\/01\/la-guia-de-mank-conoce-el-mundo-de-herman-mankiewicz-en-el-hollywood-dorado-que-retrata-la-pelicula-de-netflix-y-david-fincher-5.jpg 1024w, http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2021\/01\/la-guia-de-mank-conoce-el-mundo-de-herman-mankiewicz-en-el-hollywood-dorado-que-retrata-la-pelicula-de-netflix-y-david-fincher-6.jpg 1366w,\" data-sf-src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2021\/01\/la-guia-de-mank-conoce-el-mundo-de-herman-mankiewicz-en-el-hollywood-dorado-que-retrata-la-pelicula-de-netflix-y-david-fincher-1.jpg\" alt=\"welles mank\"> <noscript><img alt=\"welles mank\" class=\"centro_sinmarco\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2021\/01\/la-guia-de-mank-conoce-el-mundo-de-herman-mankiewicz-en-el-hollywood-dorado-que-retrata-la-pelicula-de-netflix-y-david-fincher-1.jpg\"><\/noscript> <\/div>\n<\/div>\n<p>Herman Mankiewicz ya est\u00e1 en todas partes (est\u00e1 detr\u00e1s de la explosi\u00f3n de los <a href=\"https:\/\/www.espinof.com\/tag\/hermanos-marx\">Hermanos Marx<\/a> en Paramount) y en ninguna parte al mismo tiempo. <strong>Despreciado por los estudios<\/strong> por sus maneras (llega tarde al trabajo o borracho, acumula deudas de juego), es a su vez constantemente reclamado por su instinto. Fue \u00e9l, por ejemplo, quien tuvo la deslumbrante idea de filmar en color el mundo imaginario de &#8216;<a href=\"https:\/\/www.espinof.com\/tag\/el-mago-de-oz\">El mago de Oz<\/a>&#8216;. Sin acreditar, por supuesto. Hablando de los Marx, Louis B. Mayer, poco fan de los hermanos, aparece en la pel\u00edcula de Fincher interpretado por Arliss Howard. Su gran valedor, Irving Thalberg, tambi\u00e9n se deja ver en la piel de Ferdinand Kingsley.<\/p>\n<p><!-- BREAK 5 --><\/p>\n<p>La pel\u00edcula de David Fincher comienza en 1939, despu\u00e9s de un accidente automovil\u00edstico que Herman tuvo en Nuevo M\u00e9xico y que lo obligar\u00e1 a quedarse paralizado mientras se recupera. Es en este contexto particular en el que Orson Welles (<a href=\"https:\/\/www.espinof.com\/tag\/tom-burke\">Tom Burke<\/a> en la pel\u00edcula de Fincher) se pone en contacto con \u00e9l para escribir de tapadillo la que se convertir\u00e1 en <strong>una de las pel\u00edculas m\u00e1s influyentes de la historia del cine<\/strong>. Lo hizo con la intenci\u00f3n de derribar al magnate William Randolph Hearst, interpretado en la pel\u00edcula por Charles Dance e inspiraci\u00f3n para el personaje de Kane. As\u00ed, tambi\u00e9n tomar\u00e1 como referencia a su amante, Marion Davies (interpretada por <a href=\"https:\/\/www.espinof.com\/tag\/amanda-seyfried\">Amanda Seyfried<\/a>) para el papel de Susan Alexander Kane.<\/p>\n<p><!-- BREAK 6 --><\/p>\n<div class=\"article-asset-image article-asset-normal article-asset-center\">\n<div class=\"asset-content\"> <img class=\"sf-lazy centro_sinmarco\" data-sf-srcset=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2021\/01\/la-guia-de-mank-conoce-el-mundo-de-herman-mankiewicz-en-el-hollywood-dorado-que-retrata-la-pelicula-de-netflix-y-david-fincher-2.jpg 450w, http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2021\/01\/la-guia-de-mank-conoce-el-mundo-de-herman-mankiewicz-en-el-hollywood-dorado-que-retrata-la-pelicula-de-netflix-y-david-fincher-7.jpg 681w,http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2021\/01\/la-guia-de-mank-conoce-el-mundo-de-herman-mankiewicz-en-el-hollywood-dorado-que-retrata-la-pelicula-de-netflix-y-david-fincher-8.jpg 1024w, http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2021\/01\/la-guia-de-mank-conoce-el-mundo-de-herman-mankiewicz-en-el-hollywood-dorado-que-retrata-la-pelicula-de-netflix-y-david-fincher-9.jpg 1366w,\" data-sf-src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2021\/01\/la-guia-de-mank-conoce-el-mundo-de-herman-mankiewicz-en-el-hollywood-dorado-que-retrata-la-pelicula-de-netflix-y-david-fincher-2.jpg\" alt=\"Welles\"> <noscript><img alt=\"Welles\" class=\"centro_sinmarco\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2021\/01\/la-guia-de-mank-conoce-el-mundo-de-herman-mankiewicz-en-el-hollywood-dorado-que-retrata-la-pelicula-de-netflix-y-david-fincher-2.jpg\"><\/noscript> <\/div>\n<\/div>\n<p>Consciente de la obra maestra que ha escrito, el guionista, con el respaldo del Gremio de Escritores, <strong>luchar\u00e1 contra Welles por ser mencionado<\/strong> en los cr\u00e9ditos. En 1942 gan\u00f3, junto con Welles, el Oscar al gui\u00f3n de &#8216;Ciudadano Kane&#8217;.\u200b Seg\u00fan Pauline Kael, \u00ab<em>Mankiewicz ten\u00eda abundantes pruebas de su autor\u00eda, y cuando las llev\u00f3 a la Screen Writers Guild Welles se vio obligado a compartir los cr\u00e9ditos y a ocupar el segundo lugar<\/em>\u00ab.<\/p>\n<p><!-- BREAK 7 --><\/p>\n<p>El resto de la historia es un constante declive, hasta su muerte en 1953 como consecuencia de su alcoholismo. Antes de su tr\u00e1gico final, habr\u00e1 sido testigo del ascenso al poder de su hermano peque\u00f1o, un tal Joseph L. Mankiewicz, a quien llev\u00f3 a Paramount en 1929 y que ser\u00e1 el autor de obras maestras de como &#8216;El fantasma y la se\u00f1ora Muir&#8217;, &#8216;Eva al desnudo&#8217;, &#8216;La Condesa Descalza&#8217; o &#8216;<a href=\"https:\/\/www.espinof.com\/tag\/cleopatra\">Cleopatra<\/a>&#8216;. Agradecido, <strong>Joseph pagar\u00e1 las deudas de su hermano mayor<\/strong>. Un hermano mayor que se mostr\u00f3 protector hasta el final, advirti\u00e9ndole sobre los peligros de la camarilla montada en su contra por Cecil B. DeMille y los <em>McCarthyistas para<\/em> denunciar sus ideas comunistas. DeMille reuni\u00f3 a un grupo de cineastas y tras varios discursos lleg\u00f3 el turno de <a href=\"https:\/\/www.espinof.com\/tag\/john-ford\">John Ford<\/a>, conocido por sus ideas conservadoras. \u00ab<em>Mi nombre es John Ford, hago pel\u00edculas del oeste. No me gustas, Cecil, y no me gusta lo que has estado diciendo hoy aqu\u00ed. Propongo que le demos un voto de confianza a Joe y luego nos vayamos a casa a dormir un rato<\/em>\u00ab. Eso dar\u00eda para otra pel\u00edcula tan interesante como la de Fincher. Probablemente m\u00e1s.<\/p>\n<p><!-- BREAK 8 --> <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lleg\u00f3 tarde, pero no tanto como para quedarse fuera de muchas de las listas de lo mejor de 2020. &#8216;Mank&#8216;, la pel\u00edcula de David Fincher para Netflix, se ha convertido en una de las indispensables de buena parte de la actual cinefilia online. Herman Mankiewicz, co-escritor de &#8216;Ciudadano Kane&#8216; fue un genio autodestructivo a quien [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":9218,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/9217"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=9217"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/9217\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media\/9218"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=9217"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=9217"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=9217"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}