{"id":90739,"date":"2024-12-09T03:46:44","date_gmt":"2024-12-09T03:46:44","guid":{"rendered":"https:\/\/www.ole.com.ar\/basquet\/liga-nacional-gimnasia-union-basquet_0_mrhXC9WnRj.html"},"modified":"2024-12-09T03:46:44","modified_gmt":"2024-12-09T03:46:44","slug":"gimnasia-se-recupero-y-volvio-a-la-victoria","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2024\/12\/09\/gimnasia-se-recupero-y-volvio-a-la-victoria\/","title":{"rendered":"Gimnasia se recuper\u00f3 y volvi\u00f3 a la victoria"},"content":{"rendered":"<p><img src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2024\/12\/gimnasia-se-recupero-y-volvio-a-la-victoria.jpg\"><\/p>\n<p><time class=\"createDate\" datetime=\"2024-12-09T00:46:44-03:00\">09\/12\/2024 00:46hs.<\/time><\/p>\n<div id=\"storyBody\">\n<div class=\"custom-text \" readability=\"41\">\n<p>Despu\u00e9s de su gira por Formosa y Corrientes donde cosech\u00f3 una victoria (La Uni\u00f3n) y dos derrotas (Regatas y San Mart\u00edn),<strong> Gimnasia y Esgrima de Comodoro Rivadavia volvi\u00f3 a su casa y se reencontr\u00f3 con el triunfo gracias a gran una muestra de car\u00e1cter. <\/strong>Con un trabajo preciso, sin fisuras, con clase, intensidad y mucho coraz\u00f3n, el Mens Sana se hizo gigante desde el primer minuto y termin\u00f3 llev\u00e1ndose una c\u00f3moda victoria por 91-79 ante Uni\u00f3n. En un Socios Fundadores colmado, hubo fiesta completa para el Verde que busca empezar a escalar posiciones y terminar el a\u00f1o dentro del Top 10.<\/p>\n<\/div>\n<p><h2><strong>Gimnasia 91-79 Uni\u00f3n<\/strong><\/h2>\n<\/p>\n<div class=\"custom-text \" readability=\"39\">\n<p>En un primer cuarto igualado, el encuentro tuvo un comienzo de ida y vuelta por parte de ambos equipos. No se sacaron diferencia en los primeros minutos, destac\u00e1ndose Andre Nation por el lado de Gimnasia y Randy Bell por la visita, pero en la parte final del cuarto, <strong>el conjunto santafesino logr\u00f3 sacar diferencia con un triple de Yeferson Guerra para cerrarlo 23-21.<\/strong><\/p>\n<\/div>\n<div class=\"sc-e7b891c4-0 ifHnQL image-embed\"><img alt=\"Gimnasia le gan\u00f3 a Uni\u00f3n (LNB).\" loading=\"lazy\" width=\"720\" height=\"100\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2024\/12\/gimnasia-se-recupero-y-volvio-a-la-victoria-2.jpg\"><span class=\"epigraphe\">Gimnasia le gan\u00f3 a Uni\u00f3n (LNB).<\/span><\/div>\n<div class=\"custom-text \" readability=\"37\">\n<p>Durante el segundo per\u00edodo, el Verde pudo dar vuelta el marcador (31-28) gracias a los triples de Emiliano Toretta y Anyelo Cisneros. A partir de ah\u00ed, con buenas transiciones ofensiva<strong>s, Gimnasia se fue al descanso arriba por 46-37.<\/strong><\/p>\n<\/div>\n<div class=\"sc-e7b891c4-0 ifHnQL image-embed\"><img alt=\"Gimnasia le gan\u00f3 a Uni\u00f3n (LNB).\" loading=\"lazy\" width=\"720\" height=\"100\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2024\/12\/gimnasia-se-recupero-y-volvio-a-la-victoria-3.jpg\"><span class=\"epigraphe\">Gimnasia le gan\u00f3 a Uni\u00f3n (LNB).<\/span><\/div>\n<div class=\"custom-text \" readability=\"37\">\n<p>Tras el descanso, el comienzo de la segunda mitad continu\u00f3 favorable para el local que aprovech\u00f3 las ofensivas de Jalen Jenkins y Martiniano Dato para seguir estirando la diferencia a veinti\u00fan puntos (58-37) en el marcador. A pesar de los intentos por parte de Uni\u00f3n con Mauro Cosolito y Marcos Cabot, <strong>el tercer cuarto se lo llev\u00f3 Gimnasia por 68-51.<\/strong><\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"36\">\n<p>En el \u00faltimo per\u00edodo, el conjunto patag\u00f3nico mantuvo la diferencia a su favor a lo largo del cuarto<strong>, donde poco a poco lo fue cerrando, el encuentro finaliz\u00f3 91-79.<\/strong><\/p>\n<\/div>\n<div class=\"sc-a7166897-0 eoLsBE\" readability=\"6\">\n<section readability=\"2\"><picture><img alt=\"Quimsa le gan\u00f3 a Ferro y sigue invicto de local\" loading=\"lazy\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2024\/12\/gimnasia-se-recupero-y-volvio-a-la-victoria-4.jpg\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>Quimsa le gan\u00f3 a Ferro y sigue invicto de local<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<div class=\"sc-a7166897-0 eoLsBE\" readability=\"6\">\n<section readability=\"2\"><picture><img alt=\"Liga Nacional: Ober\u00e1 es el nuevo puntero y c\u00f3mo est\u00e1 la tabla\" loading=\"lazy\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2024\/12\/gimnasia-se-recupero-y-volvio-a-la-victoria-5.jpg\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>Liga Nacional: Ober\u00e1 es el nuevo puntero y c\u00f3mo est\u00e1 la tabla<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>09\/12\/2024 00:46hs. Despu\u00e9s de su gira por Formosa y Corrientes donde cosech\u00f3 una victoria (La Uni\u00f3n) y dos derrotas (Regatas y San Mart\u00edn), Gimnasia y Esgrima de Comodoro Rivadavia volvi\u00f3 a su casa y se reencontr\u00f3 con el triunfo gracias a gran una muestra de car\u00e1cter. Con un trabajo preciso, sin fisuras, con clase, intensidad [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":90740,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[16],"tags":[],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/90739"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=90739"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/90739\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media\/90740"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=90739"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=90739"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=90739"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}