{"id":82550,"date":"2024-09-03T11:22:30","date_gmt":"2024-09-03T11:22:30","guid":{"rendered":"https:\/\/ladecimaweb.com\/?p=28922"},"modified":"2024-09-03T11:22:30","modified_gmt":"2024-09-03T11:22:30","slug":"corre-pero-igual-lo-alcanzan","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2024\/09\/03\/corre-pero-igual-lo-alcanzan\/","title":{"rendered":"Corre, pero igual lo alcanzan"},"content":{"rendered":"<div class=\"boldgrid-section\">\n<div class=\"container\">\n<div class=\"row\">\n<div class=\"col-md-12 col-xs-12 col-sm-12\">\n<p class>Un sujeto de 40 a\u00f1os con pedido de captura y que circulaba como pasajero a bordo de un taxi, fue detenido en las \u00faltimas horas en B\u00ba Las Palmas luego de huir ante un control preventivo instalado en la zona.<\/p>\n<p class>Mientras personal policial se dispon\u00eda a controlar el veh\u00edculo de alquiler en inmediaciones de calles Santa Ana y Cordero, este individuo emprendi\u00f3 la fuga arrojando una punta de destornillador en el asiento trasero.<\/p>\n<p class>A ra\u00edz de ello, se despleg\u00f3 un operativo logrando interceptar al sujeto en el sector.<\/p>\n<p class>El aprehendido fue puesto a disposici\u00f3n de la justicia junto a lo incautado.<\/p>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" title=\"Corre, corre...\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/wiZ7u8clwrg?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>La entrada <a rel=\"nofollow\" href=\"https:\/\/ladecimaweb.com\/corre-pero-igual-lo-alcanzan\/\">Corre, pero igual lo alcanzan<\/a> se public\u00f3 primero en <a rel=\"nofollow\" href=\"https:\/\/ladecimaweb.com\">LaDecima<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un sujeto de 40 a\u00f1os con pedido de captura y que circulaba como pasajero a bordo de un taxi, fue detenido en las \u00faltimas horas en B\u00ba Las Palmas luego de huir ante un control preventivo instalado en la zona. Mientras personal policial se dispon\u00eda a controlar el veh\u00edculo de alquiler en inmediaciones de calles [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[32],"tags":[],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/82550"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=82550"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/82550\/revisions"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=82550"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=82550"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=82550"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}