{"id":82515,"date":"2024-09-02T09:01:56","date_gmt":"2024-09-02T09:01:56","guid":{"rendered":"https:\/\/www.ole.com.ar\/futbol-internacional\/libertadores\/copa-libertadores-valor-equipos-lugar-ocupa-river_0_nKC9tqCeEv.html"},"modified":"2024-09-02T09:01:56","modified_gmt":"2024-09-02T09:01:56","slug":"copa-libertadores-el-valor-de-los-ocho-equipos-y-que-lugar-ocupa-river","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2024\/09\/02\/copa-libertadores-el-valor-de-los-ocho-equipos-y-que-lugar-ocupa-river\/","title":{"rendered":"Copa Libertadores: el valor de los ocho equipos y qu\u00e9 lugar ocupa River"},"content":{"rendered":"<p><img src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2024\/09\/copa-libertadores-el-valor-de-los-ocho-equipos-y-que-lugar-ocupa-river.jpg\"><\/p>\n<p><time class=\"createDate\" datetime=\"2024-09-02T06:01:56-03:00\">02\/09\/2024 06:01hs.<\/time><\/p>\n<div id=\"storyBody\">\n<div class=\"custom-text \" readability=\"42.163187855787\">\n<p><strong>La principal diferencia entre los equipos que siguen en la lucha por la <a href=\"https:\/\/www.ole.com.ar\/tema\/copa-libertadores.html\" title=\"Copa Libertadores\" alt=\"Copa Libertadores\" class=\"slug\">Copa Libertadores 2024<\/a> se encuentra, sin duda, en lo econ\u00f3mico.<\/strong> El valor de los planteles a menudo se traduce en poder\u00edo deportivo, aunque no siempre asegura el \u00e9xito, claro. Inversiones millonarias muchas veces terminan en frustraci\u00f3n, mientras que otros, con presupuestos m\u00e1s modestos, apuestan por llegar lejos. Sin embargo,<strong> en las \u00faltimas ediciones de la m\u00e1xima competici\u00f3n de Sudam\u00e9rica, la billetera de los equipos de Brasil ha prevalecido.<\/strong><\/p>\n<\/div>\n<p><h2><strong><em>Copa Libertadores: River, en el Top de equipos con mayor valor<\/em><\/strong><\/h2>\n<\/p>\n<div class=\"custom-text \" readability=\"39.534090909091\">\n<p>Los valores de los planteles de los equipos que a\u00fan pelean por este certamen continental reflejan las marcadas desigualdades econ\u00f3micas en el f\u00fatbol sudamericano. Seg\u00fan el sitio Transfermarkt.es, <strong><a href=\"https:\/\/www.ole.com.ar\/tema\/flamengo.html\" title=\"Flamengo\" alt=\"Flamengo\" class=\"slug\">Flamengo <\/a>lidera con un plantel valorado en 194,80 millones de euros.<\/strong> Al incre\u00edble plantel que ya pose\u00eda Tite, con figuras como Pedro, <a href=\"https:\/\/www.ole.com.ar\/tema\/nico-de-la-cruz.html\" title=\"Nico De la Cruz\" alt=\"Nico De la Cruz\" class=\"slug\">De La Cruz<\/a> y <a href=\"https:\/\/www.ole.com.ar\/tema\/giorgian-de-arrascaeta.html\" title=\"Giorgian De Arrascaeta\" alt=\"Giorgian De Arrascaeta\" class=\"slug\">De Arrascaeta<\/a>, sumaron en este per\u00edodo de transferencias a Charly Alcaraz (valor de 15.000.000 de euros), Michel (7.000.000), Gonzalo Plata (6.000.000) y Alex Sandro (2.000.000).<\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"37.730061349693\">\n<p><strong><a href=\"https:\/\/www.ole.com.ar\/tema\/river-plate.html\" title=\"River Plate\" alt=\"River Plate\" class=\"slug\">River <\/a>ha dado un notable salto de calidad, con respecto a la n\u00f3mina que present\u00f3 <a href=\"https:\/\/www.ole.com.ar\/tema\/martin-demichelis.html\" title=\"Martin Demichelis\" alt=\"Martin Demichelis\" class=\"slug\">Mart\u00edn Demichelis<\/a> en la fase de grupos<\/strong>. Con la vuelta de <a href=\"https:\/\/www.ole.com.ar\/tema\/marcelo-gallardo.html\" title=\"Marcelo Gallardo\" alt=\"Marcelo Gallardo\" class=\"slug\">Marcelo Gallardo<\/a> al Monumental, varios futbolsitas de peso decidieron vestir la camiseta del Millonario para esta instancia final. Fabricio Bustos (7.000.000), Marcos Acu\u00f1a (4.000.000), Maxi Meza (4.000.000) y Germ\u00e1n Pezzella (3.000.000) llevaron a que <strong>el CARP ocupe la segunda posici\u00f3n de este ranking, con un valor de 124,70 millones de euros.<\/strong><\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"41.946666666667\">\n<p><strong><a href=\"https:\/\/www.ole.com.ar\/tema\/botafogo.html\" title=\"botafogo\" alt=\"botafogo\" class=\"slug\">Botafogo<\/a><\/strong>, por su parte, ocupa el tercer lugar entre los equipos con mayor valor en esta instancia de la Copa Libertadores, con una cotizacion de 113,70 millones de euros. A pesar de haber incorporado a nombres como Matheus Martins (7.000.000), Vitinho (5.000.000) y Allan (3.500.000), <strong>quien sin dudas ha inclinado la balanza es <a href=\"https:\/\/www.ole.com.ar\/tema\/thiago-almada.html\" title=\"Thiago Almada\" alt=\"Thiago Almada\" class=\"slug\">Thiago Almada<\/a>, con un valor de 27.000.000 de euros<\/strong>, el 2\u00b0 m\u00e1s alto de la Libertaadores, detr\u00e1s de Estevao (30.000.000).<\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"39.325635103926\">\n<p>M\u00e1s all\u00e1 de las cifras astron\u00f3micas de los gigantes brasile\u00f1os y argentinos,<strong> existen clubes que, con planteles de menor valor, han logrado llegar lejos en la competencia<\/strong>. Equipos como<strong> <a href=\"https:\/\/www.ole.com.ar\/tema\/atletico-mineiro.html\" title=\"Atletico Mineiro\" alt=\"Atletico Mineiro\" class=\"slug\">Atl\u00e9tico Mineiro<\/a><\/strong> (104,90 millones), <strong><a href=\"https:\/\/www.ole.com.ar\/tema\/fluminense.html\" title=\"Fluminense\" alt=\"Fluminense\" class=\"slug\">Fluminense <\/a><\/strong>(99,05 millones) y <strong><a href=\"https:\/\/www.ole.com.ar\/tema\/sao-paulo.html\" title=\"Sao Paulo\" alt=\"Sao Paulo\" class=\"slug\">S\u00e3o Paulo<\/a><\/strong> (93,35 millones) mantienen la competitividad en la elite del f\u00fatbol sudamericano, pero enfrentan una presi\u00f3n constante por justificar sus inversiones con resultados.<\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"42.444906444906\">\n<p>En contraste, clubes como <strong><a href=\"https:\/\/www.ole.com.ar\/tema\/colo-colo.html\" title=\"colo colo\" alt=\"colo colo\" class=\"slug\">Colo Colo<\/a> y <a href=\"https:\/\/www.ole.com.ar\/tema\/penarol.html\" title=\"Pe\u00f1arol\" alt=\"Pe\u00f1arol\" class=\"slug\">Pe\u00f1arol<\/a>, con planteles valorados en 23,85 millones y 28,95 millones de euros respectivamente<\/strong>, muestran que, aunque las diferencias econ\u00f3micas sean abismales, el coraz\u00f3n y la estrategia tambi\u00e9n juegan un papel crucial en la Copa Libertadores. A lo largo de la historia del torneo, han habido ejemplos de equipos con presupuestos mucho menores que lograron superar a gigantes. En esta edici\u00f3n, \u00bfcontinuar\u00e1 la tendencia o habr\u00e1 sorpresas?<\/p>\n<\/div>\n<div class=\"sc-e7b891c4-0 ifHnQL\"><img alt=\"El River del Mu\u00f1eco, entre los ocho mejores de Am\u00e9rica. (EFE)\" loading=\"lazy\" width=\"720\" height=\"100\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2024\/09\/copa-libertadores-el-valor-de-los-ocho-equipos-y-que-lugar-ocupa-river-2.jpg\"><span class=\"epigraphe\">El River del Mu\u00f1eco, entre los ocho mejores de Am\u00e9rica. (EFE)<\/span><\/div>\n<p><h2><strong><em>Copa Libertadores: el valor de los ocho equipos en 4tos.<\/em><\/strong><\/h2>\n<\/p>\n<div class=\"custom-text \">\n<ol>\n<li>Flamengo \u2013 194,80 millones de euros<\/li>\n<li>River Plate \u2013 124,70 millones de euros<\/li>\n<li>Botafogo \u2013 113,70 millones de euros<\/li>\n<li>Atl\u00e9tico Mineiro \u2013 104,90 millones de euros<\/li>\n<li>Fluminense \u2013 99,05 millones euros<\/li>\n<li>Sao Paulo \u2013 93,35 millones de euros<\/li>\n<li>Pe\u00f1arol \u2013 28,95 millones de euros<\/li>\n<li>Colo Colo \u2013 23,85 millones de euros<\/li>\n<\/ol>\n<\/div>\n<div class=\"sc-e7b891c4-0 ifHnQL\"><img alt=\"Flamengo, el equipo con mayor valor de esta Copa Libertadores. (REUTER)\" loading=\"lazy\" width=\"720\" height=\"100\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2024\/09\/copa-libertadores-el-valor-de-los-ocho-equipos-y-que-lugar-ocupa-river-3.jpg\"><span class=\"epigraphe\">Flamengo, el equipo con mayor valor de esta Copa Libertadores. (REUTER)<\/span><\/div>\n<div class=\"sc-a7166897-0 eoLsBE\" readability=\"6.5\">\n<section readability=\"3\"><picture><img alt=\"Video: la paliza en la platea de Independiente, en el 0-0 ante River\" loading=\"lazy\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2024\/09\/copa-libertadores-el-valor-de-los-ocho-equipos-y-que-lugar-ocupa-river-4.jpg\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>Video: la paliza en la platea de Independiente, en el 0-0 ante River<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<div class=\"sc-a7166897-0 eoLsBE\" readability=\"6\">\n<section readability=\"2\"><picture><img alt=\"Un muy flojo River no pudo con un bravo Independiente\" loading=\"lazy\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2024\/09\/copa-libertadores-el-valor-de-los-ocho-equipos-y-que-lugar-ocupa-river-5.jpg\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>Un muy flojo River no pudo con un bravo Independiente<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<div class=\"sc-a7166897-0 eoLsBE\" readability=\"6.5\">\n<section readability=\"3\"><picture><img alt=\"Selecci\u00f3n: c\u00f3mo le fue a los futbolistas argentinos antes de jugar las Eliminatorias\" loading=\"lazy\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2024\/09\/copa-libertadores-el-valor-de-los-ocho-equipos-y-que-lugar-ocupa-river-6.jpg\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>Selecci\u00f3n: c\u00f3mo le fue a los futbolistas argentinos antes de jugar las Eliminatorias<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>02\/09\/2024 06:01hs. La principal diferencia entre los equipos que siguen en la lucha por la Copa Libertadores 2024 se encuentra, sin duda, en lo econ\u00f3mico. El valor de los planteles a menudo se traduce en poder\u00edo deportivo, aunque no siempre asegura el \u00e9xito, claro. Inversiones millonarias muchas veces terminan en frustraci\u00f3n, mientras que otros, con [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":82516,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[16],"tags":[],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/82515"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=82515"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/82515\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media\/82516"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=82515"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=82515"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=82515"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}