{"id":81781,"date":"2024-08-16T15:00:54","date_gmt":"2024-08-16T15:00:54","guid":{"rendered":"https:\/\/ladecimaweb.com\/?p=28676"},"modified":"2024-08-16T15:00:54","modified_gmt":"2024-08-16T15:00:54","slug":"de-que-discriminacion-nos-acusan","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2024\/08\/16\/de-que-discriminacion-nos-acusan\/","title":{"rendered":"\u00bfDe qu\u00e9 discriminaci\u00f3n nos acusan?"},"content":{"rendered":"<div class=\"boldgrid-section\">\n<div class=\"container\">\n<div class=\"row\">\n<div class=\"col-md-12 col-xs-12 col-sm-12\">\n<p class><em>(Mario Albera)<\/em> En noviembre de 2008, sali\u00f3 a la calle el primer n\u00famero de La D\u00e9cima. Aquella edici\u00f3n gr\u00e1fica, tra\u00eda en sus dos p\u00e1ginas centrales una nota con im\u00e1genes a color y una cr\u00f3nica del festejo de Urkupi\u00f1a de agosto de ese a\u00f1o. <strong>Recuerdo a algunos comerciantes y vecinos cuestionarme por haberle brindado ese espacio generoso a una fiesta de inmigrantes lim\u00edtrofes.&nbsp;<\/strong><\/p>\n<p class>Transcurrieron 15 a\u00f1os desde entonces, y nuestro peri\u00f3dico mantuvo su l\u00ednea editorial pluralista y barrial pese a las cr\u00edticas, y Urkupi\u00f1a se afianz\u00f3 como un evento religioso masivo, todo un atractivo para Villa El Libertador. Cada vez m\u00e1s vecinos y vecinas se suman a los festejos sinti\u00e9ndolo como propio por m\u00e1s que est\u00e9 vinculado con la adoraci\u00f3n de una virgen milagrosa boliviana.&nbsp;<\/p>\n<p class>Desde entonces, cada a\u00f1o reflejamos el color, la m\u00fasica y la manifestaci\u00f3n de fe religiosa de Urkupi\u00f1a con el objeto de revalorizar y defender esta tradici\u00f3n. <strong>Y lo hicimos siempre en forma desinteresada, como lo hacemos con cada noticia. Sin pedir nada a cambio.<\/strong><\/p>\n<p class>Pero en esta oportunidad, advertimos un ruido de fondo vinculado con un malestar por los precios fijados por la comisi\u00f3n organizadora para la venta del espacio p\u00fablico para las &#8220;comideras&#8221; y al tirar del piol\u00edn, la madeja se fue desanudando sola. A partir de la primera nota donde reflejamos el malestar, se comunicaron con nosotros m\u00e1s voces que, en forma abierta o confidencial, aportaron informaci\u00f3n respecto a la organizaron y sus costos, que hasta entonces se desconoc\u00edan.&nbsp; &nbsp;<\/p>\n<p class><strong>Las publicaciones no buscaban sembrar dudas sobre la honestidad de los organizadores, <\/strong>sino plantear preguntas sobre la generosa inversi\u00f3n&nbsp; del Estado para solventar la log\u00edstica de esta festividad y brindar informaci\u00f3n esclarecedora.<\/p>\n<p class><strong>Para quienes atacan nuestro profesionalismo period\u00edstico<\/strong> debo decir que todo lo publicado obedece a datos e informaci\u00f3n aportados por fuentes que directa o indirectamente participan del evento. <strong>Nuestro estilo no es inventar nada para atraer lectores, <\/strong>sino por el contrario, hace 15 a\u00f1os que buscamos hacer nuestro trabajo de forma \u00e9tica y profesional. Bien o mal, pero honesto al fin.&nbsp;<\/p>\n<p class><strong>Para quienes nos acusan de discriminar a la comunidad boliviana del barrio,<\/strong> no reparan siquiera el valor de haber realzado o jerarquizado period\u00edsticamente el evento desde nuestras p\u00e1ginas, todos estos a\u00f1os. Nosotros hacemos periodismo, y eso significa hurgar, preguntar, corroborar la informaci\u00f3n y publicar. No nos interesa potenciar los sentimientos de odio o rechazo hacia el extranjero (xenofobia) que siempre anidan en la sociedad. Asumimos un cuidado al informar, pero no podemos evitar esas retr\u00f3gradas reacciones.<\/p>\n<p class>Los contribuyentes que con sus impuestos solventan los gastos principales de estos eventos masivos tienen todo el derecho a preguntarse sobre la oportunidad y eficacia del gasto. Oportunidad porque como pa\u00eds se atraviesa una recesi\u00f3n econ\u00f3mica muy fuerte y cada gasto cuenta; y eficacia porque se sospecha del aprovechamiento comercial de una festividad por parte de algunos. Incluso de <strong>algunos pol\u00edticos de turno que colaboran (\u00bfcon dinero personal o p\u00fablico?) a cambio de disponer de un escenario para propaganda personal.&nbsp;<\/strong><\/p>\n<p class>Desde nuestro medio, <strong>defendemos el apoyo estatal a estas manifestaciones populares y culturales<\/strong>, porque aun en tiempos de escasez se necesita &#8220;pan para el alma&#8221;. <strong>Pero tambi\u00e9n reivindicamos el derecho a la libre expresi\u00f3n y a la informaci\u00f3n del soberano,<\/strong> y en ese sentido, nuestra obligaci\u00f3n como medio de comunicaci\u00f3n es proporcion\u00e1rsela cuando la tenemos.&nbsp; &nbsp;<\/p>\n<p class>&nbsp;<\/p>\n<p class>\n<div class=\"ubm_banner\"><a href=\"https:\/\/www.cba.gov.ar\/prevencion-incendios\/\" target=\"_blank\" rel=\"dofollow noopener noreferrer\"><img src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2024\/08\/de-que-discriminacion-nos-acusan.gif\" width=\"900\" alt><\/a><\/div>\n<p>&nbsp;&nbsp;<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>La entrada <a rel=\"nofollow\" href=\"https:\/\/ladecimaweb.com\/de-que-discriminacion-nos-acusan\/\">\u00bfDe qu\u00e9 discriminaci\u00f3n nos acusan?<\/a> se public\u00f3 primero en <a rel=\"nofollow\" href=\"https:\/\/ladecimaweb.com\">LaDecima<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(Mario Albera) En noviembre de 2008, sali\u00f3 a la calle el primer n\u00famero de La D\u00e9cima. Aquella edici\u00f3n gr\u00e1fica, tra\u00eda en sus dos p\u00e1ginas centrales una nota con im\u00e1genes a color y una cr\u00f3nica del festejo de Urkupi\u00f1a de agosto de ese a\u00f1o. Recuerdo a algunos comerciantes y vecinos cuestionarme por haberle brindado ese espacio [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[32],"tags":[],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/81781"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=81781"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/81781\/revisions"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=81781"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=81781"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=81781"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}