{"id":81510,"date":"2024-08-11T02:54:33","date_gmt":"2024-08-11T02:54:33","guid":{"rendered":"https:\/\/www.ole.com.ar\/futbol-internacional\/america\/atentos-boca-san-lorenzo-empataron-cruzeiro-atletico-mineiro_0_VnW3CvZIFX.html"},"modified":"2024-08-11T02:54:33","modified_gmt":"2024-08-11T02:54:33","slug":"atentos-boca-y-san-lorenzo-cruzeiro-y-mineiro-empataron-en-el-brasileirao","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2024\/08\/11\/atentos-boca-y-san-lorenzo-cruzeiro-y-mineiro-empataron-en-el-brasileirao\/","title":{"rendered":"Atentos, Boca y San Lorenzo: Cruzeiro y Mineiro empataron en el Brasileirao"},"content":{"rendered":"<p><img src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2024\/08\/atentos-boca-y-san-lorenzo-cruzeiro-y-mineiro-empataron-en-el-brasileirao.jpg\"><\/p>\n<p><time class=\"createDate\" datetime=\"2024-08-10T23:54:33-03:00\">10\/08\/2024 23:54hs.<\/time><\/p>\n<div id=\"storyBody\">\n<div class=\"custom-text \" readability=\"33.694050991501\">\n<p><a href=\"https:\/\/www.ole.com.ar\/tema\/cruzeiro.html\" title=\"Cruzeiro\" alt=\"Cruzeiro\" class=\"slug\">Cruzeiro<\/a> y <a href=\"https:\/\/www.ole.com.ar\/tema\/atletico-mineiro.html\" title=\"Atletico Mineiro\" alt=\"Atletico Mineiro\" class=\"slug\">Atl\u00e9tico Mineiro<\/a> empataron 0-0 este s\u00e1bado por la noche en el Mineirao de Belo Horizonte, por la fecha 22 del Brasileirao. No se sacaron diferencias en el cl\u00e1sico la Raposa y el Galo, <strong>que la pr\u00f3xima semana deber\u00e1n enfrentar a <a href=\"https:\/\/www.ole.com.ar\/tema\/boca-juniors.html\" title=\"Boca Juniors\" alt=\"Boca Juniors\" class=\"slug\">Boca<\/a> y <a href=\"https:\/\/www.ole.com.ar\/tema\/san-lorenzo.html\" title=\"San Lorenzo\" alt=\"San Lorenzo\" class=\"slug\">San Lorenzo<\/a> respectivamente, por los octavos de final de la Copa Sudamericana y de la Copa Libertadores. <\/strong><\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"39\">\n<p>En un estadio colmado por los hinchas locales de Cruzeiro, ambos equipos jugaron con pr\u00e1cticamente todos sus titulares, pero a ninguno le alcanz\u00f3 para abrir el marcador. Eso s\u00ed, hubo uno que tuvo muchas m\u00e1s chances para hacerlo:<strong> fue el Mineiro, que tuvo cuatro remates al arco contra apenas uno de su rival. <\/strong><\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"37\">\n<p>Ese dominio incluso se traslad\u00f3 a la posesi\u00f3n: hubo un 65% de Mineiro contra un 35% de Cruzeiro. Sin embargo, la Raposa,<strong> con C\u00e1ssio en el arco<\/strong> (verdugo de Boca en la final de la Libertadores 2012 y en los octavos de 2022), <strong>logr\u00f3 mantener el cero y llevarse un punto.<\/strong><\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"41\">\n<p>En Cruzeiro fueron titulares los argentinos Lucas Villalba, \u00c1lvaro Barreal y Lautaro D\u00edaz, mientras que Juan Ignacio Dinenno y Lucas Romero sumaron minutos desde el banco; Mineiro, por su parte, cont\u00f3 en el 11 inicial con Rodrigo Battaglia, Renzo Saravia y Fausto Vera, y Mat\u00edas Zaracho brind\u00f3 su aporte desde los 66&#8242; de la segunda mitad. <\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"36\">\n<p>Con este empate, Cruzeiro se ubica quinto en el Brasileirao con 36 puntos, a siete de Botafogo, l\u00edder en soledad; mientras que Atl\u00e9tico Mineiro se encuentra octavo con 29 unidades. <\/p>\n<\/div>\n<p><h2><strong>Cu\u00e1ndo juegan San Lorenzo &#8211; Atl\u00e9tico Mineiro y Boca &#8211; Cruzeiro<\/strong><\/h2>\n<\/p>\n<div class=\"custom-text \" readability=\"34\">\n<p>San Lorenzo recibir\u00e1 a Atl\u00e9tico Mineiro el pr\u00f3ximo martes 13 de agosto desde las 21:30 (hora argentina), mientras que Boca har\u00e1 lo propio ante Cruzeiro el jueves 15 en el mismo horario. <\/p>\n<\/div>\n<div class=\"sc-e7b891c4-0 jPbnQF\"><img alt=\"La llave de la Sudamericana.\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2024\/08\/atentos-boca-y-san-lorenzo-cruzeiro-y-mineiro-empataron-en-el-brasileirao-2.jpg\" width=\"720\" height=\"100\" decoding=\"async\" data-nimg=\"future\" loading=\"lazy\"><span class=\"epigraphe\">La llave de la Sudamericana.<\/span><\/div>\n<div class=\"sc-e7b891c4-0 jPbnQF\"><img alt=\"La llave de la Libertadores.\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2024\/08\/atentos-boca-y-san-lorenzo-cruzeiro-y-mineiro-empataron-en-el-brasileirao-3.jpg\" width=\"720\" height=\"100\" decoding=\"async\" data-nimg=\"future\" loading=\"lazy\"><span class=\"epigraphe\">La llave de la Libertadores.<\/span><\/div>\n<div class=\"sc-a7166897-0 exHLBh\" readability=\"6.5\">\n<section readability=\"3\"><picture><img alt=\"San Lorenzo, una crisis a punto de estallar\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2024\/08\/atentos-boca-y-san-lorenzo-cruzeiro-y-mineiro-empataron-en-el-brasileirao-4.jpg\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"future\" loading=\"lazy\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>San Lorenzo, una crisis a punto de estallar<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<div class=\"sc-a7166897-0 exHLBh\" readability=\"6.5\">\n<section readability=\"3\"><picture><img alt=\"El mata-mata de Mart\u00ednez: frase desconcertante, la involuci\u00f3n y &quot;una final&quot; \" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2024\/08\/atentos-boca-y-san-lorenzo-cruzeiro-y-mineiro-empataron-en-el-brasileirao-5.jpg\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"future\" loading=\"lazy\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>El mata-mata de Mart\u00ednez: frase desconcertante, la involuci\u00f3n y \u00abuna final\u00bb <\/h3>\n<\/p>\n<\/section>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>10\/08\/2024 23:54hs. Cruzeiro y Atl\u00e9tico Mineiro empataron 0-0 este s\u00e1bado por la noche en el Mineirao de Belo Horizonte, por la fecha 22 del Brasileirao. No se sacaron diferencias en el cl\u00e1sico la Raposa y el Galo, que la pr\u00f3xima semana deber\u00e1n enfrentar a Boca y San Lorenzo respectivamente, por los octavos de final de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":81511,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[16],"tags":[],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/81510"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=81510"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/81510\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media\/81511"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=81510"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=81510"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=81510"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}