{"id":80625,"date":"2024-07-21T18:24:34","date_gmt":"2024-07-21T18:24:34","guid":{"rendered":"https:\/\/www.trendencias.com\/gourmet\/receta-facil-canelones-ligeros-plato-pasta-calabacin-que-queda-muy-jugoso"},"modified":"2024-07-21T18:24:34","modified_gmt":"2024-07-21T18:24:34","slug":"receta-facil-y-ligera-de-canelones-un-plato-sin-pasta-y-con-calabacin-que-queda-muy-jugoso-perfecto-para-una-cena-de-verano","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2024\/07\/21\/receta-facil-y-ligera-de-canelones-un-plato-sin-pasta-y-con-calabacin-que-queda-muy-jugoso-perfecto-para-una-cena-de-verano\/","title":{"rendered":"Receta f\u00e1cil y ligera de canelones: un plato sin pasta y con calabac\u00edn que queda muy jugoso. Perfecto para una cena de verano"},"content":{"rendered":"<p>Una receta que mezcla jam\u00f3n y queso es dif\u00edcil que no guste a la mayor\u00eda de la gente. Una muy original, que cumple ambas premisas, son estos canelones de calabac\u00edn en los que la hortaliza sustituye las tradicionales l\u00e1minas de pasta. El resultado es <strong>una versi\u00f3n m\u00e1s ligera del cl\u00e1sico plato italiano<\/strong>, pero igual de deliciosa. Y eso que tambi\u00e9n prescinde de la salsa bechamel. No obstante, gracias al uso del calabac\u00edn, el resultado es de lo m\u00e1s jugoso. Son una excelente opci\u00f3n de entrante de un men\u00fa completo o una cena original y diferente.<\/p>\n<p><!-- BREAK 1 --> <!--more--><\/p>\n<div class=\"article-asset article-asset-normal article-asset-center\">\n<div class=\"desvio-container\">\n<div class=\"desvio\">\n<div class=\"desvio-figure js-desvio-figure\"> <a href=\"https:\/\/www.trendencias.com\/gourmet\/cena-facil-calabacin-que-recomienda-nutricionista-tardas-cinco-minutos-resultado-delicioso\"> <img loading=\"lazy\" alt=\"La cena f\u00e1cil con calabac\u00edn que recomienda una nutricionista: \u201cTardas cinco minutos y el resultado es delicioso\u201d \" width=\"375\" height=\"142\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2024\/07\/receta-facil-y-ligera-de-canelones-un-plato-sin-pasta-y-con-calabacin-que-queda-muy-jugoso-perfecto-para-una-cena-de-verano.jpg\"> <\/a> <\/div><\/div><\/div>\n<\/div>\n<p> <!-- recipe start --> <!-- recipe end --><\/p>\n<p>Empezamos laminando el calabac\u00edn <strong>a lo largo y lo m\u00e1s fino posible<\/strong>. Si tenemos una mandolina, la tarea ser\u00e1 muchos m\u00e1s f\u00e1cil. Si no es el caso, con un cuchillo afilado y paciencia basta. Despu\u00e9s, seleccionamos las 12 l\u00e1minas centrales y las cortamos por la mitad.<\/p>\n<p><!-- BREAK 2 --><\/p>\n<p>El resto del calabac\u00edn lo vamos a usar para el relleno, as\u00ed que lo picamos finamente y, despu\u00e9s, hacemos lo mismo con la cebolla. A continuaci\u00f3n, calentamos un poco de aceite en una sart\u00e9n y pochamos la cebolla a fuego suave <strong>hasta que quede trasl\u00facida<\/strong>. Agregamos el calabac\u00edn picado y continuamos pochando durante unos diez minutos m\u00e1s.<\/p>\n<p><!-- BREAK 3 --> <\/p>\n<p>Picamos las lonchas de jam\u00f3n y las incorporamos a la sart\u00e9n junto con el queso crema. Removemos hasta obtener <strong>una masa homog\u00e9nea<\/strong> y dejamos atemperar ligeramente antes de montar los canelones.<\/p>\n<p><!-- BREAK 4 --><\/p>\n<div class=\"article-asset-image article-asset-normal article-asset-center\">\n<div class=\"asset-content\"> <img class=\"centro_sinmarco\" height=\"1366\" width=\"1366\" loading=\"lazy\" decoding=\"async\" sizes=\"100vw\" fetchpriority=\"high\" srcset=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2024\/07\/receta-facil-y-ligera-de-canelones-un-plato-sin-pasta-y-con-calabacin-que-queda-muy-jugoso-perfecto-para-una-cena-de-verano-1.jpg 450w, http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2024\/07\/receta-facil-y-ligera-de-canelones-un-plato-sin-pasta-y-con-calabacin-que-queda-muy-jugoso-perfecto-para-una-cena-de-verano-3.jpg 681w, http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2024\/07\/receta-facil-y-ligera-de-canelones-un-plato-sin-pasta-y-con-calabacin-que-queda-muy-jugoso-perfecto-para-una-cena-de-verano-4.jpg 1024w, http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2024\/07\/receta-facil-y-ligera-de-canelones-un-plato-sin-pasta-y-con-calabacin-que-queda-muy-jugoso-perfecto-para-una-cena-de-verano-5.jpg 1366w\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2024\/07\/receta-facil-y-ligera-de-canelones-un-plato-sin-pasta-y-con-calabacin-que-queda-muy-jugoso-perfecto-para-una-cena-de-verano-1.jpg\" alt=\"canelones calabac\u00edn\"> <noscript><img alt=\"canelones calabac\u00edn\" class=\"centro_sinmarco\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2024\/07\/receta-facil-y-ligera-de-canelones-un-plato-sin-pasta-y-con-calabacin-que-queda-muy-jugoso-perfecto-para-una-cena-de-verano-1.jpg\"><\/noscript> <\/div>\n<\/div>\n<p>El siguiente paso es extender una l\u00e1mina de papel transparente y colocar encima cuatro l\u00e1minas de calabac\u00edn superpuestas. Ponemos un cord\u00f3n de relleno en uno de los extremos y <strong>enrollamos en forma de cilindro ayud\u00e1ndonos del papel<\/strong>. Repetimos la operaci\u00f3n con el resto de l\u00e1minas de calabac\u00edn.<\/p>\n<p><!-- BREAK 5 --><\/p>\n<p>Colocamos los cordones en una bandeja de horno, cubierta con papel vegetal, y los cubrimos con un poco de salsa de tomate. Despu\u00e9s espolvoreamos queso rallado por encima y, por \u00faltimo, <strong>los gratinamos en el horno durante tres o cuatro minutos<\/strong> o hasta que el queso comience a tomar color. Servimos el plato inmediatamente.<\/p>\n<p><!-- BREAK 6 --> <\/p>\n<p>Como hab\u00e9is visto, <strong>no hace falta precocer las l\u00e1minas de calabac\u00edn antes de montar los canelones<\/strong>. El tiempo de gratinado al final de la receta es suficiente para que queden al dente. Eso s\u00ed, se pueden meter (de forma opcional) 30 segundos en el microondas para reblandecer ligeramente y hacerlos m\u00e1s maleables.<\/p>\n<p><!-- BREAK 7 --><\/p>\n<p>Fotos | Directo al paladar<\/p>\n<p>En Trendencias | <a href=\"https:\/\/www.trendencias.com\/gourmet\/15-recetas-tartas-postres-saludables-para-incluir-tu-dieta-miedo\">21 recetas de tartas y postres saludables para incluir en tu dieta sin miedo<\/a><\/p>\n<p>En Trendencias | <a href=\"https:\/\/www.trendencias.com\/gourmet\/receta-pollo-asado-jordi-cruz-que-puedes-hacer-casa-para-quedar-bien-siempre-no-tengas-idea-cocinar\">La receta de pollo asado de Jordi Cruz que puedes hacer en casa para quedar bien siempre (aunque no tengas ni idea de cocinar)<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una receta que mezcla jam\u00f3n y queso es dif\u00edcil que no guste a la mayor\u00eda de la gente. Una muy original, que cumple ambas premisas, son estos canelones de calabac\u00edn en los que la hortaliza sustituye las tradicionales l\u00e1minas de pasta. El resultado es una versi\u00f3n m\u00e1s ligera del cl\u00e1sico plato italiano, pero igual de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":80626,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[],"tags":[],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/80625"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=80625"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/80625\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media\/80626"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=80625"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=80625"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=80625"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}