{"id":80040,"date":"2024-07-08T00:39:48","date_gmt":"2024-07-08T00:39:48","guid":{"rendered":"https:\/\/www.ole.com.ar\/seleccion\/copa-america-2024-seleccion-argentina-mata-mata-equipos-concacaf_0_h147S4oKFO.html"},"modified":"2024-07-08T00:39:48","modified_gmt":"2024-07-08T00:39:48","slug":"copa-america-2024-como-le-fue-a-la-seleccion-argentina-en-los-mata-mata-ante-equipos-de-concacaf","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2024\/07\/08\/copa-america-2024-como-le-fue-a-la-seleccion-argentina-en-los-mata-mata-ante-equipos-de-concacaf\/","title":{"rendered":"Copa Am\u00e9rica 2024: c\u00f3mo le fue a la Selecci\u00f3n Argentina en los mata-mata ante equipos de Concacaf"},"content":{"rendered":"<p><img src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2024\/07\/copa-america-2024-como-le-fue-a-la-seleccion-argentina-en-los-mata-mata-ante-equipos-de-concacaf.jpg\"><\/p>\n<p><time class=\"createDate\" datetime=\"2024-07-07T21:39:48-03:00\">08\/07\/2024 00:39hs.<\/time><\/p>\n<div id=\"storyBody\">\n<div class=\"custom-text \" readability=\"40.696920583468\">\n<p>Mientras que era esperado que la <strong><a href=\"https:\/\/www.ole.com.ar\/tema\/seleccion-argentina.html\" title=\"Selecci\u00f3n Argentina\" alt=\"Selecci\u00f3n Argentina\" class=\"slug\">Selecci\u00f3n Argentina<\/a><\/strong>, Uruguay y Colombia est\u00e9n en las semifinales de la <strong><a href=\"https:\/\/www.ole.com.ar\/tema\/copa-america-2024.html\" title=\"Copa Am\u00e9rica 2024\" alt=\"Copa Am\u00e9rica 2024\" class=\"slug\">Copa Am\u00e9rica 2024<\/a><\/strong>, <strong><a href=\"https:\/\/www.ole.com.ar\/tema\/seleccion-de-canada.html\" title=\"Selecci\u00f3n de Canad\u00e1\" alt=\"Selecci\u00f3n de Canad\u00e1\" class=\"slug\">Canad\u00e1 <\/a>dio la sorpresa.<\/strong> Primero, al quedar 2\u00b0 en el Grupo A, dejando eliminados a equipos de la talla de Chile y Per\u00fa. Y, despu\u00e9s, por dejar afuera a una Venezuela que hab\u00eda sido implacable en el Grupo B. Ahora, los equipos de <a href=\"https:\/\/www.ole.com.ar\/tema\/lionel-scaloni.html\" title=\"Lionel Scaloni\" alt=\"Lionel Scaloni\" class=\"slug\">Lionel Scaloni<\/a> y Jesse Marsch se cruzar\u00e1n por un boleto en la final de Miami, siendo la primera presencia de los Rojos en semifinales <strong>y la octava vez que la Albiceleste se mide, en un mata-mata, ante un conjunto de la Concacaf. \u00bfC\u00f3mo viene en el historial?<\/strong><\/p>\n<\/div>\n<p><h2><strong><em>Copa Am\u00e9rica 2024: Los 7 cruces de Argentina ante equipos de Concacaf<\/em><\/strong><\/h2>\n<\/p>\n<div class=\"custom-text \" readability=\"45\">\n<p>En cuanto a las Copas del Mundo, la Selecci\u00f3n Argentina no se ha medido mucho ante equipos de Concacaf, simplemente porque no han sido muchas las ocasiones en las que equipos de Norteam\u00e9rica se han metido entre los 16 mejores. <strong>A lo largo de 21 Mundiales, la Albiceleste se los ha cruzado en apenas tres oportunidades<\/strong>. La primera, en <strong>Uruguay 1930<\/strong>, con goleada 6-1 ante Estados Unidos, en semifinales. La segunda, en <strong>Alemania 2006<\/strong>, con victoria 2-1 gracias a los festejos de Crespo y Maxi Rodr\u00edguez. Y la \u00faltima vez fue en <strong>Sud\u00e1frica 2010<\/strong>, cuando el equipo de Diego Maradona super\u00f3 3-1 a M\u00e9xico, con una noche de Carlos Tevez para el recuerdo.<\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"43\">\n<p>La Copa Am\u00e9rica podr\u00eda haber representado una competencia con mayor coincidencia entre la Selecci\u00f3n y equipos de la Concacaf. Sin embargo, su inclusi\u00f3n dentro de la competencia se ha dado reci\u00e9n en los \u00faltimos 30 a\u00f1os. <strong>En Ecuador 1993, la Argentina del Coco Basile se coron\u00f3 ante M\u00e9xico<\/strong>, con doblete de Gabriel Batistuta. Volvieron a coincidir en las semis de<strong> Venezuela 2007, con goleada 3-0<\/strong>: Gabriel Heinze, Lionel Messi (pic\u00e1ndola) y Juan Rom\u00e1n Riquelme (de penal), los autores de los tantos. Y el \u00faltimo antecedente, <strong>el 4-0 con Estados Unidos, en la semifinal de la edici\u00f3n 2016<\/strong>.<\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"45\">\n<p>Tres en Mundiales, tres en Copas Am\u00e9rica y el otro cruce se dio en la <strong>Copa Confederaciones de Alemania 2005<\/strong>. Despu\u00e9s de culminar 2\u00b0 en el Grupo A, <strong>el conjunto de Nestor Pekerman debi\u00f3 medirse ante un M\u00e9xico que hab\u00eda dado la sorpresa en el Grupo B<\/strong>, sobreponi\u00e9ndose a la Brasil de Ronaldinho, Kak\u00e1 y Adriano. Y tras el 0-0 en el tiempo regular, la Selecci\u00f3n se impuso desde la tanda de penales: Riquelme, Maxi Rodr\u00edguez, Aimar, Galletti, Sor\u00edn y Cambiasso metieron sus disparos, mientras que Ricardo Osorio err\u00f3 para la Tri.<\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"40\">\n<p>De esta manera,<strong> la Selecci\u00f3n Argentina jam\u00e1s qued\u00f3 eliminada de una competici\u00f3n por un equipo de la Concacaf<\/strong>. De siete cruces, gan\u00f3 seis y empat\u00f3 uno, aunque despu\u00e9s termin\u00f3 avanzando por penales. Adem\u00e1s, marc\u00f3 un total de 21 goles y recibi\u00f3 apenas cinco tantos. No obstante, fueron solamente Estados Unidos y M\u00e9xico sus adversarios. \u00bfPodr\u00e1 agregar a Canad\u00e1 en su historial de v\u00edctimas?<\/p>\n<\/div>\n<div class=\"sc-e7b891c4-0 jPbnQF\"><img alt=\"El primer grito de Carlitos ante M\u00e9xico, en Sud\u00e1frica 2010. (FTP Clar\u00edn - Carlos Sarraf)\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2024\/07\/copa-america-2024-como-le-fue-a-la-seleccion-argentina-en-los-mata-mata-ante-equipos-de-concacaf-2.jpg\" width=\"1290\" height=\"760\" decoding=\"async\" data-nimg=\"future\" loading=\"lazy\"><span class=\"epigraphe\">El primer grito de Carlitos ante M\u00e9xico, en Sud\u00e1frica 2010. (FTP Clar\u00edn &#8211; Carlos Sarraf)<\/span><\/div>\n<p><h2><strong><em>\u00bfC\u00f3mo llegan Argentina y Canad\u00e1 a la semifinal de la Copa Am\u00e9rica?<\/em><\/strong><\/h2>\n<\/p>\n<div class=\"custom-text \" readability=\"37\">\n<p><strong>Tanto Argentina como Canad\u00e1 superaron los cuartos de final de la Copa Am\u00e9rica por penales<\/strong>. Por un lado, los hombres de Lionel Scaloni empataron 1-1 en el tiempo regular ante Ecuador y obtuvieron el pase a la semi con una destacada actuaci\u00f3n del Dibu Mart\u00ednez bajo los tres palos. Por el otro, los dirigidos por Jesse Marsch tambi\u00e9n igualaron 1-1 en el marcador con Venezuela y definieron la serie desde los 12 pasos.<\/p>\n<\/div>\n<p><h2><em>\u00bfCu\u00e1ndo juegan Argentina y Canad\u00e1 la semifinal de la Copa Am\u00e9rica?<\/em><\/h2>\n<\/p>\n<div class=\"custom-text \" readability=\"37\">\n<p>La Selecci\u00f3n Argentina y Canad\u00e1 se enfrentar\u00e1n el<strong> martes 9 de julio a las 21 horas en el MetLife Stadium de Nueva Jersey<\/strong>, Estados Unidos. Quien resulte ganador del cruce ser\u00e1 el primer finalista de la Copa Am\u00e9rica, y se enfrentar\u00e1 ante el vencedor de Uruguay-Colombia. A diferencia de las Copas del Mundo (en la que dos equipos del mismo grupo no se cruzar\u00edan hasta la final) <strong>en el partido decisivo de la Copa Am\u00e9rica jugar\u00e1n uno del Grupo A o B vs. uno del Grupo C o D.<\/strong><\/p>\n<\/div>\n<div class=\"sc-e7b891c4-0 jPbnQF\"><img alt=\"Lautaro, autor del segundo gol ante Canad\u00e1, en la fase de grupos. (REUTER)\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2024\/07\/copa-america-2024-como-le-fue-a-la-seleccion-argentina-en-los-mata-mata-ante-equipos-de-concacaf-3.jpg\" width=\"1290\" height=\"760\" decoding=\"async\" data-nimg=\"future\" loading=\"lazy\"><span class=\"epigraphe\">Lautaro, autor del segundo gol ante Canad\u00e1, en la fase de grupos. (REUTER)<\/span><\/div>\n<p><h2><strong><em>La llave de la Copa Am\u00e9rica 2024<\/em><\/strong><\/h2>\n<\/p>\n<link rel=\"stylesheet\" href=\"\/\/secure.widget.cloud.opta.net\/v3\/css\/v3.football.opta-widgets.css\" type=\"text\/css\" as=\"style\" importance=\"high\">\n<div class=\"sc-a7166897-0 exHLBh\" readability=\"6.5\">\n<section readability=\"3\"><picture><img alt=\"El gigante de Europa que busc\u00f3 al Dibu Mart\u00ednez, pero su DT se neg\u00f3\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2024\/07\/copa-america-2024-como-le-fue-a-la-seleccion-argentina-en-los-mata-mata-ante-equipos-de-concacaf-4.jpg\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"future\" loading=\"lazy\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>El gigante de Europa que busc\u00f3 al Dibu Mart\u00ednez, pero su DT se neg\u00f3<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<div class=\"sc-a7166897-0 exHLBh\" readability=\"6\">\n<section readability=\"2\"><picture><img alt=\"La abanderada a los Juegos Paral\u00edmpicos poste\u00f3 contra Milei\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2024\/07\/copa-america-2024-como-le-fue-a-la-seleccion-argentina-en-los-mata-mata-ante-equipos-de-concacaf-5.jpg\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"future\" loading=\"lazy\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>La abanderada a los Juegos Paral\u00edmpicos poste\u00f3 contra Milei<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<div class=\"sc-a7166897-0 exHLBh\" readability=\"7\">\n<section readability=\"4\"><picture><img alt=\"El post retiro de Toni Kroos: su familia, Espa\u00f1a, \u00bfy una nueva Kings League?\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2024\/07\/copa-america-2024-como-le-fue-a-la-seleccion-argentina-en-los-mata-mata-ante-equipos-de-concacaf-6.jpg\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"future\" loading=\"lazy\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>El post retiro de Toni Kroos: su familia, Espa\u00f1a, \u00bfy una nueva Kings League?<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>08\/07\/2024 00:39hs. Mientras que era esperado que la Selecci\u00f3n Argentina, Uruguay y Colombia est\u00e9n en las semifinales de la Copa Am\u00e9rica 2024, Canad\u00e1 dio la sorpresa. Primero, al quedar 2\u00b0 en el Grupo A, dejando eliminados a equipos de la talla de Chile y Per\u00fa. Y, despu\u00e9s, por dejar afuera a una Venezuela que hab\u00eda [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":80041,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[16],"tags":[],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/80040"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=80040"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/80040\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media\/80041"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=80040"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=80040"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=80040"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}