{"id":78607,"date":"2024-06-06T15:13:49","date_gmt":"2024-06-06T15:13:49","guid":{"rendered":"https:\/\/ladecimaweb.com\/?p=27406"},"modified":"2024-06-06T15:13:49","modified_gmt":"2024-06-06T15:13:49","slug":"en-los-semaforos-de-defensa-motochoros-arrebatan-a-joven-discapacitada-y-le-roban-sus-carpetas-y-libros-con-pictogramas","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2024\/06\/06\/en-los-semaforos-de-defensa-motochoros-arrebatan-a-joven-discapacitada-y-le-roban-sus-carpetas-y-libros-con-pictogramas\/","title":{"rendered":"En los sem\u00e1foros de Defensa, motochoros arrebatan a joven discapacitada y le roban sus carpetas y libros con pictogramas"},"content":{"rendered":"<div class=\"boldgrid-section\">\n<div class=\"container\">\n<div class=\"row\">\n<div class=\"col-md-12 col-xs-12 col-sm-12\">\n<p class>Todos los robos dejan secuelas, pero por incomprensibles, algunos dejan m\u00e1s secuelas que otros.&nbsp;<\/p>\n<p class>Es el caso del robo sufrido ayer por una joven discapacitada de barrio Residencial Santa Rosa.&nbsp;<\/p>\n<p class>Brisa Madera (17) regresaba del colegio en el auto de su abuelo, Alfredo Sayavedra. Sentada en el asiento de atr\u00e1s con la mochila escolar a su lado y su abuelo, como chofer, al volante.&nbsp;<\/p>\n<p class><strong>Al llegar el Fiat Siena a los sem\u00e1foros de Defensa y V\u00e9lez Sarsfield, sucede lo peor.<\/strong> <strong>Dos mavivientes a bordo de una moto los sorprenden reventando una ventanilla y arrebatando la mochila escolar. <\/strong><\/p>\n<p class>El reloj marcaba un poco m\u00e1s de las cinco de la tarde. A esa hora, el lugar es un gent\u00edo de escolares con sus padres saliendo de la escuela.&nbsp;<\/p>\n<p class>Como Brisa tiene una discapacidad llamada afasia (trastorno del lenguaje), le hicieron un da\u00f1o muy grande.&nbsp;<\/p>\n<p class><strong>&#8220;Ella se comunica en lengua de se\u00f1as como un ni\u00f1o sordo y en sus pertenencias sustra\u00eddas ten\u00eda sus carpetas y libros con sus pictogramas&#8221;, describe Roxana Sayavedra, mam\u00e1 de la joven a La D\u00e9cima.&nbsp;<\/strong><\/p>\n<p class><span>Los pictogramas son&nbsp;<\/span>signos pict\u00f3ricos que pueden entenderse sin texto ni explicaciones adicionales.<\/p>\n<p class><span>&#8220;Su mochila es de color negra&#8221;, aporta. <strong>&#8220;Lo q m\u00e1s nos duelen son sus carpetas porque son fundamentales para que ella pueda seguir con su vida cotidiana&#8221;, agrega.&nbsp;<\/strong><\/span><\/p>\n<p class>Adem\u00e1s de alertar sobre la inseguridad en esa esquina transitada de la zona sur, Roxana hace un llamado solidario a la poblaci\u00f3n del sector por si alguien encuentra la mochila o las carpetas de Brisa.&nbsp;<\/p>\n<p class>&#8220;Las carpetas y los libros, todos llevan el nombre de mi hija&#8221;, detalla la mam\u00e1, para insinuar que lo robado no tiene valor de reventa alguno. Como se dice en la calle: robaron para hacer da\u00f1o.&nbsp;&nbsp;<\/p>\n<p class><em><strong>Si alguien encuentra el material escolar o puede aportar informaci\u00f3n, comunicarse al 351 5154758.<\/strong><\/em><\/p>\n<p>&nbsp;<\/p>\n<p class>\n<div class=\"ubm_banner\"><a href=\"https:\/\/www.cba.gov.ar\/desafio-ruta-40-llega-por-primera-vez-a-cordoba\/\" target=\"_blank\" rel=\"dofollow noopener noreferrer\"><img src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2024\/06\/en-los-semaforos-de-defensa-motochoros-arrebatan-a-joven-discapacitada-y-le-roban-sus-carpetas-y-libros-con-pictogramas.gif\" width=\"900\" alt><\/a><\/div>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>La entrada <a rel=\"nofollow\" href=\"https:\/\/ladecimaweb.com\/en-los-semaforos-de-defensa-motochoros-arrebatan-a-joven-discapacitada-y-le-roban-carpetas-con-pictogramas\/\">En los sem\u00e1foros de Defensa, motochoros arrebatan a joven discapacitada y le roban sus carpetas y libros con pictogramas<\/a> se public\u00f3 primero en <a rel=\"nofollow\" href=\"https:\/\/ladecimaweb.com\">LaDecima<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Todos los robos dejan secuelas, pero por incomprensibles, algunos dejan m\u00e1s secuelas que otros.&nbsp; Es el caso del robo sufrido ayer por una joven discapacitada de barrio Residencial Santa Rosa.&nbsp; Brisa Madera (17) regresaba del colegio en el auto de su abuelo, Alfredo Sayavedra. Sentada en el asiento de atr\u00e1s con la mochila escolar a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[32],"tags":[],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/78607"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=78607"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/78607\/revisions"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=78607"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=78607"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=78607"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}