{"id":77204,"date":"2024-05-07T21:16:00","date_gmt":"2024-05-07T21:16:00","guid":{"rendered":"http:\/\/hoycordobaweb.com\/index.php\/2024\/05\/07\/que-esperar-de-la-segunda-temporada-de-wednesday-2-en-netflix-cnn-en-espanol\/"},"modified":"2024-05-07T21:16:00","modified_gmt":"2024-05-07T21:16:00","slug":"que-esperar-de-la-segunda-temporada-de-wednesday-2-en-netflix-cnn-en-espanol","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2024\/05\/07\/que-esperar-de-la-segunda-temporada-de-wednesday-2-en-netflix-cnn-en-espanol\/","title":{"rendered":"\u00bfQu\u00e9 esperar de la segunda temporada de &quot;Wednesday 2&quot; en <b>Netflix<\/b>? &#8211; CNN en Espa\u00f1ol"},"content":{"rendered":"<p><b>Netflix<\/b> dio a conocer este martes que ya &#8230; <b>Netflix<\/b> confirma segunda temporada de &quot;Wednesday 2&quot; con Jenna Ortega &#8230; \u00a9 2024 Cable <b>News<\/b> Network. A Warner&nbsp;&#8230; <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Netflix dio a conocer este martes que ya &#8230; Netflix confirma segunda temporada de &quot;Wednesday 2&quot; con Jenna Ortega &#8230; \u00a9 2024 Cable News Network. A Warner&nbsp;&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[23],"tags":[],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/77204"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=77204"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/77204\/revisions"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=77204"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=77204"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=77204"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}