{"id":74307,"date":"2024-03-08T16:42:45","date_gmt":"2024-03-08T16:42:45","guid":{"rendered":"https:\/\/www.ole.com.ar\/boca-juniors\/boca-burrito-martinez-unidos_0_1wbhpZyFz4.html"},"modified":"2024-03-08T16:42:45","modified_gmt":"2024-03-08T16:42:45","slug":"el-ex-boca-que-a-los-38-anos-fue-presentado-en-su-nuevo-club-de-estados-unidos","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2024\/03\/08\/el-ex-boca-que-a-los-38-anos-fue-presentado-en-su-nuevo-club-de-estados-unidos\/","title":{"rendered":"El ex Boca que a los 38 a\u00f1os fue presentado en su nuevo club de Estados Unidos"},"content":{"rendered":"<p><img src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2024\/03\/el-ex-boca-que-a-los-38-anos-fue-presentado-en-su-nuevo-club-de-estados-unidos.jpg\"><\/p>\n<p><time class=\"createDate\" datetime=\"2024-03-08T13:42:45-03:00\">08\/03\/2024 13:42hs.<\/time><\/p>\n<div id=\"storyBody\">\n<div class=\"custom-text \" readability=\"33.145833333333\">\n<p><strong><a href=\"https:\/\/www.ole.com.ar\/tema\/juan-manuel-martinez.html\" title=\"Juan Manuel Mart\u00ednez\" alt=\"Juan Manuel Mart\u00ednez\" class=\"slug\">Juan Manuel Mart\u00ednez<\/a> fue presentado como nuevo jugador del Club Lyon, equipo estadounidense que se fund\u00f3 en 2021<\/strong>. El delantero, que tuvo su paso por <strong><a href=\"https:\/\/www.ole.com.ar\/tema\/boca-juniors.html\" title=\"Boca Juniors\" alt=\"Boca Juniors\" class=\"slug\">Boca<\/a>, <\/strong>tiene 38 a\u00f1os y est\u00e1 ante la chance de jugar en el club n\u00famero 12 en su carrera.<\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"39\">\n<p><strong>El Club Lyon es un equipo de Orlando, Florida, que pertenece a la tercera categor\u00eda de Estados Unidos, la NISA (National Independent Soccer Association).<\/strong> Fue fundado recientemente como la gran mayor\u00eda de equipos de f\u00fatbol estadounidenses, que fueron originados hace poco tiempo ya que el deporte comienza a popularizarse cada vez m\u00e1s y los clubes siguen surgiendo.<\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"42.590618336887\">\n<p>El Burrito no estar\u00e1 solo, ya que <strong>el equipo cuenta con la presencia de cinco futbolistas argentinos<\/strong>: Mateo Borelli, Ignacio Ten L\u00f3pez, Franco Acerbi, Mat\u00edas Pourrain y Agust\u00edn Ortiz. <strong>Adem\u00e1s, el entrenador tambi\u00e9n es argentino. Se trata de H\u00e9ctor Almandoz<\/strong>, ex jugador de <a href=\"https:\/\/www.ole.com.ar\/tema\/quilmes.html\" title=\"Quilmes\" alt=\"Quilmes\" class=\"slug\">Quilmes<\/a>, <a href=\"https:\/\/www.ole.com.ar\/tema\/velez.html\" title=\"V\u00e9lez\" alt=\"V\u00e9lez\" class=\"slug\">V\u00e9lez<\/a>, <a href=\"https:\/\/www.ole.com.ar\/tema\/estudiantes-de-la-plata.html\" title=\"Estudiantes de La Plata\" alt=\"Estudiantes de La Plata\" class=\"slug\">Estudiantes<\/a>, <a href=\"https:\/\/www.ole.com.ar\/tema\/san-lorenzo.html\" title=\"San Lorenzo\" alt=\"San Lorenzo\" class=\"slug\">San Lorenzo<\/a>, <a href=\"https:\/\/www.ole.com.ar\/tema\/chacarita.html\" title=\"Chacarita\" alt=\"Chacarita\" class=\"slug\">Chacarita<\/a>, entre otros. El t\u00e9cnico de 56 a\u00f1os tuvo su paso por la Primera Divisi\u00f3n de Chile, en d\u00f3nde dirigi\u00f3 varios equipos durante ocho a\u00f1os.<\/p>\n<\/div>\n<div class=\"sc-e7b891c4-0 jPbnQF\"><img alt=\"H\u00e9ctor Almandoz dirigiendo para Copiac\u00f3, equipo de la Primera Divisi\u00f3n de Chile. (PRENSA OL\u00c9)\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2024\/03\/el-ex-boca-que-a-los-38-anos-fue-presentado-en-su-nuevo-club-de-estados-unidos-2.jpg\" width=\"720\" height=\"100\" decoding=\"async\" data-nimg=\"future\" loading=\"lazy\"><span class=\"epigraphe\">H\u00e9ctor Almandoz dirigiendo para Copiac\u00f3, equipo de la Primera Divisi\u00f3n de Chile. (PRENSA OL\u00c9)<\/span><\/div>\n<p><h2><strong>El paso del Burrito Mart\u00ednez por Boca<\/strong><\/h2>\n<\/p>\n<div class=\"custom-text \" readability=\"35.199115044248\">\n<p>El delantero oriundo de Viedma, Rio Negro, tuvo su paso por el Xeneize proveniente del <a href=\"https:\/\/www.ole.com.ar\/tema\/corinthians.html\" title=\"Corinthians\" alt=\"Corinthians\" class=\"slug\">Corinthians<\/a>. <strong>Debut\u00f3 con la camiseta de Boca en febrero de 2013<\/strong>, en la victoria 3-2 ante Quilmes en el aquel entonces llamado Torneo Final. <\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"40.578125\">\n<p>Durante su estad\u00eda en el club, el Burrito <strong>disput\u00f3 78 partidos y convirti\u00f3 12 goles<\/strong>. <strong>Fueron 36 victorias, 22 empates y 20 derrotas<\/strong>. Arranc\u00f3 de titular en casi todos los partidos que disput\u00f3, y gan\u00f3 un t\u00edtulo, el Campeonato 2015. Ese mismo a\u00f1o, jug\u00f3 su \u00faltimo encuentro oficial con la camiseta xeneize, fue ante <a href=\"https:\/\/www.ole.com.ar\/tema\/independiente-r.html\" title=\"Independiente (R)\" alt=\"Independiente (R)\" class=\"slug\">Independiente<\/a> en Avellaneda, en donde no se sacaron diferencias. <\/p>\n<\/div>\n<div class=\"sc-e7b891c4-0 jPbnQF\"><img alt=\"El Burrito con la de Boca en la Copa Libertadores 2015. (REUTER)\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2024\/03\/el-ex-boca-que-a-los-38-anos-fue-presentado-en-su-nuevo-club-de-estados-unidos-3.jpg\" width=\"720\" height=\"100\" decoding=\"async\" data-nimg=\"future\" loading=\"lazy\"><span class=\"epigraphe\">El Burrito con la de Boca en la Copa Libertadores 2015. (REUTER)<\/span><\/div>\n<div class=\"sc-a7166897-0 exHLBh\" readability=\"7\">\n<section readability=\"4\"><picture><img alt=\"Qu\u00e9 piensa Riquelme sobre el futuro de Chiquito Romero, Valentini y otros contratos que se vencen\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2024\/03\/el-ex-boca-que-a-los-38-anos-fue-presentado-en-su-nuevo-club-de-estados-unidos-4.jpg\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"future\" loading=\"lazy\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>Qu\u00e9 piensa Riquelme sobre el futuro de Chiquito Romero, Valentini y otros contratos que se vencen<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<div class=\"sc-a7166897-0 exHLBh\" readability=\"7\">\n<section readability=\"4\"><picture><img alt=\"Mart\u00edn Palermo, eliminado de la Copa Sudamericana: no disputar\u00e1 con Olimpia la fase de grupos \" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2024\/03\/el-ex-boca-que-a-los-38-anos-fue-presentado-en-su-nuevo-club-de-estados-unidos-5.jpg\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"future\" loading=\"lazy\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>Mart\u00edn Palermo, eliminado de la Copa Sudamericana: no disputar\u00e1 con Olimpia la fase de grupos<br \/>\n<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<div class=\"sc-a7166897-0 exHLBh\" readability=\"6.5\">\n<section readability=\"3\"><picture><img alt=\"La foto que subi\u00f3 el Changuito Zeballos y el mensaje que ilusiona a los hinchas de Boca\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2024\/03\/el-ex-boca-que-a-los-38-anos-fue-presentado-en-su-nuevo-club-de-estados-unidos-6.jpg\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"future\" loading=\"lazy\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>La foto que subi\u00f3 el Changuito Zeballos y el mensaje que ilusiona a los hinchas de Boca<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<div class=\"sc-a7166897-0 exHLBh\" readability=\"6\">\n<section readability=\"2\"><picture><img alt=\"Gustavo Costas palpit\u00f3 el duelo ante Boca: &quot;Debemos trabajar m\u00e1s en lo an\u00edmico&quot;\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2024\/03\/el-ex-boca-que-a-los-38-anos-fue-presentado-en-su-nuevo-club-de-estados-unidos-7.jpg\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"future\" loading=\"lazy\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>Gustavo Costas palpit\u00f3 el duelo ante Boca: \u00abDebemos trabajar m\u00e1s en lo an\u00edmico\u00bb<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<div class=\"sc-a7166897-0 exHLBh\" readability=\"6\">\n<section readability=\"2\"><picture><img alt=\"Marcos Rojo se entren\u00f3 a la par: \u00bfpuede concentrar vs. Racing el domingo?\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2024\/03\/el-ex-boca-que-a-los-38-anos-fue-presentado-en-su-nuevo-club-de-estados-unidos-8.jpg\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"future\" loading=\"lazy\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>Marcos Rojo se entren\u00f3 a la par: \u00bfpuede concentrar vs. Racing el domingo?<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<div class=\"sc-a7166897-0 exHLBh\" readability=\"6\">\n<section readability=\"2\"><picture><img alt=\"Baja de peso en Boca: Chiquito Romero no jugar\u00e1 ante Racing\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2024\/03\/el-ex-boca-que-a-los-38-anos-fue-presentado-en-su-nuevo-club-de-estados-unidos-9.jpg\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"future\" loading=\"lazy\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>Baja de peso en Boca: Chiquito Romero no jugar\u00e1 ante Racing<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<div class=\"sc-a7166897-0 exHLBh\" readability=\"6\">\n<section readability=\"2\"><picture><img alt=\"El parte m\u00e9dico de Chiquito Romero en Boca\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2024\/03\/el-ex-boca-que-a-los-38-anos-fue-presentado-en-su-nuevo-club-de-estados-unidos-10.jpg\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"future\" loading=\"lazy\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>El parte m\u00e9dico de Chiquito Romero en Boca<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>08\/03\/2024 13:42hs. Juan Manuel Mart\u00ednez fue presentado como nuevo jugador del Club Lyon, equipo estadounidense que se fund\u00f3 en 2021. El delantero, que tuvo su paso por Boca, tiene 38 a\u00f1os y est\u00e1 ante la chance de jugar en el club n\u00famero 12 en su carrera. El Club Lyon es un equipo de Orlando, Florida, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":74308,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[16],"tags":[],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/74307"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=74307"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/74307\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media\/74308"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=74307"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=74307"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=74307"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}