{"id":74101,"date":"2024-03-03T08:25:04","date_gmt":"2024-03-03T08:25:04","guid":{"rendered":"https:\/\/www.mujerhoy.com\/vivir\/ocio\/maggie-ofarrell-nuevo-libro-la-distancia-que-nos-separa-20240303182722-nt.html"},"modified":"2024-03-03T08:25:04","modified_gmt":"2024-03-03T08:25:04","slug":"maggie-ofarrell-tiene-nuevo-libro-por-que-tienes-que-leer-a-la-escritora-britanica-de-moda-en-espana","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2024\/03\/03\/maggie-ofarrell-tiene-nuevo-libro-por-que-tienes-que-leer-a-la-escritora-britanica-de-moda-en-espana\/","title":{"rendered":"Maggie O&#8217;Farrell tiene nuevo libro: por qu\u00e9 tienes que leer a la escritora brit\u00e1nica de moda en Espa\u00f1a"},"content":{"rendered":"<p><!-- AUTHOR --> <\/p>\n<div class=\"voc-author-timesocial \"> <!-- AUTHOR --> <\/p>\n<div class=\"voc-author-timesocial__signature\"> <!-- IMAGE AUTHOR --> <picture class=\"voc-image-signature\"> <img class=\"voc-image-signature__img\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2024\/03\/maggie-ofarrell-tiene-nuevo-libro-por-que-tienes-que-leer-a-la-escritora-britanica-de-moda-en-espana.jpg\" alt=\"Alo\u00f1a Fdez. Larrechi\"> <\/picture> <!-- INFO AUTHOR --> <\/div><\/div>\n<p> <!-- COMPONENTS --> <\/p>\n<p class=\"voc-paragraph\">Arranca <a data-voc-vtm-id=\"in-text-traffic\" href=\"https:\/\/www.mujerhoy.com\/vivir\/ocio\/novedades-literarias-marzo-2024-maggie-ofarrell-otessa-moshfegh-20240301171929-nt.html\" title=\"www.mujerhoy.com\">marzo<\/a> cargado de novedades literarias y aunque febrero fue generoso con quienes no se quieren perder el \u00faltimo <a data-voc-vtm-id=\"in-text-traffic\" href=\"https:\/\/www.mujerhoy.com\/vivir\/ocio\/blackwater-saga-familiar-libros-espana-blackie-booksl-20240218013313-nt.html\" title=\"www.mujerhoy.com\">fen\u00f3meno editorial<\/a> y quienes disfrutan con mujeres at\u00edpicas, como la <a data-voc-vtm-id=\"in-text-traffic\" href=\"https:\/\/www.mujerhoy.com\/vivir\/ocio\/un-hambre-insciable-alpha-decay-foodie-critica-gastronomica-20240225171738-nt.html\" title=\"www.mujerhoy.com\">protagonista m\u00e1s ingeniosa y peligrosa<\/a>, nos emociona saber que estamos a horas de poder encontrar en nuestra librer\u00eda de cabecera el nuevo libro de la <strong>escritora brit\u00e1nica de moda<\/strong> en Espa\u00f1a, Maggie O&#8217;Farrell. <\/p>\n<p class=\"voc-paragraph\">La autora norirlandesa, responsable de t\u00edtulos tan recomendables y recomendados como Hamnet y El retrato de casa, regresa con la que fue su tercera novela, <strong>La distancia que nos separa<\/strong>. Publicada originalmente en 2004, y reconocida con el prestigioso Somerset Maugham, Libros del Asteroide la traduce ahora al espa\u00f1ol para que llegue a las librer\u00edas el 4 de marzo y siga engrosando una suma de ejemplares vendidos que supera los 250.000 entre sus cinco obras.\n<\/p>\n<p class=\"voc-paragraph\">En los \u00faltimos a\u00f1os es casi imposible encontrarse a una amante de la lectura o un aficionado a la literatura que no haya le\u00eddo algunos de sus t\u00edtulos. Muchos incluso han ca\u00eddo rendidos a sus pies y han hecho de <strong>Maggie O&#8217;Farrell<\/strong> una de sus autoras favoritas. Pero, si por un casual, t\u00fa no la conoces o te has resistido (absurdamente) a sumarte a esta moda, te contamos por qu\u00e9 tienes que leer a esta fabulosa escritora. <\/p>\n<p><h3 class=\"voc-detail__title\"> Familia, pasado e identidad<br \/>\n<\/h3>\n<\/p>\n<p class=\"voc-paragraph\">Periodista de formaci\u00f3n, O&#8217;Farrell dej\u00f3 los medios tras la publicaci\u00f3n de su primera novela, en el a\u00f1o 2000. Desde entonces ha publicado 9 novelas m\u00e1s una autobiograf\u00eda, Sigo aqu\u00ed (Libros del Asteroide) y en su obra hay temas que son una constante, tanto si se trata de su primera etapa como en sus dos \u00faltimos libros, ambientados ambos en el siglo XVI: los <strong>lazos familiares<\/strong>, el peso del pasado, el amor y la necesidad humana de encontrar un lugar propio en el mundo.\n<\/p>\n<div class=\"voc-detail-photo-zoom\"> <picture data-toggle=\"modal\" data-target=\"#photoZoomModal-154\" target=\"modal\">\n<div class=\"voc-img-icon-link\"> <img loading=\"lazy\" data-original=\"\/\/static1.mujerhoy.com\/www\/multimedia\/202403\/01\/media\/cortadas\/Ofarrell-distancia-portada-kizF--650x900@MujerHoy.jpeg\" width=\"650\" height=\"900\" class=\"lazy\" alt=\"Portada de La distancia que nos separa, el libro in\u00e9dito en Espa\u00f1a que llega a las librer\u00edas el 4 de marzo. \/ Libros del Asteroide\"> <noscript> <img src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2024\/03\/maggie-ofarrell-tiene-nuevo-libro-por-que-tienes-que-leer-a-la-escritora-britanica-de-moda-en-espana.webp\" alt=\"Portada de La distancia que nos separa, el libro in\u00e9dito en Espa\u00f1a que llega a las librer\u00edas el 4 de marzo. \/ Libros del Asteroide\"> <\/noscript> <i class=\"voc-icons zoom voc-multimedia-box voc-ico-l\"><\/i> <\/div><figcaption class=\"figure-caption\">Portada de La distancia que nos separa, el libro in\u00e9dito en Espa\u00f1a que llega a las librer\u00edas el 4 de marzo. \/ Libros del Asteroide<\/figcaption><\/picture>\n<\/div>\n<div id=\"photoZoomModal-154\" class=\"voc-lightbox modal fade voc-lightbox--photo-zoom\" role=\"dialog\" data-voc-photozoom-lightbox>\n<div class=\"voc-lightbox__dialog\" role=\"document\">\n<div class=\"voc-lightbox__content\"> <!-- Modal header --> <!-- Modal content --> <\/p>\n<div class=\"voc-lightbox__photo-container\"> <picture class> <img loading=\"lazy\" data-original=\"\/\/static1.mujerhoy.com\/www\/multimedia\/202403\/01\/media\/cortadas\/Ofarrell-distancia-portada-kizF--650x900@MujerHoy.jpeg\" alt=\"Portada de La distancia que nos separa, el libro in\u00e9dito en Espa\u00f1a que llega a las librer\u00edas el 4 de marzo. \/ Libros del Asteroide\" class=\"lazy\"> <noscript> <img src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2024\/03\/maggie-ofarrell-tiene-nuevo-libro-por-que-tienes-que-leer-a-la-escritora-britanica-de-moda-en-espana.webp\" alt=\"Portada de La distancia que nos separa, el libro in\u00e9dito en Espa\u00f1a que llega a las librer\u00edas el 4 de marzo. \/ Libros del Asteroide\"> <\/noscript> <\/picture> <\/div><\/div><\/div>\n<\/div>\n<p class=\"voc-paragraph\">En La distancia que nos separa los protagonistas son Stella y Jake. Ella vive en Londres, alejada de su familia y trabajando en un programa de radio. Todo va bien hasta que se cruza con alguien que cree reconocer y decide hacer las maletas, romper con todo y marcharse a <strong>Escocia<\/strong>. \u00c9l es hijo de padres brit\u00e1nicos aunque naci\u00f3 en Hong Kong y es all\u00ed donde se ha criado. Una desgracia en la celebraci\u00f3n del A\u00f1o Nuevo Chino, le llevar\u00e1 a viajar a Europa en busca de respuestas sobre su identidad y su existencia. <\/p>\n<p class=\"voc-paragraph\">Como es habitual en la prosa de O&#8217;Farrell las historias de sus protagonistas comparten p\u00e1ginas con personajes que podr\u00edan parecer secundarios. Pero es el desarrollo de sus propios relatos lo que enriquece el cuadro final que dibuja la escritora, porque juega con el <strong>poder nost\u00e1lgico de la Historia<\/strong> y tambi\u00e9n porque, en el caso de Stella y Jake, resultan esenciales para comprender sus problemas relacionados con la identidad y su propio origen.\n<\/p>\n<p><h3 class=\"voc-detail__title\"> El libro que conmovi\u00f3 al mundo<br \/>\n<\/h3>\n<\/p>\n<p class=\"voc-paragraph\">Una de las pocas cosas buenas que nos trajo 2020 fue <strong>Hamnet<\/strong>, el libro en el que O&#8217;Farrell se mueve entre la ficci\u00f3n y la realidad para contar la historia del hijo peque\u00f1o de William Shakespeare, quien inspirar\u00eda una de sus obras maestras, Hamlet. Poco se puede a\u00f1adir sobre una novela que fue reconocida con varios premios, sigue ocupando un lugar privilegiado en las librer\u00edas y tras una adaptaci\u00f3n teatral est\u00e1 previsto que la reconocida directora Chlo\u00e9 Zhao lleve al cine.\n<\/p>\n<div class=\"voc-detail-photo-zoom\"> <picture data-toggle=\"modal\" data-target=\"#photoZoomModal-590\" target=\"modal\">\n<div class=\"voc-img-icon-link\"> <img loading=\"lazy\" data-original=\"\/\/static.mujerhoy.com\/www\/multimedia\/202403\/01\/media\/cortadas\/Ofarrell-Hamnet-kizF--650x900@MujerHoy.jpg\" width=\"650\" height=\"900\" class=\"lazy\" alt=\"Portada de Hamnet, el libro m\u00e1s importante de la recomendable bibliograf\u00eda de O'Farrell. \/Libros del Asteroide\"> <noscript> <img src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2024\/03\/maggie-ofarrell-tiene-nuevo-libro-por-que-tienes-que-leer-a-la-escritora-britanica-de-moda-en-espana-1.webp\" alt=\"Portada de Hamnet, el libro m\u00e1s importante de la recomendable bibliograf\u00eda de O'Farrell. \/Libros del Asteroide\"> <\/noscript> <i class=\"voc-icons zoom voc-multimedia-box voc-ico-l\"><\/i> <\/div><figcaption class=\"figure-caption\">Portada de Hamnet, el libro m\u00e1s importante de la recomendable bibliograf\u00eda de O&#8217;Farrell. \/Libros del Asteroide<\/figcaption><\/picture>\n<\/div>\n<div id=\"photoZoomModal-590\" class=\"voc-lightbox modal fade voc-lightbox--photo-zoom\" role=\"dialog\" data-voc-photozoom-lightbox>\n<div class=\"voc-lightbox__dialog\" role=\"document\">\n<div class=\"voc-lightbox__content\"> <!-- Modal header --> <!-- Modal content --> <\/p>\n<div class=\"voc-lightbox__photo-container\"> <picture class> <img loading=\"lazy\" data-original=\"\/\/static.mujerhoy.com\/www\/multimedia\/202403\/01\/media\/cortadas\/Ofarrell-Hamnet-kizF--650x900@MujerHoy.jpg\" alt=\"Portada de Hamnet, el libro m\u00e1s importante de la recomendable bibliograf\u00eda de O'Farrell. \/Libros del Asteroide\" class=\"lazy\"> <noscript> <img src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2024\/03\/maggie-ofarrell-tiene-nuevo-libro-por-que-tienes-que-leer-a-la-escritora-britanica-de-moda-en-espana-1.webp\" alt=\"Portada de Hamnet, el libro m\u00e1s importante de la recomendable bibliograf\u00eda de O'Farrell. \/Libros del Asteroide\"> <\/noscript> <\/picture> <\/div><\/div><\/div>\n<\/div>\n<p class=\"voc-paragraph\">La prosa detallista de O&#8217;Farrell, su inter\u00e9s por llevar a cada p\u00e1gina un retrato \u00edntimo y reconocible por el lector de sus personajes y su capacidad para crear historias que, en el pasado o en el presente, se nutren de <strong>lo cotidiano para resultar extraordinarias<\/strong> son los principales valores de unas novelas que siempre consiguen dejar poso. <\/p>\n<p class=\"voc-paragraph\">As\u00ed que si todav\u00eda no te has sumado a la fiebre por Maggie O&#8217;Farrell est\u00e1s de enhorabuena porque, de la mano de <strong>Libros del Asteroide<\/strong>, tienes seis deliciosas novelas pendientes de disfrutar. Y si ya eres una de sus seguidoras, tambi\u00e9n lo est\u00e1s porque La distancia que nos separa llega ma\u00f1ana a las librer\u00edas para hacernos disfrutar de una misteriosa historia que te atrapar\u00e1 con su desarrollo, repleto de sorpresas, y el dominio narrativo de una maestra como la novelista brit\u00e1nica. <\/p>\n<p> <!-- TOPICS --> <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Arranca marzo cargado de novedades literarias y aunque febrero fue generoso con quienes no se quieren perder el \u00faltimo fen\u00f3meno editorial y quienes disfrutan con mujeres at\u00edpicas, como la protagonista m\u00e1s ingeniosa y peligrosa, nos emociona saber que estamos a horas de poder encontrar en nuestra librer\u00eda de cabecera el nuevo libro de la escritora [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":74102,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/74101"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=74101"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/74101\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media\/74102"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=74101"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=74101"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=74101"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}