{"id":73079,"date":"2024-01-20T12:03:52","date_gmt":"2024-01-20T12:03:52","guid":{"rendered":"https:\/\/www.ole.com.ar\/futbol-internacional\/benzema-demanda-islamismo-francia-presentacion-judicial_0_cU049CEEzU.html"},"modified":"2024-01-20T12:03:52","modified_gmt":"2024-01-20T12:03:52","slug":"benzema-se-defiende-en-la-justicia-de-que-se-lo-acusa","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2024\/01\/20\/benzema-se-defiende-en-la-justicia-de-que-se-lo-acusa\/","title":{"rendered":"Benzema se defiende en la Justicia: \u00bfde qu\u00e9 se lo acusa?"},"content":{"rendered":"<p><img src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2024\/01\/benzema-se-defiende-en-la-justicia-de-que-se-lo-acusa.jpg\"><\/p>\n<p><time class=\"createDate\" datetime=\"2024-01-20T09:03:52-03:00\">20\/01\/2024 09:03hs.<\/time><\/p>\n<div id=\"storyBody\">\n<div class=\"custom-text \" readability=\"8.4845814977974\">\n<p>El futbolista franc\u00e9s <strong><a href=\"https:\/\/www.ole.com.ar\/tema\/karim-benzema.html\" title=\"Karim Benzema\" alt=\"Karim Benzema\" class=\"slug\">Karim Benzema<\/a><\/strong> <strong>present\u00f3 una demanda por difamaci\u00f3n <\/strong>contra el dirigente ultraderechista franc\u00e9s \u00c9ric Zemmour <strong>por unas declaraciones en las que lo vincul\u00f3 con asesinatos islamistas <\/strong>cometidos en Francia.<\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"10\">\n<p>La emisora RMC Sports inform\u00f3 que el abogado de Benzema, Hugues Vigier, present\u00f3 la querella en la tarde del viernes ante el Tribunal Judicial de Par\u00eds.<\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"10\">\n<p>Si la demanda es admitida a tr\u00e1mite, Zemmour se expone a una pena de hasta un a\u00f1o de prisi\u00f3n y una multa de 45.000 euros, en caso de ser declarado culpable.<\/p>\n<\/div>\n<p><h2><strong>\u00bfDe qu\u00e9 acusaron a Benzema?<\/strong><\/h2>\n<\/p>\n<div class=\"custom-text \" readability=\"11\">\n<p><strong>Zemmour, presidente del partido de extrema derecha Reconquete (Reconquista) hab\u00eda establecido un v\u00ednculo entre Benzema y los asesinatos terroristas de dos profesores de secundaria<\/strong>, Samuel Paty en 2020 y Dominique Bernard en 2023.<\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"13\">\n<p>En una entrevista televisada en octubre pasado, Zemmour dijo que Benzema \u00abes un musulm\u00e1n que quiere aplicar la &#8216;sharia&#8217; (ley isl\u00e1mica), y la &#8216;sharia&#8217; prev\u00e9 la &#8216;yihad&#8217; (guerra santa), y la &#8216;yihad&#8217; quiere decir matar a Dominique Bernard, quiere decir matar a Samuel Paty\u00bb.<\/p>\n<\/div>\n<p><h2><strong>Benzema no se qued\u00f3 con los brazos cruzados<\/strong><\/h2>\n<\/p>\n<div class=\"custom-text \" readability=\"17\">\n<p>Benzema ya se querell\u00f3 el pasado martes contra el ministro franc\u00e9s del Interior, G\u00e9rald Darmanin, quien en otra entrevista televisada, tambi\u00e9n en octubre,<strong> consider\u00f3 \u00abnotorios\u00bb los v\u00ednculos de Benzema con los Hermanos Musulmanes<\/strong>, un grupo que en algunos pa\u00edses se considera terrorista, aunque no en Francia, donde tampoco es ilegal.<\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"12\">\n<p>En la demanda, de 92 p\u00e1ginas, se acusa al ministro de generar divisi\u00f3n en Francia con sus declaraciones y de haber provocado da\u00f1os a los hijos del futbolista, que asegur\u00f3 no tener \u00abninguna relaci\u00f3n\u00bb con los Hermanos Musulmanes.<\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"11\">\n<p>\u00abCuando lo que se pretende es no importar el conflicto israelo-palestino a Francia, no se entiende que se corra el riesgo de atizar las brasas con declaraciones falsas\u00bb, indicaron los letrados del futbolista.<\/p>\n<\/div>\n<div class=\"sc-a7166897-0 exHLBh\" readability=\"6.5\">\n<section readability=\"3\"><picture><img alt=\"Benzema volvi\u00f3 a los entrenamientos, \u00bfpero sigue?\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2024\/01\/benzema-se-defiende-en-la-justicia-de-que-se-lo-acusa-2.jpg\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"future\" loading=\"lazy\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>Benzema volvi\u00f3 a los entrenamientos, \u00bfpero sigue?<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<div class=\"sc-a7166897-0 exHLBh\" readability=\"6\">\n<section readability=\"2\"><picture><img alt=\"La contundente frase del entorno de Benzema tras su conflicto con Gallardo\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2024\/01\/benzema-se-defiende-en-la-justicia-de-que-se-lo-acusa-3.jpg\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"future\" loading=\"lazy\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>La contundente frase del entorno de Benzema tras su conflicto con Gallardo<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<div class=\"sc-a7166897-0 exHLBh\" readability=\"7\">\n<section readability=\"4\"><picture><img alt=\"Lesi\u00f3n, crucero y rescisi\u00f3n de contrato: el incierto futuro de Neymar en Arabia Saudita \" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2024\/01\/benzema-se-defiende-en-la-justicia-de-que-se-lo-acusa-4.jpg\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"future\" loading=\"lazy\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>Lesi\u00f3n, crucero y rescisi\u00f3n de contrato: el incierto futuro de Neymar en Arabia Saudita<br \/>\n<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>20\/01\/2024 09:03hs. El futbolista franc\u00e9s Karim Benzema present\u00f3 una demanda por difamaci\u00f3n contra el dirigente ultraderechista franc\u00e9s \u00c9ric Zemmour por unas declaraciones en las que lo vincul\u00f3 con asesinatos islamistas cometidos en Francia. La emisora RMC Sports inform\u00f3 que el abogado de Benzema, Hugues Vigier, present\u00f3 la querella en la tarde del viernes ante el [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":73080,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[16],"tags":[],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/73079"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=73079"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/73079\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media\/73080"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=73079"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=73079"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=73079"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}