{"id":7274,"date":"2020-12-11T20:00:33","date_gmt":"2020-12-11T20:00:33","guid":{"rendered":"https:\/\/www.espinof.com\/animacion\/dug-days-pixar-nos-llevara-nuevo-al-universo-up-serie-para-disney-plus-centrada-entranable-perro"},"modified":"2020-12-11T20:00:33","modified_gmt":"2020-12-11T20:00:33","slug":"dug-days-pixar-nos-llevara-de-nuevo-al-universo-de-up-con-una-serie-para-disney-centrada-en-el-entranable-perro","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2020\/12\/11\/dug-days-pixar-nos-llevara-de-nuevo-al-universo-de-up-con-una-serie-para-disney-centrada-en-el-entranable-perro\/","title":{"rendered":"&#8216;Dug Days&#8217;: Pixar nos llevar\u00e1 de nuevo al universo de &#8216;Up&#8217; con una serie para Disney+ centrada en el entra\u00f1able perro"},"content":{"rendered":"<div readability=\"53.61958041958\">\n<p>Es, hasta cierto punto, l\u00f3gico y normal, que la inmensa mayor\u00eda de miradas proyectadas sobre los anuncios que La casa del rat\u00f3n ha hecho durante el <strong>Disney Investor Day 2020<\/strong> se hayan centrado en las dos grandes franquicias de la compa\u00f1\u00eda: <a href=\"http:\/\/www.espinof.com\/tag\/marvel\">Marvel<\/a> y <a href=\"http:\/\/www.espinof.com\/tag\/star-wars\">&#8216;Star Wars&#8217;<\/a>. Pero esto no tiene que ser impedimento para que reine cierto entusiasmo hacia las <strong>tres series de televisi\u00f3n<\/strong> que est\u00e1 preparado <a href=\"http:\/\/www.espinof.com\/tag\/pixar\">Pixar<\/a> para la plataforma Disney+. <\/p>\n<p><!-- BREAK 1 --><!--more--><\/p>\n<p>La primera de estas producciones del prestigioso estudio de animaci\u00f3n ser\u00e1 <strong>&#8216;Dug Days&#8217;<\/strong>; un inesperado <em>spin off<\/em> de la maravillosa <a href=\"http:\/\/www.espinof.com\/tag\/up\">&#8216;Up&#8217;<\/a> que codirigieron <a href=\"http:\/\/www.espinof.com\/tag\/peter-docter\">Pete Docter<\/a> y Bob Peterson en 2009, <strong>centrado en la figura del entra\u00f1able Dug<\/strong>: el perro obsesionado con las ardillas que consigui\u00f3 quitar algo de gravedad al lacrim\u00f3geno poso del largometraje original.<\/p>\n<p><!-- BREAK 2 --> <\/p>\n<div class=\"article-asset article-asset-normal article-asset-center\">\n<div class=\"desvio-container\">\n<div class=\"desvio\">\n<div class=\"desvio-figure js-desvio-figure\"> <a href=\"https:\/\/www.espinof.com\/listas\/todas-las-peliculas-de-pixar-ordenadas-de-peor-a-mejor\"> <img alt=\"Todas las pel\u00edculas de Pixar ordenadas de peor a mejor\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2020\/12\/dug-days-pixar-nos-llevara-de-nuevo-al-universo-de-up-con-una-serie-para-disney-centrada-en-el-entranable-perro.jpg\"> <\/a> <\/div><\/div><\/div>\n<\/div>\n<p>Junto a &#8216;Dug Days&#8217;, de la que a\u00fan <strong>no se conocen m\u00e1s detalles<\/strong>, ni si Ed Asner o Bob Peterson repetir\u00e1n sus papeles como Carl Fredricksen o el can protagonista, Pixar tambi\u00e9n est\u00e1 preparando una serie ambientada en el universo <a href=\"http:\/\/www.espinof.com\/tag\/cars\">&#8216;Cars&#8217;<\/a> y otro show original titulado <strong>&#8216;Win Or Lose&#8217;<\/strong>; sin duda, un mazazo para la competencia que pretenda plantar cara con productos de animaci\u00f3n en las <em>streaming wars<\/em>.<\/p>\n<p><!-- BREAK 3 --><\/p>\n<p>Se espera que &#8216;Dug Days&#8217; se estrene en Disney+ a lo largo del <strong>oto\u00f1o de 2021<\/strong>. Estaremos atentos a cualquier novedad sobre una serie que, seguro, nos arrancar\u00e1 m\u00e1s de una sonrisa.<\/p>\n<p><!-- BREAK 4 --> <\/div>\n<div readability=\"18.017509727626\">\n<div class=\"article-social-share js-article-social-share m-in-links\" readability=\"26.926380368098\">\n<p> Compartir <q class=\"article-social-share-meta\"> &#8216;Dug Days&#8217;: Pixar nos llevar\u00e1 de nuevo al universo de &#8216;Up&#8217; con una serie para Disney+ centrada en el entra\u00f1able perro <\/q> <\/p>\n<\/p><\/div>\n<div class=\"article-topics-list\"> <span class=\"article-topic-desc\">Temas<\/span> <\/p>\n<ul class=\"article-topics-categories\">\n<li><a class=\"article-topic-link\" href=\"https:\/\/www.espinof.com\/categoria\/animacion\">Animaci\u00f3n<\/a><\/li>\n<li><a class=\"article-topic-link\" href=\"https:\/\/www.espinof.com\/categoria\/series-de-ficcion\">Series de ficci\u00f3n<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Es, hasta cierto punto, l\u00f3gico y normal, que la inmensa mayor\u00eda de miradas proyectadas sobre los anuncios que La casa del rat\u00f3n ha hecho durante el Disney Investor Day 2020 se hayan centrado en las dos grandes franquicias de la compa\u00f1\u00eda: Marvel y &#8216;Star Wars&#8217;. Pero esto no tiene que ser impedimento para que reine [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":7275,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/7274"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=7274"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/7274\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media\/7275"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=7274"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=7274"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=7274"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}