{"id":71522,"date":"2023-12-19T23:40:52","date_gmt":"2023-12-19T23:40:52","guid":{"rendered":"https:\/\/www.ole.com.ar\/futbol-internacional\/espana\/video-golazo-lucas-ocampos-sevilla-granada_0_Mr727aLEbs.html"},"modified":"2023-12-19T23:40:52","modified_gmt":"2023-12-19T23:40:52","slug":"video-el-golazo-de-lucas-ocampos-en-la-goleada-del-sevilla","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2023\/12\/19\/video-el-golazo-de-lucas-ocampos-en-la-goleada-del-sevilla\/","title":{"rendered":"Video: el golazo de Lucas Ocampos en la goleada del Sevilla"},"content":{"rendered":"<p><img src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2023\/12\/video-el-golazo-de-lucas-ocampos-en-la-goleada-del-sevilla.jpg\"><\/p>\n<p><time class=\"createDate\" datetime=\"2023-12-19T20:40:52-03:00\">19\/12\/2023 20:40hs.<\/time><time class=\"modificatedDate\" datetime=\"2023-12-19T20:40:52-03:00\"><\/time><\/p>\n<div id=\"storyBody\">\n<div class=\"custom-text \" readability=\"10.626506024096\">\n<p>Luego de 10 partidos sin victorias en <a href=\"https:\/\/www.ole.com.ar\/tema\/la-liga-de-espana.html\" title=\"La Liga de Espa\u00f1a\" alt=\"La Liga de Espa\u00f1a\" class=\"slug\">La Liga de Espa\u00f1a<\/a>, <strong>el <a href=\"https:\/\/www.ole.com.ar\/tema\/sevilla.html\" title=\"Sevilla\" alt=\"Sevilla\" class=\"slug\">Sevilla <\/a><\/strong>se reencontr\u00f3 con su mejor nivel y este martes<strong> gole\u00f3 3-0 al Granada con <a href=\"https:\/\/www.ole.com.ar\/tema\/lucas-ocampos.html\" title=\"Lucas Ocampos\" alt=\"Lucas Ocampos\" class=\"slug\">Lucas Ocampos<\/a> como gran figura<\/strong>. En el debut de Enrique S\u00e1nchez Flores como DT del equipo andaluz, el argentino clav\u00f3 un verdadero golazo al \u00e1ngulo que puso el 2-0 parcial en el marcador.<\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"12.155844155844\">\n<p>Iba media hora de juego y los sevillistas ya se impon\u00edan por la m\u00ednima gracias a un tanto de Adri\u00e1 Pedrosa. En ese momento, el volante de la <strong><a href=\"https:\/\/www.ole.com.ar\/tema\/seleccion-argentina.html\" title=\"Selecci\u00f3n Argentina\" alt=\"Selecci\u00f3n Argentina\" class=\"slug\">Selecci\u00f3n Argentina<\/a><\/strong> recuper\u00f3 la pelota tras una mala salida de su rival y, sin dudarlo, sac\u00f3 un fierrazo desde 35 metros que se clav\u00f3 en el \u00e1ngulo. Inatajable.<\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"12.110749185668\">\n<p><strong>Este fue el segundo grito del argentino en la actual certamen dom\u00e9stico<\/strong>. Su anterior gol hab\u00eda llegado en la fecha 11, en el empate 2-2 ante el C\u00e1diz. Adem\u00e1s, el ex <a href=\"https:\/\/www.ole.com.ar\/tema\/river-plate.html\" title=\"River Plate\" alt=\"River Plate\" class=\"slug\">River<\/a> tambi\u00e9n hab\u00eda facturado en la primera fecha de la fase de grupos de la <a href=\"https:\/\/www.ole.com.ar\/tema\/champions-league.html\" title=\"Champions League\" alt=\"Champions League\" class=\"slug\">Champions League<\/a>, cuando su equipo igual\u00f3 1-1 con el Lens.<\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"11\">\n<p>Tras el tanto de Ocampos, el Sevilla sigui\u00f3 dominando un encuentro que termin\u00f3 siendo goleada. A trav\u00e9s de un cabezazo de Sergio Ramos, el Sevilla se qued\u00f3 un contundente 3-0 final frente a un Granada que no levanta cabeza.<\/p>\n<\/div>\n<div type=\"embed\" class=\"sc-7ce6049-0 dwIKul\">\n<div class=\"sc-7ce6049-1 bdcBBS videoText\" id=\"contentTitleembeddRKhTpjw\" type=\"embed\" readability=\"6\"><svg fill=\"#ffffff\"><symbol id=\"play\" viewBox=\"0 0 512 512\"><path d=\"M512 256C512 397.4 397.4 512 256 512C114.6 512 0 397.4 0 256C0 114.6 114.6 0 256 0C397.4 0 512 114.6 512 256zM176 168V344C176 352.7 180.7 360.7 188.3 364.9C195.8 369.2 205.1 369 212.5 364.5L356.5 276.5C363.6 272.1 368 264.4 368 256C368 247.6 363.6 239.9 356.5 235.5L212.5 147.5C205.1 142.1 195.8 142.8 188.3 147.1C180.7 151.3 176 159.3 176 168V168z\" \/><\/symbol><use xlink:href=\"#play\" \/><\/svg><\/p>\n<div class=\"right\" readability=\"7\">\n<p>Lucas Ocampos<!-- --> &#8211;<!-- --> <span>19-12-2023<\/span><\/p>\n<h2 class=\"title-vid\">Golazo de Ocampos en el triunfo del Sevilla<\/h2>\n<\/div>\n<\/div>\n<p><span class=\"back\" id=\"spanBackembeddRKhTpjw\"><\/span><\/div>\n<p><h2><strong>Una victoria necesaria<\/strong><\/h2>\n<\/p>\n<div class=\"custom-text \" readability=\"11\">\n<p>El equipo andaluz consigui\u00f3 una importante victoria que le permite despegarse de los \u00faltimos puestos del torneo dom\u00e9stico y romper una dur\u00edsima racha. <strong>Y es que el equipo andaluz acumulaba 15 partidos consecutivos sin triunfos entre La Liga y la Champions<\/strong>. Para encontrar su anterior victoria en alguno de estos torneos hay que remontarse al <strong>\u00a126 de septiembre!<\/strong>, cuando los aquel entonces dirigidos por Mendilibar golearon 5-1 al Almer\u00eda.<\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"12\">\n<p>Desde entonces, el Sevilla no hab\u00eda vuelto a ganar en estos cert\u00e1menes. Sus \u00fanicas victorias hab\u00edan sido en la Copa del Rey, cuando vencieron al Quintana (3-0) y al Atl\u00e9tico Astorga (2-0), dos conjuntos de las divisiones inferiores de Espa\u00f1a.<\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"14\">\n<p>Con esta goleada ante el Granada, el equipo que ahora dirige S\u00e1nchez Flores consigui\u00f3 apenas su tercer triunfo en el campeonato. Esto le permiti\u00f3 alcanzar el 13\u00b0 lugar de la tabla, con 16 puntos, aunque solo tres por encima de los puestos de descenso. <strong>Su pr\u00f3ximo compromiso ser\u00e1 contra el Atl\u00e9tico Madrid<\/strong> el pr\u00f3ximo s\u00e1bado, por un duelo pendiente de la cuarta fecha.<\/p>\n<\/div>\n<div class=\"sc-e7b891c4-0 jPbnQF\"><img alt=\"El Sevilla rompi\u00f3 la mala racha. (EFE)\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2023\/12\/video-el-golazo-de-lucas-ocampos-en-la-goleada-del-sevilla-2.jpg\" width=\"720\" height=\"100\" decoding=\"async\" data-nimg=\"future\" loading=\"lazy\"><span class=\"epigraphe\">El Sevilla rompi\u00f3 la mala racha. (EFE)<\/span><\/div>\n<div class=\"custom-text \" readability=\"11\">\n<p>Por el otro lado, el Granada que sigue sin levantar cabeza. Apenas gan\u00f3 uno de sus 18 compromisos en todo el certamen y el club hunde en la zona de descenso, con solamente ocho unidades y a cinco de la salvaci\u00f3n.<\/p>\n<\/div>\n<div class=\"sc-a7166897-0 exHLBh\" readability=\"6\">\n<section readability=\"2\"><picture><img alt=\"El coleccionista de t\u00edtulos: el nuevo r\u00e9cord que busca Juli\u00e1n Alvarez\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2023\/12\/video-el-golazo-de-lucas-ocampos-en-la-goleada-del-sevilla-3.jpg\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"future\" loading=\"lazy\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>El coleccionista de t\u00edtulos: el nuevo r\u00e9cord que busca Juli\u00e1n Alvarez<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<div class=\"sc-a7166897-0 exHLBh\" readability=\"6\">\n<section readability=\"2\"><picture><img alt=\"\u00bfC\u00f3mo y cu\u00e1ndo se define el Mundial de Clubes?\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2023\/12\/video-el-golazo-de-lucas-ocampos-en-la-goleada-del-sevilla-4.jpg\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"future\" loading=\"lazy\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>\u00bfC\u00f3mo y cu\u00e1ndo se define el Mundial de Clubes?<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<div class=\"sc-a7166897-0 exHLBh\" readability=\"6\">\n<section readability=\"2\"><picture><img alt=\"Macri: de las elecciones a ver al City por la FIFA\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2023\/12\/video-el-golazo-de-lucas-ocampos-en-la-goleada-del-sevilla-5.jpg\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"future\" loading=\"lazy\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>Macri: de las elecciones a ver al City por la FIFA<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>19\/12\/2023 20:40hs. Luego de 10 partidos sin victorias en La Liga de Espa\u00f1a, el Sevilla se reencontr\u00f3 con su mejor nivel y este martes gole\u00f3 3-0 al Granada con Lucas Ocampos como gran figura. En el debut de Enrique S\u00e1nchez Flores como DT del equipo andaluz, el argentino clav\u00f3 un verdadero golazo al \u00e1ngulo que [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":71523,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[16],"tags":[],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/71522"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=71522"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/71522\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media\/71523"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=71522"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=71522"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=71522"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}