{"id":70400,"date":"2023-11-28T02:25:42","date_gmt":"2023-11-28T02:25:42","guid":{"rendered":"https:\/\/www.ole.com.ar\/seleccion\/seleccion-argentina-vs-alemania-semifinal-mundial-sub-17-hora-ver-hoy-vivo-online_0_UrcEd8TC2V.html"},"modified":"2023-11-28T02:25:42","modified_gmt":"2023-11-28T02:25:42","slug":"argentina-vs-alemania-hoy-en-vivo-por-el-mundial-sub-17-gol-de-alemania-y-cae-la-seleccion","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2023\/11\/28\/argentina-vs-alemania-hoy-en-vivo-por-el-mundial-sub-17-gol-de-alemania-y-cae-la-seleccion\/","title":{"rendered":"Argentina vs. Alemania, hoy EN VIVO por el Mundial Sub 17: \u00a1Gol de Alemania y cae la Selecci\u00f3n!"},"content":{"rendered":"<p><img src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2023\/11\/argentina-vs-alemania-hoy-en-vivo-por-el-mundial-sub-17-gol-de-alemania-y-cae-la-seleccion.jpg\"><\/p>\n<div><img src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2023\/11\/argentina-vs-alemania-hoy-en-vivo-por-el-mundial-sub-17-gol-de-alemania-y-cae-la-seleccion-2.jpg\" class=\"ff-og-image-inserted\"><\/div>\n<h2><strong>\u00bfC\u00f3mo est\u00e1 el historial de Argentina y Alemania en Copas del Mundo?<\/strong><\/h2>\n<p><strong>En total, son tres victorias de Argentina, tres empates y cinco triunfos de Alemania.<\/strong> En la competencia que m\u00e1s se han visto las caras es en el Mundial de Mayores, con solo una victoria de la Albiceleste (3-2 en la final de M\u00e9xico &#8217;86), dos igualdades y cuatro triunfos para La M\u00e1quina, incluyendo las finales de Italia &#8217;90 y Brasil 2014. En la Sub 20, solo se cruzaron en una oportunidad: victoria 1-0 de la Selecci\u00f3n en la fase de grupos de Holanda 2015.<\/p>\n<p>En cuanto a los <strong>Mundiales Sub 17<\/strong>, se midieron en <strong>tres ocasiones<\/strong>, todas en fase de grupos. La primera, en <strong>Uni\u00f3n Sovi\u00e9tica &#8217;85<\/strong>: <strong>empate 1-1<\/strong>, con tanto de Fernando C\u00e1ceres para Argentina. La segunda, en <strong>Nigeria 2009<\/strong>: <strong>victoria 2-1<\/strong>, con festejos de Esteban L\u00f3pez y Sergio Araujo (y el descuento de un tal Mario Gotze para Alemania). Y, el tercero, un <strong>doloroso 4-0<\/strong> en <strong>Chile 2015<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfC\u00f3mo est\u00e1 el historial de Argentina y Alemania en Copas del Mundo? En total, son tres victorias de Argentina, tres empates y cinco triunfos de Alemania. En la competencia que m\u00e1s se han visto las caras es en el Mundial de Mayores, con solo una victoria de la Albiceleste (3-2 en la final de M\u00e9xico [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":70401,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[16],"tags":[],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/70400"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=70400"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/70400\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media\/70401"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=70400"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=70400"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=70400"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}