{"id":7033,"date":"2020-12-08T20:20:39","date_gmt":"2020-12-08T20:20:39","guid":{"rendered":"https:\/\/www.espinof.com\/proyectos\/anya-taylor-joy-cocreador-gambito-dama-se-volveran-a-reunir-para-adaptar-risa-oscuridad-nabokov"},"modified":"2020-12-08T20:20:39","modified_gmt":"2020-12-08T20:20:39","slug":"anya-taylor-joy-y-el-cocreador-de-gambito-de-dama-se-volveran-a-reunir-para-adaptar-risa-en-la-oscuridad-de-nabokov","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2020\/12\/08\/anya-taylor-joy-y-el-cocreador-de-gambito-de-dama-se-volveran-a-reunir-para-adaptar-risa-en-la-oscuridad-de-nabokov\/","title":{"rendered":"Anya Taylor-Joy y el cocreador de &#8216;Gambito de dama&#8217; se volver\u00e1n a reunir para adaptar &#8216;Risa en la oscuridad&#8217; de Nabokov"},"content":{"rendered":"<div readability=\"63.874104401228\">\n<p>&#8216;<a href=\"https:\/\/www.espinof.com\/tag\/gambito-de-dama\">Gambito de Dama<\/a>&#8216; (The Queen&#8217;s Gambit, 2020) se ha convertido en un fen\u00f3meno global que no abandona el puesto n\u00famero uno de lo m\u00e1s visto semanal en <a href=\"https:\/\/www.espinof.com\/categoria\/netflix\">Netflix<\/a>, y ahora, el co-creador <strong>Scott Frank<\/strong> y la actriz principal <strong>Anya Taylor-Joy<\/strong>, quien interpreta a la prodigio del ajedrez Beth Harmon, esperan repetir el \u00e9xito con su pr\u00f3ximo proyecto, <strong>una adaptaci\u00f3n del autor de &#8216;Lolita&#8217;, Vladimir Nabokov, con Joy como protagonista.<\/strong><\/p>\n<p><!-- BREAK 1 --><!--more--><\/p>\n<div class=\"article-asset-image article-asset-normal\">\n<div class=\"asset-content\"> <img class=\"sf-lazy centro_sinmarco\" data-sf-srcset=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2020\/12\/anya-taylor-joy-y-el-cocreador-de-gambito-de-dama-se-volveran-a-reunir-para-adaptar-risa-en-la-oscuridad-de-nabokov.jpg 450w, http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2020\/12\/anya-taylor-joy-y-el-cocreador-de-gambito-de-dama-se-volveran-a-reunir-para-adaptar-risa-en-la-oscuridad-de-nabokov-3.jpg 681w,http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2020\/12\/anya-taylor-joy-y-el-cocreador-de-gambito-de-dama-se-volveran-a-reunir-para-adaptar-risa-en-la-oscuridad-de-nabokov-4.jpg 1024w, http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2020\/12\/anya-taylor-joy-y-el-cocreador-de-gambito-de-dama-se-volveran-a-reunir-para-adaptar-risa-en-la-oscuridad-de-nabokov-5.jpg 1366w,\" data-sf-src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2020\/12\/anya-taylor-joy-y-el-cocreador-de-gambito-de-dama-se-volveran-a-reunir-para-adaptar-risa-en-la-oscuridad-de-nabokov.jpg\" alt=\"Laughter\"> <noscript><img alt=\"Laughter\" class=\"centro_sinmarco\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2020\/12\/anya-taylor-joy-y-el-cocreador-de-gambito-de-dama-se-volveran-a-reunir-para-adaptar-risa-en-la-oscuridad-de-nabokov.jpg\"><\/noscript> <\/div>\n<\/div>\n<h2>Otra nueva versi\u00f3n de la novela<\/h2>\n<p>Seg\u00fan una entrevista con el podcast &#8216;<a href=\"https:\/\/podcasts.google.com\/feed\/aHR0cHM6Ly9mZWVkcy5tZWdhcGhvbmUuZm0vdGhlLXdhdGNo\/episode\/Njk0ZTZhZTgtMGQ4Yy0xMWViLThiN2MtNGI3NDRmZmZkOWMz?hl=en&amp;ved=2ahUKEwjbsai6jL3tAhVpc98KHejNAkkQjrkEegQIBhAI&amp;ep=6\">The Ringer de The Ringer<\/a>&#8216; de <a href=\"https:\/\/www.joblo.com\/movie-news\/scott-frank-new-projects-anya-taylor-joy-clive-owen\">JoBlo.com<\/a>, Frank dice estar desarrollando actualmente una nueva adaptaci\u00f3n de la novela &#8216;<strong>Risa en la oscuridad<\/strong>&#8216; (Laughter in the Dark, 1935) describi\u00e9ndo el proyecto como:<\/p>\n<p><!-- BREAK 2 --> <\/p>\n<blockquote readability=\"7\">\n<p>\u00abUn d\u00eda de San Valent\u00edn para las pel\u00edculas, lo voy a hacer como cine negro y una pel\u00edcula dentro de una pel\u00edcula. Es un thriller realmente desagradable y maravilloso\u00bb. <\/p>\n<\/blockquote>\n<div class=\"article-asset article-asset-normal article-asset-center\">\n<div class=\"desvio-container\">\n<div class=\"desvio\">\n<div class=\"desvio-figure js-desvio-figure\"> <a href=\"https:\/\/www.espinof.com\/listas\/mejores-peliculas-series-documentales-ajedrez-para-ver-te-ha-gustado-gambito-dama\"> <img alt=\"Las 13 mejores pel\u00edculas, series y documentales sobre ajedrez para ver si te ha gustado 'Gambito de Dama'\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2020\/12\/anya-taylor-joy-y-el-cocreador-de-gambito-de-dama-se-volveran-a-reunir-para-adaptar-risa-en-la-oscuridad-de-nabokov-1.jpg\"> <\/a> <\/div><\/div><\/div>\n<\/div>\n<p>Adaptada en 1969 por <strong>Tony Richardson<\/strong>, la novela se centra en <strong>Albert Albinus<\/strong>, un cr\u00edtico de arte de mediana edad que tiene un inter\u00e9s especial en Margot Peters, una aspirante a actriz y modelo de 17 a\u00f1os. Forman una relaci\u00f3n mutuamente parasitaria, instigada por el antiguo amor de Margot, Axel Rex, quien se re\u00fane con ella para quitarle la vida a Albert. N<strong>abokov utiliz\u00f3 parte de estas ideas como base para &#8216;Lolita&#8217;, su obra m\u00e1s adaptada<\/strong>. Rainer Werner Fassbinder adapt\u00f3 la comedia negra de Nabokov sobre un <em>doppelg\u00e4nger<\/em> &#8216;<strong>Desesperaci\u00f3n<\/strong>&#8216; (Despair) en 1978.<\/p>\n<p><!-- BREAK 3 --> <\/p>\n<div class=\"article-asset-image article-asset-normal\">\n<div class=\"asset-content\"> <img class=\"sf-lazy centro_sinmarco\" data-sf-srcset=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2020\/12\/anya-taylor-joy-y-el-cocreador-de-gambito-de-dama-se-volveran-a-reunir-para-adaptar-risa-en-la-oscuridad-de-nabokov.gif 450w, http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2020\/12\/anya-taylor-joy-y-el-cocreador-de-gambito-de-dama-se-volveran-a-reunir-para-adaptar-risa-en-la-oscuridad-de-nabokov-1.gif 681w,http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2020\/12\/anya-taylor-joy-y-el-cocreador-de-gambito-de-dama-se-volveran-a-reunir-para-adaptar-risa-en-la-oscuridad-de-nabokov-2.gif 1024w, http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2020\/12\/anya-taylor-joy-y-el-cocreador-de-gambito-de-dama-se-volveran-a-reunir-para-adaptar-risa-en-la-oscuridad-de-nabokov-3.gif 1366w,\" data-sf-src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2020\/12\/anya-taylor-joy-y-el-cocreador-de-gambito-de-dama-se-volveran-a-reunir-para-adaptar-risa-en-la-oscuridad-de-nabokov.gif\" alt=\"Queensgambitgif1\"> <noscript><img alt=\"Queensgambitgif1\" class=\"centro_sinmarco\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2020\/12\/anya-taylor-joy-y-el-cocreador-de-gambito-de-dama-se-volveran-a-reunir-para-adaptar-risa-en-la-oscuridad-de-nabokov.gif\"><\/noscript> <\/div>\n<\/div>\n<p><strong>Scott Frank<\/strong>, nominado al Oscar por los guiones de &#8216;<strong>Out of Sight&#8217; y &#8216;Logan<\/strong>&#8216; dijo que tambi\u00e9n est\u00e1 trabajando en otro proyecto inspirado en las obras del novelista <strong>Dashiell Hammett<\/strong> donde Clive Owen interpretar\u00eda a un envejecido Sam Spade de 60 a\u00f1os, el protagonista de &#8216;<strong>El halc\u00f3n malt\u00e9s<\/strong>&#8216; en el que el detective es un expatriado que vive en el sur de Francia en forma de serie de seis episodios.<\/p>\n<p><!-- BREAK 4 --> <\/div>\n<div readability=\"17.354716981132\">\n<div class=\"article-social-share js-article-social-share m-in-links\" readability=\"26.963414634146\">\n<p> Compartir <q class=\"article-social-share-meta\"> Anya Taylor-Joy y el cocreador de &#8216;Gambito de dama&#8217; se volver\u00e1n a reunir para adaptar &#8216;Risa en la oscuridad&#8217; de Nabokov <\/q> <\/p>\n<\/p><\/div>\n<div class=\"article-topics-list\"> <span class=\"article-topic-desc\">Temas<\/span> <\/p>\n<ul class=\"article-topics-categories\">\n<li><a class=\"article-topic-link\" href=\"https:\/\/www.espinof.com\/categoria\/directores-y-guionistas\">Directores y guionistas<\/a><\/li>\n<li><a class=\"article-topic-link\" href=\"https:\/\/www.espinof.com\/categoria\/proyectos\">Proyectos<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>&#8216;Gambito de Dama&#8216; (The Queen&#8217;s Gambit, 2020) se ha convertido en un fen\u00f3meno global que no abandona el puesto n\u00famero uno de lo m\u00e1s visto semanal en Netflix, y ahora, el co-creador Scott Frank y la actriz principal Anya Taylor-Joy, quien interpreta a la prodigio del ajedrez Beth Harmon, esperan repetir el \u00e9xito con su [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":7034,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/7033"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=7033"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/7033\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media\/7034"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=7033"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=7033"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=7033"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}