{"id":68234,"date":"2023-10-16T19:53:43","date_gmt":"2023-10-16T19:53:43","guid":{"rendered":"https:\/\/www.ole.com.ar\/ecuador\/la-tri\/posible-alineacion-ecuador-enfrentar-colombia-eliminatorias_0_WHsJoyZmZU.html"},"modified":"2023-10-16T19:53:43","modified_gmt":"2023-10-16T19:53:43","slug":"la-posible-alineacion-de-ecuador-para-enfrentar-a-colombia-por-eliminatorias","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2023\/10\/16\/la-posible-alineacion-de-ecuador-para-enfrentar-a-colombia-por-eliminatorias\/","title":{"rendered":"La posible alineaci\u00f3n de Ecuador para enfrentar a Colombia por Eliminatorias"},"content":{"rendered":"<p><img src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2023\/10\/la-posible-alineacion-de-ecuador-para-enfrentar-a-colombia-por-eliminatorias.jpg\"><\/p>\n<p><time class=\"createDate\" datetime=\"2023-10-16T16:53:43-03:00\">16\/10\/2023 16:53hs.<\/time><time class=\"modificatedDate\" datetime=\"2023-10-16T16:53:42-03:00\"><\/time><\/p>\n<div id=\"storyBody\">\n<div class=\"custom-text \" readability=\"32.080924855491\">\n<p>Faltan pocas horas para que <a href=\"https:\/\/www.ole.com.ar\/tema\/la-tri.html\" title=\"La Tri\" alt=\"La Tri\" class=\"slug\">La Tri<\/a> nuevamente tenga acci\u00f3n por las <a href=\"https:\/\/www.ole.com.ar\/tema\/eliminatorias-sudamericanas.html\" title=\"Eliminatorias Sudamericanas\" alt=\"Eliminatorias Sudamericanas\" class=\"slug\">Eliminatorias<\/a>, esta vez frente a <a href=\"https:\/\/www.ole.com.ar\/tema\/seleccion-de-colombia.html\" title=\"Selecci\u00f3n de Colombia\" alt=\"Selecci\u00f3n de Colombia\" class=\"slug\">Colombia<\/a>. El Rodrigo Paz Delgado ser\u00e1 el escenario que reciba este encuentro a las 18.30. <strong>Ecuador buscar\u00e1 una victoria para seguir escalando posiciones en la tabla, y para lograrlo el DT <a href=\"https:\/\/www.ole.com.ar\/tema\/felix-sanchez-bas.html\" title=\"F\u00e9lix S\u00e1nchez Bas\" alt=\"F\u00e9lix S\u00e1nchez Bas\" class=\"slug\">F\u00e9lix S\u00e1nchez Bas<\/a> preparar algunos cambios en el once.<\/strong><\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"37\">\n<p>El entrenador de La Tri no ha repetido equipo desde que tom\u00f3 las riendas a inicios del 2023. Las variantes en el once las realiza de acuerdo al an\u00e1lisis que haga del rival, por lo que hay nombres que cambian, aunque tiene un basa de titulares fijo bastante amplia. <strong>La primera variante en La Tri se podr\u00eda dar en el arco.<\/strong><\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"36\">\n<p>Y es que S\u00e1nchez Bas ha rotado en varias ocasiones, dejando claro que no hay uno que sea due\u00f1o del puesto. La sorpresiva titularidad de Mois\u00e9s Ram\u00edrez en Bolivia dej\u00f3 varias dudas al mostrarse inseguro y nervioso. <strong>Hern\u00e1n Gal\u00edndez ser\u00eda el arquero que gan\u00f3 la pulseada en la pelea para ocupar el arco frente a Colombia.<\/strong><\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"38\">\n<p>La l\u00ednea de tres zagueros centrales es intocable para el DT, por lo que F\u00e9lix Torres, Willian Pacho y Piero Hincapi\u00e9 repetir\u00e1n en el once. <strong>En los carrileros est\u00e1 la duda, ya que Angelo Preciado ya se encuentra bien f\u00edsicamente y en condici\u00f3n de local se necesitar\u00e1 profundidad en las bandas.<\/strong> Por izquierda Jhoanner Ch\u00e1vez se perfila para ser titular.<\/p>\n<\/div>\n<div class=\"sc-e7b891c4-0 jPbnQF\"><img alt=\"La Tri prepara el partido con Colombia. (EFE)\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2023\/10\/la-posible-alineacion-de-ecuador-para-enfrentar-a-colombia-por-eliminatorias-2.jpg\" width=\"720\" height=\"100\" decoding=\"async\" data-nimg=\"future\" loading=\"lazy\"><span class=\"epigraphe\">La Tri prepara el partido con Colombia. (EFE)<\/span><\/div>\n<div class=\"custom-text \" readability=\"37\">\n<p>En el mediocampo Carlos Gruezo ingresar\u00eda en lugar de Joao Ortiz para conformar el tridente con Kendry P\u00e1ez y Mois\u00e9s Caicedo.<strong> Una de las dudas que tiene S\u00e1nchez Bas es en el acompa\u00f1ante de Enner Valencia en ataque<\/strong>. Jhojan Julio podr\u00eda ingresar para darle m\u00e1s velocidad en la generaci\u00f3n de juego, pero Kevin Rodr\u00edguez es la otra opci\u00f3n que maneja el estratega espa\u00f1ol, El delantero del Union Saint-Gilloise podr\u00eda ser importante para no cargar la marca de la defensa rival en Valencia.<\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"35\">\n<p><strong>No hay que descartar una sorpresa en el equipo titular, ya que S\u00e1nchez Bas es un DT al que le gusta hacer variantes y en los \u00faltimos dos partidos ya caus\u00f3 revuelo<\/strong> con el ingreso de Kendry ante Uruguay y la inclusi\u00f3n de Mois\u00e9s Ram\u00edrez y Joao Ortiz contra Bolivia.<\/p>\n<\/div>\n<div class=\"sc-e7b891c4-0 jPbnQF\"><img alt=\"Ecuador se prepara para recibir a Colombia. (@LaTri)\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2023\/10\/la-posible-alineacion-de-ecuador-para-enfrentar-a-colombia-por-eliminatorias-3.jpg\" width=\"720\" height=\"100\" decoding=\"async\" data-nimg=\"future\" loading=\"lazy\"><span class=\"epigraphe\">Ecuador se prepara para recibir a Colombia. (@LaTri)<\/span><\/div>\n<p><h2><strong>La alineaci\u00f3n de Ecuador<\/strong><\/h2>\n<\/p>\n<div class=\"custom-text \" readability=\"42\">\n<p>Con estas variantes, el once de La Tri ser\u00eda con: <strong>Hern\u00e1n Gal\u00edndez; F\u00e9lix Torres, Willian Pacho, Piero Hincapi\u00e9; Angelo Preciado, Kendry P\u00e1ez, Carlos Gruezo, Mois\u00e9s Caicedo, Jhoanner Ch\u00e1vez; Jhojan Julio\/Kevin Rodr\u00edguez, Enner Valencia.<\/strong><\/p>\n<\/div>\n<p><h2><strong>F\u00e9lix S\u00e1nchez Bas y el presente de la delantera: \u00abNo es f\u00e1cil conseguir goles\u00bb<\/strong><\/h2>\n<\/p>\n<div class=\"custom-text \" readability=\"35.75\">\n<p>\u00abEn cuanto a lo delanteros, entiendo hablamos de eficacia, no es f\u00e1cil conseguir goles. Hemos tenido distintas alternativas pero no porque no estemos convencido de los que estamos haciendo, sino porque creemos que para conseguir el objetivo a veces hay que tener distintos planteamiento\u00bb, <a href=\"https:\/\/www.ole.com.ar\/ecuador\/la-tri\/felix-sanchez-bas-presente-delantera-facil-conseguir-goles_0_8LI72ClYDB.html\" target=\"_self\" title=\"coment\u00f3 el entrenador espa\u00f1ol\" alt=\"coment\u00f3 el entrenador espa\u00f1ol\" rel=\"noopener noreferrer\">coment\u00f3 el entrenador espa\u00f1ol<\/a> en rueda de prensa previo al partido con Colombia.<\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"40\">\n<p>\u00abA todos nos gustar\u00eda llegar m\u00e1s y marcar m\u00e1s goles, pero los rivales trabajan duro para que no suceda. Hay que seguir persistiendo e intentar generar. Hay veces que somos m\u00e1s efectivos, en otras no, el rival tambi\u00e9n juega. Hay que seguir trabajando para seguir marcando goles. Las Eliminatorias son muy duras, hay resultados muy ajustados. Eso es muestra de lo dif\u00edcil que es conseguir tres puntos\u00bb, complement\u00f3.<\/p>\n<\/div>\n<div class=\"sc-e7b891c4-0 jPbnQF\"><img alt=\"S\u00e1nchez Bas tiene pensado hacer cambios. (EFE)\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2023\/10\/la-posible-alineacion-de-ecuador-para-enfrentar-a-colombia-por-eliminatorias-4.jpg\" width=\"720\" height=\"100\" decoding=\"async\" data-nimg=\"future\" loading=\"lazy\"><span class=\"epigraphe\">S\u00e1nchez Bas tiene pensado hacer cambios. (EFE)<\/span><\/div>\n<div class=\"custom-text \" readability=\"41\">\n<p>Sobre la elecci\u00f3n de Enner Valencia, Jordy Caicedo y Kevin Rodr\u00edguez como los atacantes convocados, S\u00e1nchez Bas dijo: \u00abLos delanteros, en funci\u00f3n de lo que pod\u00edamos necesitar, vino Enner porque es nuestro capit\u00e1n y nuestro referente, a Kevin y Jordy porque pensamos que nos pueden dar un plus como referencia o para poder descargar y dar acompa\u00f1amiento. Todos son opciones, puede ser un delantero o dos\u00bb.<\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"37\">\n<p>El estratega de 47 a\u00f1os tambi\u00e9n habl\u00f3 sobre la ausencia de Gonzalo Plata, quien fue uno de los referentes en ataque durante los \u00faltimos a\u00f1os y una de las grandes sorpresas de la convocatoria para esta doble fecha de Eliminatorias: \u00abHe tra\u00eddo 26 jugadores, que a d\u00eda de hoy son quienes est\u00e1n en posici\u00f3n de ayudar m\u00e1s al equipo\u00bb.<\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"36\">\n<p>S\u00e1nchez Bas no quiso dar detalles sobre el esquema que utilizar\u00e1n contra los Cafeteros al responder una pregunta sobre si jugar\u00e1 con uno o dos delanteros: \u00abNo vamos a entrar en detalles, el rival nos tiene m\u00e1s que vistos y puede pensar de una forma u otra. Vamos a jugar para ser s\u00f3lidos defensivamente y que en ataque tengamos opciones para construir del fondo al \u00faltimo tercio con buenas opciones de remate\u00bb.<\/p>\n<\/div>\n<div class=\"sc-a7166897-0 exHLBh\" readability=\"7.5\">\n<section readability=\"5\"><picture><img alt=\"S\u00e1nchez Bas, en conferencia: &quot;Ser\u00e1 un partido duro, tendremos que utilizar nuestras armas&quot;\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2023\/10\/la-posible-alineacion-de-ecuador-para-enfrentar-a-colombia-por-eliminatorias-5.jpg\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"future\" loading=\"lazy\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>S\u00e1nchez Bas, en conferencia: \u00abSer\u00e1 un partido duro, tendremos que utilizar nuestras armas\u00bb<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<div class=\"sc-a7166897-0 exHLBh\" readability=\"6.5\">\n<section readability=\"3\"><picture><img alt=\"F\u00e9lix S\u00e1nchez Bas y la competencia en el arco: &quot;Decidimos seg\u00fan el partido y el momento&quot;\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2023\/10\/la-posible-alineacion-de-ecuador-para-enfrentar-a-colombia-por-eliminatorias-6.jpg\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"future\" loading=\"lazy\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>F\u00e9lix S\u00e1nchez Bas y la competencia en el arco: \u00abDecidimos seg\u00fan el partido y el momento\u00bb<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<div class=\"sc-a7166897-0 exHLBh\" readability=\"6\">\n<section readability=\"2\"><picture><img alt=\"Jeremy Sarmiento: del consejo a Kendry P\u00e1ez al apoyo a Kevin Rodr\u00edguez\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2023\/10\/la-posible-alineacion-de-ecuador-para-enfrentar-a-colombia-por-eliminatorias-7.jpg\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"future\" loading=\"lazy\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>Jeremy Sarmiento: del consejo a Kendry P\u00e1ez al apoyo a Kevin Rodr\u00edguez<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<div class=\"sc-a7166897-0 exHLBh\" readability=\"6\">\n<section readability=\"2\"><picture><img alt=\"\u00bfC\u00f3mo le fue a La Tri con Facundo Tello como \u00e1rbitro?\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2023\/10\/la-posible-alineacion-de-ecuador-para-enfrentar-a-colombia-por-eliminatorias-8.jpg\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"future\" loading=\"lazy\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>\u00bfC\u00f3mo le fue a La Tri con Facundo Tello como \u00e1rbitro?<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<div class=\"sc-a7166897-0 exHLBh\" readability=\"6.5\">\n<section readability=\"3\"><picture><img alt=\"Qui\u00e9n es favorito y cu\u00e1nto pagan las apuestas en Ecuador vs. Colombia por Eliminatorias\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2023\/10\/la-posible-alineacion-de-ecuador-para-enfrentar-a-colombia-por-eliminatorias-9.jpg\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"future\" loading=\"lazy\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>Qui\u00e9n es favorito y cu\u00e1nto pagan las apuestas en Ecuador vs. Colombia por Eliminatorias<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<div class=\"sc-a7166897-0 exHLBh\" readability=\"7\">\n<section readability=\"4\"><picture><img alt=\"T\u00edo de Leo Campana, amigo de Chito Vera e hincha de Emelec: Daniel Noboa es el nuevo presidente de Ecuador\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2023\/10\/la-posible-alineacion-de-ecuador-para-enfrentar-a-colombia-por-eliminatorias-10.jpg\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"future\" loading=\"lazy\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>T\u00edo de Leo Campana, amigo de Chito Vera e hincha de Emelec: Daniel Noboa es el nuevo presidente de Ecuador<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<div class=\"sc-a7166897-0 exHLBh\" readability=\"6\">\n<section readability=\"2\"><picture><img alt=\"Nueva baja en Colombia para visitar a Ecuador por las Eliminatorias\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2023\/10\/la-posible-alineacion-de-ecuador-para-enfrentar-a-colombia-por-eliminatorias-11.jpg\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"future\" loading=\"lazy\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>Nueva baja en Colombia para visitar a Ecuador por las Eliminatorias<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<div class=\"sc-a7166897-0 exHLBh\" readability=\"6\">\n<section readability=\"2\"><picture><img alt=\"Dalo Bucaram sobre dirigir a 9 de Octubre: &quot;Nunca he tenido miedo a los retos&quot;\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2023\/10\/la-posible-alineacion-de-ecuador-para-enfrentar-a-colombia-por-eliminatorias-12.jpg\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"future\" loading=\"lazy\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>Dalo Bucaram sobre dirigir a 9 de Octubre: \u00abNunca he tenido miedo a los retos\u00bb<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>16\/10\/2023 16:53hs. Faltan pocas horas para que La Tri nuevamente tenga acci\u00f3n por las Eliminatorias, esta vez frente a Colombia. El Rodrigo Paz Delgado ser\u00e1 el escenario que reciba este encuentro a las 18.30. Ecuador buscar\u00e1 una victoria para seguir escalando posiciones en la tabla, y para lograrlo el DT F\u00e9lix S\u00e1nchez Bas preparar algunos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":68235,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[16],"tags":[],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/68234"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=68234"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/68234\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media\/68235"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=68234"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=68234"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=68234"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}