{"id":67491,"date":"2023-10-01T18:31:43","date_gmt":"2023-10-01T18:31:43","guid":{"rendered":"https:\/\/www.espinof.com\/actores-y-actrices\/cuando-lei-guion-no-entendia-chris-evans-admite-que-acepto-hacer-esta-excelente-pelicula-ciencia-ficcion-porque-bong-joon-ho-era-su-director"},"modified":"2023-10-01T18:31:43","modified_gmt":"2023-10-01T18:31:43","slug":"cuando-lei-el-guion-no-lo-entendia-chris-evans-admite-que-acepto-hacer-esta-excelente-pelicula-de-ciencia-ficcion-porque-bong-joon-ho-era-su-director","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2023\/10\/01\/cuando-lei-el-guion-no-lo-entendia-chris-evans-admite-que-acepto-hacer-esta-excelente-pelicula-de-ciencia-ficcion-porque-bong-joon-ho-era-su-director\/","title":{"rendered":"\u00abCuando le\u00ed el guion, no lo entend\u00eda\u00bb. Chris Evans admite que acept\u00f3 hacer esta excelente pel\u00edcula de ciencia ficci\u00f3n porque Bong Joon-ho era su director"},"content":{"rendered":"<p>La carrera de <strong>Chris Evans<\/strong> ha estado asociado durante muchos a\u00f1os a <a href=\"https:\/\/www.espinof.com\/listas\/marvel-que-orden-conviene-ver-todas-peliculas-superheroes-mcu\">Marvel<\/a> en general y el personaje del Capit\u00e1n Am\u00e9rica en general. Sin embargo, durante ese periodo tambi\u00e9n protagoniz\u00f3 varias pel\u00edculas alejadas del cine de superh\u00e9roes y quiz\u00e1 la mejor de todas ellas sea <a href=\"https:\/\/www.espinof.com\/criticas\/syfy-2014-snowpiercer-fascinante-e-imprescindible\">&#8216;Snowpiercer&#8217;<\/a>. Dirigida por <strong>Bong Joon-ho<\/strong>, el actor reconoce que inicialmente no termin\u00f3 de entender el guion, pero que acept\u00f3 igualmente la oferta.<\/p>\n<p><!-- BREAK 1 --> <\/p>\n<p>El actor ha confesado esto en una entrevista concedida a <a href=\"https:\/\/www.youtube.com\/watch?v=tT7IQe_i3N8\">GQ<\/a> en la que repasaba algunos de los personajes m\u00e1s ic\u00f3nicos de su carrera. Entre ellos se encuentra el de <a href=\"https:\/\/www.espinof.com\/criticas\/sunshine-naves-poco-misteriosas\">&#8216;Sunshine&#8217;<\/a>, que \u00e9l mismo se\u00f1al\u00f3 en el pasado que era <a href=\"https:\/\/www.espinof.com\/actores-y-actrices\/tendria-carrera-diferente-gente-hubiese-visto-pelicula-ciencia-ficcion-chris-evans-que-fracaso-injustamente-que-considera-uno-sus-mejores-trabajos\">la favorita personal de toda su filmograf\u00eda<\/a>. La pel\u00edcula de <strong>Danny Boyle<\/strong> lleg\u00f3 seis a\u00f1os antes que &#8216;Snowpiercer&#8217; y seguro que lo satisfecho que qued\u00f3 con el resultado tambi\u00e9n le ayud\u00f3 a confiar en ella, sobre la cual comenta lo siguiente:<\/p>\n<p><!-- BREAK 2 --><\/p>\n<blockquote><p>Cuando le\u00ed el guion por primera vez, no acababa de entenderlo. Me dije: &#8216;\u00bfY qu\u00e9? Siempre que se trata de una pel\u00edcula que construye un mundo, est\u00e1s creando un entorno completamente distinto. Es como si tuvieras que decir: &#8216;Vale, \u00bfas\u00ed que todo el mundo lo acepta, as\u00ed son las cosas? \u00bfNadie se escandaliza de que esta sea la estructura? Es la norma, \u00bfde acuerdo?<\/p><\/blockquote>\n<blockquote><p>Tienes que decidir en qu\u00e9 parte de tu cerebro inviertes m\u00e1s tiempo. \u00bfVas por el camino \u00edntimo y lo haces sobre el personaje? \u00bfIntentas que sea sobre lo que le cost\u00f3 a esa sociedad llegar a ese nivel? Es un reto, pero puedes ver a Tilda Swinton en la pel\u00edcula y ver c\u00f3mo se acerca a este personaje tan grande.<\/p><\/blockquote>\n<h2>\u00abGenial. T\u00fa dices salta, yo digo \u00ab\u00bfC\u00f3mo de alto?\u00bb<\/h2>\n<p>Sin embargo, Evans <strong>nunca tuvo dudas a la hora de aceptar participar en &#8216;Snowpiercer&#8217;<\/strong>, y todo se reduc\u00eda a la presencia del autor de <a href=\"https:\/\/www.espinof.com\/criticas\/parasitos-rotunda-obra-maestra\">&#8216;Par\u00e1sitos&#8217;<\/a> tras las c\u00e1maras, ya que seg\u00fan \u00e9l se trata de un visionario que tiene muy claro lo que est\u00e1 buscando:<\/p>\n<p><!-- BREAK 3 --> <\/p>\n<div class=\"article-asset article-asset-normal article-asset-center\">\n<div class=\"desvio-container\">\n<div class=\"desvio\">\n<div class=\"desvio-figure js-desvio-figure\"> <a href=\"https:\/\/www.espinof.com\/actores-y-actrices\/chris-evans-chris-hemsworth-improvisaron-su-unica-escena-juntos-vengadores-infinity-war\"> <img alt=\"C\u00f3mo Chris Evans y Chris Hemsworth improvisaron su \u00fanica escena juntos en 'Vengadores: Infinity War' \" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2023\/10\/cuando-lei-el-guion-no-lo-entendia-chris-evans-admite-que-acepto-hacer-esta-excelente-pelicula-de-ciencia-ficcion-porque-bong-joon-ho-era-su-director.jpg\"> <\/a> <\/div><\/div><\/div>\n<\/div>\n<blockquote><p>El director Bong es un visionario. Cuando trabajas con alguien que sabe exactamente lo que quiere, aunque no sea exactamente como t\u00fa lo ves, se genera confianza. Y como actor, eso es lo m\u00e1s importante, confiar en el director. Si no, est\u00e1s a la defensiva. De lo contrario, te pones en plan: &#8216;Vale, esta primera toma, bueno, voy a hacer esto, para al menos poder mantener esto. Luego probar\u00e9 esto, pero no quiero probar aquello porque no s\u00e9 si saben c\u00f3mo usar esa toma. Cualquier toma que les d\u00e9 puede ser usada en mi contra&#8217;. Y cuando tienes un director que est\u00e1 tan convencido de cu\u00e1l es su visi\u00f3n, es cuando dices: \u00abGenial. T\u00fa dices salta, yo digo \u00ab\u00bfC\u00f3mo de alto?\u00bb<\/p><\/blockquote>\n<p>Pese a que <strong>como mucho se la podr\u00eda catalogar de modesto \u00e9xito comercial<\/strong> -cost\u00f3 40 millones de d\u00f3lares y recaud\u00f3 86-, &#8216;Snowpiercer&#8217; dej\u00f3 huella y apenas unos a\u00f1os despu\u00e9s se estrenaba <a href=\"https:\/\/www.espinof.com\/criticas\/snowpiercer-rompenieves-netflix-estrena-serie-que-convierte-film-bong-joon-ho-frio-orient-express-distopico\">una serie de televisi\u00f3n de mismo t\u00edtulo<\/a> en la que Joon-ho particip\u00f3 como productor ejecutivo.<\/p>\n<p><!-- BREAK 4 --><\/p>\n<p>En Espinof:<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La carrera de Chris Evans ha estado asociado durante muchos a\u00f1os a Marvel en general y el personaje del Capit\u00e1n Am\u00e9rica en general. Sin embargo, durante ese periodo tambi\u00e9n protagoniz\u00f3 varias pel\u00edculas alejadas del cine de superh\u00e9roes y quiz\u00e1 la mejor de todas ellas sea &#8216;Snowpiercer&#8217;. Dirigida por Bong Joon-ho, el actor reconoce que inicialmente [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":67492,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[10],"tags":[],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/67491"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=67491"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/67491\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media\/67492"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=67491"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=67491"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=67491"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}