{"id":66462,"date":"2023-09-12T14:45:07","date_gmt":"2023-09-12T14:45:07","guid":{"rendered":"https:\/\/www.ole.com.ar\/basquet\/cors-quimsa-ligafemenina-basquet_0_cvVMFNtNsu.html"},"modified":"2023-09-12T14:45:07","modified_gmt":"2023-09-12T14:45:07","slug":"laura-cors-vuelve-a-la-liga-femenina-es-un-desafio-personal","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2023\/09\/12\/laura-cors-vuelve-a-la-liga-femenina-es-un-desafio-personal\/","title":{"rendered":"Laura Cors vuelve a la Liga Femenina: \u201cEs un desaf\u00edo personal\u201d"},"content":{"rendered":"<p><img src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2023\/09\/laura-cors-vuelve-a-la-liga-femenina-es-un-desafio-personal.jpg\"><\/p>\n<p><time class=\"createDate\" datetime=\"2023-09-12T11:45:007-03:00\">12\/09\/2023 11:45hs.<\/time><time class=\"modificatedDate\" datetime=\"2023-09-12T11:45:006-03:00\"><\/time><\/p>\n<div id=\"storyBody\">\n<div class=\"custom-text \" readability=\"37\">\n<p>Despu\u00e9s de seis a\u00f1os alejada de la Liga Femenina y tras haber hecho historia al ser la primera mujer en dirigir en la Liga Nacional masculina,<strong> Laura Cors tom\u00f3 la decisi\u00f3n de volver a sus or\u00edgenes al asumir el mando del primer equipo de Quimsa,<\/strong> que est\u00e1 a d\u00edas de debutar en la temporada 2023\/24 de la Liga Femenina con un objetivo: ser campe\u00f3n.<\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"40\">\n<p>Las Fusionadas, que se estrenar\u00e1n el viernes 22 en el Apertura nada menos que ante Ol\u00edmpico en el cl\u00e1sico de la ciudad, quieren sacarse la espina el \u00faltimo t\u00edtulo de Liga perdido contra Berazategui y para eso apostaron fuerte por la experiencia de Cors, coach bahiense que rechaz\u00f3 varias ofertas de su ciudad, entre ellas la de Villa Mitre, para recalar en Santiago del Estero.<\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"36\">\n<p><strong>\u00abEs un desaf\u00edo personal muy lindo, tuve ofertas para seguir con el b\u00e1squet masculino pero al recibir el llamado de Quimsa opt\u00e9 por esta decisi\u00f3n y me toca vivir este ambiente luego de unos a\u00f1os<\/strong>\u00ab, asegur\u00f3 Cors en declaraciones al departamento de prensa de Quimsa.<\/p>\n<\/div>\n<div class=\"sc-e7b891c4-0 jPbnQF\"><img alt=\"Laura Cors de Quimsa.\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2023\/09\/laura-cors-vuelve-a-la-liga-femenina-es-un-desafio-personal-2.jpg\" width=\"720\" height=\"100\" decoding=\"async\" data-nimg=\"future\" loading=\"lazy\"><span class=\"epigraphe\">Laura Cors de Quimsa.<\/span><\/div>\n<div class=\"custom-text \" readability=\"39\">\n<p>\u00abLa Liga Femenina cambi\u00f3 con formatos, reglamento, pero pude notar un cambio sustancial en la profesionalidad de las jugadoras durante estos a\u00f1os, cada vez se dedican m\u00e1s a esto\u00bb, remarc\u00f3 la coach, que lleva semanas de pretemporada con un equipo que se perfila para candidato.<\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"39\">\n<p>\u201cMe encontr\u00e9 con un club hermoso como Quimsa, que posee instalaciones divinas para el trabajo y con un grupo muy bueno de jugadoras que me permite desempe\u00f1arme en un clima de alegr\u00eda y confort\u00bb, explic\u00f3 la ex DT de Lan\u00fas, que pese a las altas expectativas que se generaron con Las Fusionadas, prefiere la cautela.<\/p>\n<\/div>\n<div class=\"sc-e7b891c4-0 jPbnQF\"><img alt=\"Laura Cors de Quimsa.\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2023\/09\/laura-cors-vuelve-a-la-liga-femenina-es-un-desafio-personal-3.jpg\" width=\"720\" height=\"100\" decoding=\"async\" data-nimg=\"future\" loading=\"lazy\"><span class=\"epigraphe\">Laura Cors de Quimsa.<\/span><\/div>\n<div class=\"custom-text \" readability=\"38\">\n<p>\u00abSomos moderados, continuamos con el armado del equipo aunque sabemos que Quimsa como instituci\u00f3n siempre busca ser altamente competitivo. En lo personal, buscar\u00e9 mantenerme en competencia dentro del juego lo m\u00e1s que se pueda y mantener muchos minutos de competencia con este equipo\u00bb, sentenci\u00f3 Cors con la templanza y la experiencia que la caracteriza.<\/p>\n<\/div>\n<div class=\"sc-7ce6049-0 dwIKul\">\n<div class=\"sc-7ce6049-1 bdcBBS videoText\" id=\"contentTitleundefinedlOlNRoqw\"><svg fill=\"#ffffff\"><symbol id=\"play\" viewBox=\"0 0 512 512\"><path d=\"M512 256C512 397.4 397.4 512 256 512C114.6 512 0 397.4 0 256C0 114.6 114.6 0 256 0C397.4 0 512 114.6 512 256zM176 168V344C176 352.7 180.7 360.7 188.3 364.9C195.8 369.2 205.1 369 212.5 364.5L356.5 276.5C363.6 272.1 368 264.4 368 256C368 247.6 363.6 239.9 356.5 235.5L212.5 147.5C205.1 142.1 195.8 142.8 188.3 147.1C180.7 151.3 176 159.3 176 168V168z\" \/><\/symbol><use xlink:href=\"#play\" \/><\/svg><\/p>\n<div class=\"right\">\n<p>QUIMSA<!-- --> &#8211;<!-- --> <span>12-9-2023<\/span><\/p>\n<h2 class=\"title-vid\">Laura Cors y su nuevo rol en el equipo femenino de Quimsa<\/h2>\n<\/div>\n<\/div>\n<p><span class=\"back\" id=\"spanBackundefinedlOlNRoqw\"><\/span><\/div>\n<p><h2><strong>As\u00ed se juega la Liga Femenina<\/strong><\/h2>\n<\/p>\n<div class=\"custom-text \" readability=\"47\">\n<p><strong>La Liga Femenina 2023\/24, que se podr\u00e1 ver en su totalidad por B\u00e1squet Pass, tendr\u00e1 dos torneos a lo largo de la temporada, <\/strong>un Apertura dividido en conferencias y una Liga Femenina de zona \u00fanica. En el primero, la Zona Norte estar\u00e1 conformada por Ameghino, Instituto, Montmartre, Ol\u00edmpico, Quimsa y Riachuelo, mientras que en la Sur estar\u00e1n Berazategui \u2013\u00faltimo campe\u00f3n de La Liga\u2013, Ferro, Obras Basket, Rocamora y Uni\u00f3n Florida.<\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"43\">\n<p>Aqu\u00ed, l<strong>a fase regular se disputar\u00e1 del 21 de septiembre al 12 de noviembre<\/strong>, con juegos ida y vuelta en las conferencias, aunque habr\u00e1 una diferencia entre una y otra: en la Norte, los dos mejores se clasificar\u00e1n directo a semifinales y en el Sur avanzar\u00e1n los tres mejores. As\u00ed, entonces, despu\u00e9s habr\u00e1 play-in con ventaja de local\u00eda para el mejor ubicado, donde en la Norte se medir\u00e1n el 3\u00b0 vs. 6\u00b0 y 4\u00b0 vs. 5\u00b0 y en la Sur, 4\u00b0 vs. el 5\u00b0.<\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"38\">\n<p><strong>Ya en playoffs, las series del Apertura ser\u00e1n al mejor de tres partidos en formato 1-2. Y<\/strong> el 15, 16 y 17 de diciembre, en sede a confirmar y justo antes del receso estival, habr\u00e1 un Final 4 en el que se definir\u00e1 el campe\u00f3n.<\/p>\n<\/div>\n<p><h2><strong>La primera fecha del Apertura<\/strong><\/h2>\n<\/p>\n<div class=\"custom-text \" readability=\"34\">\n<p><strong>El Apertura empezar\u00e1 el viernes 21 y s\u00e1bado 22 de este mes sin Obras Basket,<\/strong> que por esos d\u00edas estar\u00e1 en la WBLA 2023.<\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"32\">\n<p>21\/9 | 19.00hs | Instituto vs. Ameghino<\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"32\">\n<p>21\/9 | 19.00hs | Montmartre vs. Riachuelo<\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"32\">\n<p>21\/9 | 21.00hs | Rocamora vs. Ferro<\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"32\">\n<p>21\/9 | 21.00hs | Berazategui vs. Uni\u00f3n Florida<\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"32\">\n<p>22\/9 | 21.30hs | Quimsa vs. Ol\u00edmpico<\/p>\n<\/div>\n<div class=\"sc-a7166897-0 exHLBh\" readability=\"6.5\">\n<section readability=\"3\"><picture><img alt=\"Con nuevo logo, as\u00ed se abrir\u00e1 La Liga Nacional en su temporada 40\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2023\/09\/laura-cors-vuelve-a-la-liga-femenina-es-un-desafio-personal-4.jpg\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"future\" loading=\"lazy\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>Con nuevo logo, as\u00ed se abrir\u00e1 La Liga Nacional en su temporada 40<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<div class=\"sc-a7166897-0 exHLBh\" readability=\"6\">\n<section readability=\"2\"><picture><img alt=\"Violencia de g\u00e9nero: arrestaron a un jugador de NBA\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2023\/09\/laura-cors-vuelve-a-la-liga-femenina-es-un-desafio-personal-5.jpg\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"future\" loading=\"lazy\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>Violencia de g\u00e9nero: arrestaron a un jugador de NBA<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<div class=\"sc-a7166897-0 exHLBh\" readability=\"6\">\n<section readability=\"2\"><picture><img alt=\"Sigue Mr. Robinson: el campe\u00f3n Quimsa confirm\u00f3 la mejor noticia\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2023\/09\/laura-cors-vuelve-a-la-liga-femenina-es-un-desafio-personal-6.jpg\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"future\" loading=\"lazy\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>Sigue Mr. Robinson: el campe\u00f3n Quimsa confirm\u00f3 la mejor noticia<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>12\/09\/2023 11:45hs. Despu\u00e9s de seis a\u00f1os alejada de la Liga Femenina y tras haber hecho historia al ser la primera mujer en dirigir en la Liga Nacional masculina, Laura Cors tom\u00f3 la decisi\u00f3n de volver a sus or\u00edgenes al asumir el mando del primer equipo de Quimsa, que est\u00e1 a d\u00edas de debutar en la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":66463,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[16],"tags":[],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/66462"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=66462"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/66462\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media\/66463"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=66462"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=66462"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=66462"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}