{"id":65659,"date":"2023-08-28T14:23:00","date_gmt":"2023-08-28T14:23:00","guid":{"rendered":"http:\/\/hoycordobaweb.com\/index.php\/2023\/08\/28\/alertan-sobre-estafas-en-redes-que-ofrecen-supuestas-oportunidades-laborales\/"},"modified":"2023-08-28T14:23:00","modified_gmt":"2023-08-28T14:23:00","slug":"alertan-sobre-estafas-en-redes-que-ofrecen-supuestas-oportunidades-laborales","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2023\/08\/28\/alertan-sobre-estafas-en-redes-que-ofrecen-supuestas-oportunidades-laborales\/","title":{"rendered":"Alertan sobre estafas en redes que ofrecen supuestas oportunidades laborales"},"content":{"rendered":"<p><img src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2023\/08\/alertan-sobre-estafas-en-redes-que-ofrecen-supuestas-oportunidades-laborales.jpg\"><\/p>\n<figure class=\"mb-3\"><img loading=\"lazy\" data-src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2023\/08\/alertan-sobre-estafas-en-redes-que-ofrecen-supuestas-oportunidades-laborales-2.jpg\" src=\"https:\/\/www.telam.com.ar\/assets\/img\/not_image.png\" class=\" lazy \" width=\"100%\" height=\"100%\" alt=\"Un ejemplo de un modelo de fraude Foto Twitter \"><figcaption> Un ejemplo de un modelo de fraude \/ Foto: Twitter <\/figcaption><\/figure>\n<p>La <strong>Unidad Fiscal Especializada en Ciberdelincuencia<\/strong> (Ufeci) advirti\u00f3 sobre una nueva modalidad de fraude a trav\u00e9s de anuncios que captan personas para realizar trabajos remotos en distintas plataformas de ventas, que luego de aceptar la propuesta son enga\u00f1adas para invertir en las plataformas en base a un <strong>esquema Ponzi<\/strong>.<\/p>\n<p>De acuerdo con la investigaci\u00f3n desarrollada por la unidad especializada, la captaci\u00f3n se produce a trav\u00e9s de anuncios en redes sociales donde se ofrece la posibilidad de obtener ingresos extras mediante la realizaci\u00f3n de tareas remotas.<\/p>\n<p>Estas publicidades dirigen a las v\u00edctimas a cuentas de <strong>WhatsApp<\/strong> o <strong>Telegram<\/strong> donde son atendidas por supuestos representantes de las compa\u00f1\u00edas, quienes les indican que se registren en una plataforma para comenzar con sus tareas, precis\u00f3 la Ufeci en un comunicado.<\/p>\n<p>Una vez que las personas acceden al sistema son redirigidas a un repositorio de productos de empresas reconocidas en el que deben comprar y luego vender a un mayor costo los insumos adquiridos.<\/p>\n<p>As\u00ed, las v\u00edctimas se ven obligadas a efectuar una primera inyecci\u00f3n de dinero que supuestamente les ser\u00e1 reintegrado junto a sus comisiones.<\/p>\n<blockquote class=\"twitter-tweet\" readability=\"2.7118644067797\">\n<p lang=\"es\" dir=\"ltr\">Ac\u00e1 esta el \u00abagente\u00bb de <a href=\"https:\/\/twitter.com\/YouTubeLATAM?ref_src=twsrc%5Etfw\">@YouTubeLATAM<\/a> <a href=\"https:\/\/t.co\/z84v35ZJ4z\">pic.twitter.com\/z84v35ZJ4z<\/a><\/p>\n<p>\u2014 Horacio Azzolin (@horacioazzolin) <a href=\"https:\/\/twitter.com\/horacioazzolin\/status\/1695943750411801082?ref_src=twsrc%5Etfw\">August 27, 2023<\/a><\/p><\/blockquote>\n<p><\/p>\n<h2 class>Los pasos de la estafa<\/h2>\n<p>En un primer momento, las personas damnificadas no sospechan que se trata de una maniobra fraudulenta, pues ven, dentro de la plataforma, que se le reintegra el dinero que invirtieron y ven reflejadas las altas comisiones por las labores efectuadas.<\/p>\n<p>Sin embargo, no reparan en que los montos que transfieren -y ven acreditados dentro de la plataforma- son enviados a billeteras virtuales controladas por los propios estafadores.<\/p>\n<p><strong>Cuando las personas quieren extraer el dinero que fueron ganando con sus labores, se encuentran con un anuncio que les indica que no pueden extraer su dinero porque su orden de retiro ha superado un umbral impositivo.<\/strong><\/p>\n<p>Luego de ello, cuando las v\u00edctimas intentan contactarse con el agente de la empresa, este les ratifica la situaci\u00f3n y les informa que efectivamente deben pagar impuestos sobre los ingresos obtenidos para disponer de sus ganancias.<\/p>\n<p>Para ello, el estafador les brinda los datos de una cuenta bancaria para transferir el monto de los supuestos impuestos adeudados y as\u00ed poder cobrar el dinero que les es retenido.<\/p>\n<p>Sin embargo, una vez que la persona v\u00edctima efect\u00faa el pago, es bloqueada de la plataforma y de los canales de contacto habituales y es ah\u00ed cuando cae en la cuenta de que la estafaron.<\/p>\n<blockquote class=\"twitter-tweet\" data-conversation=\"none\" readability=\"3.1506849315068\">\n<p lang=\"es\" dir=\"ltr\">El \u00abagente\u00bb tambi\u00e9n puede ser el \u00abrecepcionista\u00bb de <a href=\"https:\/\/twitter.com\/YouTubeLATAM?ref_src=twsrc%5Etfw\">@YouTubeLATAM<\/a> <a href=\"https:\/\/t.co\/mSG2cx13xI\">pic.twitter.com\/mSG2cx13xI<\/a><\/p>\n<p>\u2014 Horacio Azzolin (@horacioazzolin) <a href=\"https:\/\/twitter.com\/horacioazzolin\/status\/1695945062843109721?ref_src=twsrc%5Etfw\">August 27, 2023<\/a><\/p><\/blockquote>\n<p><\/p>\n<h2 class>Qu\u00e9 hacer ante una estafa y c\u00f3mo prevenirla<\/h2>\n<p>Para no ser v\u00edctima de este tipo de maniobras y saber c\u00f3mo actuar frente a estos casos, la Ufeci recomienda que, antes de invertir en este tipo de plataformas, se busque informaci\u00f3n en l\u00ednea, la reputaci\u00f3n de las empresas y si, m\u00ednimamente, est\u00e1n registradas ante las autoridades competentes para ofrecer este tipo de servicios.<\/p>\n<p>Adem\u00e1s, recomienda <strong>sospechar de los rendimientos excesivamente altos<\/strong>; nunca efectuar aportes de dinero ni realizar transferencias sin haber verificado la legitimidad de la oferta; y no brindar informaci\u00f3n personal ni bancaria a trav\u00e9s de plataformas digitales ni telef\u00f3nicamente.<\/p>\n<p><strong>En caso de resultar v\u00edctima, puede reportar los hechos a la casilla denunciasufeci@mpf.gov.ar.<\/strong> <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un ejemplo de un modelo de fraude \/ Foto: Twitter La Unidad Fiscal Especializada en Ciberdelincuencia (Ufeci) advirti\u00f3 sobre una nueva modalidad de fraude a trav\u00e9s de anuncios que captan personas para realizar trabajos remotos en distintas plataformas de ventas, que luego de aceptar la propuesta son enga\u00f1adas para invertir en las plataformas en base [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":65660,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[19],"tags":[],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/65659"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=65659"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/65659\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media\/65660"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=65659"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=65659"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=65659"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}