{"id":65612,"date":"2023-08-27T16:55:16","date_gmt":"2023-08-27T16:55:16","guid":{"rendered":"https:\/\/www.clarin.com\/espectaculos\/tv\/primera-semana-got-talent-reality-busca-repetir-rating-gran-hermano_0_DzheKe33Yd.html"},"modified":"2023-08-27T16:55:16","modified_gmt":"2023-08-27T16:55:16","slug":"como-fue-la-primera-semana-de-got-talent-el-reality-que-busca-repetir-el-rating-de-gran-hermano","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2023\/08\/27\/como-fue-la-primera-semana-de-got-talent-el-reality-que-busca-repetir-el-rating-de-gran-hermano\/","title":{"rendered":"C\u00f3mo fue la primera semana de Got Talent, el reality que busca repetir el rating de Gran hermano"},"content":{"rendered":"<p><strong>Desde que se estren\u00f3&nbsp;fue lo m\u00e1s visto del d\u00eda,<\/strong> muy lejos del pelot\u00f3n que lo secundaba. Si bien no se sab\u00eda qu\u00e9 suerte correr\u00eda, se esperaba que <strong>Got Talent<\/strong> (a las 21.45, por Telefe) no s\u00f3lo ganara el rating diario, sino que<strong> lograra subir la vara de la medici\u00f3n a los niveles que hasta marzo hab\u00eda manejado Gran hermano<\/strong>, merodeando la barrera de los 20 puntos.<\/p>\n<p>La idea inicial de Telefe era estrenar este reality de talentos ni bien terminara el de cocina, pero <strong>el producto no estaba listo para salir al aire y entonces el canal opt\u00f3 por emitir la telenovela turca Traicionada en modo marat\u00f3n<\/strong>. Y mal no le fue.<\/p>\n<p>Pero<strong> necesitaba mejorar su marca, superando los 13\/14 puntos que hac\u00eda MasterChef<\/strong>, que ganaba cada d\u00eda, pero no era una marca llamativa como s\u00ed lo hab\u00eda conseguido en su momento <strong>GH<\/strong>.<\/p>\n<h2>Los primeros n\u00fameros<\/h2>\n<p>Y el lunes 21, cuando se corri\u00f3 el tel\u00f3n de <strong>Got Talent<\/strong>, el \u00abminuto a minuto\u00bb parec\u00eda calentar la pantalla, subiendo hasta los 20. <strong>El ciclo comandado por Lizy Tagliani debut\u00f3 con un&nbsp;promedio de 18,1 puntos de rating<\/strong>. Y algunas cr\u00edticas a su contenido (especialmente por <strong>la sobreactuaci\u00f3n de su jurado: Florencia Pe\u00f1a, <a data-cke-saved-href=\"http:\/\/www.clarin.com\/tema\/abel_pintos.html\" target=\"_blank\" href=\"http:\/\/www.clarin.com\/tema\/abel_pintos.html\" rel=\"noopener noreferrer\">Abel Pintos<\/a>, La Joaqui y Emir Abdul<\/strong>).<\/p>\n<div class=\"sp__Normal embed-box embed-body-photo\" data-index=\"1\">\n<picture class=\"pointer\">\n<img class=\"img-expand\" width=\"100\" height=\"100\" loading=\"lazy\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2023\/08\/como-fue-la-primera-semana-de-got-talent-el-reality-que-busca-repetir-el-rating-de-gran-hermano.jpg\" alt=\"Lizy Tagliani junto a Abel Pintos, Florencia Pe\u00f1a, La Joaqui y Emir Abdul en &quot;Got Talent Argentina&quot;. Foto de prensa.\"><br \/>\n<span class=\"bt-expand\"><br \/>\n<svg class=\"ico white_mod\">\n<use class=\"use-expand\" xlink:href=\"#icon-expand\" \/>\n<\/svg><br \/>\n<\/span>\n<\/picture><figcaption>Lizy Tagliani junto a Abel Pintos, Florencia Pe\u00f1a, La Joaqui y Emir Abdul en \u00abGot Talent Argentina\u00bb. Foto de prensa. <\/figcaption><\/div>\n<p>As\u00ed y todo, <strong>el martes consigui\u00f3 mejorar su rating, con picos que pasaron los 20 puntos<\/strong> y un promedio que se instal\u00f3 en 19,7. Las cr\u00edticas siguieron, porque la versi\u00f3n local del ciclo que brilla en varios pa\u00edses presenta algunas desprolijidades de edici\u00f3n y <strong>las devoluciones del jurado asoman, por momentos, como contradictorias<\/strong>.<\/p>\n<p>El mi\u00e9rcoles, el reality no sali\u00f3 al aire porque Telefe transmiti\u00f3 el partido de ida de la Copa Libertadores por los cuartos de final entre <a data-cke-saved-href=\"http:\/\/www.clarin.com\/tema\/racing.html\" target=\"_blank\" href=\"http:\/\/www.clarin.com\/tema\/racing.html\" rel=\"noopener noreferrer\">Boca y Racing, que termin\u00f3 empatado en 0<\/a>.<\/p>\n<p>El jueves, cuando <strong>Got Talent<\/strong> volvi\u00f3 a las 21.45, <strong>los n\u00fameros ya no eran tan buenos como al principio<\/strong>, pero le alcanzaron para ser lo m\u00e1s visto del d\u00eda.<strong> En su tercera emisi\u00f3n redonde\u00f3 17,5 puntos<\/strong>, dos menos que en la anterior.<\/p>\n<p>Veremos c\u00f3mo le va en su primera gala dominical (este 27 de agosto a las 22.15). Hasta el momento lleva promediados 18,4 puntos, my buena cifra para la televisi\u00f3n que tenemos, pero con un contenido al que le faltar\u00edan algunos ajustes. <strong>Lizy Tagliani sale airosa de una conducci\u00f3n que busca empatizar con los participantes<\/strong>, sin soltarle la mano al humor.<\/p>\n<div class=\"sp__Normal embed-box embed-body-photo\" data-index=\"2\">\n<picture class=\"pointer\">\n<img class=\"img-expand\" width=\"100\" height=\"100\" loading=\"lazy\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2023\/08\/como-fue-la-primera-semana-de-got-talent-el-reality-que-busca-repetir-el-rating-de-gran-hermano-1.jpg\" alt=\"Lizy Tagliani es la conductora de la edici\u00f3n 2023 de &quot;Got Talent Argentina&quot;. Foto de prensa.\"><br \/>\n<span class=\"bt-expand\"><br \/>\n<svg class=\"ico white_mod\">\n<use class=\"use-expand\" xlink:href=\"#icon-expand\" \/>\n<\/svg><br \/>\n<\/span>\n<\/picture><figcaption>Lizy Tagliani es la conductora de la edici\u00f3n 2023 de \u00abGot Talent Argentina\u00bb. Foto de prensa. <\/figcaption><\/div>\n<h2>Detalles del formato<\/h2>\n<p>El show de talentos m\u00e1s reconocido del mundo regres\u00f3&nbsp;a la pantalla con <strong>un jurado de grandes figuras<\/strong>: el artista n\u00famero uno de la escena musical argentina en la actualidad (Abel Pintos), una de las m\u00e1ximas referentes del g\u00e9nero urbano y el RKT (La Joaqui), un bailar\u00edn y core\u00f3grafo uruguayo con millones de seguidores en redes sociales (Emir Abdul) y una de las actrices con m\u00e1s pantalla de la Argentina&nbsp;(Flor Pe\u00f1a).<\/p>\n<p>En un estudio impactante, <strong>artistas de diferentes disciplinas buscan conquistar a los expertos en la etapa de audiciones.<\/strong> Solistas, d\u00faos o grupos, sin importar la destreza y sin l\u00edmite de edad, se presentan sobre el escenario para demostrar su talento. Pero solo algunos de ellos logran convencer al jurado y pasar a la siguiente etapa.<\/p>\n<p><strong>M\u00e1s de 450 artistas fueron seleccionados <\/strong>en los numerosos castings realizados alrededor de todo el pa\u00eds desde noviembre del a\u00f1o pasado. Hay&nbsp;m\u00fasica, canto, baile, acrobacia, magia, destrezas inesperadas y otras disciplinas del entretenimiento.<\/p>\n<div class=\"sp__Normal embed-box embed-body-photo\" data-index=\"3\">\n<picture class=\"pointer\">\n<img class=\"img-expand\" width=\"100\" height=\"100\" loading=\"lazy\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2023\/08\/como-fue-la-primera-semana-de-got-talent-el-reality-que-busca-repetir-el-rating-de-gran-hermano-2.jpg\" alt=\"Abel Pintos, desde este lunes jurado de &quot;Got Talent Argentina&quot;. Foto de prensa.\"><br \/>\n<span class=\"bt-expand\"><br \/>\n<svg class=\"ico white_mod\">\n<use class=\"use-expand\" xlink:href=\"#icon-expand\" \/>\n<\/svg><br \/>\n<\/span>\n<\/picture><figcaption>Abel Pintos, desde este lunes jurado de \u00abGot Talent Argentina\u00bb. Foto de prensa. <\/figcaption><\/div>\n<p>Seg\u00fan cont\u00f3 Abel Pintos, \u00abes una linda experiencia, muy nutritiva, aprendo mucho de mis compa\u00f1eros y de los participantes, y hasta de m\u00ed mismo, porque me vi envuelto en situaciones en las que tuve que resolver cuestiones que cuando terminaban me dec\u00eda <em>&#8216;Ah, esto nunca lo hab\u00eda visto de esta manera&#8217;,<\/em> que un artista me llevara a poder entenderlas de cierta forma. Fue muy interesante haber aceptado este desaf\u00edo\u00bb.<\/p>\n<h2>D\u00f3nde verlo<\/h2>\n<p>El programa tambi\u00e9n se puede&nbsp;ver en<strong> Streams Telefe<\/strong> y&nbsp;en los canales de <strong>YouTube y Twitch de Telefe<\/strong>, donde todas las noches Lula Miranda invitar\u00e1 a reaccionar en vivo a todo lo que suceda en la competencia y comentar\u00e1 cada performance, junto a los usuarios.<\/p>\n<div class=\"sp__Normal embed-box embed-body-photo\" data-index=\"4\">\n<picture class=\"pointer\">\n<img class=\"img-expand\" width=\"100\" height=\"100\" loading=\"lazy\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2023\/08\/como-fue-la-primera-semana-de-got-talent-el-reality-que-busca-repetir-el-rating-de-gran-hermano-3.jpg\" alt=\"La Joaqui se emocion\u00f3 en casi todas sus devoluciones.\"><br \/>\n<span class=\"bt-expand\"><br \/>\n<svg class=\"ico white_mod\">\n<use class=\"use-expand\" xlink:href=\"#icon-expand\" \/>\n<\/svg><br \/>\n<\/span>\n<\/picture><figcaption>La Joaqui se emocion\u00f3 en casi todas sus devoluciones. <\/figcaption><\/div>\n<p> Todos los programas de <em>Got Talent Argentina<\/em> est\u00e1n disponibles en exclusiva por <strong>Pluto TV<\/strong>, dentro de la secci\u00f3n On Demand de la plataforma.<\/p>\n<p> En coproducci\u00f3n con RGB Entertainment, es un big show que sorprender\u00e1 a todos, donde los grandes talentos de nuestro pa\u00eds se enfrentar\u00e1n en busca de consagrarse y llevarse un premio millonario.<\/p>\n<p>Creado en 2006 por el productor discogr\u00e1fico ingl\u00e9s Simon Cowell, <strong>el formato se multiplic\u00f3&nbsp;con m\u00e1s de 70 adaptaciones en otras latitudes<\/strong> y lleg\u00f3 a la se\u00f1al de aire argentina en 2008 como <em>Talento argentino,<\/em> con Mariano Peluffo en el rol de conductor y Catherine Fulop, Maximiliano Guerra y Kike Teruel como jueces.<strong> Se despidi\u00f3 a principios de 2011 luego de tres temporadas<\/strong>.<\/p>\n<p> <span class=\"title-related\">Mir\u00e1 tambi\u00e9n<\/span> <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desde que se estren\u00f3&nbsp;fue lo m\u00e1s visto del d\u00eda, muy lejos del pelot\u00f3n que lo secundaba. Si bien no se sab\u00eda qu\u00e9 suerte correr\u00eda, se esperaba que Got Talent (a las 21.45, por Telefe) no s\u00f3lo ganara el rating diario, sino que lograra subir la vara de la medici\u00f3n a los niveles que hasta marzo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":65613,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[10],"tags":[],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/65612"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=65612"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/65612\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media\/65613"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=65612"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=65612"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=65612"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}