{"id":62263,"date":"2023-06-25T22:46:35","date_gmt":"2023-06-25T22:46:35","guid":{"rendered":"https:\/\/www.ole.com.ar\/river-plate\/demichelis-mensaje-river-libertadores-liga_0_EdlDrm5V8T.html"},"modified":"2023-06-25T22:46:35","modified_gmt":"2023-06-25T22:46:35","slug":"demichelis-y-su-mensaje-para-river-que-nadie-se-relaje","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2023\/06\/25\/demichelis-y-su-mensaje-para-river-que-nadie-se-relaje\/","title":{"rendered":"Demichelis y su mensaje para River: que nadie se relaje"},"content":{"rendered":"<p><img src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2023\/06\/demichelis-y-su-mensaje-para-river-que-nadie-se-relaje.jpg\"><\/p>\n<p><time class=\"createDate\" datetime=\"2023-06-25T19:46:35-03:00\">25\/06\/2023 19:46hs.<\/time><time class=\"modificatedDate\" datetime=\"2023-06-25T19:46:35-03:00\"><\/time><\/p>\n<div id=\"storyBody\">\n<div class=\"custom-text \" readability=\"38.582051282051\">\n<p>\u00abNo vamos a ser hip\u00f3critas y no reconocer que se acerca el final, pero como les digo a los jugadores, esto es d\u00eda a d\u00eda y no quiero que nadie se piense que ya somos los campeones, porque hoy no hubo escenario, entrega de medallas, nada&#8230;\u201d. El presente de <a href=\"https:\/\/www.ole.com.ar\/tema\/river-plate.html\" title=\"River Plate\" alt=\"River Plate\" class=\"slug\">River <\/a>es poco menos que perfecto, pero <a href=\"https:\/\/www.ole.com.ar\/tema\/martin-demichelis.html\" title=\"Martin Demichelis\" alt=\"Martin Demichelis\" class=\"slug\">Mart\u00edn Demichelis<\/a> no quiere que ninguno de sus futbolistas se confunda ni pierda el foco.<\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"38\">\n<p>As\u00ed como mand\u00f3 un mensaje puertas adentro para no pensar todav\u00eda en un mercado de pases que en Argentina est\u00e1 desfasado, el entrenador no quiere relajaci\u00f3n justo en este momento. Lo dec\u00eda tras el triunfo ante Instituto, incluso sin saber que un par de d\u00edas despu\u00e9s<strong> la derrota de Talleres en cancha de Lan\u00fas iba a acercar a\u00fan m\u00e1s a su equipo al objetivo del t\u00edtulo en la Liga<\/strong>. Ahora bien, Demichelis sabe tambi\u00e9n que el panorama casi ideal que se le presenta a River puede cambiar de un momento a otro: y es que este martes el CARP juega una final.<\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"38.887070376432\">\n<p>Claro, lo que pase con The Strongest no cambiar\u00e1 las grandes posibilidades de ganar la LPF, pero es un partido, contra los bolivianos, a todo o nada que en el caso de un traspi\u00e9 s\u00ed podr\u00eda proyectar su sombra sobre una eventual consagraci\u00f3n. River necesitar\u00e1 ganar este martes si quiere seguir adelante en la <a href=\"https:\/\/www.ole.com.ar\/tema\/copa-libertadores.html\" title=\"Copa Libertadores\" alt=\"Copa Libertadores\" class=\"slug\">Copa Libertadores<\/a>: luego del gran 2-0 a Fluminense que desbloque\u00f3 su escenario en el grupo D, asegurar\u00e1 su pase a octavos si vence en un Monumental repleto a un rival que tendr\u00e1 tambi\u00e9n que salir a buscar la \u00e9pica y que vive un presente conflictivo que incluy\u00f3 un nuevo cambio de entrenador. <\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"36\">\n<p>El gol tempranero de Instituto en el Liberti el jueves deber\u00e1 ser un llamado de atenci\u00f3n para un River que, al contrario de lo que vive en un torneo en el que acumula un margen de 10 puntos, no tiene lugar para un tropiezo en el plano internacional.<\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"39\">\n<p>En la Copa estar\u00e1 en juego no s\u00f3lo el prestigio que se gan\u00f3 a nivel continental (pas\u00f3 a playoffs en las \u00faltimas ocho ediciones durante la era Gallardo) sino tambi\u00e9n buena parte del futuro en t\u00e9rminos de mercado y de presupuesto: el juego con TS, entre premios por pase a octavos, por ganar de local y por recaudaci\u00f3n estimada para el primer chico de local, representa<strong> poco menos de cinco millones de d\u00f3lares<\/strong>. S\u00ed, motivos suficientes como para que nadie se relaje ni pierda el foco justo en un momento bisagra.<\/p>\n<\/div>\n<div class=\"sc-a7166897-0 exHLBh\" readability=\"6\">\n<section readability=\"2\"><picture><img alt=\"El contundente triunfo de River contra Boca en Infantiles\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2023\/06\/demichelis-y-su-mensaje-para-river-que-nadie-se-relaje-2.jpg\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"future\" loading=\"lazy\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>El contundente triunfo de River contra Boca en Infantiles<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<div class=\"sc-a7166897-0 exHLBh\" readability=\"6.5\">\n<section readability=\"3\"><picture><img alt=\"Gallardo, ovacionado en el recital de La Bersuit\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2023\/06\/demichelis-y-su-mensaje-para-river-que-nadie-se-relaje-3.jpg\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"future\" loading=\"lazy\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>Gallardo, ovacionado en el recital de La Bersuit<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<div class=\"sc-a7166897-0 exHLBh\" readability=\"6.5\">\n<section readability=\"3\"><picture><img alt=\"La tabla de la Liga: River lidera con 10 de ventaja sobre Talleres y c\u00f3mo se cierra la fecha 21\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2023\/06\/demichelis-y-su-mensaje-para-river-que-nadie-se-relaje-4.jpg\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"future\" loading=\"lazy\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>La tabla de la Liga: River lidera con 10 de ventaja sobre Talleres y c\u00f3mo se cierra la fecha 21<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<div class=\"sc-a7166897-0 exHLBh\" readability=\"6\">\n<section readability=\"2\"><picture><img alt=\"El posible 11 de River ante The Strongest\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2023\/06\/demichelis-y-su-mensaje-para-river-que-nadie-se-relaje-5.jpg\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"future\" loading=\"lazy\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>El posible 11 de River ante The Strongest<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>25\/06\/2023 19:46hs. \u00abNo vamos a ser hip\u00f3critas y no reconocer que se acerca el final, pero como les digo a los jugadores, esto es d\u00eda a d\u00eda y no quiero que nadie se piense que ya somos los campeones, porque hoy no hubo escenario, entrega de medallas, nada&#8230;\u201d. El presente de River es poco menos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":62264,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[16],"tags":[],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/62263"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=62263"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/62263\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media\/62264"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=62263"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=62263"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=62263"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}