{"id":60868,"date":"2023-05-31T00:59:59","date_gmt":"2023-05-31T00:59:59","guid":{"rendered":"https:\/\/www.ole.com.ar\/futbol-primera\/unsain-defensa_0_A2E90ERv5R.html"},"modified":"2023-05-31T00:59:59","modified_gmt":"2023-05-31T00:59:59","slug":"ezequiel-unsain-muy-cerca-de-ser-vendido-al-necaxa-de-mexico","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2023\/05\/31\/ezequiel-unsain-muy-cerca-de-ser-vendido-al-necaxa-de-mexico\/","title":{"rendered":"Ezequiel Unsain muy cerca de ser vendido al Necaxa de M\u00e9xico"},"content":{"rendered":"<p><img src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2023\/05\/ezequiel-unsain-muy-cerca-de-ser-vendido-al-necaxa-de-mexico.jpg\"><\/p>\n<p><time class=\"createDate\" datetime=\"2023-05-30T21:59:59-03:00\">30\/05\/2023 21:59hs.<\/time><time class=\"modificatedDate\" datetime=\"2023\/05\/30T21:59:59-03:00\"><\/time><\/p>\n<div id=\"storyBody\">\n<div class=\"custom-text \" readability=\"11.345454545455\">\n<p><a href=\"https:\/\/www.ole.com.ar\/tema\/defensa-y-justicia.html\" title=\"Defensa y Justicia\" alt=\"Defensa y Justicia\" class=\"slug\"><strong>Defensa<\/strong><\/a><strong> est\u00e1 a punto de perder a una de sus piezas claves en estos \u00faltimos a\u00f1os: Ezequiel Unsain. El arquero de 28 a\u00f1os tiene negociaciones avanzadas para irse al <\/strong><a href=\"https:\/\/www.ole.com.ar\/tema\/necaxa.html\" title=\"Necaxa\" alt=\"Necaxa\" class=\"slug\"><strong>Necaxa de M\u00e9xico<\/strong><\/a><strong> y en los pr\u00f3ximos d\u00edas podr\u00eda cerrarse.<\/strong> El club mexicano ofert\u00f3 por el 50% y desde la CD quieren desprenderse de la totalidad del pase, que est\u00e1 tasado en cuatro milllones de d\u00f3lares. Adem\u00e1s, buscan retenerlo hasta que termine la Copa Sudamericana.<\/p>\n<\/div>\n<div class=\"sc-e7b891c4-0 jPbnQF\"><img alt=\"Unsain festejando una victoria en Brasil. (Bruna Prado\/Pool via AP)\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2023\/05\/ezequiel-unsain-muy-cerca-de-ser-vendido-al-necaxa-de-mexico-2.jpg\" width=\"72\" height=\"10\" decoding=\"async\" data-nimg=\"future\" loading=\"lazy\"><span class=\"epigraphe\">Unsain festejando una victoria en Brasil. (Bruna Prado\/Pool via AP)<\/span><\/div>\n<div class=\"custom-text \" readability=\"15.617647058824\">\n<p><strong>Y pese a que el Flaco es uno de los jugadores m\u00e1s importantes en el equipo dirigido por <\/strong><a href=\"https:\/\/www.ole.com.ar\/tema\/julio-vaccari.html\" title=\"Julio Vaccari\" alt=\"Julio Vaccari\" class=\"slug\"><strong>Julio Vaccari<\/strong><\/a><strong>, el club no le pondr\u00e1 trabas a su salida como un gesto de buena voluntad a todo lo que brind\u00f3 al Halc\u00f3n: 218 encuentros disputados, 74 vallas invictas y la obtenci\u00f3n de la Copa Sudamericana y Recopa Sudamericana en 2020 y 2021, respectivamente.<\/strong> La r\u00e1pida e inesperada salida podr\u00eda darse porque Hugo Gonz\u00e1lez, arquero de los Rayos, se fue a Mazatl\u00e1n y el puesto qued\u00f3 libre. Ah\u00ed, se abri\u00f3 el hueco y el deseo de contar con Unsain.<\/p>\n<\/div>\n<div class=\"sc-e7b891c4-0 jPbnQF\"><img alt=\"Ezequiel Unsain, referente del Halc\u00f3n junto a Tiziano, un hincha.\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2023\/05\/ezequiel-unsain-muy-cerca-de-ser-vendido-al-necaxa-de-mexico-3.jpg\" width=\"72\" height=\"10\" decoding=\"async\" data-nimg=\"future\" loading=\"lazy\"><span class=\"epigraphe\">Ezequiel Unsain, referente del Halc\u00f3n junto a Tiziano, un hincha.<\/span><\/div>\n<div class=\"custom-text \" readability=\"14.555555555556\">\n<p>Por lo que <a href=\"https:\/\/www.ole.com.ar\/tema\/julio-vaccari.html\" title=\"Julio Vaccari\" alt=\"Julio Vaccari\" class=\"slug\">Vaccari<\/a>, pensando en el partido que se viene ante <a href=\"https:\/\/www.ole.com.ar\/tema\/river-plate.html\" title=\"River Plate\" alt=\"River Plate\" class=\"slug\">River<\/a>, todav\u00eda espera poder contar con su arquero titular.<strong> En caso de que el traspaso se cierre y el jugador deba irse en lo inmediato, Enrique Bologna, justamente un ex jugador del Millonario, se pondr\u00e1 el buzo y saldr\u00e1 a la cancha en un partido clave para las aspiraciones del Halc\u00f3n de seguir con chances de pelear hasta el final la LPF.<\/strong><\/p>\n<\/div>\n<div class=\"sc-e7b891c4-0 jPbnQF\"><img alt=\"Bologna firmando su contrato con Defensa. Vermouth Deportivo\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2023\/05\/ezequiel-unsain-muy-cerca-de-ser-vendido-al-necaxa-de-mexico-4.jpg\" width=\"72\" height=\"10\" decoding=\"async\" data-nimg=\"future\" loading=\"lazy\"><span class=\"epigraphe\">Bologna firmando su contrato con Defensa. Vermouth Deportivo<\/span><\/div>\n<div class=\"custom-text \" readability=\"11\">\n<p>Los de Florencio Varela ya conocen de rearmarse y seguir siendo competitivos, lo han hecho y es una de las caracter\u00edsticas principales de la instituci\u00f3n. Pero generalmente fue con jugadores en otras l\u00edneas y no con un puesto tan dif\u00edcil de sustituir. <strong>Habr\u00e1 que ver si los mexicanos van a fondo y Defensa acepta la oferta.<\/strong><\/p>\n<\/div>\n<p><h2><strong>ALGUNAS ATAJAS DE UNSAIN EN DEFENSA<\/strong><\/h2>\n<\/p>\n<div class=\"sc-7ce6049-0 dwIKul\">\n<div class=\"sc-7ce6049-1 bdcBBS videoText\" id=\"contentTitleundefinedophDop76\" readability=\"6\"><svg fill=\"#ffffff\"><symbol id=\"play\" viewBox=\"0 0 512 512\"><path d=\"M512 256C512 397.4 397.4 512 256 512C114.6 512 0 397.4 0 256C0 114.6 114.6 0 256 0C397.4 0 512 114.6 512 256zM176 168V344C176 352.7 180.7 360.7 188.3 364.9C195.8 369.2 205.1 369 212.5 364.5L356.5 276.5C363.6 272.1 368 264.4 368 256C368 247.6 363.6 239.9 356.5 235.5L212.5 147.5C205.1 142.1 195.8 142.8 188.3 147.1C180.7 151.3 176 159.3 176 168V168z\" \/><\/symbol><use xlink:href=\"#play\" \/><\/svg><\/p>\n<div class=\"right\" readability=\"7\">\n<p>Ezequiel Unsain<!-- --> &#8211;<!-- --> <span>30-5-2023<\/span><\/p>\n<h2 class=\"title-vid\">Tremenda atajada de Unsain para salvar a Defensa<\/h2>\n<\/div>\n<\/div>\n<p><span class=\"back\" id=\"spanBackundefinedophDop76\"><\/span><\/div>\n<div class=\"sc-7ce6049-0 dwIKul\">\n<div class=\"sc-7ce6049-1 bdcBBS videoText\" id=\"contentTitleundefineduQtsYfX7\" readability=\"6\"><svg fill=\"#ffffff\"><symbol id=\"play\" viewBox=\"0 0 512 512\"><path d=\"M512 256C512 397.4 397.4 512 256 512C114.6 512 0 397.4 0 256C0 114.6 114.6 0 256 0C397.4 0 512 114.6 512 256zM176 168V344C176 352.7 180.7 360.7 188.3 364.9C195.8 369.2 205.1 369 212.5 364.5L356.5 276.5C363.6 272.1 368 264.4 368 256C368 247.6 363.6 239.9 356.5 235.5L212.5 147.5C205.1 142.1 195.8 142.8 188.3 147.1C180.7 151.3 176 159.3 176 168V168z\" \/><\/symbol><use xlink:href=\"#play\" \/><\/svg><\/p>\n<div class=\"right\" readability=\"7\">\n<p>Defensa y Justicia<!-- --> &#8211;<!-- --> <span>30-5-2023<\/span><\/p>\n<h2 class=\"title-vid\">Unsain se lo tap\u00f3 a Rony<\/h2>\n<\/div>\n<\/div>\n<p><span class=\"back\" id=\"spanBackundefineduQtsYfX7\"><\/span><\/div>\n<div class=\"sc-7ce6049-0 dwIKul\">\n<div class=\"sc-7ce6049-1 bdcBBS videoText\" id=\"contentTitleundefinedARHk9DAz\" readability=\"6\"><svg fill=\"#ffffff\"><symbol id=\"play\" viewBox=\"0 0 512 512\"><path d=\"M512 256C512 397.4 397.4 512 256 512C114.6 512 0 397.4 0 256C0 114.6 114.6 0 256 0C397.4 0 512 114.6 512 256zM176 168V344C176 352.7 180.7 360.7 188.3 364.9C195.8 369.2 205.1 369 212.5 364.5L356.5 276.5C363.6 272.1 368 264.4 368 256C368 247.6 363.6 239.9 356.5 235.5L212.5 147.5C205.1 142.1 195.8 142.8 188.3 147.1C180.7 151.3 176 159.3 176 168V168z\" \/><\/symbol><use xlink:href=\"#play\" \/><\/svg><\/p>\n<div class=\"right\" readability=\"7\">\n<p>Liga Profesional<!-- --> &#8211;<!-- --> <span>30-5-2023<\/span><\/p>\n<h2 class=\"title-vid\">Tremenda tapada de Unsain a Leguizam\u00f3n<\/h2>\n<\/div>\n<\/div>\n<p><span class=\"back\" id=\"spanBackundefinedARHk9DAz\"><\/span><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>30\/05\/2023 21:59hs. Defensa est\u00e1 a punto de perder a una de sus piezas claves en estos \u00faltimos a\u00f1os: Ezequiel Unsain. El arquero de 28 a\u00f1os tiene negociaciones avanzadas para irse al Necaxa de M\u00e9xico y en los pr\u00f3ximos d\u00edas podr\u00eda cerrarse. El club mexicano ofert\u00f3 por el 50% y desde la CD quieren desprenderse de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":60869,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[16],"tags":[],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/60868"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=60868"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/60868\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media\/60869"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=60868"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=60868"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=60868"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}