{"id":59129,"date":"2023-04-28T11:39:00","date_gmt":"2023-04-28T11:39:00","guid":{"rendered":"http:\/\/hoycordobaweb.com\/index.php\/2023\/04\/28\/newells-y-argentinos-van-por-la-recuperacion-en-la-liga-profesional-en-rosario\/"},"modified":"2023-04-28T11:39:00","modified_gmt":"2023-04-28T11:39:00","slug":"newells-y-argentinos-van-por-la-recuperacion-en-la-liga-profesional-en-rosario","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2023\/04\/28\/newells-y-argentinos-van-por-la-recuperacion-en-la-liga-profesional-en-rosario\/","title":{"rendered":"Newell&#8217;s y Argentinos van por la recuperaci\u00f3n en la Liga Profesional en Rosario"},"content":{"rendered":"<p><img src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2023\/04\/newells-y-argentinos-van-por-la-recuperacion-en-la-liga-profesional-en-rosario.jpg\"><\/p>\n<figure class=\"mb-3\"><img loading=\"lazy\" data-src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2023\/04\/newells-y-argentinos-van-por-la-recuperacion-en-la-liga-profesional-en-rosario-2.jpg\" src=\"https:\/\/www.telam.com.ar\/assets\/img\/not_image.png\" class=\" lazy \" width=\"100%\" height=\"100%\" alt=\"La ltima vez que se enfrentaron fue el ao pasado en Rosario Foto Archivo Tlam\"><figcaption> La \u00faltima vez que se enfrentaron fue el a\u00f1o pasado en Rosario. Foto: Archivo T\u00e9lam. <\/figcaption><\/figure>\n<p><strong>Newell&#8217;s Old Boys, que arrastra dos derrotas seguidas<\/strong>, River en Rosario y Belgrano en C\u00f3rdoba, recibir\u00e1 a <strong>Argentinos Juniors, que fue sorprendido en La Paternal por Gimnasia La Plata<\/strong>, en un partido de la fecha 14 de la Liga Profesional de F\u00fatbol (LPF) entre dos equipos que intentar\u00e1n recuperarse.<\/p>\n<p>El encuentro se jugar\u00e1 a partir de las 19 en el estadio Coloso Marcelo Bielsa del Parque de la Independencia de Rosario, con el arbitraje de Luis Lobo Medina y televisaci\u00f3n de TNT Sports.<\/p>\n<p><strong>Newell`s y Argentinos tienen ambos 18 puntos <\/strong>y, adem\u00e1s, deben jugar el martes por la Copa Sudamericana contra Santos de local y por la Copa Libertadores contra Liverpool en Uruguay, respectivamente, motivo por el cual sus entrenadores podr\u00edan preservar algunos jugadores titulares.<\/p>\n<blockquote class><p>El historial entre ambos es de 122 partidos y favorece a Newell&#8217;s, que se impuso en 49 ocasiones contra 34 de Argentinos<\/p><\/blockquote>\n<p>El historial entre ambos es de 122 partidos y favorece a Newell&#8217;s, que se impuso en 49 ocasiones contra 34 de Argentinos, y adem\u00e1s empataron 39 veces.<\/p>\n<p>La \u00faltima vez que se enfrentaron fue el a\u00f1o pasado en Rosario, por la cuarta fecha de la Liga Profesional, y gan\u00f3 Newell&#8217;s por 1-0 con un gol del colombiano Willar Ditta.<\/p>\n<h2 class>Probables Formaciones<\/h2>\n<p>Newell&#8217;s Old Boys: Lucas Hoyos; Armando M\u00e9ndez o Jherson Mosquera, Gustavo Vel\u00e1zquez, Willter Ditta y Bruno Pitt\u00f3n o \u00c1ngelo Martino; Iv\u00e1n G\u00f3mez, Juan Sforza y Lisandro Montenegro o Marcos Portillo; Brian Aguirre o Jerem\u00edas P\u00e9rez Tica, Djorkaeff Reasco o Jorge Recalde y Ramiro Sordo. DT: Gabriel Heinze.<\/p>\n<p>Argentinos Junios: Federico Lanzillotta; Luciano S\u00e1nchez, MIguel Torr\u00e9n, Lucas Villalba y Mat\u00edas Vera; Javier Cabrera, Federico Redondo y Francisco Gonz\u00e1lez Metilli; Santiago Montiel, Leonardo Heredia y Gabriel \u00c1valos. DT: Gabriel Milito.<\/p>\n<p>\u00c1rbitro: Luis Lobo Medina.<\/p>\n<p>VAR: Germ\u00e1n Delfino.<\/p>\n<p>Cancha: Newell&#8217;s Old Boys.<\/p>\n<p>Hora de inicio: 19.<\/p>\n<p>TV: TNT Sports.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La \u00faltima vez que se enfrentaron fue el a\u00f1o pasado en Rosario. Foto: Archivo T\u00e9lam. Newell&#8217;s Old Boys, que arrastra dos derrotas seguidas, River en Rosario y Belgrano en C\u00f3rdoba, recibir\u00e1 a Argentinos Juniors, que fue sorprendido en La Paternal por Gimnasia La Plata, en un partido de la fecha 14 de la Liga Profesional [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":59130,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[16],"tags":[],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/59129"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=59129"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/59129\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media\/59130"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=59129"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=59129"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=59129"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}