{"id":57138,"date":"2023-03-19T16:27:27","date_gmt":"2023-03-19T16:27:27","guid":{"rendered":"https:\/\/www.ole.com.ar\/ecuador\/internacional\/carlos-gruezo-marco-angulo-michael-estrada-cruz-azul-liga-mx-mls-angeles-fc-seattle-sounders_0_puEcleT79o.html"},"modified":"2023-03-19T16:27:27","modified_gmt":"2023-03-19T16:27:27","slug":"los-ecuatorianos-tuvieron-accion-en-la-mls-y-la-liga-mx","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2023\/03\/19\/los-ecuatorianos-tuvieron-accion-en-la-mls-y-la-liga-mx\/","title":{"rendered":"Los ecuatorianos tuvieron acci\u00f3n en la MLS y la Liga MX"},"content":{"rendered":"<p><img src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2023\/03\/los-ecuatorianos-tuvieron-accion-en-la-mls-y-la-liga-mx.jpg\"><\/p>\n<p><time class=\"createDate\" datetime=\"2023-03-19T13:27:27-03:00\">19\/03\/2023 13:27hs.<\/time><time class=\"modificatedDate\" datetime=\"2023\/03\/19T13:27:27-03:00\"><\/time><\/p>\n<div id=\"storyBody\">\n<div class=\"custom-text \" readability=\"33.645333333333\">\n<p>Las diferentes ligas del mundo tuvieron acci\u00f3n este fin de semana previo a la fecha FIFA. <strong>Varios futbolistas ecuatorianos tuvieron minutos en sus equipos, con la <\/strong><a href=\"https:\/\/www.ole.com.ar\/tema\/major-league-beisbol.html\" title=\"Major League Beisbol\" alt=\"Major League Beisbol\" class=\"slug\"><strong>MLS<\/strong><\/a><strong> y la <\/strong><a href=\"https:\/\/www.ole.com.ar\/tema\/liga-bbva-mx.html\" title=\"Liga BBVA MX\" alt=\"Liga BBVA MX\" class=\"slug\"><strong>Liga MX<\/strong><\/a><strong> como los torneos donde saltaron a la cancha.<\/strong> <a href=\"https:\/\/www.ole.com.ar\/tema\/michael-estrada.html\" title=\"Michael Estrada\" alt=\"Michael Estrada\" class=\"slug\">Michael Estrada<\/a> fue el \u00fanico tricolor que consigui\u00f3 una victoria con su equipo este s\u00e1bado, con <a href=\"https:\/\/www.ole.com.ar\/tema\/cruz-azul.html\" title=\"Cruz Azul\" alt=\"Cruz Azul\" class=\"slug\">Cruz Azul<\/a> derrotando por 1-0 al Atl\u00e9tico San Luis.<\/p>\n<\/div>\n<div class=\"sc-489cef11-0 jHGTKj\" readability=\"6\">\n<section readability=\"2\"><picture><img class=\"img\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2023\/03\/los-ecuatorianos-tuvieron-accion-en-la-mls-y-la-liga-mx-2.jpg\" alt=\"Mart\u00edn Anselmi: &quot;IDV juega para ampliar el resultado constantemente&quot;\" height=\"290\" width=\"290\" loading=\"lazy\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>Mart\u00edn Anselmi: \u00abIDV juega para ampliar el resultado constantemente\u00bb<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<div class=\"sc-489cef11-0 jHGTKj\" readability=\"6\">\n<section readability=\"2\"><picture><img class=\"img\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2023\/03\/los-ecuatorianos-tuvieron-accion-en-la-mls-y-la-liga-mx-3.jpg\" alt=\"M\u00e1s de 50 millones: lo que gasta el Manchester United por un futbolista que no juega\" height=\"290\" width=\"290\" loading=\"lazy\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>M\u00e1s de 50 millones: lo que gasta el Manchester United por un futbolista que no juega<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<div class=\"sc-489cef11-0 jHGTKj\" readability=\"6\">\n<section readability=\"2\"><picture><img class=\"img\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2023\/03\/los-ecuatorianos-tuvieron-accion-en-la-mls-y-la-liga-mx-4.jpg\" alt=\"Sornoza: &quot;Volver a la Selecci\u00f3n despu\u00e9s de tanto tiempo es muy motivante&quot;\" height=\"290\" width=\"290\" loading=\"lazy\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>Sornoza: \u00abVolver a la Selecci\u00f3n despu\u00e9s de tanto tiempo es muy motivante\u00bb<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<div class=\"custom-text \" readability=\"38\">\n<p><strong>Estrada fue suplente en la M\u00e1quina Cementera, pero ingres\u00f3 para el segundo tiempo, siendo importante en el ataque al tener oportunidades de gol.<\/strong> Iv\u00e1n Morales fue quien le dio la victoria a Cruz Azul convirtiendo un penal a los 82 minutos. Con esta victoria suman 16 puntos y ocupan la octava posici\u00f3n, la cual da la clasificaci\u00f3n a la liguilla. El Monterrey tuvo a Joao Rojas en la banca en la victoria frente a Tigres por 1-0.<\/p>\n<\/div>\n<div class=\"sc-996041c8-0 kvfKM\"><img alt=\"Cruz Azul's Argentine midfielder Augusto Lotti celebrates with teammates after scoring against Atlas during their Mexican Clausura 2023 tournament football match at the Azteca stadium in Mexico City, on February 22, 2023. (Photo by PEDRO PARDO \/ AFP)\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2023\/03\/los-ecuatorianos-tuvieron-accion-en-la-mls-y-la-liga-mx-5.jpg\" width=\"720\" height=\"0\" decoding=\"async\" data-nimg=\"future\" loading=\"lazy\"><span>Cruz Azul&#8217;s Argentine midfielder Augusto Lotti celebrates with teammates after scoring against Atlas during their Mexican Clausura 2023 tournament football match at the Azteca stadium in Mexico City, on February 22, 2023. (Photo by PEDRO PARDO \/ AFP)<\/span><\/div>\n<div class=\"custom-text \" readability=\"35\">\n<p><strong>Desde la MLS lleg\u00f3 una mala noticia para La Tri por la lesi\u00f3n que sufri\u00f3 Carlos Gruezo en la derrota del San Jos\u00e9 Earthquakes frente al St Louis City por 3-0<\/strong>. El volante ecuatoriano dej\u00f3 la cancha a los 29 minutos con cara de preocupaci\u00f3n por la molestia f\u00edsica. En las pr\u00f3ximas horas se realizar\u00e1 estudios para conocer la gravedad de la lesi\u00f3n y si podr\u00e1 estar en los amistosos frente a Australia con La Tri.<\/p>\n<\/div>\n<div class=\"sc-996041c8-0 kvfKM\"><img alt=\"Carlos Gruezo sali\u00f3 lesionado y es duda para la fecha FIFA.\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2023\/03\/los-ecuatorianos-tuvieron-accion-en-la-mls-y-la-liga-mx-6.jpg\" width=\"720\" height=\"0\" decoding=\"async\" data-nimg=\"future\" loading=\"lazy\"><span>Carlos Gruezo sali\u00f3 lesionado y es duda para la fecha FIFA.<\/span><\/div>\n<div class=\"custom-text \" readability=\"36\">\n<p><strong>Marco Angulo tuvo su primera titularidad en el FC Cincinnati. El equipo del mediocampista de 20 a\u00f1os empat\u00f3 3-3 con el Chicago Fire en un partido muy entretenido<\/strong>. El FC Cincinnati perd\u00eda 3-1 al entrar a los 10 minutos finales y empat\u00f3 el marcador en tan solo 3 minutos. J\u00fanior Moreno con un doblete y Sergio Santos fueron los goleadores para el club de Angulo, quien jug\u00f3 80 minutos.<\/p>\n<\/div>\n<div class=\"sc-996041c8-0 kvfKM\"><img alt=\"Angulo fue titular. (Reuter)\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2023\/03\/los-ecuatorianos-tuvieron-accion-en-la-mls-y-la-liga-mx-7.jpg\" width=\"720\" height=\"0\" decoding=\"async\" data-nimg=\"future\" loading=\"lazy\"><span>Angulo fue titular. (Reuter)<\/span><\/div>\n<div class=\"custom-text \" readability=\"36\">\n<p>Los Vancouver Whitecaps empataron 1-1 en su visita a Los Angeles Galaxy. <strong>Pedro Vite fue suplente en el equipo visitante e ingres\u00f3 al terreno de juego a los 43 minutos en lugar de Sergio C\u00f3rdoba<\/strong>. Los Whitecaps se pusieron en ventaja al minuto 14 con gol de Tristan Blackmon, pero en el final del primer tiempo Kelvin Leerdam empat\u00f3 para los Galaxy y puso el 1-1 final.<\/p>\n<\/div>\n<div class=\"sc-996041c8-0 kvfKM\"><img alt=\"Vite ingres\u00f3 al cambio. (Reuter)\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2023\/03\/los-ecuatorianos-tuvieron-accion-en-la-mls-y-la-liga-mx-8.jpg\" width=\"720\" height=\"0\" decoding=\"async\" data-nimg=\"future\" loading=\"lazy\"><span>Vite ingres\u00f3 al cambio. (Reuter)<\/span><\/div>\n<div class=\"custom-text \" readability=\"38\">\n<p><strong>Un duelo entre ecuatorianos se dio en el Seattle Sounders vs Los Angeles FC<\/strong>. Pese a la gran cantidad de futbolistas de la Selecci\u00f3n, solo fue titular Palacios: el lateral izquierdo complet\u00f3 los 90 minutos para el equipo dirigido por Steven Cherundolo. El entrenador estadounidense mand\u00f3 a la cancha a Cifuentes a los 65&#8242;, cuando el volante ingres\u00f3 por Timothy Tillman para aportar m\u00e1s equilibro en la mitad de la cancha. Por su lado, Xavier Arreaga ingres\u00f3 a los 55 minutos en el cuadro local.<\/p>\n<\/div>\n<div class=\"sc-996041c8-0 kvfKM\"><img alt=\"Seattle y LAFC se enfrentaron. (Reuter)\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2023\/03\/los-ecuatorianos-tuvieron-accion-en-la-mls-y-la-liga-mx-9.jpg\" width=\"720\" height=\"0\" decoding=\"async\" data-nimg=\"future\" loading=\"lazy\"><span>Seattle y LAFC se enfrentaron. (Reuter)<\/span><\/div>\n<div class=\"custom-text \" readability=\"37\">\n<p><strong>Leonardo Campana sigue recuper\u00e1ndose de su lesi\u00f3n y no fue convocado en el Inter Miami, equipo que perdi\u00f3 2-0 en su visita al Toronto FC<\/strong>. El Columbus Crew de Gustavo Vallecilla perdi\u00f3 2-1 frente a los New York Red Bulls, pero el zaguero ecuatoriano no ingres\u00f3 a la cancha y vio el partido desde el banco de suplentes. El balance para los tricolores en la jornada del s\u00e1bado no fue positiva al tener una sola victoria con Michael Estrada.<\/p>\n<\/div>\n<div class=\"sc-996041c8-0 kvfKM\"><img alt=\"Leonardo Campana sigue lesionado.\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2023\/03\/los-ecuatorianos-tuvieron-accion-en-la-mls-y-la-liga-mx-10.jpg\" width=\"720\" height=\"0\" decoding=\"async\" data-nimg=\"future\" loading=\"lazy\"><span>Leonardo Campana sigue lesionado.<\/span><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>19\/03\/2023 13:27hs. Las diferentes ligas del mundo tuvieron acci\u00f3n este fin de semana previo a la fecha FIFA. Varios futbolistas ecuatorianos tuvieron minutos en sus equipos, con la MLS y la Liga MX como los torneos donde saltaron a la cancha. Michael Estrada fue el \u00fanico tricolor que consigui\u00f3 una victoria con su equipo este [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":57139,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[16],"tags":[],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/57138"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=57138"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/57138\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media\/57139"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=57138"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=57138"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=57138"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}