{"id":54925,"date":"2023-02-04T14:58:00","date_gmt":"2023-02-04T14:58:00","guid":{"rendered":"http:\/\/hoycordobaweb.com\/index.php\/2023\/02\/04\/sequia-el-gobierno-invertira-70-000-millones-para-asistir-a-productores\/"},"modified":"2023-02-04T14:58:00","modified_gmt":"2023-02-04T14:58:00","slug":"sequia-el-gobierno-invertira-70-000-millones-para-asistir-a-productores","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2023\/02\/04\/sequia-el-gobierno-invertira-70-000-millones-para-asistir-a-productores\/","title":{"rendered":"Sequ\u00eda: el Gobierno invertir\u00e1 $70.000 millones para asistir a productores"},"content":{"rendered":"<p><img src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2023\/02\/sequia-el-gobierno-invertira-70-000-millones-para-asistir-a-productores.jpg\"><\/p>\n<figure class=\"mb-3\"><img loading=\"lazy\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2023\/02\/sequia-el-gobierno-invertira-70-000-millones-para-asistir-a-productores-2.jpg\" width=\"100%\" height=\"100%\" alt=\"Foto Pepe Mateos\"><figcaption> Foto Pepe Mateos. <\/figcaption><\/figure>\n<p>El Gobierno nacional destinar\u00e1 $70.000 millones para asistir y ayudar a productores agropecuarios afectados por la sequ\u00eda, a trav\u00e9s de fondos rotatorios y cr\u00e9ditos a tasas subsidiadas anunciados el \u00faltimo martes dentro de un paquete de medidas para el sector.<\/p>\n<p>Los fondos partir\u00e1n en mayor medida del Banco Naci\u00f3n, entidad que pondr\u00e1 a disposici\u00f3n de los agricultores damnificados por la falta de lluvias $50.000 millones en cr\u00e9ditos a tasa subsidiada, en la que el Ministerio de Econom\u00eda se har\u00e1 cargo de 15 puntos.<\/p>\n<p>De esos 15 puntos, 10 correr\u00e1n por parte de la Secretaria de Agricultura, Ganader\u00eda y Pesca, lo que le demandar\u00e1 una inversi\u00f3n de $10.000 millones, y 5 corresponder\u00e1n a la Secretar\u00eda de Industria y Desarrollo Productivo por $5.000 millones, inform\u00f3 a T\u00e9lam la cartera agropecuaria.<\/p>\n<p>De esta manera, habr\u00e1 dos l\u00edneas de cr\u00e9dito a tasa subsidiada para aquellos productores comprendidos en la emergencia.<\/p>\n<figure class=\"mb-3\"><img loading=\"lazy\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2023\/02\/sequia-el-gobierno-invertira-70-000-millones-para-asistir-a-productores-3.jpg\" width=\"100%\" height=\"100%\" alt=\"Foto Pepe Mateos\"><figcaption> Foto Pepe Mateos. <\/figcaption><\/figure>\n<p>Seg\u00fan coment\u00f3 durante la semana la presidenta del Banco Naci\u00f3n, Silvina Batakis, existe \u00abuna l\u00ednea especifica para el sector agropecuario pyme que est\u00e1 vigente y que tiene una tasa promedio del 40,6%\u00bb.<\/p>\n<p>Como parte de las medidas, \u00abse van a sostener estas tasas de origen\u00bb sin modificarlas, y se otorgar\u00e1 \u00abun a\u00f1o de plazo de gracia para que los productores tengan ese per\u00edodo para recomponer sus ingresos y empiecen a devolver (el cr\u00e9dito) reci\u00e9n el a\u00f1o que viene\u00bb.<\/p>\n<p>Otra medida -precis\u00f3 Batakis- es una l\u00ednea nueva donde pondr\u00e1n a disposici\u00f3n $ 20.000 millones a una tasa de inter\u00e9s del 49,5%, y que tambi\u00e9n posee un a\u00f1o de gracia.<\/p>\n<p>Es en estos pr\u00e9stamos donde Agricultura e Industria aportar\u00e1n $15.000 millones para subsidiar 15 puntos en la tasa.<\/p>\n<p>Al paquete crediticio hay que sumarle los fondos rotatorios por $5.000 millones para llegar a los peque\u00f1os productores, que se canalizar\u00e1 a trav\u00e9s de convenios con provincias, municipios y\/o cooperativas agropecuarias, sistema con el que se aspira a asistir a 18.000 peque\u00f1os productores, monto que es aportado de la cartera agropecuaria.<\/p>\n<p>As\u00ed, el Estado nacional invertir\u00e1 $70.000 millones en asistencia financiera y cr\u00e9ditos subsidiados para el agro, sin tomar en cuenta las medidas que tendr\u00e1n impacto fiscal anunciadas el martes pasado por el ministro de Econom\u00eda, Sergio Massa, como lo son la suspensi\u00f3n del pago del anticipo de Ganancias y de los juicios de ejecuci\u00f3n fiscal y del embargo de Cuentas Corrientes.<\/p>\n<p>Adem\u00e1s, se tendr\u00e1 en cuenta la venta forzosa de hacienda para el c\u00e1lculo de impuestos a las Ganancias y la homologaci\u00f3n de los pedidos de emergencia en tr\u00e1mite en la Secretar\u00eda de Agricultura, entre otros puntos.<\/p>\n<p>Seg\u00fan marc\u00f3 Massa tras realizar los anuncios en una reuni\u00f3n que mantuvo con los titulares de las entidades integrantes de la Mesa de Enlace y de la Mesa Agroalimentaria, estos beneficios podr\u00edan llegar \u00aba un universo de 54.100 productores de la Argentina que de alguna manera van a estar abarcados por estas medidas\u00bb.<\/p>\n<figure class=\"mb-3\"><img loading=\"lazy\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2023\/02\/sequia-el-gobierno-invertira-70-000-millones-para-asistir-a-productores-4.jpg\" width=\"100%\" height=\"100%\" alt=\"Foto Pepe Mateos\"><figcaption> Foto Pepe Mateos. <\/figcaption><\/figure>\n<p>\u00abTenemos la responsabilidad de trabajar todos juntos, m\u00e1s all\u00e1 del pensamiento de cada uno y el rol de cada uno, para tenderles una mano y ayudarlos a superar esta circunstancia clim\u00e1tica agravada este \u00faltimo a\u00f1o pero que viene siendo recurrente con un cambio de cronograma clim\u00e1tico, por un lado, pero por otro con un fuerte impacto de la sequ\u00eda en el \u00faltimo a\u00f1o\u00bb, agreg\u00f3 el titular del Palacio de Hacienda.<\/p>\n<p>De hecho, desde las entidades agropecuarias se mostr\u00f3 conformidad con la bater\u00eda de anuncios realizados por Massa, lo cual le vali\u00f3 a los dirigentes de la Mesa de Enlace fuertes cr\u00edticas de los sectores m\u00e1s radicalizados del sector, como los autoconvocados o el llamado \u00abGrupo Independencia\u00bb.<\/p>\n<p>Argentina enfrenta una de las peores sequ\u00edas de los \u00faltimos tiempos, que se agrav\u00f3 durante el \u00faltimo semestre de 2022, en un contexto donde el fen\u00f3meno clim\u00e1tico de La Ni\u00f1a se desarrolla por tercera vez consecutiva en el pa\u00eds.<\/p>\n<p>Esto produjo un severo impacto en los cultivos de invierno; seg\u00fan la Bolsa de Cereales de Buenos Aires (BCBA) la cosecha de trigo cay\u00f3 10 millones de toneladas respecto de la campa\u00f1a pasada hasta las 12,4 millones de toneladas, mientras que se esperan ca\u00eddas de 7,5 millones de toneladas en ma\u00edz y 2,3 millones de toneladas en soja.<\/p>\n<p>Asimismo, gener\u00f3 un fuerte impacto en las econom\u00edas regionales, sobre todo las que se encuentran en la franja este del pa\u00eds, y tambi\u00e9n en la ganader\u00eda, aunque por el momento es imposible obtener un an\u00e1lisis concreto de las p\u00e9rdidas.<\/p>\n<p>Seg\u00fan un informe de la Bolsa de Comercio de Rosario (BCR), las mermas en los ingresos de los productores de soja, ma\u00edz y trigo podr\u00edan alcanzar los US$ 10.425 millones por la sequ\u00eda.<\/p>\n<p>De ese total, se prev\u00e9 que las p\u00e9rdidas del sector productivo en hect\u00e1reas cosechadas alcance los US$ 8.530 millones, mientras que en hect\u00e1reas sembradas y no cosechadas se ubique en US$ 757 millones, y en hect\u00e1reas no sembradas por falta de humedad en US$ 1.139 millones. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Foto Pepe Mateos. El Gobierno nacional destinar\u00e1 $70.000 millones para asistir y ayudar a productores agropecuarios afectados por la sequ\u00eda, a trav\u00e9s de fondos rotatorios y cr\u00e9ditos a tasas subsidiadas anunciados el \u00faltimo martes dentro de un paquete de medidas para el sector. Los fondos partir\u00e1n en mayor medida del Banco Naci\u00f3n, entidad que pondr\u00e1 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":54926,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[19],"tags":[],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/54925"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=54925"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/54925\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media\/54926"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=54925"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=54925"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=54925"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}