{"id":54446,"date":"2023-01-22T13:46:37","date_gmt":"2023-01-22T13:46:37","guid":{"rendered":"https:\/\/ladecimaweb.com\/?p=15725"},"modified":"2023-01-22T13:46:37","modified_gmt":"2023-01-22T13:46:37","slug":"turismo-de-cercania-tres-localidades-para-visitar-a-pocos-kilometros-de-la-capital","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2023\/01\/22\/turismo-de-cercania-tres-localidades-para-visitar-a-pocos-kilometros-de-la-capital\/","title":{"rendered":"Turismo de cercan\u00eda: tres localidades para visitar a pocos kil\u00f3metros de la capital"},"content":{"rendered":"<div class=\"boldgrid-section\">\n<div class=\"container\">\n<div class=\"row\">\n<div class=\"col-md-12 col-xs-12 col-sm-12\">\n<p>C\u00f3rdoba capital durante este tiempo se ha vuelto el epicentro de los turistas que hacen base para recorrer distintos puntos de nuestra regi\u00f3n. Uno de los privilegios de la capital provincial es la cercan\u00eda con sitios naturales, a pocos kil\u00f3metros de distancia.<\/p>\n<p>Esta particularidad facilita a los turistas poder recorrer campings, r\u00edos, cascadas, cerros, sin tener que viajar largos tramos.&nbsp;<\/p>\n<p>Este trinomio de localidades es el refugio perfecto para visitar en el d\u00eda, para aquellos que no tengan planificadas actividades.<\/p>\n<h4><strong>Tres cascadas de Ascochinga<\/strong><\/h4>\n<p>A unos 60 kil\u00f3metros de la capital, la localidad de Ascochinga tiene una de las perlitas de las Sierras Chicas. Una muralla de piedra atraviesa el curso del r\u00edo de San Miguel. Estas tres ca\u00eddas de agua se encuentran a resguardo dentro de la reserva natural Ascochinga.<\/p>\n<p>La llegada a este maravilloso paisaje es por medio de un sendero de mediana dificultad de unos 500 metros de distancia. Para llegar a este destino -desde C\u00f3rdoba- se debe tomar la autov\u00eda E-53 hasta el camino E-66 y recorrer un aproximado de 9 kil\u00f3metros.&nbsp;<\/p>\n<figure class=\"wp-block-image aligncenter size-full\">\n<p class=\"mod-reset\"><a href=\"https:\/\/www.facebook.com\/photo\/?fbid=10156459486007869&amp;set=a.10150303174617869\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" class=\"wp-image-533820 aligncenter\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2023\/01\/turismo-de-cercania-tres-localidades-para-visitar-a-pocos-kilometros-de-la-capital.jpg\" alt=\"\" width=\"444\" height=\"296\"><\/a><\/p>\n<\/figure>\n<h4><strong>Falda del Carmen<\/strong><\/h4>\n<p>Si queremos un plan alternativo al r\u00edo -para d\u00edas nublados-<strong><span>&nbsp;<\/span><\/strong>a 40 kil\u00f3metros de esta en la localidad de Falda del Carmen se encuentra la Estaci\u00f3n Astrof\u00edsica Bosque Alegre. All\u00ed, un enorme telescopio permite observar el cielo ubicado a unos 1290 metros de altura.<\/p>\n<p>La recorrida por este lugar termina con la visita a restaurantes emblem\u00e1ticos: son opciones recomendables el Gran Vadori, de tradici\u00f3n gourmet, La Pulper\u00eda de Ach\u00e1val, entre pastas y parrilla, y el Almac\u00e9n de Quito, conocido por sus s\u00e1ndwiches de fiambres.<\/p>\n<p>Una regi\u00f3n en la que se respira tranquilidad y propone el disfrute de diversos paseos a la orilla del arroyo hom\u00f3nimo. Falda del Carmen es un peque\u00f1o enclave cordob\u00e9s en el departamento de Santa Mar\u00eda, a unos 35 kil\u00f3metros de la ciudad de C\u00f3rdoba. Se puede llegar por la RP 5 o por la RN20 y la RP C45.&nbsp;<\/p>\n<h4><strong>San Clemente<\/strong><\/h4>\n<p>Calma y serenidad son dos de las caracter\u00edsticas de los paisajes serranos de San Clemente. Se puede disfrutar de una jornada de calor sumergido, o de un d\u00eda de fr\u00edo caminando por las orillas de sus r\u00edos: San Jos\u00e9, San Pedro y Suela,<\/p>\n<p>Estos son rincones muy elegidos por turistas que deciden descansar con sus acompa\u00f1antes. Tirar una mantita a la vera de estos cursos de agua ser\u00e1 todo el plan necesario para \u201cdesenchufarse\u201d del ritmo de la ciudad.<\/p>\n<p class=\"\">Adem\u00e1s, en este rinc\u00f3n del valle de Paravachasca re\u00fane a fan\u00e1ticos y aficionados de la pesca de truchas como una de las actividades preferidas. En consecuencia, destaca la presencia del Club Trucha C\u00f3rdoba. Los r\u00edos Condorito, Sur, Los Espinillos, San Pedro y San Jos\u00e9 son los escenarios elegidos para esta actividad.<\/p>\n<p>&nbsp;<\/p>\n<p class=\"\">\n<div class=\"ubm_banner\"><a href=\"https:\/\/www.cba.gov.ar\" target=\"_blank\" rel=\"dofollow noopener noreferrer\"><img src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2023\/01\/turismo-de-cercania-tres-localidades-para-visitar-a-pocos-kilometros-de-la-capital.gif\" alt=\"\"><\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>La entrada <a rel=\"nofollow\" href=\"https:\/\/ladecimaweb.com\/turismo-de-cercania-tres-localidades-para-visitar-a-pocos-kilometros-de-la-capital\/\">Turismo de cercan\u00eda: tres localidades para visitar a pocos kil\u00f3metros de la capital<\/a> se public\u00f3 primero en <a rel=\"nofollow\" href=\"https:\/\/ladecimaweb.com\">LaDecima<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>C\u00f3rdoba capital durante este tiempo se ha vuelto el epicentro de los turistas que hacen base para recorrer distintos puntos de nuestra regi\u00f3n. Uno de los privilegios de la capital provincial es la cercan\u00eda con sitios naturales, a pocos kil\u00f3metros de distancia. Esta particularidad facilita a los turistas poder recorrer campings, r\u00edos, cascadas, cerros, sin [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":54447,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[19],"tags":[],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/54446"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=54446"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/54446\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media\/54447"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=54446"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=54446"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=54446"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}