{"id":54286,"date":"2023-01-18T14:50:13","date_gmt":"2023-01-18T14:50:13","guid":{"rendered":"https:\/\/ladecimaweb.com\/?p=15698"},"modified":"2023-01-18T14:50:13","modified_gmt":"2023-01-18T14:50:13","slug":"los-fuertes-vientos-ocasionaron-la-caida-de-arboles-postes-y-voladura-de-techos-de-zinc","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2023\/01\/18\/los-fuertes-vientos-ocasionaron-la-caida-de-arboles-postes-y-voladura-de-techos-de-zinc\/","title":{"rendered":"Los fuertes vientos ocasionaron la ca\u00edda de \u00e1rboles, postes y voladura de techos de zinc"},"content":{"rendered":"<div class=\"boldgrid-section\">\n<div class=\"container\">\n<div class=\"row\">\n<div class=\"col-md-12 col-xs-12 col-sm-12\">\n<p class=\"\">La direcci\u00f3n de Defensa Civil municipal informa que anoche se registraron vientos de entre 13 y 22 kil\u00f3metros por hora, causando en la ciudad un total de dos postes de alumbrado y ocho \u00e1rboles ca\u00eddos, dos quebraduras de ramas, tres cables de Epec tendidos sobre carpeta asf\u00e1ltica y cuarto postes de la empresa Provincial de Energ\u00eda ca\u00eddos y\/o quebrados.<\/p>\n<p class=\"\">En Villa El Libertador, por caso, se produjo la voladura de un techo de chapa en una vivienda, sin que sus ocupantes resultaran heridos.<\/p>\n<div class=\"ubm_banner\"><a href=\"https:\/\/www.cba.gov.ar\" target=\"_blank\" rel=\"dofollow noopener noreferrer\"><img src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2023\/01\/los-fuertes-vientos-ocasionaron-la-caida-de-arboles-postes-y-voladura-de-techos-de-zinc.gif\" alt=\"\"><\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>La entrada <a rel=\"nofollow\" href=\"https:\/\/ladecimaweb.com\/los-fuertes-vientos-ocasionaron-la-caida-de-arboles-postes-y-voladura-de-techos-de-zinc\/\">Los fuertes vientos ocasionaron la ca\u00edda de \u00e1rboles, postes y voladura de techos de zinc<\/a> se public\u00f3 primero en <a rel=\"nofollow\" href=\"https:\/\/ladecimaweb.com\">LaDecima<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La direcci\u00f3n de Defensa Civil municipal informa que anoche se registraron vientos de entre 13 y 22 kil\u00f3metros por hora, causando en la ciudad un total de dos postes de alumbrado y ocho \u00e1rboles ca\u00eddos, dos quebraduras de ramas, tres cables de Epec tendidos sobre carpeta asf\u00e1ltica y cuarto postes de la empresa Provincial de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":54287,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[19],"tags":[],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/54286"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=54286"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/54286\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media\/54287"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=54286"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=54286"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=54286"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}