{"id":53425,"date":"2022-12-31T01:52:26","date_gmt":"2022-12-31T01:52:26","guid":{"rendered":"https:\/\/www.ole.com.ar\/ecuador\/la-tri\/la-tri-momentos-ano-2022-gustavo-alfaro-mundial-eliminatorias-castillo-chile_0_zHVHAMhj0H.html"},"modified":"2022-12-31T01:52:26","modified_gmt":"2022-12-31T01:52:26","slug":"los-cinco-momentos-que-marcaron-el-2022-de-la-tri","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2022\/12\/31\/los-cinco-momentos-que-marcaron-el-2022-de-la-tri\/","title":{"rendered":"Los cinco momentos que marcaron el 2022 de La Tri"},"content":{"rendered":"<p><img src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/12\/los-cinco-momentos-que-marcaron-el-2022-de-la-tri.jpg\"><\/p>\n<div class=\"custom-text \" readability=\"38.461538461538\">\n<p>El almanaque tendr\u00e1 una nueva p\u00e1gina. Se va el 2022 y con \u00e9l un conjunto de emociones alrededor de <a href=\"https:\/\/www.ole.com.ar\/tema\/la-tri.html\" title=\"La Tri\" alt=\"La Tri\" class=\"slug\">La Tri<\/a>, que fueron desde la ilusi\u00f3n al orgullo por disputar el cuarto Mundial en su historia, pasando por la desaz\u00f3n y la incertidumbre de lo que dej\u00f3 Qatar y lo que comunicar\u00e1 <a href=\"https:\/\/www.ole.com.ar\/tema\/gustavo-alfaro.html\" title=\"Gustavo Alfaro\" alt=\"Gustavo Alfaro\" class=\"slug\">Gustavo Alfaro<\/a> respecto a su posible continuidad. A continuaci\u00f3n, <strong>Ol\u00e9 Ecuador realiza un repaso de los cinco momentos que marcaron un calendario movido<\/strong>, con pol\u00e9micas, goles y sobre todo experiencia para los representantes tricolores. <\/p>\n<\/div>\n<div class=\"sc-489cef11-0 jHGTKj\" readability=\"6\">\n<section readability=\"2\"><picture><img class=\"img\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/12\/los-cinco-momentos-que-marcaron-el-2022-de-la-tri-2.jpg\" alt=\"Overmars delicado: sufri\u00f3 un derrame cerebral\" height=\"290\" width=\"290\" loading=\"lazy\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>Overmars delicado: sufri\u00f3 un derrame cerebral<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<div class=\"sc-489cef11-0 jHGTKj\" readability=\"6.5\">\n<section readability=\"3\"><picture><img class=\"img\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/12\/los-cinco-momentos-que-marcaron-el-2022-de-la-tri-3.jpg\" alt=\"Jug\u00f3 en la Premier y La Liga, pero ahora es Pr\u00edncipe en Indonesia\" height=\"290\" width=\"290\" loading=\"lazy\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>Jug\u00f3 en la Premier y La Liga, pero ahora es Pr\u00edncipe en Indonesia<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<p><h2>1- La emoci\u00f3n por la clasificaci\u00f3n mundialista<\/h2>\n<\/p>\n<div class=\"custom-text \" readability=\"39\">\n<p><strong>El 24 de marzo se dio el grito anhelado por todo Ecuador: \u00a1Estamos en el Mundial!. <\/strong>Tras ausentarse en Rusia 2018, esa noche en el Estadio Antonio Aranda Encina de Ciudad del Este,<strong> el combinado tricolor perd\u00eda 3-1 frente a Paraguay por la jornada 17 de las Eliminatorias<\/strong>, pero la derrota en simult\u00e1neo de Per\u00fa (1-0 con Uruguay), le otrogaba el pasaje de forma directa a los comandados por el Profesor rumbo a la Copa del Mundo. <\/p>\n<\/div>\n<div class=\"sc-489cef11-0 jHGTKj\" readability=\"6\">\n<section readability=\"2\"><picture><img class=\"img\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/12\/los-cinco-momentos-que-marcaron-el-2022-de-la-tri-4.jpg\" alt=\"Hab\u00eda dejado el f\u00fatbol a los 24 a\u00f1os y el Brighton lo contrat\u00f3 en juveniles\" height=\"290\" width=\"290\" loading=\"lazy\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>Hab\u00eda dejado el f\u00fatbol a los 24 a\u00f1os y el Brighton lo contrat\u00f3 en juveniles<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<div class=\"sc-996041c8-0 kvfKM\"><img alt=\"El homenaje de Ol\u00e9 Ecuador para la clasificaci\u00f3n de La Tri.\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/12\/los-cinco-momentos-que-marcaron-el-2022-de-la-tri-5.jpg\" width=\"720\" height=\"0\" decoding=\"async\" data-nimg=\"future\" loading=\"lazy\"><span>El homenaje de Ol\u00e9 Ecuador para la clasificaci\u00f3n de La Tri.<\/span><\/div>\n<div class=\"sc-489cef11-0 jHGTKj\" readability=\"6\">\n<section readability=\"2\"><picture><img class=\"img\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/12\/los-cinco-momentos-que-marcaron-el-2022-de-la-tri-6.jpg\" alt=\"Ins\u00f3lito: un defensor se hizo dos goles en contra \u00a1en siete minutos!\" height=\"290\" width=\"290\" loading=\"lazy\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>Ins\u00f3lito: un defensor se hizo dos goles en contra \u00a1en siete minutos!<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<div class=\"sc-489cef11-0 jHGTKj\" readability=\"6.5\">\n<section readability=\"3\"><picture><img class=\"img\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/12\/los-cinco-momentos-que-marcaron-el-2022-de-la-tri-7.jpg\" alt=\"Mercado de fichajes: altas, bajas y rumores para la LigaPro 2023\" height=\"290\" width=\"290\" loading=\"lazy\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>Mercado de fichajes: altas, bajas y rumores para la LigaPro 2023<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<div class=\"custom-text \" readability=\"41\">\n<p>Finalmente, luego de igualar 1-1 con Argentina en condici\u00f3n de local para cerrar el proceso clasificatorio el 29\/3; Ecuador se clasific\u00f3 cuarto con dos puntos de ventaja sobre los peruanos (fueron a Repechaje y perdieron con Australia en los penales) tras una campa\u00f1a de siete victorias, cinco empates y seis derrotas. Para destacar: La Tri fue la segunda con m\u00e1s goles anotados (27, detr\u00e1s de Brasil con 40) y la tercera que menos le convirtieron (19, tambi\u00e9n por debajo de los brasile\u00f1os y argentinos). El equipo de Alfaro sustent\u00f3 su \u00e9xito en la fortaleza de su casa (5-3-1), que esta vez intercal\u00f3 tanto en la altura de Quito como en el llano de Guayaquil, seg\u00fan el rival.<\/p>\n<\/div>\n<div class=\"sc-996041c8-0 kvfKM\"><img alt=\"Los hinchas de Ecuador y la alegr\u00eda en Guayaquil.\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/12\/los-cinco-momentos-que-marcaron-el-2022-de-la-tri-8.jpg\" width=\"720\" height=\"0\" decoding=\"async\" data-nimg=\"future\" loading=\"lazy\"><span>Los hinchas de Ecuador y la alegr\u00eda en Guayaquil.<\/span><\/div>\n<div class=\"custom-text \" readability=\"44\">\n<p>Al poco tiempo de asumir al frente de Ecuador (sucedi\u00f3 en agosto del 2020), Lechuga encar\u00f3 un recambio en plena carrera hacia Qatar, combinando jugadores de experiencia con rodaje en Brasil 2014 (Carlos Gruezo, Renato Ibarra y Enner Valencia, entre otros) con la camada joven que gan\u00f3 el Sudamericano Sub 20 de Chile y fue tercero en el Mundial Juvenil de Polonia, ambos con C\u00e9lico como DT. Los que m\u00e1s mostraron proyecci\u00f3n fueron Mois\u00e9s Caicedo, Piero Hincapi\u00e9, Jackson Porozo, Jos\u00e9 Cifuentes, Diego Palacios y Gonzalo Plata. <\/p>\n<\/div>\n<div class=\"sc-489cef11-0 jHGTKj\" readability=\"6\">\n<section readability=\"2\"><picture><img class=\"img\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/12\/los-cinco-momentos-que-marcaron-el-2022-de-la-tri-9.jpg\" alt=\"Oficial: \u00a1Cristiano jugar\u00e1 en el Al Nassr!\" height=\"290\" width=\"290\" loading=\"lazy\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>Oficial: \u00a1Cristiano jugar\u00e1 en el Al Nassr!<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<div class=\"sc-489cef11-0 jHGTKj\" readability=\"6\">\n<section readability=\"2\"><picture><img class=\"img\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/12\/los-cinco-momentos-que-marcaron-el-2022-de-la-tri-2.jpg\" alt=\"Overmars delicado: sufri\u00f3 un derrame cerebral\" height=\"290\" width=\"290\" loading=\"lazy\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>Overmars delicado: sufri\u00f3 un derrame cerebral<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<p><h2>2- Ante los ojos del mundo, la felicidad del estreno con Qatar<\/h2>\n<\/p>\n<div class=\"custom-text \" readability=\"37\">\n<p>Sucedi\u00f3 hace poquito, pero en el c\u00f3ctel de emociones que le continuaron parece haber sido hace a\u00f1os. El 20 de noviembre Ecuador se present\u00f3 en el Al Bayt Stadium para disputar -nada m\u00e1s ni nada menos- el partido inaugural del Mundial (este estaba previsto el 21\/11 con Pa\u00edses Bajos vs. Senegal, pero en agosto la FIFA modific\u00f3 esa cuesti\u00f3n del calendario y adelant\u00f3 la fiesta tradicional). <\/p>\n<\/div>\n<div class=\"sc-489cef11-0 jHGTKj\" readability=\"6\">\n<section readability=\"2\"><picture><img class=\"img\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/12\/los-cinco-momentos-que-marcaron-el-2022-de-la-tri-10.jpg\" alt=\"Despedida amarilla: Dar\u00edo Aimar se va de Barcelona\" height=\"290\" width=\"290\" loading=\"lazy\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>Despedida amarilla: Dar\u00edo Aimar se va de Barcelona<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<div class=\"sc-88287e78-0 hmcJvF\">\n<div class=\"sc-88287e78-1 idaaCN videoText\" id=\"contentTitleundefinedFWysO6rS\" readability=\"56\"><svg fill=\"#ffffff\"><symbol id=\"play\" viewBox=\"0 0 512 512\"><path d=\"M512 256C512 397.4 397.4 512 256 512C114.6 512 0 397.4 0 256C0 114.6 114.6 0 256 0C397.4 0 512 114.6 512 256zM176 168V344C176 352.7 180.7 360.7 188.3 364.9C195.8 369.2 205.1 369 212.5 364.5L356.5 276.5C363.6 272.1 368 264.4 368 256C368 247.6 363.6 239.9 356.5 235.5L212.5 147.5C205.1 142.1 195.8 142.8 188.3 147.1C180.7 151.3 176 159.3 176 168V168z\" \/><\/symbol><use xlink:href=\"#play\" \/><\/svg><\/p>\n<div class=\"right\" readability=\"7\">\n<p>Selecci\u00f3n de Ecuador<!-- --> &#8211; <span>30-12-2022<\/span><\/p>\n<h2 class=\"title-vid\">Ecuador marc\u00f3 el primer gol del Mundial<\/h2>\n<\/div>\n<\/div>\n<p><span class=\"back\" id=\"spanBackundefinedFWysO6rS\"><\/span><\/div>\n<div class=\"sc-88287e78-0 hmcJvF\">\n<div class=\"sc-88287e78-1 idaaCN videoText\" id=\"contentTitleundefinedvyk0db4J\" readability=\"56\"><svg fill=\"#ffffff\"><symbol id=\"play\" viewBox=\"0 0 512 512\"><path d=\"M512 256C512 397.4 397.4 512 256 512C114.6 512 0 397.4 0 256C0 114.6 114.6 0 256 0C397.4 0 512 114.6 512 256zM176 168V344C176 352.7 180.7 360.7 188.3 364.9C195.8 369.2 205.1 369 212.5 364.5L356.5 276.5C363.6 272.1 368 264.4 368 256C368 247.6 363.6 239.9 356.5 235.5L212.5 147.5C205.1 142.1 195.8 142.8 188.3 147.1C180.7 151.3 176 159.3 176 168V168z\" \/><\/symbol><use xlink:href=\"#play\" \/><\/svg><\/p>\n<div class=\"right\" readability=\"7\">\n<p>Selecci\u00f3n de Ecuador<!-- --> &#8211; <span>30-12-2022<\/span><\/p>\n<h2 class=\"title-vid\">Cabezazo y doblete de Valencia<\/h2>\n<\/div>\n<\/div>\n<p><span class=\"back\" id=\"spanBackundefinedvyk0db4J\"><\/span><\/div>\n<div class=\"custom-text \" readability=\"42\">\n<p>As\u00ed, la delegaci\u00f3n tricolor en Doha estuvo ante los ojos del planeta jugando un partido que finalmente fue hist\u00f3rico: por primera vez en la historia el anfitri\u00f3n ca\u00eda en el estreno. Fue 2-0 por doblete de Enner Valencia, aunque pudieron ser muchos m\u00e1s, porque los qatar\u00edes mostraron un nivel mucho m\u00e1s flojo del esperado, porque a Superman le anularon otro tanto por posici\u00f3n adelantada y porque con el correr de los minutos el equipo nacional baj\u00f3 la intensidad. Otro hecho m\u00e1s que destacable, es que se hicieron presentes -y sobre todo se hicieron sentir- miles de ecuatorianos en las tribunas alentando.<strong> El marco, dentro y fuera del campo de juego, fue un \u00e9xito y muy festivo. Momento imborrable.<\/strong><\/p>\n<\/div>\n<div class=\"sc-489cef11-0 jHGTKj\" readability=\"6\">\n<section readability=\"2\"><picture><img class=\"img\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/12\/los-cinco-momentos-que-marcaron-el-2022-de-la-tri-11.jpg\" alt=\"As\u00ed gana el Madrid: atajad\u00f3n de Courtois y doblete de Benzema\" height=\"290\" width=\"290\" loading=\"lazy\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>As\u00ed gana el Madrid: atajad\u00f3n de Courtois y doblete de Benzema<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<p><h2>3- Pa\u00edses Bajos y Senegal. Del cielo con las manos al infierno. <\/h2>\n<\/p>\n<div class=\"custom-text \" readability=\"41\">\n<p>Ecuador hab\u00eda cumplido con creces en su debut mundialista y luego med\u00eda fuerzas contra el cuco del Grupo A. Pa\u00edses Bajos, por jerarqu\u00eda e historia, era el gran candidato a quedarse con la zona (de hecho, lo termin\u00f3 haciendo) y ven\u00eda de vencer a Senegal (2-0). Pero Alfaro no se achic\u00f3 y el 25 de noviembre le gan\u00f3 el duelo t\u00e1ctico a Van Gaal. Con l\u00ednea de cinco defensores, no solo neutraliz\u00f3 al rival europeo, sino que hasta por momentos domin\u00f3 las acciones y mereci\u00f3 un triunfo que no lleg\u00f3. Cody Gakpo le rompi\u00f3 el arco a Hern\u00e1n Gal\u00edndez apenas iniciado el cotejo y Enner Valencia -qui\u00e9n sino- igual\u00f3 un marcador que se celebr\u00f3, aunque dej\u00f3 el sabor amargo de haber merecido m\u00e1s. <\/p>\n<\/div>\n<div class=\"sc-88287e78-0 hmcJvF\">\n<div class=\"sc-88287e78-1 idaaCN videoText\" id=\"contentTitleundefined6LZ2hdxM\" readability=\"56\"><svg fill=\"#ffffff\"><symbol id=\"play\" viewBox=\"0 0 512 512\"><path d=\"M512 256C512 397.4 397.4 512 256 512C114.6 512 0 397.4 0 256C0 114.6 114.6 0 256 0C397.4 0 512 114.6 512 256zM176 168V344C176 352.7 180.7 360.7 188.3 364.9C195.8 369.2 205.1 369 212.5 364.5L356.5 276.5C363.6 272.1 368 264.4 368 256C368 247.6 363.6 239.9 356.5 235.5L212.5 147.5C205.1 142.1 195.8 142.8 188.3 147.1C180.7 151.3 176 159.3 176 168V168z\" \/><\/symbol><use xlink:href=\"#play\" \/><\/svg><\/p>\n<div class=\"right\" readability=\"7\">\n<p>Selecci\u00f3n de Ecuador<!-- --> &#8211; <span>30-12-2022<\/span><\/p>\n<h2 class=\"title-vid\">Enner Valencia apareci\u00f3 y puso el empate ante Pa\u00edses Bajos<\/h2>\n<\/div>\n<\/div>\n<p><span class=\"back\" id=\"spanBackundefined6LZ2hdxM\"><\/span><\/div>\n<div class=\"sc-88287e78-0 hmcJvF\">\n<div class=\"sc-88287e78-1 idaaCN videoText\" id=\"contentTitleundefineduKET80Az\" readability=\"56\"><svg fill=\"#ffffff\"><symbol id=\"play\" viewBox=\"0 0 512 512\"><path d=\"M512 256C512 397.4 397.4 512 256 512C114.6 512 0 397.4 0 256C0 114.6 114.6 0 256 0C397.4 0 512 114.6 512 256zM176 168V344C176 352.7 180.7 360.7 188.3 364.9C195.8 369.2 205.1 369 212.5 364.5L356.5 276.5C363.6 272.1 368 264.4 368 256C368 247.6 363.6 239.9 356.5 235.5L212.5 147.5C205.1 142.1 195.8 142.8 188.3 147.1C180.7 151.3 176 159.3 176 168V168z\" \/><\/symbol><use xlink:href=\"#play\" \/><\/svg><\/p>\n<div class=\"right\" readability=\"7\">\n<p>Louis Van Gaal<!-- --> &#8211; <span>30-12-2022<\/span><\/p>\n<h2 class=\"title-vid\">La felicitacio\u0301n de Van Gaal a Alfaro<\/h2>\n<\/div>\n<\/div>\n<p><span class=\"back\" id=\"spanBackundefineduKET80Az\"><\/span><\/div>\n<div class=\"sc-88287e78-0 hmcJvF\">\n<div class=\"sc-88287e78-1 idaaCN videoText\" id=\"contentTitleundefinedMDi0AgDi\" readability=\"56\"><svg fill=\"#ffffff\"><symbol id=\"play\" viewBox=\"0 0 512 512\"><path d=\"M512 256C512 397.4 397.4 512 256 512C114.6 512 0 397.4 0 256C0 114.6 114.6 0 256 0C397.4 0 512 114.6 512 256zM176 168V344C176 352.7 180.7 360.7 188.3 364.9C195.8 369.2 205.1 369 212.5 364.5L356.5 276.5C363.6 272.1 368 264.4 368 256C368 247.6 363.6 239.9 356.5 235.5L212.5 147.5C205.1 142.1 195.8 142.8 188.3 147.1C180.7 151.3 176 159.3 176 168V168z\" \/><\/symbol><use xlink:href=\"#play\" \/><\/svg><\/p>\n<div class=\"right\" readability=\"7\">\n<p>Selecci\u00f3n de Ecuador<!-- --> &#8211; <span>30-12-2022<\/span><\/p>\n<h2 class=\"title-vid\">Gonzalo Plata revent\u00f3 el bal\u00f3n en el travesa\u00f1o<\/h2>\n<\/div>\n<\/div>\n<p><span class=\"back\" id=\"spanBackundefinedMDi0AgDi\"><\/span><\/div>\n<div class=\"custom-text \" readability=\"40\">\n<p>El triunfo previo de los senegaleses (unas horas antes hab\u00edan vencido 3-1 al local) despert\u00f3 las alarmas en La Tri, aunque el empate en la \u00faltima jornada le permit\u00eda cumplir con el gran objetivo de pasar de ronda. Sin embargo, el martes 29 el Khalifa International Stadium fue el escenario de un golpe de nocaut: los africanos, con poco, se impusieron 2-1 y tiraron a la basura cualquier ilusi\u00f3n ecuatoriana. Sin Man\u00e9, el elenco de Aliou Ciss\u00e9 se despidi\u00f3 de la competencia en octavos al ser aplastado por Inglaterra. \u00bfEcuador pudo haberle hecho frente? Una pregunta que nunca tendr\u00e1 respuesta&#8230;<\/p>\n<\/div>\n<div class=\"sc-88287e78-0 hmcJvF\">\n<div class=\"sc-88287e78-1 idaaCN videoText\" id=\"contentTitleundefined4IcpgEbt\" readability=\"56\"><svg fill=\"#ffffff\"><symbol id=\"play\" viewBox=\"0 0 512 512\"><path d=\"M512 256C512 397.4 397.4 512 256 512C114.6 512 0 397.4 0 256C0 114.6 114.6 0 256 0C397.4 0 512 114.6 512 256zM176 168V344C176 352.7 180.7 360.7 188.3 364.9C195.8 369.2 205.1 369 212.5 364.5L356.5 276.5C363.6 272.1 368 264.4 368 256C368 247.6 363.6 239.9 356.5 235.5L212.5 147.5C205.1 142.1 195.8 142.8 188.3 147.1C180.7 151.3 176 159.3 176 168V168z\" \/><\/symbol><use xlink:href=\"#play\" \/><\/svg><\/p>\n<div class=\"right\" readability=\"7\">\n<p>Mudial Qatar<!-- --> &#8211; <span>30-12-2022<\/span><\/p>\n<h2 class=\"title-vid\">Sarr puso en ventaja a Senegal<\/h2>\n<\/div>\n<\/div>\n<p><span class=\"back\" id=\"spanBackundefined4IcpgEbt\"><\/span><\/div>\n<div class=\"sc-88287e78-0 hmcJvF\">\n<div class=\"sc-88287e78-1 idaaCN videoText\" id=\"contentTitleundefinedye5EDLpF\" readability=\"56\"><svg fill=\"#ffffff\"><symbol id=\"play\" viewBox=\"0 0 512 512\"><path d=\"M512 256C512 397.4 397.4 512 256 512C114.6 512 0 397.4 0 256C0 114.6 114.6 0 256 0C397.4 0 512 114.6 512 256zM176 168V344C176 352.7 180.7 360.7 188.3 364.9C195.8 369.2 205.1 369 212.5 364.5L356.5 276.5C363.6 272.1 368 264.4 368 256C368 247.6 363.6 239.9 356.5 235.5L212.5 147.5C205.1 142.1 195.8 142.8 188.3 147.1C180.7 151.3 176 159.3 176 168V168z\" \/><\/symbol><use xlink:href=\"#play\" \/><\/svg><\/p>\n<div class=\"right\" readability=\"7\">\n<p>Mundial Qatar 2022<!-- --> &#8211; <span>30-12-2022<\/span><\/p>\n<h2 class=\"title-vid\">Caicedo marc\u00f3 el 1 a 1 de Ecuador<\/h2>\n<\/div>\n<\/div>\n<p><span class=\"back\" id=\"spanBackundefinedye5EDLpF\"><\/span><\/div>\n<div class=\"sc-88287e78-0 hmcJvF\">\n<div class=\"sc-88287e78-1 idaaCN videoText\" id=\"contentTitleundefinedlJskp632\" readability=\"56\"><svg fill=\"#ffffff\"><symbol id=\"play\" viewBox=\"0 0 512 512\"><path d=\"M512 256C512 397.4 397.4 512 256 512C114.6 512 0 397.4 0 256C0 114.6 114.6 0 256 0C397.4 0 512 114.6 512 256zM176 168V344C176 352.7 180.7 360.7 188.3 364.9C195.8 369.2 205.1 369 212.5 364.5L356.5 276.5C363.6 272.1 368 264.4 368 256C368 247.6 363.6 239.9 356.5 235.5L212.5 147.5C205.1 142.1 195.8 142.8 188.3 147.1C180.7 151.3 176 159.3 176 168V168z\" \/><\/symbol><use xlink:href=\"#play\" \/><\/svg><\/p>\n<div class=\"right\" readability=\"7\">\n<p>Mundial Qatar 2022<!-- --> &#8211; <span>30-12-2022<\/span><\/p>\n<h2 class=\"title-vid\">Koulibaly anot\u00f3 el 2 a 1 de Senegal<\/h2>\n<\/div>\n<\/div>\n<p><span class=\"back\" id=\"spanBackundefinedlJskp632\"><\/span><\/div>\n<div class=\"sc-489cef11-0 jHGTKj\" readability=\"6\">\n<section readability=\"2\"><picture><img class=\"img\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/12\/los-cinco-momentos-que-marcaron-el-2022-de-la-tri-12.jpg\" alt=\"Amistosos definidos para la pretemporada de Barcelona\" height=\"290\" width=\"290\" loading=\"lazy\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>Amistosos definidos para la pretemporada de Barcelona<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<div class=\"sc-489cef11-0 jHGTKj\" readability=\"6\">\n<section readability=\"2\"><picture><img class=\"img\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/12\/los-cinco-momentos-que-marcaron-el-2022-de-la-tri-13.jpg\" alt=\"Agente de Hincapi\u00e9 confirm\u00f3 el inter\u00e9s de un grande por el tricolor\" height=\"290\" width=\"290\" loading=\"lazy\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>Agente de Hincapi\u00e9 confirm\u00f3 el inter\u00e9s de un grande por el tricolor<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<p><h2>4- El reclamo de Chile y Per\u00fa por Byron Castillo<\/h2>\n<\/p>\n<div class=\"custom-text \" readability=\"40\">\n<p>Cronol\u00f3gicamente pas\u00f3 antes del Mundial, pero constantemente y por mucho tiempo signific\u00f3 una piedra en el zapato para la Federaci\u00f3n Ecuatoriana de F\u00fatbol. All\u00e1 por mayo, la ANFP (Asociaci\u00f3n Nacional de F\u00fatbol Profesional de Chile) iniciaba un camino legal contra la FEF y Byron Castillo. \u00bfEl motivo? Como no lograron la clasificaci\u00f3n mundialista por los puntos, la buscaban en los escritorios y acusaron al defensor de una eventual falsificaci\u00f3n de los documentos que establec\u00edan su nacionalidad ecuatoriana, as\u00ed como tambi\u00e9n su supuesta inelegibilidad para jugar los partidos entre septiembre de 2021 y marzo de 2022, correspondientes a las Eliminatorias.<\/p>\n<\/div>\n<div class=\"sc-88287e78-0 hmcJvF\">\n<div class=\"sc-88287e78-1 idaaCN videoText\" id=\"contentTitleundefinedTm8DVURn\" readability=\"56\"><svg fill=\"#ffffff\"><symbol id=\"play\" viewBox=\"0 0 512 512\"><path d=\"M512 256C512 397.4 397.4 512 256 512C114.6 512 0 397.4 0 256C0 114.6 114.6 0 256 0C397.4 0 512 114.6 512 256zM176 168V344C176 352.7 180.7 360.7 188.3 364.9C195.8 369.2 205.1 369 212.5 364.5L356.5 276.5C363.6 272.1 368 264.4 368 256C368 247.6 363.6 239.9 356.5 235.5L212.5 147.5C205.1 142.1 195.8 142.8 188.3 147.1C180.7 151.3 176 159.3 176 168V168z\" \/><\/symbol><use xlink:href=\"#play\" \/><\/svg><\/p>\n<div class=\"right\" readability=\"7\">\n<p>Selecci\u00f3n de Ecuador<!-- --> &#8211; <span>30-12-2022<\/span><\/p>\n<h2 class=\"title-vid\">Los c\u00e1nticos de Ecuador contra Chile<\/h2>\n<\/div>\n<\/div>\n<p><span class=\"back\" id=\"spanBackundefinedTm8DVURn\"><\/span><\/div>\n<div class=\"sc-489cef11-0 jHGTKj\" readability=\"6\">\n<section readability=\"2\"><picture><img class=\"img\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/12\/los-cinco-momentos-que-marcaron-el-2022-de-la-tri-14.jpg\" alt=\"Romario Ibarra ser\u00e1 baja por tres meses en Pachuca\" height=\"290\" width=\"290\" loading=\"lazy\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>Romario Ibarra ser\u00e1 baja por tres meses en Pachuca<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<p><h2>5- El fallo de la FIFA, confirmando el pasaje a Qatar y desestimando el pedido chileno<\/h2>\n<\/p>\n<div class=\"custom-text \" readability=\"38\">\n<p>\u00bfQu\u00e9 pas\u00f3 despu\u00e9s? El Comit\u00e9 Disciplinario de la FIFA inici\u00f3 un procedimiento disciplinario y dict\u00f3 su decisi\u00f3n el 10 de junio, con la que desestim\u00f3 todos los cargos contra la FEF, de que Castillo hab\u00eda nacido en Colombia y merec\u00eda la quita de puntos obtenidos en esos ocho cotejos participados, con lo que se daba por terminado el procedimiento. Pero&#8230;<\/p>\n<\/div>\n<div class=\"sc-489cef11-0 jHGTKj\" readability=\"6\">\n<section readability=\"2\"><picture><img class=\"img\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/12\/los-cinco-momentos-que-marcaron-el-2022-de-la-tri-15.jpg\" alt=\"\u00bfCu\u00e1ntas fechas le dieron a Neymar por su expulsi\u00f3n?\" height=\"290\" width=\"290\" loading=\"lazy\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>\u00bfCu\u00e1ntas fechas le dieron a Neymar por su expulsi\u00f3n?<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<div class=\"custom-text \" readability=\"40\">\n<p>La Federaci\u00f3n de Per\u00fa (se prendi\u00f3 al reclamo pidiendo que, por haber terminado en quinto lugar, eran ellos los que merec\u00edan ir al Mundial) y la de Chile apelaron dicha decisi\u00f3n ante la Comisi\u00f3n de Apelaci\u00f3n de la FIFA, la cual desestim\u00f3 dichos recursos y confirm\u00f3 as\u00ed la determinaci\u00f3n de la primera instancia. M\u00e1s all\u00e1 de eso, despu\u00e9s continu\u00f3 todo con el TAS. Y con ella, m\u00e1s confusi\u00f3n y problemas.<\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"38\">\n<p>A solo 12 d\u00edas del comienzo del Mundial, sali\u00f3 a la luz el comunicado oficial acerca de la resoluci\u00f3n del Caso Byron Castillo. FIFA confirm\u00f3 y valid\u00f3 la utilizaci\u00f3n del jugador para la Selecci\u00f3n de Ecuador. Sin embargo, castig\u00f3 a la Federaci\u00f3n Ecuatoriana de F\u00fatbol por violar una normativa, y la sancion\u00f3 con una quita de puntos para la pr\u00f3xima Eliminatoria Sudamericana y una multa de CHF 100.000.<\/p>\n<\/div>\n<div class=\"sc-489cef11-0 jHGTKj\" readability=\"6\">\n<section readability=\"2\"><picture><img class=\"img\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/12\/los-cinco-momentos-que-marcaron-el-2022-de-la-tri-16.jpg\" alt=\"De Zerbi sobre Moi: &quot;Me gustar\u00eda mantener a todos los jugadores&quot;\" height=\"290\" width=\"290\" loading=\"lazy\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>De Zerbi sobre Moi: \u00abMe gustar\u00eda mantener a todos los jugadores\u00bb<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<div class=\"custom-text \" readability=\"38\">\n<p>La sentencia dej\u00f3 que hubo irregularidades en su partida de nacimiento, pero que igualmente era seleccionable. Sin embargo, Alfaro y los directivos de La Tri finalmente no convocaron al defensor pese a que este fue parte de los \u00faltimos partidos preparativos a Qatar, siendo el \u00faltimo el 12\/11 en el empate con Irak. <\/p>\n<\/div>\n<div class=\"sc-489cef11-0 jHGTKj\" readability=\"6\">\n<section readability=\"2\"><picture><img class=\"img\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/12\/los-cinco-momentos-que-marcaron-el-2022-de-la-tri-17.jpg\" alt=\"China: su rival no se present\u00f3 por casos de Covid-19 y salieron campeones\" height=\"290\" width=\"290\" loading=\"lazy\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>China: su rival no se present\u00f3 por casos de Covid-19 y salieron campeones<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<div class=\"sc-489cef11-0 jHGTKj\" readability=\"6\">\n<section readability=\"2\"><picture><img class=\"img\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/12\/los-cinco-momentos-que-marcaron-el-2022-de-la-tri-18.jpg\" alt=\"El homenaje del Maracan\u00e1 y de Wembley a Pel\u00e9\" height=\"290\" width=\"290\" loading=\"lazy\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>El homenaje del Maracan\u00e1 y de Wembley a Pel\u00e9<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<div class=\"custom-text \" readability=\"33\">\n<p>As\u00ed pasa el 2022 cargado de sentimientos y los mismos se renovar\u00e1n de cara a un 2023 repleto de ilusiones en un nuevo camino eliminatorio&#8230;.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>El almanaque tendr\u00e1 una nueva p\u00e1gina. Se va el 2022 y con \u00e9l un conjunto de emociones alrededor de La Tri, que fueron desde la ilusi\u00f3n al orgullo por disputar el cuarto Mundial en su historia, pasando por la desaz\u00f3n y la incertidumbre de lo que dej\u00f3 Qatar y lo que comunicar\u00e1 Gustavo Alfaro respecto [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":53426,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[16],"tags":[],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/53425"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=53425"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/53425\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media\/53426"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=53425"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=53425"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=53425"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}