{"id":51335,"date":"2022-11-16T22:56:47","date_gmt":"2022-11-16T22:56:47","guid":{"rendered":"https:\/\/www.espinof.com\/series-de-ficcion\/series-exitosas-hbo-cancelada-motivo-triste-posible-zoe-kravitz-explica-que-no-habra-temporada-3-big-little-lies"},"modified":"2022-11-16T22:56:47","modified_gmt":"2022-11-16T22:56:47","slug":"una-de-las-series-mas-exitosas-de-hbo-es-cancelada-por-el-motivo-mas-triste-posible-zoe-kravitz-explica-por-que-no-habra-temporada-3-de-big-little-lies","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2022\/11\/16\/una-de-las-series-mas-exitosas-de-hbo-es-cancelada-por-el-motivo-mas-triste-posible-zoe-kravitz-explica-por-que-no-habra-temporada-3-de-big-little-lies\/","title":{"rendered":"Una de las series m\u00e1s exitosas de HBO es cancelada por el motivo m\u00e1s triste posible: Zo\u00eb Kravitz explica por qu\u00e9 no habr\u00e1 temporada 3 de &#8216;Big Little Lies&#8217;"},"content":{"rendered":"<p>Hace ya m\u00e1s de tres a\u00f1os del estreno de la segunda temporada de <a href=\"https:\/\/www.espinof.com\/criticas\/big-little-lies-regresa-fuerza-a-hbo-temporada-2-que-prolonga-naturalidad-vida-monterey\">&#8216;Big Little Lies&#8217;<\/a>, una de las series m\u00e1s populares de <a class=\"js-ecommerce\" href=\"https:\/\/www.espinof.com\/redirect?url=https%3A%2F%2Fwww.hbomax.com%2Fes%2Fes&amp;category=series-de-ficcion\" data-vars-affiliate-url=\"https:\/\/www.espinof.com\/redirect?url=https%3A%2F%2Fwww.hbomax.com%2Fes%2Fes&amp;category=series-de-ficcion\">HBO<\/a>, y todav\u00eda no estaba claro cu\u00e1l iba a ser el futuro de la serie. Ahora la actriz <strong>Zo\u00eb Kravitz ha confirmado su cancelaci\u00f3n<\/strong> y que no tendr\u00e1 una tercera entrega.<\/p>\n<p><!-- BREAK 1 --><\/p>\n<p>Eso s\u00ed, el motivo de que la serie se quede ah\u00ed <strong>no tiene nada que ver con las audiencias<\/strong>, pues es una serie muy exitosa, hasta el punto de que su segunda temporada mejor\u00f3 las audiencias de <a href=\"https:\/\/www.espinof.com\/series-de-ficcion\/big-little-lies-es-una-maravillosa-exploracion-de-las-caretas-que-usamos-en-nuestra-vida-social\">la primera<\/a>. Y no nos olvidemos de que inicialmente iba a ser una miniserie, pero funcion\u00f3 tan bien que sus implicados no pudieron resistirse en seguir adelante con ella.<\/p>\n<p><!-- BREAK 2 --> <\/p>\n<p>La propia Kravitz ha dejado claro que el gran motivo por el que no se har\u00e1 una tercera temporada de &#8216;Big Little Lies&#8217; es la muerte del director <strong>Jean-Marc Vall\u00e9e<\/strong>. En su momento fue quien se ocup\u00f3 de la puesta en escena de la primera temporada y luego <a href=\"https:\/\/www.espinof.com\/directores-y-guionistas\/hbo-responde-a-polemica-big-little-lies-television-director-no-tiene-control-creativo-final\">se habl\u00f3 mucho<\/a> de c\u00f3mo hab\u00eda arrebatado el control a <strong>Andrea Arnold<\/strong> en la segunda.<\/p>\n<p><!-- BREAK 3 --><\/p>\n<div class=\"article-asset article-asset-normal article-asset-center\">\n<div class=\"desvio-container\">\n<div class=\"desvio\">\n<div class=\"desvio-figure js-desvio-figure\"> <a href=\"https:\/\/www.espinof.com\/listas\/29-mejores-series-intriga-suspense-netflix-hbo-amazon-movistar\"> <img alt=\"Las 29 mejores series de intriga y suspense en Netflix, HBO Max, Amazon Prime Video, Disney+ y Movistar\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/11\/una-de-las-series-mas-exitosas-de-hbo-es-cancelada-por-el-motivo-mas-triste-posible-zoe-kravitz-explica-por-que-no-habra-temporada-3-de-big-little-lies.jpg\"> <\/a> <\/div><\/div><\/div>\n<\/div>\n<p>La actriz ha declarado que <em>\u00abHablamos mucho de hacer una tercera temporada y, desgraciadamente, Jean-Marc Vall\u00e9e, nuestro incre\u00edble director, falleci\u00f3 el a\u00f1o pasado, lo cual es desgarrador, y no puedo imaginarme continuar sin \u00e9l. Realmente fue el visionario de la serie. As\u00ed que, por desgracia, se acab\u00f3<\/em>\u00ab. <strong>M\u00e1s clara no ha podido ser.<\/strong><\/p>\n<p><!-- BREAK 4 --><\/p>\n<p>Vall\u00e9e, tambi\u00e9n responsable de pel\u00edculas como <a href=\"https:\/\/www.espinof.com\/criticas\/dallas-buyers-club-asombro-interpretativo\">&#8216;Dallas Buyers Club&#8217;<\/a> o <a href=\"https:\/\/www.espinof.com\/criticas\/alma-salvaje-un-viaje-inutil\">&#8216;Alma salvaje&#8217;<\/a>, falleci\u00f3 el pasado mes de diciembre a los 58 a\u00f1os de edad como consecuencia de <strong>una arritmia cardiaca<\/strong> que sufr\u00eda.<\/p>\n<p><!-- BREAK 5 --><\/p>\n<p><strong>En Espinof<\/strong>:<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hace ya m\u00e1s de tres a\u00f1os del estreno de la segunda temporada de &#8216;Big Little Lies&#8217;, una de las series m\u00e1s populares de HBO, y todav\u00eda no estaba claro cu\u00e1l iba a ser el futuro de la serie. Ahora la actriz Zo\u00eb Kravitz ha confirmado su cancelaci\u00f3n y que no tendr\u00e1 una tercera entrega. Eso [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":51336,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/51335"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=51335"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/51335\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media\/51336"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=51335"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=51335"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=51335"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}