{"id":50487,"date":"2022-10-25T19:01:14","date_gmt":"2022-10-25T19:01:14","guid":{"rendered":"https:\/\/www.espinof.com\/estrenos\/terrifier-2-escandaloso-fenomeno-terror-censura-que-bate-inesperados-records-usa-podra-verse-pronto-espana"},"modified":"2022-10-25T19:01:14","modified_gmt":"2022-10-25T19:01:14","slug":"terrifier-2-el-escandaloso-fenomeno-de-terror-sin-censura-que-bate-records-de-taquilla-en-usa-podra-verse-pronto-en-espana","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2022\/10\/25\/terrifier-2-el-escandaloso-fenomeno-de-terror-sin-censura-que-bate-records-de-taquilla-en-usa-podra-verse-pronto-en-espana\/","title":{"rendered":"\u2018Terrifier 2\u2019: el escandaloso fen\u00f3meno de terror sin censura que bate r\u00e9cords de taquilla en USA podr\u00e1 verse pronto en Espa\u00f1a"},"content":{"rendered":"<p>Tras la decepci\u00f3n de \u2018<a href=\"https:\/\/www.espinof.com\/criticas\/halloween-final-empieza-muy-bien-luego-cierre-muy-discreto-para-historia-michael-myers\">Halloween: el final<\/a>\u2019, los fans del cine slasher est\u00e1n de enhorabuena. Por cada chasco de terror siempre hay una ventaja inesperada. \u2018<a href=\"https:\/\/www.espinof.com\/trailers\/terrifier-2-asi-brutal-pelicula-terror-que-esta-provocando-vomitos-desmayos-publico-cines-estados-unidos\">Terrifier 2<\/a>\u2019 es una locura gore como las de anta\u00f1o que <strong>ha creado a un icono del g\u00e9nero con Art, el payaso asesino, dentro del cine underground<\/strong>. Las buenas noticias es que su nueva aventura llegar\u00e1 a Espa\u00f1a mucho antes de lo que crees.<\/p>\n<p><!-- BREAK 1 --><\/p>\n<p>La historia de \u2018Terrifier 2\u2019 est\u00e1 empezando a ser de esas que los estudios deben empezar a estudiar cuando se propongan abordar el g\u00e9nero. Se supon\u00eda que la epopeya slasher de Damien Leone tendr\u00eda un estreno limitado a un fin de semana en los cines de Estados Unidos, empezando su andadura el 6 de octubre, antes de su lanzamiento en la peque\u00f1a plataforma SCREAMBOX antes de llegar a Digital y Blu-ray. Varias semanas m\u00e1s tarde <strong>no solo contin\u00faa en salas, desafiando todas las probabilidades, sino que va aumentando su recaudaci\u00f3n a cada fin de semana.<\/strong><\/p>\n<p><!-- BREAK 2 --> <\/p>\n<p>Producida por la p\u00e1gina web Bloody Disgusting, con financiamiento ultraindependiente, la pel\u00edcula experiment\u00f3 un aumento del 100 % en su ingreso de taquilla en el \u00faltimo fin de semana pasado. <a href=\"https:\/\/www.espinof.com\/otros\/aficionados-debaten-2022-ha-sido-mejor-ano-cine-terror-historia-que-haya-acabado\">Si el terror ha sido el g\u00e9nero<\/a> de referencia para una gran parte del p\u00fablico cin\u00e9filo este a\u00f1o, con cinco n\u00fameros uno de taquilla, y el \u00e9xito de \u2018<a href=\"https:\/\/www.espinof.com\/criticas\/fin-pelicula-que-da-miedo-2022-smile-magistral-carrusel-sustos-impacto-horror-estado-puro-que-no-busca-ser-otra-cosa\">Smile<\/a>\u2019 todav\u00eda <strong>rompiendo cualquier expectativa, el caso del payaso asesino es ins\u00f3lito<\/strong> por muchas razones.<\/p>\n<p><!-- BREAK 3 --><\/p>\n<h2>Un fen\u00f3meno inesperado que todos quieren ver<\/h2>\n<p>\u2018Terrifier 2\u2019 recaud\u00f3 2,1 millones de d\u00f3lares en su tercer fin de semana de estreno. Ahora tiene un bruto interno total de 5,4 millones con un presupuesto 250.000 d\u00f3lares, lo que es realmente una haza\u00f1a notable, ya que alcanza la friolera de 2.511 d\u00f3lares de promedio por sala. B\u00e1sicamente, un efecto viral aumentado por <a href=\"https:\/\/eu.usatoday.com\/story\/entertainment\/movies\/2022\/10\/16\/terrifier-2-fans-vomiting-fainting-over-graphic-violence\/10519066002\/\">sus pol\u00e9micas<\/a>, (con padres exigiendo que se retire de los cines porque da pesadillas a los ni\u00f1os) que ha alargado su vida hasta la llegada del fin de semana de Halloween cuando<strong> la productora ha estimado buena idea ampliar a m\u00e1s de 1.000 cines su exhibici\u00f3n<\/strong> en el pa\u00eds.<\/p>\n<p><!-- BREAK 4 --><\/p>\n<div class=\"article-asset article-asset-normal article-asset-center\">\n<div class=\"desvio-container\">\n<div class=\"desvio\">\n<div class=\"desvio-figure js-desvio-figure\"> <a href=\"https:\/\/www.espinof.com\/otros\/aficionados-debaten-2022-ha-sido-mejor-ano-cine-terror-historia-que-haya-acabado\"> <img alt=\"Los aficionados ya debaten si 2022 ha sido el mejor a\u00f1o del cine de terror de la historia sin que haya acabado\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/10\/terrifier-2-el-escandaloso-fenomeno-de-terror-sin-censura-que-bate-records-de-taquilla-en-usa-podra-verse-pronto-en-espana.jpg\"> <\/a> <\/div><\/div><\/div>\n<\/div>\n<p>Los n\u00fameros en s\u00ed no son un r\u00e9cord per s\u00e9, otros hitos del terror de bajo presupuesto s\u00ed que se han convertido en verdaderos bombazos de taquilla como \u2018<a href=\"https:\/\/www.espinof.com\/otros\/20-anos-proyecto-bruja-blair-pelicula-que-cambio-cine-terror\">El proyecto de la Bruja de Blair<\/a>\u2019 (The Blair Witch Project, 1999), \u2018<a href=\"https:\/\/www.espinof.com\/estrenos\/hostel-sadismo-y-sufrimiento-enfermizos\">Hostel<\/a>\u2019 (2005), \u2018<a href=\"https:\/\/www.espinof.com\/listas\/saw-todas-peliculas-saga-ordenadas-peor-a-mejor\">SAW<\/a>\u2019 (2004) o \u2018<a href=\"https:\/\/www.espinof.com\/tag\/paranormal-activity\">Paranormal Activity<\/a>\u2019 (2008), pero en todos esos casos hab\u00eda un estudio que facilitaba distribuci\u00f3n extensa mundial y consigui\u00f3 pasar por el filtro de la MPAA, que como mucho les dio una calificaci\u00f3n R. En este caso, hay <strong>una pel\u00edcula de 138 minutos plagada de gore absolutamente bizarro sin ning\u00fan corte.<\/strong><\/p>\n<p><!-- BREAK 5 --><\/p>\n<p>Esto significa que no ha sido calificada, lo que <strong>a efectos de distribuci\u00f3n en Estados Unidos es como mover una pel\u00edcula pornogr\u00e1fica,<\/strong> lo que deja todas las probabilidades en su contra. Una propuesta anti-Hollywood, el tipo de pel\u00edcula rechazada por el sistema sin respaldo ninguno de un estudio y sin apenas dinero para marketing. Por eso, el aumento paulatino de salas y el contenido brutal de la pel\u00edcula la convierte en una rareza cuyo \u00e9xito ha sido solo posible gracias al boca-oreja y el efecto viral de la informaci\u00f3n.<\/p>\n<p><!-- BREAK 6 --><\/p>\n<div class=\"article-asset-image article-asset-normal article-asset-center\">\n<div class=\"asset-content\">\n<div class=\"base-wrapper-image\"> <img class=\"sf-lazy centro_sinmarco\" data-sf-srcset=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/10\/terrifier-2-el-escandaloso-fenomeno-de-terror-sin-censura-que-bate-records-de-taquilla-en-usa-podra-verse-pronto-en-espana-1.jpg 450w, http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/10\/terrifier-2-el-escandaloso-fenomeno-de-terror-sin-censura-que-bate-records-de-taquilla-en-usa-podra-verse-pronto-en-espana-5.jpg 681w,http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/10\/terrifier-2-el-escandaloso-fenomeno-de-terror-sin-censura-que-bate-records-de-taquilla-en-usa-podra-verse-pronto-en-espana-6.jpg 1024w, http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/10\/terrifier-2-el-escandaloso-fenomeno-de-terror-sin-censura-que-bate-records-de-taquilla-en-usa-podra-verse-pronto-en-espana-7.jpg 1366w,\" data-sf-src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/10\/terrifier-2-el-escandaloso-fenomeno-de-terror-sin-censura-que-bate-records-de-taquilla-en-usa-podra-verse-pronto-en-espana-1.jpg\" alt=\"Terrifiert Art Clown\"> <noscript><img alt=\"Terrifiert Art Clown\" class=\"centro_sinmarco\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/10\/terrifier-2-el-escandaloso-fenomeno-de-terror-sin-censura-que-bate-records-de-taquilla-en-usa-podra-verse-pronto-en-espana-1.jpg\"><\/noscript> <\/div><\/div>\n<\/div>\n<p>Esto, en una \u00e9poca en la que todo est\u00e1 visto, todo est\u00e1 al alcance de la mano y al mismo tiempo tan oculto, indica c\u00f3mo funcionan las tendencias virales, lo caprichoso de la atenci\u00f3n del p\u00fablico y c\u00f3mo el nuevo escenario de plataformas y contenido sin descanso ha creado una capa de indiferencia que solo se ha roto con la idea de algo realmente prohibido, <strong>algo que el p\u00fablico ha elegido y no se basa en recetas de bancos de big data<\/strong>, inteligencias artificiales calculando qu\u00e9 apetece y el aroma transgresor del viejo gore por el gore.<\/p>\n<p><!-- BREAK 7 --><\/p>\n<h2>Un prestreno en Espa\u00f1a cerca, pero limitado<\/h2>\n<p>La pel\u00edcula es un slasher sobrenatural que funciona por el dise\u00f1o de su payaso, un viejo conocido de fans del terror que le conoc\u00edan de anteriores entrega, que sabe captar la esencia de los <strong>iconos como Freddy Krueger, Leatherface, Chucky, Michael Myers, Jason Voorhees o el propio Pennywise<\/strong>. Y al mismo tiempo recupera la suciedad divertida del cine de <strong>Herschell Gordon Lewis<\/strong>, en la que el efecto gore era el rey, y la sangre de la matanza era pura diversi\u00f3n por el efecto Grand Guignol, cuanto m\u00e1s exagerado mejor.<\/p>\n<p><!-- BREAK 8 --><\/p>\n<div class=\"article-asset article-asset-normal article-asset-center\">\n<div class=\"desvio-container\">\n<div class=\"desvio\">\n<div class=\"desvio-figure js-desvio-figure\"> <a href=\"https:\/\/www.espinof.com\/listas\/mejores-peliculas-terror-2022\"> <img alt=\"Las 9 mejores pel\u00edculas de terror de 2022 (por ahora)\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/10\/terrifier-2-el-escandaloso-fenomeno-de-terror-sin-censura-que-bate-records-de-taquilla-en-usa-podra-verse-pronto-en-espana-2.jpg\"> <\/a> <\/div><\/div><\/div>\n<\/div>\n<p>Adem\u00e1s, va guardando el aspecto teatral de aquellas representaciones con <strong>una vuelta a los efectos tradicionales hechos frente a la c\u00e1mara<\/strong>. Puede que la producci\u00f3n sea rupestre, pero al mismo tiempo hay una dedicaci\u00f3n artesanal al propio efecto especial que evita el CGI y mantiene un sentido del humor macabro mientras el traje del payaso se empapa de sangre una y otra vez. \u00bfY cu\u00e1ndo podr\u00e1 verse en Espa\u00f1a? Pues de momento solo hay una fecha disponible.<\/p>\n<p><!-- BREAK 9 --><\/p>\n<div class=\"article-asset-image article-asset-normal article-asset-center\">\n<div class=\"asset-content\">\n<div class=\"base-wrapper-image\"> <img class=\"sf-lazy centro_sinmarco\" data-sf-srcset=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/10\/terrifier-2-el-escandaloso-fenomeno-de-terror-sin-censura-que-bate-records-de-taquilla-en-usa-podra-verse-pronto-en-espana-3.jpg 450w, http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/10\/terrifier-2-el-escandaloso-fenomeno-de-terror-sin-censura-que-bate-records-de-taquilla-en-usa-podra-verse-pronto-en-espana-8.jpg 681w,http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/10\/terrifier-2-el-escandaloso-fenomeno-de-terror-sin-censura-que-bate-records-de-taquilla-en-usa-podra-verse-pronto-en-espana-9.jpg 1024w, http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/10\/terrifier-2-el-escandaloso-fenomeno-de-terror-sin-censura-que-bate-records-de-taquilla-en-usa-podra-verse-pronto-en-espana-10.jpg 1366w,\" data-sf-src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/10\/terrifier-2-el-escandaloso-fenomeno-de-terror-sin-censura-que-bate-records-de-taquilla-en-usa-podra-verse-pronto-en-espana-3.jpg\" alt=\"Terrifier 2\"> <noscript><img alt=\"Terrifier 2\" class=\"centro_sinmarco\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/10\/terrifier-2-el-escandaloso-fenomeno-de-terror-sin-censura-que-bate-records-de-taquilla-en-usa-podra-verse-pronto-en-espana-3.jpg\"><\/noscript> <\/div><\/div>\n<\/div>\n<p>No parece que vaya a haber estreno en cines por el momento, as\u00ed que <strong>la \u00fanica forma de ver \u2018Terrifier 2\u2019 por el momento es en su exhibici\u00f3n en el Festival Terrormolins<\/strong>, en el que se proyectar\u00e1 el d\u00eda 6 de noviembre, aunque quedan muy <a href=\"https:\/\/entradas.codetickets.com\/entradas\/terrifier-2\/33776\/festivaldecinedeterrordemolinsderei\/online\">pocas entradas<\/a> disponibles. Es posible que la incluyan en su programaci\u00f3n online, pero por lo pronto son los \u00fanicos que se han atrevido con la pel\u00edcula de terror que est\u00e1 levantando ampollas y generando inesperados beneficios en Estados Unidos.<\/p>\n<p><!-- BREAK 10 --><\/p>\n<p><strong>En Espinof<\/strong>:<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tras la decepci\u00f3n de \u2018Halloween: el final\u2019, los fans del cine slasher est\u00e1n de enhorabuena. Por cada chasco de terror siempre hay una ventaja inesperada. \u2018Terrifier 2\u2019 es una locura gore como las de anta\u00f1o que ha creado a un icono del g\u00e9nero con Art, el payaso asesino, dentro del cine underground. Las buenas noticias [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":50488,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/50487"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=50487"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/50487\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media\/50488"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=50487"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=50487"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=50487"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}