{"id":49194,"date":"2022-09-29T21:37:20","date_gmt":"2022-09-29T21:37:20","guid":{"rendered":"https:\/\/www.ole.com.ar\/informacion-general\/neymar-bolsonaro-apoyo-brasil_0_FvRhL4MDVN.html"},"modified":"2022-09-29T21:37:20","modified_gmt":"2022-09-29T21:37:20","slug":"neymar-apoyo-a-bolsonaro","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2022\/09\/29\/neymar-apoyo-a-bolsonaro\/","title":{"rendered":"Neymar apoy\u00f3 a Bolsonaro"},"content":{"rendered":"<p><img src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/09\/neymar-apoyo-a-bolsonaro.jpg\"><\/p>\n<p><strong>El presidente de Brasil, Jair Bolsonaro,<\/strong> sac\u00f3 una de sus \u00faltimas cartas para la elecci\u00f3n de este domingo, en la que compite contra Lula, ex jefe de Estado: <a alt=\"neymar\" class=\"slug\" href=\"https:\/\/www.ole.com.ar\/tema\/neymar.html\" target=\"_blank\" title=\"neymar\" rel=\"noopener noreferrer\">Neymar<\/a>. El pol\u00edtico difundi\u00f3 un video en el que<em> <\/em><strong>la estrella del <a alt=\"paris-saint-germain\" class=\"slug\" href=\"https:\/\/www.ole.com.ar\/tema\/paris-saint-germain.html\" target=\"_blank\" title=\"paris-saint-germain\" rel=\"noopener noreferrer\">Paris Saint Germain<\/a> muestra el n\u00famero 22, la lista oficialista, junto a otras personas, muchas ataviadas con ropa de futbolistas, <\/strong>con un jingle dedicado a Jair.<\/p>\n<p>En su cuenta de Twitter, Bolsonaro escribi\u00f3 un mensaje optimista en el que las palabras reelecci\u00f3n y hexa (el t\u00edtulo que busca la Verdeamarela en <a alt=\"qatar-2022\" class=\"slug\" href=\"https:\/\/www.ole.com.ar\/tema\/qatar-2022.html\" target=\"_blank\" title=\"qatar-2022\" rel=\"noopener noreferrer\">Qatar<\/a>, se dan la mano. \u00ab\u00a1Brasil por encima de todo! \u00a1Dios sobre todo!\u00bb, tuite\u00f3 el presidente.<\/p>\n<h2><strong>Mir\u00e1 el video<\/strong><\/h2>\n<p>El mismo video despu\u00e9s fue difundido por Ney en su cuenta de Tiktok, lo cual ratifica la posici\u00f3n del jugador.&nbsp;<\/p>\n<p>Entre Neymar y Bolsonaro siempre hubo buena relaci\u00f3n, aunque el jugador no es de exponer p\u00fablicamente sus ideas pol\u00edticas. Los partidarios de Lula relacionaron esto con un supuesto beneficio que recibi\u00f3 el padre de Ney para no pagar 88 millones de reales en impuestos, por actividades entre 2011 y 2013.<\/p>\n<p>De todas maneras, todas las encuestas dan como favorito a Lula para volver a la presidencia, aunque lo m\u00e1s probable es que se resuelva en una segunda vuelta. Los per\u00edodos presidenciales en Brasil son de cinco a\u00f1os.&nbsp;<\/p>\n<div class=\"sp__Normal\">\n<div class=\"image-embeb image-trigger\" readability=\"6\">\n<picture><source media=\"(min-width: 720px)\" srcset=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/09\/neymar-apoyo-a-bolsonaro-2.jpg\"><img itemprop=\"image\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/09\/neymar-apoyo-a-bolsonaro-2.jpg\" loading=\"lazy\" alt=\"Neymar y Bolsonaro juntos en 2019.\">\n<\/picture><figcaption readability=\"2\">\n<p>Neymar y Bolsonaro juntos en 2019.\n<\/p>\n<\/figcaption><\/div>\n<\/div>\n<div class=\"sp__SM\">\n<div class=\"content-new \">\n<span class=\"tit-mobile\">Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<div class=\"mg\">\n<div class=\"wrap-figure\">\n<picture>\n<a href=\"https:\/\/www.ole.com.ar\/futbol-internacional\/pele-records-brasil-gabigol-neymar_0_IrTDANceXq.html\" target=\"_self\" rel=\"noopener noreferrer\"><br \/>\n<img class=\"img-responsive\" alt=\"A Pel\u00e9 le arrebatan los r\u00e9cords en Brasil...\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/09\/neymar-apoyo-a-bolsonaro-3.jpg\" loading=\"lazy\"><br \/>\n<\/a>\n<\/picture>\n<\/div>\n<\/div><\/div>\n<\/div>\n<div class=\"sp__Normal\">\n<div class=\"image-embeb image-trigger\" readability=\"6\">\n<picture><source media=\"(min-width: 720px)\" srcset=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/09\/neymar-apoyo-a-bolsonaro-4.jpg\"><img itemprop=\"image\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/09\/neymar-apoyo-a-bolsonaro-4.jpg\" loading=\"lazy\" alt=\"Captura de pantalla de Ney con el 22.\">\n<\/picture><figcaption readability=\"2\">\n<p>Captura de pantalla de Ney con el 22.\n<\/p>\n<\/figcaption><\/div>\n<\/div>\n<div class=\"sp__SM\">\n<div class=\"content-new \">\n<span class=\"tit-mobile\">Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<div class=\"mg\">\n<div class=\"wrap-figure\">\n<picture>\n<a href=\"https:\/\/www.ole.com.ar\/futbol-internacional\/dani-alves-twitter-mundial_0_sJwIi6ndlA.html\" target=\"_self\" rel=\"noopener noreferrer\"><br \/>\n<img class=\"img-responsive\" alt=\"Dani Alves respondi\u00f3 en Twitter: no se baja del Mundial\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/09\/neymar-apoyo-a-bolsonaro-5.jpg\" loading=\"lazy\"><br \/>\n<\/a>\n<\/picture>\n<\/div>\n<\/div><\/div>\n<\/div>\n<div class=\"entry-tags\">\n<h2>TEMAS QUE APARECEN EN ESTA NOTA<\/h2>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>El presidente de Brasil, Jair Bolsonaro, sac\u00f3 una de sus \u00faltimas cartas para la elecci\u00f3n de este domingo, en la que compite contra Lula, ex jefe de Estado: Neymar. El pol\u00edtico difundi\u00f3 un video en el que la estrella del Paris Saint Germain muestra el n\u00famero 22, la lista oficialista, junto a otras personas, muchas [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":49195,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[16],"tags":[],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/49194"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=49194"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/49194\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media\/49195"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=49194"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=49194"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=49194"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}