{"id":48808,"date":"2022-09-22T17:31:39","date_gmt":"2022-09-22T17:31:39","guid":{"rendered":"https:\/\/www.espinof.com\/series-de-ficcion\/gran-cambio-casa-dragon-respecto-al-libro-george-r-r-martin-que-podria-ser-problema-para-futuro-serie-hbo-max"},"modified":"2022-09-22T17:31:39","modified_gmt":"2022-09-22T17:31:39","slug":"el-gran-cambio-de-la-casa-del-dragon-respecto-al-libro-de-george-r-r-martin-que-podria-ser-un-problema-para-el-futuro-de-la-serie-de-hbo-max","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2022\/09\/22\/el-gran-cambio-de-la-casa-del-dragon-respecto-al-libro-de-george-r-r-martin-que-podria-ser-un-problema-para-el-futuro-de-la-serie-de-hbo-max\/","title":{"rendered":"El gran cambio de &#8216;La casa del drag\u00f3n&#8217; respecto al libro de George R. R. Martin que podr\u00eda ser un problema para el futuro de la serie de HBO Max"},"content":{"rendered":"<p>Todas las adaptaciones hacen cambios respecto a la obra original, pero en algunos casos se notan m\u00e1s que en otros. Con <a href=\"https:\/\/www.espinof.com\/fecha-de-estreno\/house-of-the-dragon-todo-que-sabemos-precuela-juego-tronos\">&#8216;La casa del drag\u00f3n&#8217;<\/a> hay uno que est\u00e1 destacando poderosamente en la primera temporada de la serie de <a class=\"js-ecommerce\" href=\"https:\/\/www.espinof.com\/redirect?url=https%3A%2F%2Fwww.hbomax.com%2Fes%2Fes&amp;category=series-de-ficcion\" data-vars-affiliate-url=\"https:\/\/www.espinof.com\/redirect?url=https%3A%2F%2Fwww.hbomax.com%2Fes%2Fes&amp;category=series-de-ficcion\">HBO Max<\/a>, hasta el punto de que <strong>podr\u00eda convertirse en un importante problema para el futuro de la serie<\/strong>.<\/p>\n<p><!-- BREAK 1 --><\/p>\n<blockquote><p>Cuidado con los <strong>spoilers<\/strong> a partir de aqu\u00ed, tanto de la serie hasta ahora como del libro &#8216;Fuego y sangre&#8217;.<\/p><\/blockquote>\n<h2>La enfermedad de Viserys<\/h2>\n<p>El cambio en cuesti\u00f3n afecta a Viserys, el rey de Poniente interpretado por <strong>Paddy Considine<\/strong>. Hace ya tiempo que qued\u00f3 claro que su salud es bastante delicada y Otto Hightower (<strong>Rhys Ifans<\/strong>) no dud\u00f3 en afirmar al comienzo de <a href=\"https:\/\/www.espinof.com\/criticas\/casa-dragon-1x05-mejor-episodio-ahora-trae-otra-boda-sangrienta-llamada-a-marcar-antes-despues-poniente\">&#8216;Iluminamos el camino&#8217;<\/a> que iba a durar poco con vida. El motivo es la enfermedad que padece, la cual Considine no tuvo problemas en desvelar en el podcast <a href=\"https:\/\/podcasts.apple.com\/us\/podcast\/ews-west-of-westeros\/id1099326209\">West of Westeros<\/a><\/p>\n<p><!-- BREAK 2 --> <\/p>\n<blockquote><p>Sufre de una forma de lepra. Su cuerpo se est\u00e1 deteriorando, sus huesos tambi\u00e9n. No es realmente viejo, todav\u00eda es una persona joven. Desafortunadamente, eso se ha apoderado de su cuerpo. Es una especie de met\u00e1fora de ser rey, el estr\u00e9s y la presi\u00f3n que supone y lo que te hace f\u00edsicamente y mentalmente.<\/p><\/blockquote>\n<p>Quiz\u00e1 algunos espectadores hayan asumido que Viserys muerte al final del quinto episodio, pero lo cierto es que <strong>el avance del sexo deja claro que sigue vivo y reinando<\/strong>. Eso s\u00ed, su deterioro f\u00edsico no ha dejado de ir a m\u00e1s y ahora hasta luce una m\u00e1scara para ocultar los efectos de la lepra en su rostro.<\/p>\n<p><!-- BREAK 3 --><\/p>\n<div class=\"article-asset article-asset-normal article-asset-center\">\n<div class=\"desvio-container\">\n<div class=\"desvio\">\n<div class=\"desvio-figure js-desvio-figure\"> <a href=\"https:\/\/www.espinof.com\/series-de-ficcion\/cifras-exito-casa-dragon-asustan-van-a-juego-tronos-tardo-siete-temporadas-superar-que-ha-conseguido-apenas-cinco-episodios\"> <img alt=\"Las cifras del \u00e9xito de 'La casa del drag\u00f3n' asustan y van a m\u00e1s: 'Juego de Tronos' tard\u00f3 siete temporadas en superar lo que ha conseguido con apenas cinco episodios \" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/09\/el-gran-cambio-de-la-casa-del-dragon-respecto-al-libro-de-george-r-r-martin-que-podria-ser-un-problema-para-el-futuro-de-la-serie-de-hbo-max.jpg\"> <\/a> <\/div><\/div><\/div>\n<\/div>\n<p>Esta decisi\u00f3n resulta un tanto problem\u00e1tica, ya que en el sexto episodio se har\u00e1 <a href=\"https:\/\/www.espinof.com\/hbo\/casa-dragon-dice-adios-a-rhaenyra-alicent-adolescentes-este-nuevo-reparto-para-episodio-6-serie-hbo-max\">un importante salto en el tiempo<\/a> de 10 a\u00f1os, por lo que la credibilidad sobre el hecho de que Viserys siga con vida empieza a ser cuestionable. Vale que es el rey y que tendr\u00e1 los mejores cuidados posibles, pero <strong>no puede decirse que la ciencia m\u00e9dica est\u00e9 muy avanzada en Poniente<\/strong>&#8230;<\/p>\n<p><!-- BREAK 4 --><\/p>\n<div class=\"article-asset-image article-asset-large\">\n<div class=\"asset-content\">\n<div class=\"base-wrapper-image\"> <img class=\"sf-lazy \" data-sf-srcset=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/09\/el-gran-cambio-de-la-casa-del-dragon-respecto-al-libro-de-george-r-r-martin-que-podria-ser-un-problema-para-el-futuro-de-la-serie-de-hbo-max-1.jpg 450w, http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/09\/el-gran-cambio-de-la-casa-del-dragon-respecto-al-libro-de-george-r-r-martin-que-podria-ser-un-problema-para-el-futuro-de-la-serie-de-hbo-max-3.jpg 681w,http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/09\/el-gran-cambio-de-la-casa-del-dragon-respecto-al-libro-de-george-r-r-martin-que-podria-ser-un-problema-para-el-futuro-de-la-serie-de-hbo-max-4.jpg 1024w, http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/09\/el-gran-cambio-de-la-casa-del-dragon-respecto-al-libro-de-george-r-r-martin-que-podria-ser-un-problema-para-el-futuro-de-la-serie-de-hbo-max-5.jpg 1366w,\" data-sf-src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/09\/el-gran-cambio-de-la-casa-del-dragon-respecto-al-libro-de-george-r-r-martin-que-podria-ser-un-problema-para-el-futuro-de-la-serie-de-hbo-max-1.jpg\" alt=\"Viserys Lepra\"> <noscript><img alt=\"Viserys Lepra\" class src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/09\/el-gran-cambio-de-la-casa-del-dragon-respecto-al-libro-de-george-r-r-martin-que-podria-ser-un-problema-para-el-futuro-de-la-serie-de-hbo-max-1.jpg\"><\/noscript> <\/div><\/div>\n<\/div>\n<p>Adem\u00e1s, <strong>su inevitable muerte juega un papel esencial en la historia<\/strong>, pues es lo que desencadena la Danza de los Dragones, una guerra civil de los Targaryen para ver qui\u00e9n era el nuevo rey de Poniente. En los libros, Viserys no contrae la enfermedad que acaba con \u00e9l hasta dos a\u00f1os antes de su fallecimiento, por lo que la desviaci\u00f3n respecto a lo ideado por Martin es bastante grande.<\/p>\n<p><!-- BREAK 5 --><\/p>\n<p><strong>Si ten\u00e9is curiosidad por saber qu\u00e9 sucede con el personaje en los libros<\/strong>, en cierto momento Viserys se resbala y se hace un corte en la mano con el Trono de Hierro. El corte se infecta y Viserys solamente se recupera tras sufrir la amputaci\u00f3n de dos dedos. Sin embargo, nunca recupera su fuerza y apenas dos a\u00f1os despu\u00e9s muere mientras est\u00e1 echando una siesta.<\/p>\n<p><!-- BREAK 6 --> <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Todas las adaptaciones hacen cambios respecto a la obra original, pero en algunos casos se notan m\u00e1s que en otros. Con &#8216;La casa del drag\u00f3n&#8217; hay uno que est\u00e1 destacando poderosamente en la primera temporada de la serie de HBO Max, hasta el punto de que podr\u00eda convertirse en un importante problema para el futuro [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":48809,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/48808"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=48808"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/48808\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media\/48809"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=48808"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=48808"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=48808"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}