{"id":46929,"date":"2022-08-16T10:35:16","date_gmt":"2022-08-16T10:35:16","guid":{"rendered":"http:\/\/hoycordobaweb.com\/index.php\/2022\/08\/16\/bullet-train-netflix-hbo-max-disney-plus-movistar-donde-ver-esquire\/"},"modified":"2022-08-16T10:35:16","modified_gmt":"2022-08-16T10:35:16","slug":"bullet-train-netflix-hbo-max-disney-plus-movistar-donde-ver-esquire","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2022\/08\/16\/bullet-train-netflix-hbo-max-disney-plus-movistar-donde-ver-esquire\/","title":{"rendered":"&#039;Bullet train&#039;: <b>Netflix<\/b>, HBO Max, Disney Plus, Movistar, d\u00f3nde ver &#8211; Esquire"},"content":{"rendered":"<p>Quieres ver &#39;Bullet train&#39; en castellano online? Vas a tener que esperar una larga temporada antes de que la pel\u00edcula de Brad Pitt llegue para&nbsp;&#8230; <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quieres ver &#39;Bullet train&#39; en castellano online? Vas a tener que esperar una larga temporada antes de que la pel\u00edcula de Brad Pitt llegue para&nbsp;&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[23],"tags":[],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/46929"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=46929"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/46929\/revisions"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=46929"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=46929"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=46929"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}