{"id":46645,"date":"2022-08-10T19:27:36","date_gmt":"2022-08-10T19:27:36","guid":{"rendered":"https:\/\/www.ole.com.ar\/river-plate\/encuesta-river-gallardo-elias-gomez_0_TnwoNLrrAv.html"},"modified":"2022-08-10T19:27:36","modified_gmt":"2022-08-10T19:27:36","slug":"encuesta-river-que-deberia-hacer-gallardo-en-el-lateral-izquierdo","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2022\/08\/10\/encuesta-river-que-deberia-hacer-gallardo-en-el-lateral-izquierdo\/","title":{"rendered":"Encuesta River: \u00bfqu\u00e9 deber\u00eda hacer Gallardo en el lateral izquierdo?"},"content":{"rendered":"<p><img src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/08\/encuesta-river-que-deberia-hacer-gallardo-en-el-lateral-izquierdo.jpg\"><\/p>\n<p><strong>\u00abConfianza viejo. Tenete confianza\u00bb. <\/strong>El en\u00e9rgico aliento de <strong><a alt=\"marcelo-gallardo\" class=\"slug\" href=\"https:\/\/www.ole.com.ar\/tema\/marcelo-gallardo.html\" target=\"_blank\" title=\"marcelo-gallardo\" rel=\"noopener noreferrer\">Marcelo Gallardo<\/a><\/strong> a <strong><a alt=\"elias-gomez\" class=\"slug\" href=\"https:\/\/www.ole.com.ar\/tema\/elias-gomez.html\" target=\"_blank\" title=\"elias-gomez\" rel=\"noopener noreferrer\">El\u00edas G\u00f3mez<\/a> <\/strong>ante <strong><a alt=\"club-atletico-independiente\" class=\"slug\" href=\"https:\/\/www.ole.com.ar\/tema\/club-atletico-independiente.html\" target=\"_blank\" title=\"club-atletico-independiente\" rel=\"noopener noreferrer\">Independiente<\/a><\/strong> no fue una simple reacci\u00f3n al pasar del DT. El lateral izquierdo se transform\u00f3 en una fija en la posici\u00f3n, <strong>aunque eso no se ve reflejado en su rendimiento y su nivel en los \u00faltimos partidos est\u00e1 en descenso. <\/strong>El Mu\u00f1eco lo sabe, como tambi\u00e9n es consciente que sacarlo del equipo no es sencillo, teniendo en cuenta los ajustes que deber\u00eda realizar en el fondo.<\/p>\n<div class=\"sp__SM\">\n<div class=\"content-new \"> <span class=\"tit-mobile\">Mir\u00e1 tambi\u00e9n<\/span> <\/p>\n<div class=\"mg\">\n<div class=\"wrap-figure\"> <picture> <a href=\"https:\/\/www.ole.com.ar\/river-plate\/instagram-pablo-solari-paulo-diaz-river_0_806O2SWLX5.html\" target=\"_self\" rel=\"noopener noreferrer\"> <img class=\"img-responsive\" alt=\"El divertido cruce entre Solari y Paulo D\u00edaz por Instagram\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/08\/encuesta-river-que-deberia-hacer-gallardo-en-el-lateral-izquierdo-2.jpg\" loading=\"lazy\"> <\/a> <\/picture> <\/div><\/div><\/div>\n<\/div>\n<p><strong>La voluntad, el desgaste y sus ganas de pasar constantemente al ataque son indudables. <\/strong>Cuando la tiene, toca, se manda hacia adelante y suele llegar hasta el fondo de la cancha, <strong>sector en el que aparece su principal d\u00e9ficit. <\/strong>Si MG lo pidi\u00f3 con insistencia fue por<strong> los centros venenosos <\/strong>que realizaba con la camiseta de Argentinos, <strong>virtud que todav\u00eda no pudo demostrar con la banda roja en el pecho.<\/strong><\/p>\n<div class=\"sp__SM\">\n<div class=\"content-new \"> <span class=\"tit-mobile\">Mir\u00e1 tambi\u00e9n<\/span> <\/p>\n<div class=\"mg\">\n<div class=\"wrap-figure\"> <picture> <a href=\"https:\/\/www.ole.com.ar\/river-plate\/river-alta-enzo-perez-barco_0_Ht1f66OSVH.html\" target=\"_self\" rel=\"noopener noreferrer\"> <img class=\"img-responsive\" alt=\"Alegr\u00eda en River: alta para Enzo P\u00e9rez\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/08\/encuesta-river-que-deberia-hacer-gallardo-en-el-lateral-izquierdo-3.jpg\" loading=\"lazy\"> <\/a> <\/picture> <\/div><\/div><\/div>\n<\/div>\n<div class=\"sp__Normal\">\n<div class=\"image-embeb image-trigger\" readability=\"6\"> <picture><source media=\"(min-width: 720px)\" srcset=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/08\/encuesta-river-que-deberia-hacer-gallardo-en-el-lateral-izquierdo-4.jpg\"><img itemprop=\"image\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/08\/encuesta-river-que-deberia-hacer-gallardo-en-el-lateral-izquierdo-4.jpg\" loading=\"lazy\" alt=\"Elias G\u00f3mez. Prensa River.\"> <\/picture><figcaption readability=\"2\">\n<p>Elias G\u00f3mez. Prensa River. <\/p>\n<\/figcaption><\/div>\n<\/div>\n<p>Impreciso, con dudas y con esa evidente falta de confianza que not\u00f3 MG,<strong> sus env\u00edos suelen encontrar con mucha m\u00e1s frecuencia a los defensores rivales que a sus compa\u00f1eros y el equipo lo siente. <\/strong>Acostumbrado a ser muy riguroso con los jugadores que bajan sus rendimientos, el caso EG29 es complicado para Gallardo y<strong> si form\u00f3 parte del 11 inicial en 13 de los 15 partidos de la Liga Profesional es por los problemas en la otra banda.<\/strong><\/p>\n<div class=\"sp__SM\">\n<div class=\"content-new \"> <span class=\"tit-mobile\">Mir\u00e1 tambi\u00e9n<\/span> <\/p>\n<div class=\"mg\">\n<div class=\"wrap-figure\"> <picture> <a href=\"https:\/\/www.ole.com.ar\/futbol-internacional\/champions\/enzo-fernandez-river-benfica-portugal_0_qS5XGm2B3x.html\" target=\"_self\" rel=\"noopener noreferrer\"> <img class=\"img-responsive\" alt=\"&quot;Enzo matador&quot;: furor por Fern\u00e1ndez en Portugal\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/08\/encuesta-river-que-deberia-hacer-gallardo-en-el-lateral-izquierdo-5.jpg\" loading=\"lazy\"> <\/a> <\/picture> <\/div><\/div><\/div>\n<\/div>\n<p>Sin<strong> Robert Rojas<\/strong>, que a partir de septiembre podr\u00eda volver a las canchas tras la fractura de tibia y peron\u00e9, el Mu\u00f1eco trajo a <strong>Andr\u00e9s Herrera<\/strong>. M\u00e1s all\u00e1 de algunos chispazos, el ex San Lorenzo no logr\u00f3 consolidarse y la prueba con <strong>Mammana<\/strong> sirvi\u00f3 hasta que se consolid\u00f3 como central, su posici\u00f3n natural. As\u00ed, al DT no le qued\u00f3 otra que ubicar al polifuncional <strong>Milton Casco <\/strong>en la derecha y a <strong>El\u00edas <\/strong>por la izquierda.<\/p>\n<div class=\"sp__SM\">\n<div class=\"content-new \"> <span class=\"tit-mobile\">Mir\u00e1 tambi\u00e9n<\/span> <\/p>\n<div class=\"mg\">\n<div class=\"wrap-figure\"> <picture> <a href=\"https:\/\/www.ole.com.ar\/river-plate\/river-juveniles-athletico-paranaense_0_jOXDqueMhA.html\" target=\"_self\" rel=\"noopener noreferrer\"> <img class=\"img-responsive\" alt=\"Los dos pibes de River que se fueron a Paranaense\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/08\/encuesta-river-que-deberia-hacer-gallardo-en-el-lateral-izquierdo-6.jpg\" loading=\"lazy\"> <\/a> <\/picture> <\/div><\/div><\/div>\n<\/div>\n<div class=\"sp__Normal\">\n<div class=\"image-embeb image-trigger\" readability=\"6\"> <picture><source media=\"(min-width: 720px)\" srcset=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/08\/encuesta-river-que-deberia-hacer-gallardo-en-el-lateral-izquierdo-7.jpg\"><img itemprop=\"image\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/08\/encuesta-river-que-deberia-hacer-gallardo-en-el-lateral-izquierdo-7.jpg\" loading=\"lazy\" alt=\"El\u00edas G\u00f3mez no logra sostener su nivel. Foto: Diego Haliasz \/ prensa River\"> <\/picture><figcaption readability=\"2\">\n<p>El\u00edas G\u00f3mez no logra sostener su nivel. Foto: Diego Haliasz \/ prensa River <\/p>\n<\/figcaption><\/div>\n<\/div>\n<p>Pasando en limpio, Gallardo encontr\u00f3 un mecanismo en el fondo y que<strong> El\u00edas se sostenga en la titularidad es producto de una reorganizaci\u00f3n de la defensa que de a poco se va afianzando. <\/strong>Y si tiene que tocar a Casco, eso podr\u00eda generar una nueva descompaginaci\u00f3n.<\/p>\n<div class=\"sp__SM\">\n<div class=\"content-new \"> <span class=\"tit-mobile\">Mir\u00e1 tambi\u00e9n<\/span> <\/p>\n<div class=\"mg\">\n<div class=\"wrap-figure\"> <picture> <a href=\"https:\/\/www.ole.com.ar\/seleccion\/enzofernandez-benfica-seleccion_0_Wu4d9n8Rkx.html\" target=\"_self\" rel=\"noopener noreferrer\"> <img class=\"img-responsive\" alt=\"El boom Enzo Fern\u00e1ndez: \u00bfqu\u00e9 chances tiene de Mundial?\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/08\/encuesta-river-que-deberia-hacer-gallardo-en-el-lateral-izquierdo-8.jpg\" loading=\"lazy\"> <\/a> <\/picture> <\/div><\/div><\/div>\n<\/div>\n<div class=\"sp__Normal\">\n<div class=\"image-embeb image-trigger\" readability=\"7\"> <picture><source media=\"(min-width: 720px)\" srcset=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/08\/encuesta-river-que-deberia-hacer-gallardo-en-el-lateral-izquierdo-9.jpg\"><img itemprop=\"image\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/08\/encuesta-river-que-deberia-hacer-gallardo-en-el-lateral-izquierdo-9.jpg\" loading=\"lazy\" alt=\"Casco, por ahora, sigue por la derecha. Telam\"> <\/picture><figcaption readability=\"4\">\n<p>Casco, por ahora, sigue por la derecha. Telam <\/p>\n<\/figcaption><\/div>\n<\/div>\n<p>\u00bfQu\u00e9 pasar\u00e1 si pasan los partidos y el zurdo no levanta? Ese es el gran dilema y en <strong>Ol\u00e9<\/strong> abrimos el debate con una encuesta. \u00bfDebe seguir bancando al ex Bichos? \u00bfO tendr\u00e1 que poner a Casco y buscar una nueva alternativa por la derecha? Ponete el buzo de DT y opin\u00e1.<\/p>\n<div class=\"sp__SM\">\n<div class=\"content-new \"> <span class=\"tit-mobile\">Mir\u00e1 tambi\u00e9n<\/span> <\/p>\n<div class=\"mg\">\n<div class=\"wrap-figure\"> <picture> <a href=\"https:\/\/www.ole.com.ar\/river-plate\/river-gallardo-tatuaje-firma_0_IJ3X1dPNmv.html\" target=\"_self\" rel=\"noopener noreferrer\"> <img class=\"img-responsive\" alt=\"La fan\u00e1tica de Gallardo cumpli\u00f3: \u00a1se tatu\u00f3 la firma del Mu\u00f1eco!\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/08\/encuesta-river-que-deberia-hacer-gallardo-en-el-lateral-izquierdo-10.jpg\" loading=\"lazy\"> <\/a> <\/picture> <\/div><\/div><\/div>\n<\/div>\n<h2><strong>Vot\u00e1 en la encuesta Ol\u00e9<\/strong><\/h2>\n<div class=\"entry-tags\">\n<h2>TEMAS QUE APARECEN EN ESTA NOTA<\/h2>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u00abConfianza viejo. Tenete confianza\u00bb. El en\u00e9rgico aliento de Marcelo Gallardo a El\u00edas G\u00f3mez ante Independiente no fue una simple reacci\u00f3n al pasar del DT. El lateral izquierdo se transform\u00f3 en una fija en la posici\u00f3n, aunque eso no se ve reflejado en su rendimiento y su nivel en los \u00faltimos partidos est\u00e1 en descenso. El [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":46646,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[16],"tags":[],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/46645"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=46645"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/46645\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media\/46646"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=46645"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=46645"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=46645"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}