{"id":45988,"date":"2022-07-28T19:54:00","date_gmt":"2022-07-28T19:54:00","guid":{"rendered":"http:\/\/hoycordobaweb.com\/index.php\/2022\/07\/28\/el-banco-central-subio-la-tasa-de-politica-monetaria-de-52-a-60\/"},"modified":"2022-07-28T19:54:00","modified_gmt":"2022-07-28T19:54:00","slug":"el-banco-central-subio-la-tasa-de-politica-monetaria-de-52-a-60","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2022\/07\/28\/el-banco-central-subio-la-tasa-de-politica-monetaria-de-52-a-60\/","title":{"rendered":"El Banco Central subi\u00f3 la tasa de pol\u00edtica monetaria de 52% a 60%"},"content":{"rendered":"<p><img src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/07\/el-banco-central-subio-la-tasa-de-politica-monetaria-de-52-a-60.jpg\"><\/p>\n<figure class=\"mb-3\"><img loading=\"lazy\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/07\/el-banco-central-subio-la-tasa-de-politica-monetaria-de-52-a-60-2.jpg\" width=\"100%\" height=\"100%\" alt=\"La medida dispuesta por el Directorio de la autoridad monetaria incluye a su vez una suba en las tasas de inters sobre los plazos fijos de personas humanas\"><figcaption> La medida, dispuesta por el Directorio de la autoridad monetaria, incluye, a su vez, una suba en las tasas de inter\u00e9s sobre los plazos fijos de personas humanas. <\/figcaption><\/figure>\n<p>El Banco Central (BCRA) subi\u00f3 este jueves 800 puntos b\u00e1sicos la tasa de pol\u00edtica monetaria, que <strong>pas\u00f3 de 52% a 60% anual en su licitaci\u00f3n de Letras de Liquidez (Leliq a 28 d\u00edas)<\/strong>, con el objetivo de lograr un descenso de la inflaci\u00f3n.<\/p>\n<p>El incremento se dio luego de que el Tesoro este mi\u00e9rcoles decidiera convalidar una fuerte suba en los intereses que paga por sus t\u00edtulos en pesos.<\/p>\n<p>La medida, dispuesta por el Directorio de la autoridad monetaria, incluye, a su vez, una <strong>suba en las tasas de inter\u00e9s sobre los plazos fijos de personas humanas, que pasan a tener un nuevo piso de 61%<\/strong> anual.<\/p>\n<p>Esto representa un rendimiento de 81,3% en t\u00e9rminos efectivos anuales para los dep\u00f3sitos a 30 d\u00edas hasta 10 millones de pesos.<\/p>\n<p>Para el resto de los dep\u00f3sitos a plazo fijo del sector privado la tasa m\u00ednima garantizada se establece en 54%, lo que representa una tasa efectiva anual de 69,6%.<\/p>\n<blockquote class=\"twitter-tweet\" readability=\"6.4702194357367\">\n<p lang=\"es\" dir=\"ltr\">El BCRA acelera el proceso de normalizaci\u00f3n de la tasa de <a href=\"https:\/\/twitter.com\/hashtag\/Pol%C3%ADticaMonetaria?src=hash&amp;ref_src=twsrc%5Etfw\">#Pol\u00edticaMonetaria<\/a> y refuerza su coordinaci\u00f3n financiera con el Tesoro.<br \/>Elev\u00f3 la tasa de inter\u00e9s nominal anual de las Letras de Liquidez <a href=\"https:\/\/twitter.com\/hashtag\/Leliq?src=hash&amp;ref_src=twsrc%5Etfw\">#Leliq<\/a> a 28 d\u00edas a 60% (Tasa Efectiva Anual de 79,8%): <a href=\"https:\/\/t.co\/wqsoTK2I6c\">https:\/\/t.co\/wqsoTK2I6c<\/a><\/p>\n<p>\u2014 BCRA (@BancoCentral_AR) <a href=\"https:\/\/twitter.com\/BancoCentral_AR\/status\/1552740821694353413?ref_src=twsrc%5Etfw\">July 28, 2022<\/a><\/p><\/blockquote>\n<p>\u00abEn l\u00ednea con los Objetivos y Planes 2022, la autoridad monetaria considera necesario acelerar el proceso de normalizaci\u00f3n de la tasa de pol\u00edtica y del resto de la estructura de tasas de inter\u00e9s de la econom\u00eda para llevarlas a un terreno positivo en t\u00e9rminos reales, de forma de contribuir a preservar la estabilidad financiera y cambiaria\u00bb, se\u00f1al\u00f3 el BCRA en un comunicado.<\/p>\n<p>En ese sentido, dijo que <strong>\u00abespera que estas acciones contribuyan a un descenso consistente de la inflaci\u00f3n\u00bb<\/strong> y, para ello, busca incentivar a que bancos, empresas y ahorristas tomen a la deuda del Tesoro Nacional como el instrumento de inversi\u00f3n seguro y de mayor rendimiento.<\/p>\n<p>Para ello en las \u00faltimas semanas profundiz\u00f3 la coordinaci\u00f3n con el Ministerio de Econom\u00eda \u00aba los efectos de establecer una estrategia financiera que posibilite ir disminuyendo de manera progresiva el financiamiento monetario al Tesoro\u00bb.<\/p>\n<p>\u00abDentro de esta coordinaci\u00f3n <strong>se destaca el establecimiento de una estructura de tasas de inter\u00e9s o \u00abcorredor\u00bb con spreads razonables <\/strong>entre los instrumentos del BCRA (Leliq y pases) y las letras del Tesoro (Ledes)\u00bb, detall\u00f3 el BCRA.<\/p>\n<p>El corredor est\u00e1 conformado por las Letras del Tesoro de corto plazo como l\u00edmite superior del corredor (hoy en 90% de TIR), la tasa efectiva anual (TEA) de las Leliq a 28 d\u00edas (79,8%) como referencia media y la tasa de Pases a un d\u00eda como l\u00edmite inferior (de 75% de TEA).<\/p>\n<p>\u00abLos resultados positivos de las \u00faltimas licitaciones de instrumentos de deuda en pesos en t\u00e9rminos de financiamiento neto robustecen la perspectiva de un stock decreciente de pasivos remunerados del BCRA en t\u00e9rminos del PIB\u00bb, se\u00f1al\u00f3 el Central.<\/p>\n<p><strong>El Tesoro confirm\u00f3 este jueves que cerr\u00f3 julio con un endeudamiento neto de $372.000 millones <\/strong>y que, en lo que va de 2022, pudo refinanciar el 130% de sus vencimientos, un n\u00famero en l\u00ednea con los objetivos fijados en el acuerdo con el FMI.<\/p>\n<p>\u00abEl BCRA continuar\u00e1 calibrando la tasa de inter\u00e9s de pol\u00edtica en el marco del proceso de normalizaci\u00f3n de la pol\u00edtica monetaria en marcha, prestando especial atenci\u00f3n a la evoluci\u00f3n pasada y prospectiva del nivel general de precios y la din\u00e1mica del mercado de cambios\u00bb, concluy\u00f3 el comunicado. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>La medida, dispuesta por el Directorio de la autoridad monetaria, incluye, a su vez, una suba en las tasas de inter\u00e9s sobre los plazos fijos de personas humanas. El Banco Central (BCRA) subi\u00f3 este jueves 800 puntos b\u00e1sicos la tasa de pol\u00edtica monetaria, que pas\u00f3 de 52% a 60% anual en su licitaci\u00f3n de Letras [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":45989,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[19],"tags":[],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/45988"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=45988"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/45988\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media\/45989"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=45988"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=45988"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=45988"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}