{"id":45062,"date":"2022-07-13T17:39:28","date_gmt":"2022-07-13T17:39:28","guid":{"rendered":"https:\/\/ladecimaweb.com\/?p=13916"},"modified":"2022-07-13T17:39:28","modified_gmt":"2022-07-13T17:39:28","slug":"confirman-dos-nuevos-casos-de-viruela-simica-en-cordoba","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2022\/07\/13\/confirman-dos-nuevos-casos-de-viruela-simica-en-cordoba\/","title":{"rendered":"Confirman dos nuevos casos de viruela s\u00edmica en C\u00f3rdoba"},"content":{"rendered":"<div class=\"boldgrid-section\">\n<div class=\"container\">\n<div class=\"row\">\n<div class=\"col-md-12 col-xs-12 col-sm-12\">\n<p class=\"\">El Ministerio de Salud<span>&nbsp;<\/span><strong>inform\u00f3 el diagn\u00f3stico de viruela en dos hombres de 29 y 34 a\u00f1os de edad, oriundos de C\u00f3rdoba<\/strong>,<span>&nbsp;<\/span><strong>con antecedente de viaje a Europa.<\/strong><\/p>\n<p>Es importante destacar que uno de los pacientes se confirm\u00f3 por t\u00e9cnicas de laboratorio y el otro, por los d\u00edas de evoluci\u00f3n, por nexo epidemiol\u00f3gico.&nbsp;Los estudios fueron realizados en el Laboratorio Central de la Provincia y el caso confirmado por la ANLIS Malbr\u00e1n.<\/p>\n<p>Desde el \u00e1rea de Epidemiolog\u00eda de la Provincia detallaron que la personas comenzaron con s\u00edntomas entre el 3 y 5 de julio. Uno de los casos present\u00f3 fiebre, cefalea, mialgias, astenia, p\u00fastulas y costras en la piel; el segundo caso manifest\u00f3 sintomatolog\u00eda muy leve. No registran contactos de riesgo en nuestro pa\u00eds.<\/p>\n<p>Los viajeros consultaron el 7 de julio en el Hospital Rawson donde sospecharon la infecci\u00f3n y se tomaron las muestras correspondientes para realizar el diagn\u00f3stico. Las mismas fueron derivadas al Laboratorio central de la provincia de C\u00f3rdoba donde la prueba PCR dio positivo para viruela s\u00edmica y luego enviadas al ANLIS Malbr\u00e1n donde se confirm\u00f3 el resultado el d\u00eda 12 de julio.<\/p>\n<p>Cabe destacar que las personas, permanecen en aislamiento y&nbsp;<strong>evolucionan favorablemente con control domiciliario por parte del Hospital Rawson.<\/strong><\/p>\n<p>Desde el 27 de mayo hasta la fecha, se registraron en Argentina doce personas con este diagn\u00f3stico: cinco de la Ciudad Aut\u00f3noma de Buenos Aires, tres de la provincia Buenos Aires, tres de C\u00f3rdoba y una de Mendoza. Once de los doce casos presentaron antecedentes de viaje.<\/p>\n<p><strong>Sobre la viruela s\u00edmica o de mono<\/strong><\/p>\n<p class=\"\">Si bien es una infecci\u00f3n que<span>&nbsp;<\/span><strong>puede transmitirse de animales a personas<\/strong><span>&nbsp;<\/span>(zoonosis), en nuestro pa\u00eds y en la actualidad, la transmisi\u00f3n persona a persona es la que cobra relevancia<strong>.<\/strong><span>&nbsp;<\/span>Esta afecci\u00f3n es causada por el virus de la viruela del simio, que pertenece a la familia de los ortopoxvirus.<\/p>\n<p class=\"\">El contagio<span>&nbsp;<\/span><strong>de una persona a otra<\/strong><span>&nbsp;<\/span>puede ocurrir por<span>&nbsp;<\/span><strong>contacto estrecho con secreciones de las v\u00edas respiratorias<\/strong>, o<span>&nbsp;<\/span><strong>lesiones en la piel<\/strong><span>&nbsp;<\/span>de quien cursa la infecci\u00f3n o con<span>&nbsp;<\/span><strong>objetos contaminados<\/strong><span>&nbsp;<\/span>recientemente con los fluidos del paciente o materiales de la lesi\u00f3n. Cabe destacar que, debido al contacto \u00edntimo con lesiones cut\u00e1neas infecciosas, el contacto sexual constituye un modo probable de transmisi\u00f3n. Asimismo,<span>&nbsp;<\/span><strong>puede ocurrir por inoculaci\u00f3n o a trav\u00e9s de la placenta<\/strong><span>&nbsp;<\/span>(viruela s\u00edmica cong\u00e9nita).<\/p>\n<p class=\"\">\n<div class=\"ubm_banner\"><a href=\"https:\/\/www.cba.gov.ar\/10-https:\/\/www.cba.gov.ar\/10-mil-viviendas\/?csrt=8333084810548506306\" target=\"_blank\" rel=\"dofollow noopener noreferrer\"><img src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/07\/confirman-dos-nuevos-casos-de-viruela-simica-en-cordoba.gif\" alt=\"\"><\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>La entrada <a rel=\"nofollow\" href=\"https:\/\/ladecimaweb.com\/confirman-dos-nuevos-casos-de-viruela-simica-en-cordoba\/\">Confirman dos nuevos casos de viruela s\u00edmica en C\u00f3rdoba<\/a> se public\u00f3 primero en <a rel=\"nofollow\" href=\"https:\/\/ladecimaweb.com\">LaDecima<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Ministerio de Salud&nbsp;inform\u00f3 el diagn\u00f3stico de viruela en dos hombres de 29 y 34 a\u00f1os de edad, oriundos de C\u00f3rdoba,&nbsp;con antecedente de viaje a Europa. Es importante destacar que uno de los pacientes se confirm\u00f3 por t\u00e9cnicas de laboratorio y el otro, por los d\u00edas de evoluci\u00f3n, por nexo epidemiol\u00f3gico.&nbsp;Los estudios fueron realizados en [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":45063,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[19],"tags":[],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/45062"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=45062"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/45062\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media\/45063"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=45062"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=45062"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=45062"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}