{"id":45051,"date":"2022-07-15T12:40:00","date_gmt":"2022-07-15T12:40:00","guid":{"rendered":"https:\/\/fm-comunicar.com.ar\/contenido\/19407\/convocan-a-audiencia-publica-por-la-actualizacion-de-tarifa-de-taxis-y-remises"},"modified":"2022-07-15T12:40:00","modified_gmt":"2022-07-15T12:40:00","slug":"convocan-a-audiencia-publica-por-la-actualizacion-de-tarifa-de-taxis-y-remises","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2022\/07\/15\/convocan-a-audiencia-publica-por-la-actualizacion-de-tarifa-de-taxis-y-remises\/","title":{"rendered":"Convocan a Audiencia P\u00fablica por la actualizaci\u00f3n de tarifa de taxis y remises"},"content":{"rendered":"<p>El Concejo Deliberante invita a los vecinos a participar el pr\u00f3ximo mi\u00e9rcoles 20 de julio, en la sala ubicada al costado del edificio municipal. El proyect\u00f3 prev\u00e9 una diferenciaci\u00f3n en los precios de la tarifa diurna y nocturna.<img src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/07\/convocan-a-audiencia-publica-por-la-actualizacion-de-tarifa-de-taxis-y-remises.jpg\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Concejo Deliberante invita a los vecinos a participar el pr\u00f3ximo mi\u00e9rcoles 20 de julio, en la sala ubicada al costado del edificio municipal. El proyect\u00f3 prev\u00e9 una diferenciaci\u00f3n en los precios de la tarifa diurna y nocturna.<\/p>\n","protected":false},"author":1,"featured_media":45052,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[18],"tags":[],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/45051"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=45051"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/45051\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media\/45052"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=45051"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=45051"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=45051"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}