{"id":43967,"date":"2022-07-01T10:31:03","date_gmt":"2022-07-01T10:31:03","guid":{"rendered":"https:\/\/www.espinof.com\/hbo\/que-ver-hbo-max-esta-impresionante-adaptacion-dc-natalie-portman-sacada-adelante-directoras-matrix-llega-hoy-a-plataforma"},"modified":"2022-07-01T10:31:03","modified_gmt":"2022-07-01T10:31:03","slug":"que-ver-en-hbo-max-esta-impresionante-adaptacion-de-dc-con-natalie-portman-sacada-adelante-por-las-directoras-de-matrix-llega-hoy-a-la-plataforma","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2022\/07\/01\/que-ver-en-hbo-max-esta-impresionante-adaptacion-de-dc-con-natalie-portman-sacada-adelante-por-las-directoras-de-matrix-llega-hoy-a-la-plataforma\/","title":{"rendered":"Qu\u00e9 ver en HBO Max: esta impresionante adaptaci\u00f3n de DC con Natalie Portman, sacada adelante por las directoras de &#8216;Matrix&#8217;, llega hoy a la plataforma"},"content":{"rendered":"<p><strong>El nombre de DC est\u00e1 invariablemente asociado a los superh\u00e9roes<\/strong>. Es l\u00f3gico, al tener en su cat\u00e1logo varios de los h\u00e9roes m\u00e1s grandes y reconocibles de la cultura pop. No significa, eso s\u00ed, que una adaptaci\u00f3n de un c\u00f3mic de DC implique necesariamente mallas. Puede implicar, por ejemplo, el nombre de <a href=\"https:\/\/www.espinof.com\/listas\/que-ver-david-cronenberg-tres-peliculas-genio-nueva-carne-que-fueron-exhibidas-cannes-estan-disponibles-streaming\">David Cronenberg<\/a>, como en el caso de &#8216;<a href=\"https:\/\/www.espinof.com\/criticas\/david-cronenberg-una-historia-de-violencia-la-naturaleza-humana\">Una historia de violencia<\/a>&#8216;.<\/p>\n<p><!-- BREAK 1 --><\/p>\n<p>Tambi\u00e9n puede asociarse a las directoras de &#8216;<a href=\"https:\/\/www.espinof.com\/listas\/matrix-que-orden-conviene-ver-todas-peliculas-saga\">Matrix<\/a>&#8216;, <a href=\"https:\/\/www.espinof.com\/tag\/lilly-wachowski\">Lilly Wachowski<\/a> y <a href=\"https:\/\/www.espinof.com\/tag\/lana-wachowski\">Lana Wachowski<\/a>. Juntas elaboraron el guion, produjeron y asistieron a su colaborador habitual <a href=\"https:\/\/www.espinof.com\/tag\/james-mcteigue\">James McTeigue<\/a> para llevar a la gran pantalla una gran novela gr\u00e1fica de <a href=\"https:\/\/www.espinof.com\/tag\/alan-moore\">Alan Moore<\/a>. <strong>Una adaptaci\u00f3n que sigue siendo ic\u00f3nica<\/strong>. Esa es &#8216;<a href=\"https:\/\/www.espinof.com\/criticas\/comic-en-cine-v-de-vendetta-de-james-mcteigue\">V de Vendetta<\/a>&#8216;, la famosa pel\u00edcula que desde hoy puedes <a class=\"js-ecommerce\" href=\"https:\/\/www.espinof.com\/redirect?url=https%3A%2F%2Fwww.hbomax.com%2Fes%2Fes&amp;category=hbo\" data-vars-affiliate-url=\"https:\/\/www.espinof.com\/redirect?url=https%3A%2F%2Fwww.hbomax.com%2Fes%2Fes&amp;category=hbo\">ver en HBO Max<\/a>.<\/p>\n<p><!-- BREAK 2 --> <\/p>\n<h2>Revoluci\u00f3n o terrorismo<\/h2>\n<p>La pel\u00edcula, al igual que el c\u00f3mic de Moore, plantea una distopia no muy lejana en la que Reino Unido se rige de manera totalitaria por un tirano (<a href=\"https:\/\/www.espinof.com\/tag\/john-hurt\">John Hurt<\/a>). Hay toque de queda, <strong>restricciones de libertades y m\u00e1s atropellos a derechos humanos realizadas por el Estado<\/strong>, ante el cual los ciudadanos no tienen m\u00e1s remedio que tener la cabeza gacha para no sufrir represalias.<\/p>\n<p><!-- BREAK 3 --><\/p>\n<div class=\"article-asset article-asset-normal article-asset-center\">\n<div class=\"desvio-container\">\n<div class=\"desvio\">\n<div class=\"desvio-figure js-desvio-figure\"> <a href=\"https:\/\/www.espinof.com\/listas\/mejores-peliculas-basadas-comics-novelas-graficas\"> <img alt=\"Las 37 mejores pel\u00edculas basadas en c\u00f3mics y novelas gr\u00e1ficas\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/07\/que-ver-en-hbo-max-esta-impresionante-adaptacion-de-dc-con-natalie-portman-sacada-adelante-por-las-directoras-de-matrix-llega-hoy-a-la-plataforma.jpg\"> <\/a> <\/div><\/div><\/div>\n<\/div>\n<p>En medio de esta situaci\u00f3n, una joven (<a href=\"https:\/\/www.espinof.com\/tag\/natalie-portman\">Natalie Portman<\/a>) entra en contacto con un enmascarado (<a href=\"https:\/\/www.espinof.com\/tag\/hugo-weaving\">Hugo Weaving<\/a>) que le vende <strong>un discurso lleno de ansias por la libertad, donde es el Estado quien teme a los ciudadanos<\/strong> y no al rev\u00e9s. Oculto tras una m\u00e1scara que evoca al revolucionario Guy Fawkes, este extra\u00f1o hombre desplegar\u00e1 un ambicioso y peligroso plan para derrocar al gobierno fascista.<\/p>\n<p><!-- BREAK 4 --><\/p>\n<p>Es muy f\u00e1cil conectar el discurso de libertad y rebeli\u00f3n de Moore con las Wachowski, ya que su saga m\u00e1s famosa conecta precisamente con esas ideas. Y, al igual que en aquellas pel\u00edculas, <strong>se atreve a ir un poco m\u00e1s all\u00e1 diseccionando la compleja figura que est\u00e1 llamando a la revoluci\u00f3n<\/strong>. \u00bfEs un salvador? \u00bfUn terrorista vali\u00e9ndose de una justa causa? \u00bfMeramente un vengador? La pel\u00edcula trata de indagar esas complejidades morales mientras trata de hacer un film accesible y entretenido.<\/p>\n<p><!-- BREAK 5 --><\/p>\n<h2>&#8216;V de Vendetta&#8217;: osada y compleja<\/h2>\n<p>Para una historia que recurre poco a los momentos espectaculares, McTeigue y su equipo se las apa\u00f1an para hacer <strong>una pel\u00edcula muy atractiva visualmente<\/strong>, que expande las buenas ideas de dise\u00f1o ya presentadas en la novela gr\u00e1fica. Consigue una pel\u00edcula de buen ritmo y notable acci\u00f3n sin dejar por ello de hacer una interesante exploraci\u00f3n de ideas sobre el vigilantismo y el conseguir despertar a la poblaci\u00f3n a cualquier coste.<\/p>\n<p><!-- BREAK 6 --><\/p>\n<div class=\"article-asset article-asset-normal article-asset-center\">\n<div class=\"desvio-container\">\n<div class=\"desvio\">\n<div class=\"desvio-figure js-desvio-figure\"> <a href=\"https:\/\/www.espinof.com\/otros\/21-peliculas-distopicas-alucinantes-que-todo-fan-de-blade-runner-ya-deberia-haber-visto\"> <img alt=\"21 pel\u00edculas dist\u00f3picas alucinantes que todo fan de 'Blade Runner' ya deber\u00eda haber visto\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/07\/que-ver-en-hbo-max-esta-impresionante-adaptacion-de-dc-con-natalie-portman-sacada-adelante-por-las-directoras-de-matrix-llega-hoy-a-la-plataforma-1.jpg\"> <\/a> <\/div><\/div><\/div>\n<\/div>\n<p>Es una pel\u00edcula bastante m\u00e1s osada en lo ideol\u00f3gico de lo que su popularidad puede dar a entender. Muchos revolucionarios modernos han robado su iconograf\u00eda y calcado sus discursos sin ara\u00f1ar la superficie, que es capaz tambi\u00e9n de dejar interesantes conflictos entre los personajes de Portman y Weaving. Ese buen trabajo dram\u00e1tico la hacen <strong>una pel\u00edcula muy notable, que ha conseguido resistir el tiempo mejor de lo que cabr\u00eda pensar<\/strong>. Ya s\u00f3lo por ello, es una cinta que hay que recuperar.<\/p>\n<p><!-- BREAK 7 --> <\/p>\n","protected":false},"excerpt":{"rendered":"<p>El nombre de DC est\u00e1 invariablemente asociado a los superh\u00e9roes. Es l\u00f3gico, al tener en su cat\u00e1logo varios de los h\u00e9roes m\u00e1s grandes y reconocibles de la cultura pop. No significa, eso s\u00ed, que una adaptaci\u00f3n de un c\u00f3mic de DC implique necesariamente mallas. Puede implicar, por ejemplo, el nombre de David Cronenberg, como en [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":43968,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/43967"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=43967"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/43967\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media\/43968"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=43967"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=43967"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=43967"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}