{"id":43865,"date":"2022-06-29T00:49:00","date_gmt":"2022-06-29T00:49:00","guid":{"rendered":"https:\/\/fm-comunicar.com.ar\/contenido\/19343\/habra-sorteo-entre-38-familias-para-adjudicar-10-terrenos"},"modified":"2022-06-29T00:49:00","modified_gmt":"2022-06-29T00:49:00","slug":"habra-sorteo-entre-38-familias-para-adjudicar-10-terrenos","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2022\/06\/29\/habra-sorteo-entre-38-familias-para-adjudicar-10-terrenos\/","title":{"rendered":"Habr\u00e1 sorteo entre 38 familias para adjudicar 10\u00a0 terrenos"},"content":{"rendered":"<p>El registro de aspirantes cerr\u00f3 el pasado viernes 24, con un total de 58 inscriptos, de los cuales finalmente quedaron 38 que cumpl\u00edan con todos los requisitos, entre ellos residir en Colonia Caroya y no tener ninguna propiedad.\u00a0<img src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/06\/habra-sorteo-entre-38-familias-para-adjudicar-10-terrenos.jpg\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El registro de aspirantes cerr\u00f3 el pasado viernes 24, con un total de 58 inscriptos, de los cuales finalmente quedaron 38 que cumpl\u00edan con todos los requisitos, entre ellos residir en Colonia Caroya y no tener ninguna propiedad.\u00a0<\/p>\n","protected":false},"author":1,"featured_media":43866,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[18],"tags":[],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/43865"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=43865"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/43865\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media\/43866"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=43865"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=43865"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=43865"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}