{"id":4221,"date":"2020-10-30T21:49:06","date_gmt":"2020-10-30T21:49:06","guid":{"rendered":"https:\/\/www.ole.com.ar\/futbol-ascenso\/amistoso-villa-san-carlos-canuelas_0_9U3bb0TyP.html"},"modified":"2020-10-30T21:49:06","modified_gmt":"2020-10-30T21:49:06","slug":"golpe-de-categoria","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2020\/10\/30\/golpe-de-categoria\/","title":{"rendered":"Golpe de categor\u00eda"},"content":{"rendered":"<div><img src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2020\/10\/golpe-de-categoria.jpg\" class=\"ff-og-image-inserted\"><\/div>\n<p>En el predio de CN Sports, Villa San Carlos, de la Primera B, se enfrent\u00f3 ante Ca\u00f1uelas, de la PC. Se jugaron dos partidos de 80 minutos cada uno. <\/p>\n<p>En el primer encuentro los dirigidos por Gonzalo M\u00e1rquez supieron golpear en los momentos justos y se llevaron un triunfo merecido. \u00bfLos goles? Luciano Machin en contra y Santiago Sosa en el complemento. <\/p>\n<p>En el \u00faltimo encuentro los roles cambiaron y el que tom\u00f3 la posta fue San Carlos, que termin\u00f3 logrando el&nbsp;triunfo por la m\u00ednima diferencia gracias al tanto de Samuel Portillo.<\/p>\n<p><mark>S\u00edntesis:<\/mark> <\/p>\n<p><strong>Villa San Carlos<\/strong>:&nbsp;Nicol\u00e1s Tauber; Manuel Molina, Federico Slezack, Luciano Mach\u00edn, Agust\u00edn Prida;&nbsp;Juan Saborido, Gonzalo Raverta, Ignacio Oron\u00e1, Alexis Alegre;&nbsp;Tom\u00e1s Bolzicco y&nbsp;Bryan Schmidt. DT: Jorge Vivaldo.<\/p>\n<p><strong>Ca\u00f1uelas<\/strong>:&nbsp;Fernando Vijande; Juli\u00e1n Cano, Germ\u00e1n Mendoza, Hugo Paniagua, Iv\u00e1n Fassione; Franco Quinteros, Emanuel Trejo, Mauro Frattini, Lautaro Su\u00e1rez Costa, Santiago Sosa; Diego Aguirre DT: Gonzalo M\u00e1rquez.<\/p>\n<p><strong>Goles<\/strong>: PT 13&#8242; Luciano Mach\u00edn (e\/c) (CA\u00d1), 46&#8242; Santiago Sosa (CA\u00d1)<\/p>\n<p><strong>Cancha<\/strong>: predio de CN Sports.<\/p>\n<p><strong>Detalle<\/strong>: dos partidos de 80\u00b4. <\/p>\n<p><strong>Segundo PJ<\/strong>: San carlos 1 &#8211; Ca\u00f1uelas 0.&nbsp;<\/p>\n<div class=\"entry-tags\">\n<h2>TEMAS QUE APARECEN EN ESTA NOTA<\/h2>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>En el predio de CN Sports, Villa San Carlos, de la Primera B, se enfrent\u00f3 ante Ca\u00f1uelas, de la PC. Se jugaron dos partidos de 80 minutos cada uno. En el primer encuentro los dirigidos por Gonzalo M\u00e1rquez supieron golpear en los momentos justos y se llevaron un triunfo merecido. \u00bfLos goles? Luciano Machin en [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4222,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[16],"tags":[],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/4221"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=4221"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/4221\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media\/4222"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=4221"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=4221"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=4221"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}