{"id":41704,"date":"2022-05-18T02:56:00","date_gmt":"2022-05-18T02:56:00","guid":{"rendered":"http:\/\/hoycordobaweb.com\/index.php\/2022\/05\/18\/boca-igualo-con-corinthians-y-ahora-se-juega-todo-la-semana-que-viene-ante-deportivo-cali\/"},"modified":"2022-05-18T02:56:00","modified_gmt":"2022-05-18T02:56:00","slug":"boca-igualo-con-corinthians-y-ahora-se-juega-todo-la-semana-que-viene-ante-deportivo-cali","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2022\/05\/18\/boca-igualo-con-corinthians-y-ahora-se-juega-todo-la-semana-que-viene-ante-deportivo-cali\/","title":{"rendered":"Boca igual\u00f3 con Corinthians y ahora se juega todo la semana que viene ante Deportivo Cali"},"content":{"rendered":"<p><img src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/05\/boca-igualo-con-corinthians-y-ahora-se-juega-todo-la-semana-que-viene-ante-deportivo-cali.jpg\"><\/p>\n<figure class=\"mb-3\"><img loading=\"lazy\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/05\/boca-igualo-con-corinthians-y-ahora-se-juega-todo-la-semana-que-viene-ante-deportivo-cali-2.jpg\" width=\"100%\" height=\"100%\" alt=\"Foto Maximiliano Luna\"><figcaption> (Foto: Maximiliano Luna). <\/figcaption><\/figure>\n<p>Boca empat\u00f3 esta noche 1 a 1 como local ante Corinthians, de Brasil, y sigue ocupando el segundo puesto de la Zona E de la Copa Libertadores detr\u00e1s de su rival de este martes, aunque depende de s\u00ed mismo para clasificarse a octavos de final cuando en la sexta y \u00faltima fecha de la fase de grupos reciba a Deportivo Cali, de Colombia.<\/p>\n<p><strong>Boca jug\u00f3 su mejor partido de esta Copa Libertadores <\/strong>y por extensi\u00f3n tambi\u00e9n la mejor del a\u00f1o teniendo en cuenta la jerarqu\u00eda del rival.<\/p>\n<p>El conjunto dirigido por Sebasti\u00e1n Battaglia jug\u00f3 como deb\u00eda hacerlo ante un compromiso de esta envergadura, de manera muy diferente a la que lo hab\u00eda hecho el fin de semana ante Racing Club por la semifinal de la Copa de la Liga Profesional, cuando pas\u00f3 a la final sin patear ni un tiro al arco.<\/p>\n<p><strong>Esta vez Boca fue un equipo activo en la primera presi\u00f3n<\/strong>, que por lo general es blanda pero en esta oportunidad no lo fue tanto, sobre todo por la prodigalidad del pibe Exequiel Zeballos, bien secundado en esa funci\u00f3n por Dar\u00edo Benedetto y Eduardo Salvio.<\/p>\n<p><strong>Pero el que se llev\u00f3 la mayor cantidad de loas fue Alan Varela<\/strong>, volviendo a sus buenos momentos como volante central de un terceto, el de la MVA, que integraba la media cancha de Boca que completaban Agust\u00edn Almendra y Cristian Medina.<\/p>\n<figure class=\"mb-3\"><img loading=\"lazy\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/05\/boca-igualo-con-corinthians-y-ahora-se-juega-todo-la-semana-que-viene-ante-deportivo-cali-3.jpg\" width=\"100%\" height=\"100%\" alt=\"Foto Maximiliano Luna\"><figcaption> (Foto: Maximiliano Luna). <\/figcaption><\/figure>\n<p>Claro que todo eso de bueno que estaba realizando Boca desde el pitazo inicial del uruguayo Christian Ferreyra pareci\u00f3 derrumbarse apenas transcurrido el cuarto de hora de la primera etapa cuando un remate sin demasiada potencia desde el borde del \u00e1rea de Du Quiroz no logr\u00f3 ser alcanzado por Agust\u00edn Rossi.<\/p>\n<p>Pero si lo de Boca hab\u00eda sido bueno desde la ambici\u00f3n por la victoria cuando estaban 0 a 0, mucho m\u00e1s lo fue a partir de estar y, sobre todo, \u00absentirse\u00bb en desventaja.<\/p>\n<p>Pero todos esos atributos que hab\u00eda mostrado el cuestionado equipo de Battaglia al que anoche sali\u00f3 a defender su vicepresidente, Juan Rom\u00e1n Riquelme, iban a tener su premio cuando ya expiraba el primer tiempo y <strong>el peruano Carlos Zambrano le baj\u00f3 de cabeza un centro a Benedetto para que este celebrara con el gol del empate su cumplea\u00f1os n\u00famero 32.<\/strong><\/p>\n<figure class=\"mb-3\"><img loading=\"lazy\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/05\/boca-igualo-con-corinthians-y-ahora-se-juega-todo-la-semana-que-viene-ante-deportivo-cali-4.jpg\" width=\"100%\" height=\"100%\" alt=\"Foto Maximiliano Luna\"><figcaption> (Foto: Maximiliano Luna). <\/figcaption><\/figure>\n<p>Todo qued\u00f3 servido entonces para que Boca se lanzara en pos del triunfo en la segunda mitad, ya que no solamente era dominador del partido desde lo futbol\u00edstico, sino que a partir de ese gol postrero, tambi\u00e9n desde la an\u00edmico.<\/p>\n<p>Y esto se maximiz\u00f3 cuando promediando la etapa s<strong>e fue expulsado el colombiano V\u00edctor Cantilo por propinarle un golpe con el pu\u00f1o derecho a Guillermo \u00abPol\u00bb Fern\u00e1ndez, lo que gener\u00f3 un arremolinamiento de cinco minutos entre los jugadores de ambos equipos en la mitad de la cancha.<\/strong><\/p>\n<p>A partir de all\u00ed (tambi\u00e9n fue expulsado el t\u00e9cnico visitante V\u00edtor Pereira) fue un dominio absoluto el que ejerci\u00f3 el conjunto boquense con Varela y Fern\u00e1ndez como conductores, y dos veces estuvo Eduardo Salvio cerca de romper la paridad, primero con un mano a mano que gan\u00f3 el arquero Cassio y sobre el ep\u00edlogo con un cabezazo en la boca del \u00e1rea chica tras un preciso centro de \u00d3scar Romero que se fue junto al poste derecho.<\/p>\n<figure class=\"mb-3\"><img loading=\"lazy\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/05\/boca-igualo-con-corinthians-y-ahora-se-juega-todo-la-semana-que-viene-ante-deportivo-cali-5.jpg\" width=\"100%\" height=\"100%\" alt=\"Foto Maximiliano Luna\"><figcaption> (Foto: Maximiliano Luna). <\/figcaption><\/figure>\n<p>Y con esa posibilidad se esfum\u00f3 tambi\u00e9n la chance de que Boca empezara a ajustar su clasificaci\u00f3n a octavos de final, ya que con el empate no modific\u00f3 su status quo en el grupo, que sigue siendo encabezado por Corinthians, ahora con 8 unidades (los brasile\u00f1os tambi\u00e9n son tambi\u00e9n \u00fanicos punteros del Brasileirao), seguido por el \u00abxeneize\u00bb con 7, pero si Deportivo Cali (5) le gana el jueves a Always Ready (4) lo superar\u00e1.<\/p>\n<p><strong>A favor tendr\u00e1 Boca sin embargo que todo depender\u00e1 de si mismo, porque justamente el jueves 26 de mayo recibir\u00e1 a los colombianos en la Bombonera para cerrar la fase de grupos<\/strong>, y siempre y cuando se de la victoria de estos sobre los bolivianos, el equipo de la \u00abRibera\u00bb se terminar\u00e1 clasificando en caso de salir victorioso, sin depender de lo que ocurra en San Pablo entre Corinthians y Always Ready.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(Foto: Maximiliano Luna). Boca empat\u00f3 esta noche 1 a 1 como local ante Corinthians, de Brasil, y sigue ocupando el segundo puesto de la Zona E de la Copa Libertadores detr\u00e1s de su rival de este martes, aunque depende de s\u00ed mismo para clasificarse a octavos de final cuando en la sexta y \u00faltima fecha [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":41705,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[16],"tags":[],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/41704"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=41704"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/41704\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media\/41705"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=41704"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=41704"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=41704"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}