{"id":41323,"date":"2022-05-10T19:01:31","date_gmt":"2022-05-10T19:01:31","guid":{"rendered":"https:\/\/www.espinof.com\/actores-y-actrices\/guardianes-galaxia-3-dave-bautista-se-despide-drax-afirma-que-pelicula-final-viaje-que-cambio-mi-vida"},"modified":"2022-05-10T19:01:31","modified_gmt":"2022-05-10T19:01:31","slug":"guardianes-de-la-galaxia-3-dave-bautista-se-despide-de-drax-y-afirma-que-la-pelicula-es-el-final-de-un-viaje-que-cambio-mi-vida","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2022\/05\/10\/guardianes-de-la-galaxia-3-dave-bautista-se-despide-de-drax-y-afirma-que-la-pelicula-es-el-final-de-un-viaje-que-cambio-mi-vida\/","title":{"rendered":"&#8216;Guardianes de la Galaxia 3&#8217;: Dave Bautista se despide de Drax y afirma que la pel\u00edcula es \u00abel final de un viaje que cambi\u00f3 mi vida\u00bb"},"content":{"rendered":"<p>El rodaje de la muy esperada <a href=\"https:\/\/www.espinof.com\/tag\/guardianes-de-la-galaxia-vol-3\">&#8216;Guardianes de la Galaxia Vol. 3&#8217;<\/a> lleg\u00f3 a su final hace apenas unos d\u00edas. Todav\u00eda tendremos que esperar hasta el 5 de mayo de 2023 para ver esta aventura de <a href=\"https:\/\/www.espinof.com\/listas\/marvel-que-orden-conviene-ver-todas-peliculas-superheroes-mcu\">Marvel<\/a>, pero una cosa que parece ha quedado bastante clara es que <strong>ser\u00e1 la \u00faltima vez que Dave Bautista interprete a Drax.<\/strong><\/p>\n<p><!-- BREAK 1 --><\/p>\n<h2>El mensaje de Bautista<\/h2>\n<p>El antiguo luchador de <a href=\"https:\/\/www.espinof.com\/deportes\/pressing-catch-el-arte-de-las-peleas-sin-sentido\">&#8216;Pressing Catch&#8217;<\/a> ha publicado <a href=\"https:\/\/www.instagram.com\/p\/CdV2CrxONF5\/\">un mensaje<\/a> un mensaje en su cuenta de Instagram sobre \u00ab<em>el final del viaje que cambi\u00f3 mi vida<\/em>\u00bb refiri\u00e9ndose a la tercera entrega de la trilog\u00eda dirigida por <strong>James Gunn.<\/strong> Adem\u00e1s, Bautista no ha dudado en utilizar el hashtag #GoodbyeDrax por si quedaba alg\u00fan tipo de duda:<\/p>\n<p><!-- BREAK 2 --> <\/p>\n<div class=\"article-asset article-asset-normal article-asset-center\">\n<div class=\"desvio-container\">\n<div class=\"desvio\">\n<div class=\"desvio-figure js-desvio-figure\"> <a href=\"https:\/\/www.espinof.com\/listas\/mejores-peliculas-superheroes-decada-2010-2019\"> <img alt=\"Las 29 mejores pel\u00edculas de superh\u00e9roes de la d\u00e9cada (2010-2019)\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/05\/guardianes-de-la-galaxia-3-dave-bautista-se-despide-de-drax-y-afirma-que-la-pelicula-es-el-final-de-un-viaje-que-cambio-mi-vida.jpg\"> <\/a> <\/div><\/div><\/div>\n<\/div>\n<blockquote><p>Todav\u00eda no he encontrado las palabras. Termin\u00f3 tan repentinamente y yo estaba en mi siguiente pel\u00edcula antes de poder procesarlo todo. El final de un viaje que cambi\u00f3 mi vida.<\/p><\/blockquote>\n<p>Lo cierto es que Gunn <a href=\"https:\/\/collider.com\/guardians-of-the-galaxy-3-james-gunn-final-film-comments\/\">ya coment\u00f3<\/a> hace unos meses que &#8216;Guardianes de la Galaxia Vol. 3&#8217; era <strong>la \u00faltima pel\u00edcula con estos miembros del equipo de superh\u00e9roes.<\/strong> Sigue quedando la duda sobre si se refer\u00eda a que algunos personajes desaparecen o si va a ser una renovaci\u00f3n total. Por lo pronto, ya podemos dar por perdido a Drax.<\/p>\n<p><!-- BREAK 3 --><\/p>\n<p>Eso s\u00ed, nos quedan por ver al menos <strong>otra pel\u00edcula que Bautista retoma el personaje de Drax<\/strong>, pues los Guardianes de la Galaxia tambi\u00e9n har\u00e1n acto de presencia en <a href=\"https:\/\/www.espinof.com\/fecha-de-estreno\/thor-love-and-thunder-todo-que-sabemos-pelicula-marvel-protagonizada-chris-hemsworth-natalie-portman\">&#8216;Thor: Love and Thunder&#8217;<\/a>, cuya llegada a los cines est\u00e1 prevista para el pr\u00f3ximo 8 de julio. Sin duda, <a href=\"https:\/\/www.espinof.com\/listas\/peliculas-estreno-esperadas-2022\">uno de los estrenos m\u00e1s esperados del a\u00f1o.<\/a><\/p>\n<p><!-- BREAK 4 --><\/p>\n<div class=\"article-asset article-asset-normal article-asset-center\">\n<div class=\"desvio-container\">\n<div class=\"desvio\">\n<div class=\"desvio-figure js-desvio-figure\"> <a href=\"https:\/\/www.espinof.com\/listas\/marvel-que-orden-conviene-ver-todas-peliculas-superheroes-mcu\"> <img alt=\"\u00a1Vengadores, un\u00edos! En qu\u00e9 orden conviene ver todas las pel\u00edculas y series del Universo Marvel\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/05\/guardianes-de-la-galaxia-3-dave-bautista-se-despide-de-drax-y-afirma-que-la-pelicula-es-el-final-de-un-viaje-que-cambio-mi-vida-1.jpg\"> <\/a> <\/div><\/div><\/div>\n<\/div>\n<p><strong>Chris Pratt, Zoe Salda\u00f1a,, Vin Diesel, Bradley Cooper, Karen Gillan, Pom Klementieff, Sean Gunn y Sylvester Stallone<\/strong> tambi\u00e9n retomar\u00e1n en &#8216;Guardianes de la Galaxia Vol. 3&#8217; los personajes que interpretaron en anteriores entregas. Adem\u00e1s, se suma al reparto Will Poulter para dar vida <a href=\"https:\/\/www.espinof.com\/actores-y-actrices\/guardians-of-the-galaxy-vol-3-will-poulter-sera-adam-warlock-cierre-trilogia-james-wann-para-marvel\">al gran villano de la funci\u00f3n<\/a>.<\/p>\n<p><!-- BREAK 5 --> <\/p>\n","protected":false},"excerpt":{"rendered":"<p>El rodaje de la muy esperada &#8216;Guardianes de la Galaxia Vol. 3&#8217; lleg\u00f3 a su final hace apenas unos d\u00edas. Todav\u00eda tendremos que esperar hasta el 5 de mayo de 2023 para ver esta aventura de Marvel, pero una cosa que parece ha quedado bastante clara es que ser\u00e1 la \u00faltima vez que Dave Bautista [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":41324,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/41323"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=41323"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/41323\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media\/41324"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=41323"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=41323"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=41323"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}