{"id":40862,"date":"2022-05-01T16:30:48","date_gmt":"2022-05-01T16:30:48","guid":{"rendered":"https:\/\/www.espinof.com\/criticas\/the-green-hornet-avispon-verde-era-blockbuster-perfecto-adaptacion-llena-humor-accion-hermosa-decada-pasada"},"modified":"2022-05-01T16:30:48","modified_gmt":"2022-05-01T16:30:48","slug":"the-green-hornet-el-avispon-verde-era-el-blockbuster-perfecto-una-adaptacion-llena-de-humor-con-la-accion-mas-hermosa-de-la-decada-pasada","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2022\/05\/01\/the-green-hornet-el-avispon-verde-era-el-blockbuster-perfecto-una-adaptacion-llena-de-humor-con-la-accion-mas-hermosa-de-la-decada-pasada\/","title":{"rendered":"&#8216;The Green Hornet (El avisp\u00f3n verde)&#8217; era el blockbuster perfecto: una adaptaci\u00f3n llena de humor con la acci\u00f3n m\u00e1s hermosa de la d\u00e9cada pasada"},"content":{"rendered":"<p>Nadie habr\u00eda apostado por un blockbuster de acci\u00f3n protagonizado por el rey de la comedia fumeta y dirigido por el rey del artisteo del momento, el realizador de &#8216;<a href=\"https:\/\/www.espinof.com\/criticas\/olvidate-de-mi-embriagador-y-amargo-amor\">Olv\u00eddate de m\u00ed<\/a>&#8216; o &#8216;<a href=\"https:\/\/www.espinof.com\/criticas\/la-ciencia-del-sueno-el-alquimista-de-mundos\">La ciencia del sue\u00f1o<\/a>&#8216;, <a href=\"https:\/\/www.espinof.com\/tag\/michel-gondry\">Michel Gondry<\/a>.Basada en el serial radiof\u00f3nico de los a\u00f1os 30, con un villano rid\u00edculo y divertid\u00edsimo encarnado por <a href=\"https:\/\/www.espinof.com\/tag\/christoph-waltz\">Christoph Waltz<\/a>, la a\u00f1orada <a href=\"https:\/\/www.espinof.com\/tag\/cameron-diaz\">Cameron Diaz<\/a> y la presencia de Jay Chou, &#8216;<strong>The Green Hornet<\/strong>&#8216; era <strong>el blockbuster perfecto<\/strong> y nadie se dio cuenta.<\/p>\n<p><!-- BREAK 1 --><\/p>\n<h2>El gran h\u00e9roe americano<\/h2>\n<p>En un mundo perfecto, teniendo en cuenta que la pel\u00edcula se estren\u00f3 hace poco m\u00e1s de diez a\u00f1os, estar\u00edamos ahora con una tercera entrega m\u00e1s o menos reciente del personaje, pero el mundo no es como a nosotros nos gustar\u00eda. La <strong>inversi\u00f3n de 120 millones de d\u00f3lares<\/strong> de Neal H. Moritz, productor de obras maestras como las dos pel\u00edculas basadas en Jump Street de <a href=\"https:\/\/www.espinof.com\/tag\/phil-lord\">Phil Lord y Christopher Miller<\/a> o &#8216;<strong>Tres idiotas y una bruja<\/strong>&#8216;, <strong>la incre\u00edble comedia m\u00e1s perfecta<\/strong> del a\u00f1o 2000, tampoco es que fuera un fiasco.<\/p>\n<p><!-- BREAK 2 --> <\/p>\n<div class=\"article-asset article-asset-normal article-asset-center\">\n<div class=\"desvio-container\">\n<div class=\"desvio\">\n<div class=\"desvio-figure js-desvio-figure\"> <a href=\"https:\/\/www.espinof.com\/listas\/mejores-series-basadas-peliculas\"> <img alt=\"Cuando las pel\u00edculas originan grandes series: 17 adaptaciones televisivas que encontraron su propia voz\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/05\/the-green-hornet-el-avispon-verde-era-el-blockbuster-perfecto-una-adaptacion-llena-de-humor-con-la-accion-mas-hermosa-de-la-decada-pasada.jpg\"> <\/a> <\/div><\/div><\/div>\n<\/div>\n<p>&#8216;<strong>El avisp\u00f3n verde<\/strong>&#8216; casi recaud\u00f3 el doble de su presupuesto con una recaudaci\u00f3n de cerca de 230 millones en todo el mundo, pero las expectativas eran mucho m\u00e1s ambiciosas, la respuesta cr\u00edtica no fue demasiado cari\u00f1osa y, bueno, la industria. Pero nada de eso importa porque podemos disfrutar cuando nos venga en gana de <strong>uno de los guiones mejor medidos de Seth Rogen y Evan Goldberg<\/strong> para un acontecimiento que en realidad se parece a una de las fiestas de su necio protagonista.<\/p>\n<p><!-- BREAK 3 --><\/p>\n<div class=\"article-asset-image article-asset-normal article-asset-center\">\n<div class=\"asset-content\">\n<div class=\"base-wrapper-image\"> <img class=\"sf-lazy centro_sinmarco\" data-sf-srcset=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/05\/the-green-hornet-el-avispon-verde-era-el-blockbuster-perfecto-una-adaptacion-llena-de-humor-con-la-accion-mas-hermosa-de-la-decada-pasada-1.jpg 450w, http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/05\/the-green-hornet-el-avispon-verde-era-el-blockbuster-perfecto-una-adaptacion-llena-de-humor-con-la-accion-mas-hermosa-de-la-decada-pasada-6.jpg 681w,http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/05\/the-green-hornet-el-avispon-verde-era-el-blockbuster-perfecto-una-adaptacion-llena-de-humor-con-la-accion-mas-hermosa-de-la-decada-pasada-7.jpg 1024w, http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/05\/the-green-hornet-el-avispon-verde-era-el-blockbuster-perfecto-una-adaptacion-llena-de-humor-con-la-accion-mas-hermosa-de-la-decada-pasada-8.jpg 1366w,\" data-sf-src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/05\/the-green-hornet-el-avispon-verde-era-el-blockbuster-perfecto-una-adaptacion-llena-de-humor-con-la-accion-mas-hermosa-de-la-decada-pasada-1.jpg\" alt=\"The Green Hornet\"> <noscript><img alt=\"The Green Hornet\" class=\"centro_sinmarco\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/05\/the-green-hornet-el-avispon-verde-era-el-blockbuster-perfecto-una-adaptacion-llena-de-humor-con-la-accion-mas-hermosa-de-la-decada-pasada-1.jpg\"><\/noscript> <\/div><\/div>\n<\/div>\n<p>La pel\u00edcula de Gondry es <strong>divertida, trepidante y realmente hermosa<\/strong>, pero es que el veneno de este aguij\u00f3n es su inigualable estilo de comedia creciente con alivios en forma de elegantes explosiones. S\u00ed, es una pel\u00edcula tan loca que los alivios no son c\u00f3micos, son de acci\u00f3n. El mundo al rev\u00e9s. Misi\u00f3n cumplida.<\/p>\n<p><!-- BREAK 4 --><\/p>\n<p>Llena de hallazgos visuales, piruetas imposibles y el Gondry del videoclip buscando su lugar en la cima del mundo, &#8216;The Green Hornet&#8217; era <strong>un ejemplar blockbuster de acci\u00f3n<\/strong> como ning\u00fan otro. Un <del>perro <\/del>avisp\u00f3n verde que lo puso todo de su parte para agradar a una platea que hace once a\u00f1os ya estaba necesitada de <strong>cine de evasi\u00f3n algo m\u00e1s adulto<\/strong> que el habitual.<\/p>\n<p><!-- BREAK 5 --><\/p>\n<p>Lo cierto es que su taquilla es mucho m\u00e1s digna de lo que uno podr\u00eda pensar en una \u00e9poca en la que las <strong>producciones y adaptaciones de c\u00f3mics<\/strong> iban a devorar la maquinaria. Seth Rogen y Michel Gondry apostaron por un personaje menos emblem\u00e1tico, pero tambi\u00e9n mucho m\u00e1s libre, al que poder insuflar su estilo sin apenas riesgo de provocar la ira de alg\u00fan fan pasado de rosca. Aunque seguro que se encontraron a m\u00e1s de uno.<\/p>\n<p><!-- BREAK 6 --><\/p>\n<div class=\"article-asset-image article-asset-normal article-asset-center\">\n<div class=\"asset-content\">\n<div class=\"base-wrapper-image\"> <img class=\"sf-lazy centro_sinmarco\" data-sf-srcset=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/05\/the-green-hornet-el-avispon-verde-era-el-blockbuster-perfecto-una-adaptacion-llena-de-humor-con-la-accion-mas-hermosa-de-la-decada-pasada-2.jpg 450w, http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/05\/the-green-hornet-el-avispon-verde-era-el-blockbuster-perfecto-una-adaptacion-llena-de-humor-con-la-accion-mas-hermosa-de-la-decada-pasada-9.jpg 681w,http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/05\/the-green-hornet-el-avispon-verde-era-el-blockbuster-perfecto-una-adaptacion-llena-de-humor-con-la-accion-mas-hermosa-de-la-decada-pasada-10.jpg 1024w, http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/05\/the-green-hornet-el-avispon-verde-era-el-blockbuster-perfecto-una-adaptacion-llena-de-humor-con-la-accion-mas-hermosa-de-la-decada-pasada-11.jpg 1366w,\" data-sf-src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/05\/the-green-hornet-el-avispon-verde-era-el-blockbuster-perfecto-una-adaptacion-llena-de-humor-con-la-accion-mas-hermosa-de-la-decada-pasada-2.jpg\" alt=\"Kato\"> <noscript><img alt=\"Kato\" class=\"centro_sinmarco\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/05\/the-green-hornet-el-avispon-verde-era-el-blockbuster-perfecto-una-adaptacion-llena-de-humor-con-la-accion-mas-hermosa-de-la-decada-pasada-2.jpg\"><\/noscript> <\/div><\/div>\n<\/div>\n<p>Hijo de un magnate de la prensa, arrogante, irresponsable y ego\u00edsta, Britt lleva una vida de desenfreno hasta que su padre muere de manera repentina. Pronto conoce al ch\u00f3fer de su padre, Kato (Jay Chou), un joven enigm\u00e1tico, genio mec\u00e1nico y espectacular barista. Juntos, unidos por el hast\u00edo y el aburrimiento, Britt y Kato se convertir\u00e1n, casi a su pesar, en <strong>los salvadores enmascarados de los barrios marginales<\/strong> de Los \u00c1ngeles. Algo que por supuesto pondr\u00e1 de los nervios al rid\u00edculo Chudnofsky, villano de la funci\u00f3n.<\/p>\n<p><!-- BREAK 7 --><\/p>\n<p>La clave de la eficacia de la pel\u00edcula de Gondry se encuentra en sus di\u00e1logos, r\u00e9plicas y la total libertad de Rogen y Goldberg con el material de partida. El resultado es una comedia divertid\u00edsima, con espectaculares dosis de acci\u00f3n y aventuras que <strong>recuerda los \u00e9xitos de taquilla de la d\u00e9cada de los 80<\/strong> con clase y brillantez.<\/p>\n<p><!-- BREAK 8 --><\/p>\n<div class=\"article-asset-image article-asset-normal article-asset-center\">\n<div class=\"asset-content\">\n<div class=\"base-wrapper-image\"> <img class=\"sf-lazy centro_sinmarco\" data-sf-srcset=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/05\/the-green-hornet-el-avispon-verde-era-el-blockbuster-perfecto-una-adaptacion-llena-de-humor-con-la-accion-mas-hermosa-de-la-decada-pasada-3.jpg 450w, http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/05\/the-green-hornet-el-avispon-verde-era-el-blockbuster-perfecto-una-adaptacion-llena-de-humor-con-la-accion-mas-hermosa-de-la-decada-pasada-12.jpg 681w,http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/05\/the-green-hornet-el-avispon-verde-era-el-blockbuster-perfecto-una-adaptacion-llena-de-humor-con-la-accion-mas-hermosa-de-la-decada-pasada-13.jpg 1024w, http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/05\/the-green-hornet-el-avispon-verde-era-el-blockbuster-perfecto-una-adaptacion-llena-de-humor-con-la-accion-mas-hermosa-de-la-decada-pasada-14.jpg 1366w,\" data-sf-src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/05\/the-green-hornet-el-avispon-verde-era-el-blockbuster-perfecto-una-adaptacion-llena-de-humor-con-la-accion-mas-hermosa-de-la-decada-pasada-3.jpg\" alt=\"The Green Hornet 2011\"> <noscript><img alt=\"The Green Hornet 2011\" class=\"centro_sinmarco\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/05\/the-green-hornet-el-avispon-verde-era-el-blockbuster-perfecto-una-adaptacion-llena-de-humor-con-la-accion-mas-hermosa-de-la-decada-pasada-3.jpg\"><\/noscript> <\/div><\/div>\n<\/div>\n<p>Aqu\u00ed nadie est\u00e1 interesado en encontrar un nuevo Batman ni un futuro trepamuros. El Britt Reid\/Green Hornet de Rogen <strong>es idiota, cobarde, mis\u00f3gino y siempre tronchante<\/strong>. Puede que en realidad esa fuera su losa: mientras todos estaban buscando <strong>h\u00e9roes torturados, grandes poderes y responsabilidades<\/strong>, llegaron estos tipos a montar jaleo desde la primera secuencia. En ella un hilarante <a href=\"https:\/\/www.espinof.com\/tag\/james-franco\">James Franco<\/a> intenta marcar territorio con unas l\u00edneas desternillantes para abrir el juego.<\/p>\n<p><!-- BREAK 9 --><\/p>\n<div class=\"article-asset article-asset-normal article-asset-center\">\n<div class=\"desvio-container\">\n<div class=\"desvio\">\n<div class=\"desvio-figure js-desvio-figure\"> <a href=\"https:\/\/www.espinof.com\/estrenos\/the-batman-peliculas-que-parecen-miniseries-matt-reeves-firma-modernizacion-mitologia-detectivesca-dc-estructura-episodica\"> <img alt=\"'The Batman' y las pel\u00edculas que parecen miniseries: Matt Reeves firma una modernizaci\u00f3n de la mitolog\u00eda detectivesca de DC con estructura epis\u00f3dica\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/05\/the-green-hornet-el-avispon-verde-era-el-blockbuster-perfecto-una-adaptacion-llena-de-humor-con-la-accion-mas-hermosa-de-la-decada-pasada-4.jpg\"> <\/a> <\/div><\/div><\/div>\n<\/div>\n<p>La impronta de Gondry es visible constantemente, sobre todo en el incre\u00edble y nunca superado <strong>plano secuencia m\u00faltiple<\/strong>, una escena que seguramente hizo muy feliz a <a href=\"https:\/\/www.espinof.com\/listas\/mejores-peliculas-brian-palma-ordenadas-peor-a-mejor\">Brian De Palma<\/a>. Pero tambi\u00e9n hay mucho del Gondry m\u00e1s rom\u00e1ntico, lo que hace de &#8216;The Green Hornet&#8217; un entretenimiento absurdo, necesario y, qu\u00e9 putada, irrepetible.<\/p>\n<p><!-- BREAK 10 --><\/p>\n<p>Ahora que Sony \/ Columbia se encarga de los blockbusters m\u00e1s casposos imaginables (&#8216;Venom&#8217;), del fandom m\u00e1s empalagoso (&#8216;Spider-Man: No Way Home&#8217;) y de los comebacks m\u00e1s repelentes (&#8216;Cazafantasmas: M\u00e1s all\u00e1&#8217;) supongo que <strong>no tenemos ning\u00fan derecho a quejarnos<\/strong> cuando dejamos pasar gemas como este avisp\u00f3n nocturno. Qu\u00e9 pena, eh.<\/p>\n<p><!-- BREAK 11 --> <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nadie habr\u00eda apostado por un blockbuster de acci\u00f3n protagonizado por el rey de la comedia fumeta y dirigido por el rey del artisteo del momento, el realizador de &#8216;Olv\u00eddate de m\u00ed&#8216; o &#8216;La ciencia del sue\u00f1o&#8216;, Michel Gondry.Basada en el serial radiof\u00f3nico de los a\u00f1os 30, con un villano rid\u00edculo y divertid\u00edsimo encarnado por Christoph [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":40863,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/40862"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=40862"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/40862\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media\/40863"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=40862"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=40862"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=40862"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}