{"id":4006,"date":"2020-10-26T19:34:13","date_gmt":"2020-10-26T19:34:13","guid":{"rendered":"https:\/\/www.perfil.com\/noticias\/politica\/cristina-kirchner-hablo-sobre-el-dolar-no-es-un-problema-ideologico-no-es-de-izquierda-ni-derecha.phtml"},"modified":"2020-10-26T19:34:13","modified_gmt":"2020-10-26T19:34:13","slug":"cristina-kirchner-hablo-sobre-el-dolar-no-es-un-problema-ideologico-no-es-de-izquierda-ni-derecha","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2020\/10\/26\/cristina-kirchner-hablo-sobre-el-dolar-no-es-un-problema-ideologico-no-es-de-izquierda-ni-derecha\/","title":{"rendered":"Cristina Kirchner habl\u00f3 sobre el d\u00f3lar: \u00abNo es un problema ideol\u00f3gico, no es de izquierda ni derecha\u00bb"},"content":{"rendered":"<p><img src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2020\/10\/cristina-kirchner-hablo-sobre-el-dolar-no-es-un-problema-ideologico-no-es-de-izquierda-ni-derecha.jpg\"><\/p>\n<div><img src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2020\/10\/cristina-kirchner-hablo-sobre-el-dolar-no-es-un-problema-ideologico-no-es-de-izquierda-ni-derecha-2.jpg\" class=\"ff-og-image-inserted\"><\/div>\n<aside class=\"relatedPost\">\n<h3>Noticias Relacionadas<\/h3>\n<\/aside>\n<p><strong>La vicepresidenta Cristina Kirchner escribi\u00f3 una carta p\u00fablica<\/strong> <a target=\"_blank\" href=\"https:\/\/www.perfil.com\/noticias\/politica\/cinco-anecdotas-sobre-la-muerte-de-nestor-kirchner.phtml\" rel=\"noopener noreferrer\"><strong>a prop\u00f3sito de los diez a\u00f1os de la muerte de N\u00e9stor Kirchner<\/strong><\/a> con \u00abtres certezas\u00bb. Una de ellas fue sobre el problema del d\u00f3lar. \u00abNo es un problema ideol\u00f3gico, no es de izquierda ni de derecha. Todos los gobiernos nos topamos con ello\u00bb, explic\u00f3.&nbsp;<\/p>\n<p>Cristina tambi\u00e9n consider\u00f3 que hay un ataque permanente <a target=\"_blank\" href=\"https:\/\/www.perfil.com\/noticias\/politica\/beatriz-sarlo-pense-que-alberto-fernandez-era-un-hombre-ambicioso.phtml\" rel=\"noopener noreferrer\">a la figura de Alberto Fern\u00e1ndez<\/a>. Y sugiri\u00f3 que hay funcionarios y funcionarias que no hacen bien su trabajo, aunque sin dar nombres. Tambi\u00e9n adelant\u00f3 que <a target=\"_blank\" href=\"https:\/\/www.perfil.com\/noticias\/politica\/estatua-en-cck-caravana-mil-flores-como-sera-homenaje-nestor-kirchner.phtml\" rel=\"noopener noreferrer\">no participar\u00e1 del acto aniversario.&nbsp;<\/a><\/p>\n<p>En la carta, la vicepresidenta explic\u00f3 su teor\u00eda sobre la dificultad de los gobiernos para resolver <a target=\"_blank\" href=\"https:\/\/www.perfil.com\/noticias\/economia\/el-super-cepo-acelero-la-fuga-de-capitales-y-economistas-piden-medidas-urgentes.phtml\" rel=\"noopener noreferrer\">la brecha con el d\u00f3lar<\/a>. Lo abord\u00f3 en la tercera certeza.&nbsp;<\/p>\n<h2>Dijo sobre el d\u00f3lar<\/h2>\n<ul>\n<li>\u00abEl problema de la econom\u00eda bimonetaria no es ideol\u00f3gico. No es de izquierda ni de derecha. Ni siquiera del centro. Y no hay prueba m\u00e1s objetiva de esto que la alternancia de modelos pol\u00edticos y econ\u00f3micos opuestos que se oper\u00f3 el 10 de diciembre de 2015\u00bb.<\/li>\n<\/ul>\n<ul readability=\"14\">\n<li>\u00abTodos los gobiernos nos hemos topado con \u00e9l. Unos intentamos gestionarlo con responsabilidad, desendeudando al pa\u00eds en un marco de inclusi\u00f3n social y desarrollo industrial. Otros de orientaci\u00f3n inversa -como el de Mauricio Macri- siempre han \u201cchocado la calesita\u201d con endeudamiento y fuga. Pero lo cierto es que ese funcionamiento bimonetario es un problema estructural de la econom\u00eda argentina\u00bb.&nbsp;<\/li>\n<li readability=\"7\">\n<p>\u00abTampoco es una cuesti\u00f3n de clase: los d\u00f3lares los compran tanto trabajadores para ahorrar o para hacer una diferencia que mejore el salario, como empresarios para pagar las importaciones necesarias para hacer funcionar su empresa, para ahorrar y tambi\u00e9n, bueno es decirlo, para fugar formando activos financieros en el exterior, siendo esta \u00faltima actitud una de las que m\u00e1s han contribu\u00eddo a las crisis c\u00edclicas de la Argentina\u00bb.&nbsp;<\/p>\n<\/li>\n<li readability=\"3\">\n<p>\u00abTampoco es producto de las experiencias hiperinflacionarias de la Argentina. Circula en redes un peque\u00f1o video de un reconocido humorista ya fallecido, sobre la pasi\u00f3n nacional por el d\u00f3lar. El video data de 1962: Arturo Illia no hab\u00eda asumido como Presidente y Ra\u00fal Alfons\u00edn estar\u00eda todav\u00eda de pantalones cortos en Chascom\u00fas. La coartada de la \u201chiper\u201d para explicar el problema es tambi\u00e9n insuficiente. Basta recordar a Per\u00f3n Presidente en la d\u00e9cada del \u201950 preguntando: \u201c\u00bfAlguien vi\u00f3 alguna vez un d\u00f3lar?\u201d\u00bb<\/p>\n<\/li>\n<li readability=\"9\">\n<p>\u00abTercera certeza: la Argentina es ese extra\u00f1o lugar en donde mueren todas las teor\u00edas. Por eso, el problema de la econom\u00eda bimonetaria que es, sin dudas, el m\u00e1s grave que tiene nuestro pa\u00eds, <strong>es de imposible soluci\u00f3n sin un acuerdo que abarque al conjunto de los sectores pol\u00edticos, econ\u00f3micos, medi\u00e1ticos y sociales de la Rep\u00fablica Argentina<\/strong>. Nos guste o no nos guste, esa es la realidad y con ella se puede hacer cualquier cosa menos ignorarla\u00bb.<\/p>\n<\/li>\n<li readability=\"3\">\n<p>\u00abEs que la Argentina es el \u00fanico pa\u00eds con una econom\u00eda bimonetaria: se utiliza el peso argentino que el pa\u00eds emite para las transacciones cotidianas y el d\u00f3lar estadounidense que el pa\u00eds -obviamente- no emite, como moneda de ahorro y para determinadas transacciones como las que tienen lugar en el mercado inmobiliario. \u00bfAlguien puede pensar seriamente que la econom\u00eda de un pa\u00eds pueda funcionar con normalidad de esa manera?\u00bb<\/p>\n<\/li>\n<\/ul>\n<blockquote class=\"twitter-tweet\" readability=\"4.685393258427\">\n<p lang=\"es\" dir=\"ltr\">Ma\u00f1ana&#8230; 27 de octubre.<br \/>A diez a\u00f1os sin \u00e9l y a uno del triunfo electoral: sentimientos y certezas.<a href=\"https:\/\/t.co\/vzo5Vziiw5\">https:\/\/t.co\/vzo5Vziiw5<\/a><\/p>\n<p>\u2014 Cristina Kirchner (@CFKArgentina) <a href=\"https:\/\/twitter.com\/CFKArgentina\/status\/1320802414774095875?ref_src=twsrc%5Etfw\">October 26, 2020<\/a><\/p><\/blockquote>\n<h2>Sobre su relaci\u00f3n con Alberto Fern\u00e1ndez<\/h2>\n<p>Pero Cristina Kirchner tambi\u00e9n habl\u00f3 sobre su relaci\u00f3n con Alberto Fern\u00e1ndez y ratific\u00f3 que es \u00e9l y no ella el que manda en Argentina. \u00abEl relato del \u201cPresidente t\u00edtere\u201d lo utilizaron con N\u00e9stor respecto de Duhalde, conmigo respecto de N\u00e9stor y, ahora, con Alberto respecto de m\u00ed\u00bb, escribi\u00f3.<\/p>\n<ul>\n<li>\u00abSegunda certeza: en la Argentina el que decide es el Presidente. Puede gustarte o no lo que decida, pero el que decide es \u00e9l. Que nadie te quiera convencer de lo contrario. Si alguien intentara hacerlo, preguntale que intereses lo o la mueven\u00bb, explic\u00f3.<\/li>\n<\/ul>\n<ul>\n<li>La vicepresidenta tambi\u00e9n consider\u00f3 que a Alberto lo castiga y no es por las formas que le criticaban a ella. \u00abCastigan al Presidente como si tuviera las mismas formas que tanto me criticaron durante a\u00f1os. A esta altura ya resulta inocultable que, en realidad, el problema nunca fueron las formas. En realidad, lo que no aceptan es que el peronismo volvi\u00f3 al gobierno y que la apuesta pol\u00edtica y medi\u00e1tica de un gobierno de empresarios con Mauricio Macri a la cabeza, fracas\u00f3\u00bb, indic\u00f3.<\/li>\n<\/ul>\n<ul>\n<li>\u00abEs notable, sobre todo en el empresariado argentino, el prejuicio antiperonista. Notable y adem\u00e1s inentendible si uno mira los resultados de los balances de esas empresas durante la gesti\u00f3n de los gobiernos peronistas o kirchneristas -como m\u00e1s les guste-. Este prejuicio no encuentra explicaci\u00f3n ni desde la pol\u00edtica, ni desde la econom\u00eda, y a esta altura me permito decir que ni siquiera desde la psicolog\u00eda\u2026 aunque ya les advert\u00ed que de eso no s\u00e9. Pero no quedan dudas que esta actitud incomprensible ha sido y es una de las dificultades m\u00e1s grandes para encauzar definitivamente a la Argentina\u00bb.<\/li>\n<li>Tambi\u00e9n, la vice se refiri\u00f3 a funcionarios y funcionarias \u00abque no funcionan\u00bb y a aciertos \u00aby desaciertos\u00bb.&nbsp;<\/li>\n<\/ul>\n<p>MC<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Noticias Relacionadas La vicepresidenta Cristina Kirchner escribi\u00f3 una carta p\u00fablica a prop\u00f3sito de los diez a\u00f1os de la muerte de N\u00e9stor Kirchner con \u00abtres certezas\u00bb. Una de ellas fue sobre el problema del d\u00f3lar. \u00abNo es un problema ideol\u00f3gico, no es de izquierda ni de derecha. Todos los gobiernos nos topamos con ello\u00bb, explic\u00f3.&nbsp; Cristina [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4007,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/4006"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=4006"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/4006\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media\/4007"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=4006"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=4006"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=4006"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}